{"id":18598,"date":"2011-06-09T00:00:00","date_gmt":"2011-06-09T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/9-juin-2011\/"},"modified":"2011-06-09T00:00:00","modified_gmt":"2011-06-09T00:00:00","slug":"9-juin-2011","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/9-juin-2011\/","title":{"rendered":"9 juin 2011"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\"PARIS, 09 Jui 2011 (AFP) - \n\t\tDeux organisations non gouvernementales (ONG), Sherpa et Transparence \n\t\tInternational France, ont annonc\u00e9 jeudi le d\u00e9p\u00f4t d'une nouvelle plainte \n\t\t\u00e0 Paris \u00e0 l\u2019encontre de l'ancien pr\u00e9sident tunisien Ben Ali et de son \n\t\tentourage afin d'obtenir la d\u00e9signation d'un juge d'instruction.\" http-equiv=\"Content-Type\"\/><\/head><body><body><\/p>\n<div>\n<div align=\"center\" dir=\"ltr\"><font face=\"Bookman Old Style\" size=\"7\"><strong>TUNISNEWS <\/strong><\/font><\/div>\n<div align=\"center\" dir=\"ltr\"><strong><font face=\"Arial\" size=\"2\">11 \u00e8me ann\u00e9e, N\u00b04034 du 09.06.2011<\/font><\/strong><\/div>\n<div align=\"center\" dir=\"ltr\"><font face=\"Arial\" size=\"2\"><strong>archives : <\/strong><\/font><a target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\"><strong>www.tunisnews.net<\/strong><\/font><\/a><span lang=\"FR\"><strong><font face=\"Arial\" size=\"2\"><\/font><\/strong><\/span><\/div>\n<p><span lang=\"FR\"><\/p>\n<p><font face=\"Arial\" size=\"2\"><\/p>\n<div align=\"center\" dir=\"ltr\">\n<hr\/>\n<\/div>\n<div align=\"left\" dir=\"ltr\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>Reuters: Biens de Ben Ali: deux ONG veulent la d\u00e9signation d&rsquo;une juge d&rsquo;instruction<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>ANSA: Tunisia: ammontano a 55 milioni di franchi beni Ben Ali in Svizzera<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>AFP: Tunisie: le fort afflux de r\u00e9fugi\u00e9s libyens se poursuit<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Conseil JAI : lettre ouverte de d\u00e9put\u00e9s europ\u00e9ens aux ministres de l\u2019int\u00e9rieur de l\u2019ue sur le cas des migrants tunisiens<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>La Presse: Transition d\u00e9mocratique &#8211; Election de la Constituante : J \u2013137<\/strong><\/font><\/h2>\n<\/div>\n<div>\n<p><font face=\"Arial\" size=\"2\"><strong><font>Le Temps: Ce sera le 23 octobre et avec 50 &#8211; 50 entre femmes et hommes Un arrangement plut\u00f4t qu\u2019une Constituante au forceps<\/font> <\/strong><\/font><\/p>\n<\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>Kapitalis : Tunisie. La \u00abr\u00e9conciliation nationale\u00bb selon Yadh Ben Achour<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Tribune de Gen\u00e8ve : Venez faire revivre l\u2019image de cette Tunisie qui \u00abchante et qui danse\u00bb<\/strong><\/font><\/div>\n<div>\n<p><font face=\"Arial\" size=\"2\"><strong>Afrik.com: Des membres de l\u2019ex-parti au pouvoir soup\u00e7onn\u00e9s d\u2019\u00eatre impliqu\u00e9s dans les violences tribales de Metlaoui<\/strong><\/font><\/p>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Kapitalis: La veille strat\u00e9gique pour le maintien du tourisme en Tunisie<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>Reuters: Kadhafi a encourag\u00e9 les viols d&rsquo;opposants &#8211; procureur de la CPI<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>AFP: La perspective d&rsquo;une guerre civile plane sur la Syrie<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>AFP: Mosqu\u00e9e et Facebook : les deux vecteurs de la contestation en Syrie<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Reuters: Les \u00e9lections l\u00e9gislatives en Turquie<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>AFP: Turquie: un mode de scrutin qui favorise les grands partis<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>AFP: Erdogan, recordman de long\u00e9vit\u00e9 politique, figure charismatique et controvers\u00e9e<\/strong><\/font><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>AFP: Erdogan brigue un troisi\u00e8me mandat, durcit le ton contre l&rsquo;opposition<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Reuters: Erdogan: The boy bread vendor who changed Turkey<\/strong><\/font><\/div>\n<div>\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong>Reuters: Islamic trade finance seen lifting growth of sector<\/strong><\/font><\/h3>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Rue89: Les r\u00e9volutions arabes et la d\u00e9soccidentalisation du monde<\/strong><\/font><\/div>\n<div>\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong>L\u00b4Express: R\u00e9volutions arabes et tourisme sexuel<\/strong><\/font><\/h3>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>My Europ: Cameron d\u00e9fend les \u00ab\u00a0valeurs traditionnelles\u00a0\u00bb contre l&rsquo;islam radical<\/strong><\/font><\/div>\n<div>\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong>Le Temps Suisse: Les Russes d\u00e9couvrent avec incr\u00e9dulit\u00e9 les origines juives de L\u00e9nine<\/strong><\/font><\/h3>\n<p><font face=\"Calibri\"><\/font><\/div>\n<p><font face=\"Arial\" size=\"2\"><\/p>\n<div>\n<hr\/>\n<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Reuters, le 9 juin 2011 \u00e0 09h46 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h3 style=\"color: blue;\"><font face=\"Arial\">Biens de Ben Ali: deux ONG veulent la d\u00e9signation d&rsquo;une juge d&rsquo;instruction<\/font><\/h3>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">PARIS, 09 Jui 2011 (AFP) &#8211; Deux organisations non gouvernementales (ONG), Sherpa et Transparence International France, ont annonc\u00e9 jeudi le d\u00e9p\u00f4t d&rsquo;une nouvelle plainte \u00e0 Paris \u00e0 l\u2019encontre de l&rsquo;ancien pr\u00e9sident tunisien Ben Ali et de son entourage afin d&rsquo;obtenir la d\u00e9signation d&rsquo;un juge d&rsquo;instruction.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Cette plainte avec constitution de partie civile intervient apr\u00e8s<span><\/span>l\u2019ouverture d\u2019une enqu\u00eate pr\u00e9liminaire en janvier cons\u00e9cutive au d\u00e9p\u00f4t d&rsquo;une plainte simple par ces deux ONG.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La plainte vise des faits pr\u00e9sum\u00e9s de d\u00e9tournement de fonds publics, abus de biens sociaux, abus de confiance et blanchiment aggrav\u00e9 commis en bande organis\u00e9e.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;ouverture d&rsquo;une information judiciaire \u00ab\u00a0devrait permettre d\u2019\u00e9tablir le caract\u00e8re licite ou non des avoirs recens\u00e9s sur le sol fran\u00e7ais et d\u2019engager le plus rapidement possible la restitution au peuple tunisien (&#8230;) des avoirs ill\u00e9galement constitu\u00e9s\u00a0\u00bb, ont soulign\u00e9 les deux ONG dans un communiqu\u00e9.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Cette d\u00e9marche nous para\u00eet plus que n\u00e9cessaire compte tenu des faibles avanc\u00e9es de l\u2019enqu\u00eate de police d\u2019une part et des pouvoirs qui sont ceux du juge d\u2019instruction dans la conduite des enqu\u00eates d\u2019autre part\u00a0\u00bb, ont-elles ajout\u00e9.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Sherpa, Transparency International et la Commission arabe des droits humains, avaient port\u00e9 plainte le 19 janvier contre l&rsquo;ancien pr\u00e9sident tunisien, Zine El Abidine Ben Ali et son entourage, quelques jours apr\u00e8s sa fuite en Arabie Saoudite.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le parquet avait ouvert quelques jours plus tard une enqu\u00eate pr\u00e9liminaire pour recenser et identifier l&rsquo;origine des biens d\u00e9tenus en France par l&rsquo;ancien pr\u00e9sident.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Dans le cadre de cette enqu\u00eate, douze comptes appartenant \u00e0 quatre proches du pr\u00e9sident tunisien d\u00e9chu ont \u00e9t\u00e9 r\u00e9cemment saisis en France, pour un montant de 12 millions d&rsquo;euros.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le 1er f\u00e9vrier, la justice fran\u00e7aise avait d\u00e9j\u00e0 saisi \u00e0 l&rsquo;a\u00e9roport du Bourget, pr\u00e8s de Paris, un avion priv\u00e9 appartenant \u00e0 la famille Mabrouk, dont un des membres est un gendre de Ben Ali.<\/font><\/span><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANSA, le 9 juin 2011 \u00e0 10h00 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"IT\"><\/p>\n<h3 style=\"color: blue;\"><font face=\"Arial\">Tunisia: ammontano a 55 milioni di franchi beni Ben Ali in Svizzera<\/font><\/h3>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"IT\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><font size=\"2\"><span lang=\"IT\"><font face=\"Arial\">TUNISI (ansa) Ammontano all&rsquo;equivalente di circa 55 milioni di franchi i beni accumulati dall&rsquo;ex presidente tunisino Zine El Abidine Ben Ali in Svizzera e di cui ora il governo di Tunisi sta cercando di rientrare in possesso.<\/font><\/span><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><span lang=\"IT\"><font face=\"Arial\">Il denaro &#8211; riferisce oggi l&rsquo;agenzia di stampa tunisina Tap \u2013 \u00e8 depositato sia in conti nominativi che cifrati, che intestati a societ\u00e0 di comodo o prestanome riconducibili all&rsquo;ex presidente o ad appartenenti al suo clan familiare.<\/font><\/span><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><span lang=\"IT\"><font face=\"Arial\">Per individuare gli strumenti capaci di fare rientrare in Tunisia i beni, accumulati in oltre vent&rsquo;anni di dittatura da parte di Ben Ali e dei suoi familiari, il primo ministro ad interim tunisino, Beji Caid Essebsi, ha presieduto una riunione tecnica, cui ha partecipato anche Sami Remadi, presidente dell&rsquo;Associazione tunisina per la trasparenza finanziaria, che opera di concerto con il ministero della giustizia.<\/font><\/span><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><span lang=\"IT\"><font face=\"Arial\">La Svizzera ha temporaneamente respinto, perch\u00e9 non sufficientemente motivate, le richieste di assistenza giudiziaria presentate dalle autorit\u00e0 del Cairo e di Tunisi per la restituzione degli averi degli ex presidenti Hosni Mubarak e Ben Ali. Berna aiuter\u00e0 comunque attivamente i due governi a migliorare le domande, affinch\u00e9 diventino conformi alle norme, aveva comunicato in aprile l&rsquo;Ufficio federale di giustizia.<\/font><\/span><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><span lang=\"IT\"><font face=\"Arial\">A inizio maggio la consigliera federale Micheline Calmy-Rey aveva parlato di beni potenzialmente illeciti per un totale di 830 milioni di franchi riconducibili a Ben Ali, Mubarak e al leader libico Muammar Gheddafi.<\/font><\/span><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h3 style=\"color: blue;\"><font size=\"3\"><strong>Tunisie: le fort afflux de r\u00e9fugi\u00e9s libyens se poursuit<\/strong><\/font><\/h3>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div> <font>(AFP) \u2013 Il y a 2 heures TUNIS \u2014 Quelque 6.000 nouveaux r\u00e9fugi\u00e9s libyens fuyant les violences ont franchi la fronti\u00e8re tunisienne au poste de Ras Jedir mercredi, selon l&rsquo;agence officielle TAP, alors que l&rsquo;Otan a intensifi\u00e9 ces derniers jours ses op\u00e9rations militaires dans l&rsquo;ouest de la Libye.<\/font><\/div>\n<div> <font>Environ 200 familles libyennes sont \u00e9galement entr\u00e9es en Tunisie mercredi en empruntant des pistes sahariennes, pr\u00e9cise la TAP. Entre lundi et mardi matin, 6.850 r\u00e9fugi\u00e9s venant de Libye avaient d\u00e9j\u00e0 franchi la fronti\u00e8re tunisienne, dont plus de 6.000 Libyens, selon des chiffres du minist\u00e8re tunisien de la D\u00e9fense.<\/font><\/div>\n<div> <font>Mardi, une embarcation transportant 18 ressortissants libyens, dont de hauts grad\u00e9s, avait accost\u00e9 au port El Ketef, \u00e0 quelques kilom\u00e8tres du poste-fronti\u00e8re tunisien de Ras Jedir (sud), selon la TAP.<\/font><\/div>\n<div> \u00a0<\/div>\n<hr\/>\n<div align=\"center\">\n<p><font face=\"Arial\"><strong><font>CONSEIL JAI : LETTRE OUVERTE DE D\u00c9PUT\u00c9S EUROP\u00c9ENS AUX MINISTRES DE L\u2019INT\u00c9RIEUR DE L\u2019UE SUR LE CAS DES MIGRANTS TUNISIENS<\/font><\/strong><\/font><\/p>\n<\/div>\n<div align=\"center\">\u00a0<\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\">COMMUNIQU\u00c9 DE PRESSE &#8211; Strasbourg, le 9 juin 2011<\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div><font face=\"Arial\" size=\"2\">9 juin 2011 par H\u00e9l\u00e8ne Flautre<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">H\u00e9l\u00e8ne Flautre, d\u00e9put\u00e9e europ\u00e9enne du Groupe Verts\/ALE ainsi que plusieurs eurod\u00e9put\u00e9s de diff\u00e9rents Groupes politiques du PE, ont adress\u00e9 une lettre ouverte \u00e0 l\u2019attention des Ministres de l\u2019Int\u00e9rieur des Etats membres de l\u2019UE en vue de leur r\u00e9union du Conseil JAI des 9 et 10 juin.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Suite \u00e0 la visite au Parlement europ\u00e9en d\u2019une d\u00e9l\u00e9gation de migrants tunisiens arriv\u00e9s sur le sol de l\u2019Union europ\u00e9enne par l\u2019\u00eele de Lampedusa, les d\u00e9put\u00e9s demandent solennellement de bien vouloir mettre fin \u00e0 la situation pr\u00e9caire et humiliante de ces personnes en d\u00e9cidant, lors de la r\u00e9union de Conseil JAI, d\u2019activer la directive 55\/2001 octroyant une protection temporaire en cas d\u2019afflux massif.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Lettre ouverte de d\u00e9put\u00e9s europ\u00e9ens aux Ministres des Etats membres de l\u2019UE en charge des Affaires Int\u00e9rieures en vue de la r\u00e9union du Conseil JAI des 9 et 10 juin.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Ce mercredi 8 juin, nous avons re\u00e7u au Parlement europ\u00e9en une d\u00e9l\u00e9gation de Tunisiens arriv\u00e9s sur le sol de l\u2019Union europ\u00e9enne par l\u2019\u00eele de Lampedusa depuis le 14 janvier. Ils plaident au nom des 25 000 tunisiens qui ont quitt\u00e9 la Tunisie suite \u00e0 la chute du r\u00e9gime de Ben Ali, en faveur de l\u2019activation de la directive 55\/2001 qui permet l\u2019octroi d\u2019une protection temporaire en cas d\u2019afflux massif.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Les t\u00e9moignages que nous avons recueillis motivent l\u2019octroi d\u2019un tel droit temporaire au s\u00e9jour et au travail pour ces personnes tunisiennes, notamment issues du sud Est de la Tunisie. Cette r\u00e9gion historiquement d\u00e9sh\u00e9rit\u00e9e souffre durement de la baisse drastique des activit\u00e9s touristiques et transfrontali\u00e8res, directement impact\u00e9e par les cons\u00e9quences humaines et sociales dramatiques de la guerre en Lybie.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Ces circonstances exceptionnelles rendent le retour \u00e0 court terme en Tunisie particuli\u00e8rement difficile. Au contraire, l\u2019accueil temporaire dans l\u2019UE permettrait une issue positive pour tous ceux qui apr\u00e8s avoir conquis leur libert\u00e9 veulent tout simplement voir leur dignit\u00e9 respect\u00e9e. C\u2019est essentiel pour eux-m\u00eames, pour leurs proches et pour le soutien effectif au processus de d\u00e9mocratisation en cours.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">C\u2019est pourquoi, consid\u00e9rant que les conditions de mise en \u0153uvre sont aujourd\u2019hui r\u00e9unies, nous vous demandons solennellement de bien vouloir mettre fin \u00e0 la situation pr\u00e9caire et humiliante de ces personnes en d\u00e9cidant, lors de la r\u00e9union de Conseil JAI des 9 et 10 Juin prochains, d\u2019activer la directive 55\/2001.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Veuillez agr\u00e9er, Messieurs les Ministres, nos salutations respectueuses.<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Kader Arif (France, S&amp;D)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Jean-Luc Bennahmias (France, ALDE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Jos\u00e9 Bov\u00e9 (France, Verts\/ALE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Rosario Crocetta (Italie, S&amp;D)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Karima Delli (France, Verts\/ALE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">H\u00e9l\u00e8ne Flautre (France, Verts\/ALE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Nathalie Griesbeck (France, ALDE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Sylvie Guillaume (France, S&amp;D)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Eva Joly (France, Verts\/ALE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Nicole Kiil-Nielsen (France, Verts\/ALE)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Patrick Le Hyaric (France, GUE\/NGL)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Catherine Trautmann (France, S&amp;D)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Marie-Christine Vergiat (France, GUE\/NGL)<\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">Bernadettte Vergnaud (France, S&amp;D)<\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h3 style=\"color: blue;\"><font size=\"3\"><font>Transition d\u00e9mocratique  <\/font>Election de la Constituante : J -137<\/font><\/h3>\n<p><\/strong><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div> <font>La date des \u00e9lections de l&rsquo;Assembl\u00e9e nationale constituante a \u00e9t\u00e9 fix\u00e9e au 23 octobre 2011, a annonc\u00e9 le Premier ministre du gouvernement de transition, M. B\u00e9ji Ca\u00efd Essebsi, soulignant la volont\u00e9 de veiller au succ\u00e8s de la transition d\u00e9mocratique et d&rsquo;organiser des \u00e9lections libres et transparentes sur la base du consensus entre toutes les parties politiques, gouvernement, partis et composantes de la soci\u00e9t\u00e9 civile.  S&rsquo;exprimant lors d&rsquo;une r\u00e9union qui a eu lieu, hier, au Palais des Congr\u00e8s \u00e0 Tunis, M. Ca\u00efd Essebsi a rappel\u00e9 que le gouvernement de transition a choisi, au d\u00e9part, le 24 juillet comme date de ces \u00e9lections, date qui, selon l&rsquo;Instance sup\u00e9rieure ind\u00e9pendante pour les \u00e9lections, est impossible \u00e0 respecter, compte tenu de la contrainte du temps et des conditions mat\u00e9rielles, techniques et logistiques n\u00e9cessaires pour organiser des \u00e9lections libres et transparentes, sugg\u00e9rant la date du 16 octobre 2011.  La date du d\u00e9roulement des \u00e9lections n&rsquo;est pas sacr\u00e9e, a-t-il relev\u00e9, le plus important \u00e9tant de parvenir \u00e0 un consensus autour de cette \u00e9ch\u00e9ance, d&rsquo;en r\u00e9unir les conditions de succ\u00e8s et d&rsquo;instaurer un climat de s\u00e9curit\u00e9 et de stabilit\u00e9 dans le pays .  A cet \u00e9gard, M. B\u00e9ji Ca\u00efd Essebsi a appel\u00e9 les partis politiques et les m\u00e9dias nationaux \u00e0 soutenir les efforts du gouvernement transitoire en cette phase difficile de l&rsquo;histoire de la Tunisie.<\/font><\/div>\n<div> <font>Il s&rsquo;agit, a-t-il ajout\u00e9, de contribuer \u00e0 l&rsquo;approfondissement de la conscience collective et \u00e0 l&rsquo;encadrement de l&rsquo;opinion publique, notamment face \u00e0 la poursuite des gr\u00e8ves et des protestations et \u00e0 ses retomb\u00e9es n\u00e9gatives sur l&rsquo;\u00e9conomie nationale.<\/font><\/div>\n<div> <font>Il a, \u00e9galement, \u00e9voqu\u00e9 les conditions s\u00e9curitaires difficiles que traverse le pays, en raison de la situation dans les zones frontali\u00e8res et des \u00e9v\u00e9nements dans la ville de M\u00e9tlaoui \u00e0 cause des conflits tribaux.<\/font><\/div>\n<div> <font>M. Ca\u00efd Essebsi a rendu hommage aux forces de s\u00e9curit\u00e9 int\u00e9rieure et de l&rsquo;arm\u00e9e nationale pour leurs efforts en faveur du r\u00e9tablissement de la s\u00e9curit\u00e9, de la d\u00e9fense de la patrie et de la protection des citoyens.<\/font><\/div>\n<div> <font>Au sujet de la situation sur les fronti\u00e8res tuniso- libyennes, le Premier ministre du gouvernement de transition a rappel\u00e9 que la Tunisie a accueilli, jusqu&rsquo;\u00e0 pr\u00e9sent, 471 mille r\u00e9fugi\u00e9s, toutes nationalit\u00e9s confondues, en provenance de Libye, saluant, \u00e0 ce propos, l&rsquo;accueil r\u00e9serv\u00e9 par les citoyens dans les zones frontali\u00e8res aux r\u00e9fugi\u00e9s libyens.<\/font><\/div>\n<div> <font>Le Premier ministre du gouvernement de transition s&rsquo;est f\u00e9licit\u00e9 de la r\u00e9ussite de la Tunisie \u00e0 poser les jalons d&rsquo;un syst\u00e8me d\u00e9mocratique, forte en cela de la maturit\u00e9 de son peuple et du r\u00f4le de la femme dans la vie publique, mettant l&rsquo;accent sur le souci du gouvernement de consacrer le principe de parit\u00e9 au sein de l&rsquo;Assembl\u00e9e nationale constituante qui, a-t-il ajout\u00e9, constitue une premi\u00e8re dans le monde. M. Ca\u00efd Essebsi a affirm\u00e9 que le gouvernement de transition est soucieux de respecter les d\u00e9cisions et engagements du gouvernement pr\u00e9c\u00e9dent, dont notamment la cr\u00e9ation des trois commissions ind\u00e9pendantes. Il a, dans ce sens, soulign\u00e9 que la commission pour l&rsquo;\u00e9tablissement des faits sur les malversations et la corruption a examin\u00e9 7.700 dossiers, et la commission d&rsquo;\u00e9tablissement des faits sur les d\u00e9passements au cours des derniers \u00e9v\u00e9nements a d\u00e9j\u00e0 re\u00e7u 1.500 dossiers.<\/font><\/div>\n<div> <font>Il a, en outre, indiqu\u00e9 que la commission de la r\u00e9forme politique, devenue la Haute Instance pour la r\u00e9alisation des objectifs de la r\u00e9volution, la r\u00e9forme politique et la transition d\u00e9mocratique, a pris d&rsquo;importantes d\u00e9cisions, notamment celles relatives au Code \u00e9lectoral ou encore l&rsquo;\u00e9laboration d&rsquo;une feuille de route pour la prochaine \u00e9tape politique, que le gouvernement veille \u00e0 mettre en \u0153uvre en toute l\u00e9gitimit\u00e9 consensuelle.<\/font><\/div>\n<div> <font>Les \u00e9v\u00e9nements qui ont suivi la r\u00e9volution, a indiqu\u00e9 le Premier ministre, ont s\u00e9rieusement affect\u00e9 l&rsquo;\u00e9conomie nationale, en particulier le tourisme et l&rsquo;investissement ext\u00e9rieur, et pes\u00e9 lourd sur le budget de l&rsquo;Etat qui veille \u00e0 poursuivre la subvention des produits de consommation de base et des carburants. Le gouvernement doit en m\u00eame temps, a-t-il fait remarquer, relever d&rsquo;autres d\u00e9fis majeurs comme l&rsquo;augmentation des salaires, le d\u00e9dommagement de 281 entreprises \u00e9conomiques touch\u00e9es par la crise et l&#8217;embauche de 700 mille ch\u00f4meurs. \u00ab\u00a0La r\u00e9alisation de ces objectifs ne peut pas se faire du jour au lendemain, il faut du temps, de la patience et la conjugaison des efforts de tous\u00a0\u00bb, a-t-il affirm\u00e9.<\/font><\/div>\n<div> <font>M. Ca\u00efd Essebsi a, d&rsquo;autre part, indiqu\u00e9 que sa participation au Sommet du G8, r\u00e9cemment \u00e0 Deauville, a \u00e9t\u00e9 l&rsquo;occasion de r\u00e9affirmer la d\u00e9termination du gouvernement de transition \u00e0 assurer le succ\u00e8s du processus d\u00e9mocratique et \u00e0 instaurer un Etat civil, d&rsquo;autant plus, a-t-il fait noter, que la r\u00e9volution tunisienne a \u00e9t\u00e9 le point de d\u00e9part pour une nouvelle donne dans toute la r\u00e9gion, un souffle nouveau que le monde se pla\u00eet \u00e0 appeler \u00ab\u00a0le printemps arabe\u00a0\u00bb.<\/font><\/div>\n<div> <font>En conclusion, le Premier ministre du gouvernement de transition a appel\u00e9 les repr\u00e9sentants des partis politiques et de la soci\u00e9t\u00e9 civile ainsi que les m\u00e9dias et les personnalit\u00e9s nationales pr\u00e9sentes \u00e0 appuyer les efforts du gouvernement, \u00e0 lui faire confiance, \u00e0 ne pas douter de ses intentions et \u00e0 d\u00e9passer les consid\u00e9rations personnelles \u00e9troites pour contribuer \u00e0 la r\u00e9alisation des objectifs escompt\u00e9s dans le respect de l&rsquo;avis contraire et au service de l&rsquo;int\u00e9r\u00eat sup\u00e9rieur de la nation.<\/font><\/div>\n<div>\u00a0<\/div>\n<div><strong><font>(Source: \u00ab La Presse\u00bb (Quotidien \u2013 Tunis), le 9 Juin 2011)\u200f<\/font><\/strong> <a href=\"http:\/\/www.lapresse.tn\/08062011\/30920\/election-de-la-constituante-j-137.html\" target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.lapresse.tn\/08062011\/30920\/election-de-la-constituante-j-137.html<\/font><\/a><\/div>\n<hr\/>\n<div>\u00a0<\/div>\n<div align=\"center\"><strong><\/p>\n<p><font size=\"3\">Ce sera le 23 octobre et avec 50 &#8211; 50 entre femmes et hommes Un arrangement plut\u00f4t qu\u2019une Constituante au forces<\/font><\/p>\n<p><\/strong><font><\/font> \u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div><font>Ca\u00efd Essebsi mange du lion: \u00ab D\u2019ici l\u00e0, plus de sit-in, ni de perturbations d\u2019ordre s\u00e9curitaire\u2026 Pensons \u00e0 la situation \u00e9conomique grave \u00bb \u00ab Nous r\u00e9ussirons notre D\u00e9mocratie bien avant tout le monde \u00bb Clin d\u2019\u0153il \u00e0 Ghannouchi: \u00ab J\u2019affirme qu\u2019Islam et D\u00e9mocratie ne sont pas anti-th\u00e9tiques \u00bb \u00ab On reproche \u00e0 ce gouvernement de ne pas avoir de l\u00e9gitimit\u00e9 fonctionnelle \u00bb. En d\u2019autres termes, moi, B\u00e9ji Ca\u00efd Essebsi, je ne suis pas un rejeton de la Nation et ce gouvernement est, d\u2019abord, dans une logique de transition d\u00e9mocratique, mais il est aussi dans une logique r\u00e9volutionnaire.   Plus qu\u2019un expos\u00e9 institutionnel, comme \u00e0 son accoutum\u00e9e, quelque peu caustique, taquin, irritable, mais visc\u00e9ralement excentrique, le Premier ministre dit tout, ne s\u2019emp\u00eachant pas d\u2019en placer une \u00e0 chaque coin de phrase.  Les absents \u00e0 ce grand rassemblement ? Il pense qu\u2019ils ont eu tort ! Sinon, il ponctue strat\u00e9giquement ses d\u00e9monstrations de morceaux de versets coraniques, de quelques hyperboles emprunt\u00e9es aux Hadiths ; il \u00e9voque m\u00eame une belle effusion lyrique de Mustapha Filali, \u00e0 propos de la libert\u00e9.<\/font><\/div>\n<div> <font>\u00ab Savoir pardonner \u00bb<\/font><\/div>\n<div> <font>En bon croyant, il consid\u00e8re qu\u2019il faut savoir pardonner et l\u00e0 il parle de cette affaire d\u2019indignit\u00e9 des Rc\u00e9distes. Il tient mordicus \u00e0 couper la poire presque en deux : 10 ans et non 23 ans, ce qui serait parfaitement logique et, m\u00eame juste, parce que, dans la logique \u00ab totalitaire \u00bb des 23 ans d\u2019indignit\u00e9, tous ceux qui ont travaill\u00e9 avec Ben Ali, des hommes comme Sa\u00e2deddine Zmerli ou feu Mohamed Charfi seraient interdits de d\u00e9mocratie, eux qui avaient tant lutt\u00e9 pour.<\/font><\/div>\n<div> <font>Pardonner oui, punir aussi : L\u00e0, B\u00e9ji Ca\u00efd Essebsi se met dans la psychologie de Foucault, m\u00eame si, en bon Bourguibiste, il ne cache pas son aversion pour la corruption et tout simplement pour l\u2019argent. Cet argent au centre de toutes les malversations du r\u00e9gime d\u00e9chu ; r\u00e9gime corrompu et absolutiste \u2013 n\u2019est-ce pas la m\u00eame chose finalement !<\/font><\/div>\n<div> <font>Dans ce m\u00eame ordre d\u2019id\u00e9es, B\u00e9ji Ca\u00efd Essebsi vante les m\u00e9rites des trois commissions form\u00e9es du temps de Mohamed Ghannouchi, tout juste apr\u00e8s le 14 janvier. Il explique, sensibilise l\u2019assistance, clarifie des points importants. La commission pr\u00e9sid\u00e9e par Abdelfattah Amor traite quelque chose comme 7700 dossiers ; 1500 par celle de Taoufik Bouderbala ; et l\u2019autre commission, celle qui a la responsabilit\u00e9 politique de la sauvegarde des int\u00e9r\u00eats de la R\u00e9volution, pr\u00e9sid\u00e9e par Yadh Ben Achour, a d\u00e9ploy\u00e9, selon le Premier ministre, un travail titanesque. De cette commission est n\u00e9e la Haute Instance pour les \u00e9lections.<\/font><\/div>\n<div> <font>Il est peut-\u00eatre difficile pour les Tunisiens de croire qu\u2019un Premier ministre n\u2019a pas qualit\u00e9 pour infl\u00e9chir les d\u00e9cisions de la justice qui est en train de recouvrer toute sa souverainet\u00e9. En r\u00e9alit\u00e9, nous sommes de facto dans un r\u00e9gime parlementaire \u2013 m\u00eame s\u2019il manque une composante essentielle, le Parlement \u2013 et dans cet esprit, les pouvoirs du Pr\u00e9sident de la R\u00e9publique sont limit\u00e9s pour ne pas dire entre les mains du Premier ministre avec une attitude \u00e9quidistante vis-\u00e0-vis de la Justice. Certes, B\u00e9ji Ca\u00efd Essebsi dit s\u2019interdire d\u2019imposer quoi que ce soit \u00e0 ses ministres (comme \u00e0 Farhat Rajhi ?), mais il est assez politiquement fort pour \u00eatre trop d\u00e9mocrate et en tous les cas, quand on poss\u00e8de un tel charisme avec un sens th\u00e9\u00e2tral aussi consomm\u00e9, on ne peut \u00eatre que le chef !<\/font><\/div>\n<div> <font>D\u2019ici le 23 octobre\u2026<\/font><\/div>\n<div> <font>Tout un travail d\u2019approche ; des digressions bien calcul\u00e9es pour faire avaler la pilule : \u00ab Ce sera le 23 octobre \u00bb. Ce jour l\u00e0 consacrera l\u2019\u00e9lection de la Constituante. Et avec 50-50 entre femmes et hommes. Non \u00e9v\u00e9nement, dirait-on ! Oui, mais qu\u2019y a-t-il derri\u00e8re ? Et si la Constituante adoptait le sc\u00e9nario gard\u00e9 secret, para\u00eet-il : Six mois, \u00e0 partir du 23 octobre pour pr\u00e9parer une Constitution, puis des \u00e9lections pr\u00e9sidentielle et l\u00e9gislatives. Auquel cas, B\u00e9ji Ca\u00efd Essebsi et Foued M\u2019baza\u00e2 resteraient \u00e0 la barre durant cette p\u00e9riode l\u00e0. Entre-temps, le Premier ministre devient ferme, et m\u00eame belliqueux : \u00ab nous sommes l\u00e0 jusqu\u2019au 23 octobre. Je prends \u00e0 t\u00e9moin le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019UGTT : nous ne pouvons plus tol\u00e9rer de sit-in ou de perturbations. Il faut en finir avec le climat de suspicion. Nous venons d\u2019\u00e9laborer un projet compl\u00e9mentaire de loi de finances. Le tourisme est aux abois et il fait vivre un million de personnes. On enregistre 281 entreprises sinistr\u00e9es. Nous ne pouvons pas donner du travail \u00e0 700.000 ch\u00f4meurs \u00e0 la fois. Et, en plus, le taux de croissance (1%) n\u2019en permet d\u2019employer que 16 mille ! Je demande \u00e0 mes concitoyens d\u2019\u00eatre conscients de ce qui se passe : une guerre fait rage \u00e0 nos fronti\u00e8res, nos forces sont mobilis\u00e9es pour assurer l\u2019int\u00e9grit\u00e9 territoriale du pays. Nous h\u00e9bergeons \u00e0 ce jour 471000 r\u00e9fugi\u00e9s libyens alors que l\u2019Europe \u00ab flippe \u00bb pour les 9000 qui s\u2019y sont rendus. Je rends, oui, je rends hommage au peuple tunisien et j\u2019ai bien dit aux Europ\u00e9ens que nous ne refoulerons pas les fr\u00e8res et s\u0153urs libyens ! \u00bb. Arrogance et sens de path\u00e9tique \u00e0 la fois.<\/font><\/div>\n<div> <font>L\u2019air grave aussi, un peu \u00e0 la Churchill au moment o\u00f9 il pr\u00e9parait les Anglais \u00e0 l\u2019attaque nazie sur Londres !<\/font><\/div>\n<div> <font>Clin d\u2019\u0153il pour\u2026 Ghannouchi<\/font><\/div>\n<div> <font>L\u2019Europe, le G8 repr\u00e9sentent la transition id\u00e9ale dans son discours (sans papier !).  \u00ab Nous avons une excellente r\u00e9putation \u00bb. Et l\u00e9gitimement jaloux des acquis de la R\u00e9volution. Il se transforme en un Jules C\u00e9sar : \u00ab Veni, vidi, vici \u00bb.  En d\u2019autres termes : \u00ab La R\u00e9volution gagne, dit-il. Nous battrons tout le monde (clin d\u2019\u0153il aux Egyptiens) parce que le mod\u00e8le qu\u2019\u00e9pousera la Tunisie en imposera au monde tout entier. Au G8, partout, on est conscient qu\u2019ISLAM et DEMOCRATIE ne sont pas antith\u00e9tiques \u00bb. Et cette fois le clin d\u2019\u0153il, c\u2019est pour \u00ab l\u2019ami \u00bb Ghannouchi.<\/font><\/div>\n<div> <strong><font>Raouf KHALSI<\/font><\/strong><\/div>\n<div> <strong><font>(Source: \u00ab le Temps \u00bb (Quotidien \u2013 Tunis), le 9 Juin 2011)\u200f<\/font><\/strong> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.letemps.com.tn\/article-56555.html<\/font><\/a> \u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><font face=\"Arial\">Tunisie. La \u00abr\u00e9conciliation nationale\u00bb selon Yadh Ben Achour<\/font><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><i><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Invit\u00e9 mardi par l\u2019Utica, Yadh Ben Achour a pass\u00e9 en revue les \u00e9tapes de sa vie universitaire et politique pendant, durant et apr\u00e8s Ben Ali, presque dans le d\u00e9tail. Il a appel\u00e9 ensuite \u00e0 la \u00abr\u00e9conciliation nationale\u00bb. <\/font><\/span><\/i><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Par Zohra Abid<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Une musique tr\u00e8s agr\u00e9able aux oreilles des membres du Bureau ex\u00e9cutif de l\u2019Union tunisienne de l\u2019industrie, du commerce et de l\u2019artisanat (Utica), dont certains \u00e9taient des piliers de l\u2019ancien r\u00e9gime. Mais c\u2019est l\u00e0 une autre histoire.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Des paroles de sagesse<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Et parce qu\u2019il y a deux tendances, aujourd\u2019hui, au sein de l\u2019Utica, l\u2019une pour la continuit\u00e9 \u2013 on prend les m\u00eames et on recommence \u2013 et l\u2019autre pour la rupture \u2013 du pass\u00e9 on fait table rase \u2013, l\u2019intervention de Ben Achour \u00e9tait tr\u00e8s attendue. Ecouter les paroles d\u2019un professeur \u00e9minent, et qui a son mot \u00e0 dire sur les affaires du pays (il est le pr\u00e9sident de la Haute instance pour la r\u00e9alisation des objectifs de la r\u00e9volution, la r\u00e9forme politique et la transition d\u00e9mocratique) est une occasion pour mieux savoir o\u00f9 va la Tunisie. Et, surtout, comment elle y va.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Comme pour plaire \u00e0 ses h\u00f4tes, et surtout les rassurer, l\u2019invit\u00e9 d\u2019honneur de la centrale patronale n\u2019a pas cess\u00e9 d\u2019appeler au \u00abpardon\u00bb. Un mot qui, on l\u2019a compris, p\u00e8se tr\u00e8s lourd dans l\u2019\u00e9conomie nationale, aujourd\u2019hui en mauvaise posture. On se serre la main, machinalement, les uns les autres. On fait comme si\u2026 et on passe l\u2019\u00e9ponge. Question de remettre le compteur de l\u2019\u00e9conomie en marche. Qui a parl\u00e9 de chantage \u00e0 l\u2019investissement?<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ce n\u2019est pas l\u00e0, on l\u2019a compris, le souci de M. Ben Achour, dont le speech, tr\u00e8s port\u00e9 sur son parcours personnel, nous a rappel\u00e9, par le fond comme par la forme (le ton, les intonations, le rythme, le style narratif\u2026), ceux d\u2019un certain Habib Bourguiba que tout le monde, consciemment ou inconsciemment, se met aujourd\u2019hui \u00e0 imiter. Mais c\u2019est l\u00e0 une autre histoire\u2026<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Un parcours d\u2019indignation et de r\u00e9volte<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pr\u00e8s d\u2019une heure, l\u2019homme de 66 ans a parl\u00e9 de lui-m\u00eame, de son parcours \u00e0 la fac, de son opposition \u00e0 Ben Ali, lorsqu\u2019il a d\u00e9missionn\u00e9 du Conseil constitutionnel pour protester contre une loi ciblant la Ligue tunisienne des droits de l\u2019homme (Ltdh), en 1992, ou encore lorsqu\u2019il a soutenu, en novembre 2005, les gr\u00e9vistes de la faim en marge du Sommet mondial de la soci\u00e9t\u00e9 de l\u2019information (Smsi) ou, enfin, son soutien \u00e0 la candidature de Mohamed Ali Halouani \u00e0 la pr\u00e9sidence de la r\u00e9publique en 2004\u2026 Entre autres \u00e9pisodes d\u2019une vie dont le conf\u00e9rencier a voulu souligner la port\u00e9e militante.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pourquoi Ben Achour a-t-il senti le besoin de raconter ainsi sa vie aux patrons venus l\u2019\u00e9couter? C\u2019est ce parcours-l\u00e0, souligne-t-il, qui lui a valu d\u2019\u00eatre, aujourd\u2019hui, le pr\u00e9sident de la Haute instance pour la r\u00e9alisation des objectifs de la r\u00e9volution. Et c\u2019est en raison de son int\u00e9grit\u00e9 morale et intellectuelle que Mohamed Ghannouchi, ancien Premier ministre (sous Ben Ali ensuite au premier gouvernement de transition), lui a propos\u00e9 de pr\u00e9sider cette instance. Mais nul ne doute de tout cela, M. Ben Achour, rassurez-vous!<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abJ\u2019ai fait appel \u00e0 des experts. Ils sont tous des universitaires. Ils sont venus de toutes les facult\u00e9s de droit du pays pour faire une op\u00e9ration de nettoyage des textes de loi. Nous \u00e9tions une vingtaine\u00bb, a poursuivi M. Ben Achour, pour raconter les nombreux rebondissements qu\u2019a connus son instance jusqu\u2019\u00e0 ce jour, notamment l\u2019int\u00e9gration des membres du Comit\u00e9 de protection de la r\u00e9volution, ainsi autoproclam\u00e9, et qui n\u2019a, aux yeux de Ben Achour, aucune v\u00e9ritable l\u00e9gitimit\u00e9, la r\u00e9volution ayant \u00e9t\u00e9 faite en dehors de tout encadrement politique partisan.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Diff\u00e9rents, mais la main dans la main<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abLa Haute Instance compte aujourd\u2019hui 155 membres et ressemble plut\u00f4t \u00e0 un parlement qu\u2019\u00e0 une commission\u00bb, d\u00e9plore-t-il. Et de souligner la difficult\u00e9 qu\u2019il a eue \u00e0 mettre d\u2019accord des gens venus d\u2019horizons divers et qui se chamaillent pour chaque point ou chaque virgule. N\u2019emp\u00eache que malgr\u00e9 ces difficult\u00e9s dans le d\u00e9bat, la Haute instance a pu quand m\u00eame aboutir \u00e0 un accord sur l\u2019\u00e9lection de l\u2019Assembl\u00e9e nationale constituante \u00aben seulement trois semaines\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abAujourd\u2019hui, notre seul objectif est la r\u00e9conciliation nationale. Nous devons suivre l\u2019exemple de l\u2019Afrique du Sud. Seul le pardon pourrait nous conduire \u00e0 la r\u00e9ussite. Mettons la main dans la main. Les Tunisiens doivent faire la paix entre eux\u2026 Nous n\u2019avons pas le choix.\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Dans ce contexte, M. Ben Achour<span> <\/span>a appel\u00e9 \u00e0 l\u2019organisation d\u2019un congr\u00e8s conjoint entre l\u2019Utica et l\u2019Union g\u00e9n\u00e9rale tunisienne du travail (Ugtt, syndicat ouvrier). Une telle r\u00e9union permettrait un \u00e9change des points de vues entre les hommes d\u2019affaires et la classe ouvri\u00e8re qui aiderait \u00e0 relever les d\u00e9fis auxquels fait face l\u2019entreprise tunisienne. Il a mis aussi l\u2019accent sur la n\u00e9cessit\u00e9 d\u2019entamer une r\u00e9flexion sur la r\u00e9vision du syst\u00e8me fiscal tunisien et de mettre en place une politique fiscale plus juste et plus incitative pour les employ\u00e9s et l\u2019entreprise.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il faut que toutes les parties \u0153uvrent \u00abpour que l\u2019\u00e9conomie, aujourd\u2019hui essouffl\u00e9e, reprenne au plus vite\u00bb.<\/font><\/span><\/div>\n<div align=\"left\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Et de conclure sur une note personnelle en disant qu\u2019il n\u2019a aucune ambition politique. \u00abC\u2019est l\u2019int\u00e9r\u00eat du pays qui doit l\u2019emporter\u00bb, lance-t-il \u00e0 ces chers hommes d\u2019affaires! Personne n\u2019en doute\u2026<\/font><\/span><\/div>\n<div align=\"left\"><b><span dir=\"ltr\" lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">(Source : \u00ab Kapitalis \u00bb, le 9 juin 2011)<\/font><\/span><\/b><\/div>\n<div align=\"left\">\u00a0<\/div>\n<div align=\"center\" dir=\"rtl\">\u00a0<\/div>\n<hr dir=\"rtl\"\/>\n<div align=\"center\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\"><strong>Opinions<\/strong><\/font><\/span><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><font face=\"Arial\">Venez faire revivre l\u2019image de cette Tunisie qui \u00abchante et qui danse\u00bb<\/font><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Laurence B\u00e9zaguet<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abC\u2019est terrible, le tourisme a chut\u00e9 de 80% par rapport \u00e0 l\u2019an dernier\u00bb, constate avec d\u00e9solation une intellectuelle tunisienne, r\u00e9cemment rencontr\u00e9e \u00e0 Sousse.<\/font><\/span><\/div>\n<div><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il est vrai qu\u2019\u00e0 l\u2019approche de l\u2019\u00e9t\u00e9, cette r\u00e9put\u00e9e station baln\u00e9aire, situ\u00e9e \u00e0 150 kilom\u00e8tres au sud de Tunis, souffre d\u2019un cruel manque de visiteurs. L\u2019image export\u00e9e de la Tunisie qui \u00abchante et qui danse\u00bb a s\u00e9rieusement vol\u00e9 en \u00e9clats avec l\u2019av\u00e8nement des r\u00e9voltes populaires dans le monde arabe.<\/font><\/span><\/div>\n<div><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le coup de frein a \u00e9t\u00e9 brutal, comme le confirme le dernier num\u00e9ro deTravel Inside, le journal suisse du tourisme. \u00abDu 1er<span> <\/span>janvier au 30<span> <\/span>avril, le nombre global de nuit\u00e9es a chut\u00e9 de 72,4% et les recettes ont baiss\u00e9 de 75,7%\u00bb, pr\u00e9cise Tahar Khadraoui, directeur g\u00e9n\u00e9ral de l\u2019agence de voyages Air Marin, dans ce journal.<\/font><\/span><\/div>\n<div><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Cette baisse catastrophique semble inimaginable, tant la Tunisie a longtemps \u00e9t\u00e9 une destination idyllique tr\u00e8s pris\u00e9e. En empruntant le bel axe autoroutier qui relie Tunis aux grandes destinations baln\u00e9aires du centre (Hammamet, Sousse, Monastir), on reste d\u2019ailleurs illumin\u00e9 par les odorants lauriers multicolores. Et on se dit que la sinistrose ne va pas durer.<\/font><\/span><\/div>\n<div><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abFaites venir des touristes\u00bb, encourage Amina, chaleureuse et attentionn\u00e9e commer\u00e7ante d\u2019une \u00e9choppe artisanale de Sousse. La qualit\u00e9 de l\u2019accueil, la richesse des \u00e9changes restent assur\u00e9ment un atout de poids pour relancer la machine.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00abJ\u2019ai \u00e9t\u00e9 trait\u00e9e comme une reine, t\u00e9moigne Yolanda, de retour de Djerba. Je ne voulais pas me rendre en Tunisie sous Ben Ali. Mais apr\u00e8s la chute du dictateur, malgr\u00e9 la p\u00e9riode d\u2019instabilit\u00e9 en cours, je n\u2019ai pas h\u00e9sit\u00e9 un instant. Une belle fa\u00e7on, par la m\u00eame occasion, de passer des vacances citoyennes!\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Et cette Genevoise engag\u00e9e ne l\u2019a pas regrett\u00e9. R\u00e9put\u00e9s \u00abaux petits soins\u00bb, les professionnels du tourisme tunisien bichonnent encore davantage les trop rares \u00e9trangers de passage.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ceux-ci n\u2019h\u00e9sitaient pourtant pas \u00e0 venir jadis se dorer sur les plages du pays du Jasmin\u2026 malgr\u00e9 l\u2019oppressant r\u00e9gime. Leurs h\u00f4tes n\u2019osaient alors pas parler et beaucoup se sentaient spoli\u00e9s. Aujourd\u2019hui, les Tunisiens parlent et ils sont fiers de leur r\u00e9volution au parfum de d\u00e9mocratie.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Alors, \u00e0 tous ceux qui redoutent \u00e0 pr\u00e9sent une forte immigration nord-africaine\u2026 vous pouvez emp\u00eacher cette d\u00e9ferlante en aidant la r\u00e9gion \u00e0 se reconstruire: traversez la M\u00e9diterran\u00e9e, le tourisme tunisien a besoin de vous.<\/font><\/span><\/div>\n<div align=\"justify\"><font size=\"2\"><font face=\"Arial\"><span lang=\"FR-CH\">Et puis il est si emballant de sentir la vitalit\u00e9 que d\u00e9gage ce pays plein de promesses. Une Tunisie qui vit une p\u00e9riode exaltante de cr\u00e9ativit\u00e9 politique. La chape de plomb a saut\u00e9, les portes s\u2019ouvrent. Engouffrez-vous<\/span><span dir=\"rtl\" lang=\"AR-SA\">!<\/span><\/font><\/font><\/div>\n<div align=\"justify\"><b><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">(Source : \u00ab Tribune de Gen\u00e8ve \u00bb (Quotidien \u2013 Suisse), le 8 juin 2011)<\/font><\/span><\/b><\/div>\n<div dir=\"rtl\">\u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<p><font size=\"3\"><font>La Tunisie aux prises avec ses vieux d\u00e9mons <\/font>Des membres de l\u2019ex-parti au pouvoir soup\u00e7onn\u00e9s d\u2019\u00eatre impliqu\u00e9s dans les violences tribales de Metlaoui<\/font><\/p>\n<p><\/strong><\/div>\n<div>\n<hr\/>\n<\/div>\n<div> <font>mercredi 8 juin 2011 \/ par Assanatou Bald\u00e9  Des cadres de l\u2019ancien parti au pouvoir, le Rassemblement constitutionnel d\u00e9mocratique (RCD), figurent, selon les autorit\u00e9s, parmi les 105 personnes interpell\u00e9es mardi par les forces de l\u2019ordre. Des arrestations qui font suite aux affrontements tribaux survenus de vendredi \u00e0 dimanche dans la ville de Metlaoui (Sud-ouest). Ces violences ont fait au moins 12 morts et 100 bless\u00e9s. La Tunisie, dans l\u2019attente d\u2019un nouveau pouvoir \u00e9lu, demeure instable. Le Premier ministre tunisien de la transition, B\u00e9ji Ca\u00efd Essebsi, a annonc\u00e9 ce mercredi que les \u00e9lections de l\u2019Assembl\u00e9e constituante \u00e9taient report\u00e9es au 23 octobre.<\/font><\/div>\n<div> <font>Nouveaux troubles en Tunisie. L\u2019arm\u00e9e et la police ont interpell\u00e9 105 personnes mises en cause dans les violences qui ont oppos\u00e9 en fin de semaine derni\u00e8re deux tribus de la ville mini\u00e8re de Metlaoui, dans la r\u00e9gion de Gafsa, situ\u00e9e au sud-ouest de la Tunisie. Contre toute attente, figurent parmi elles des membres de l\u2019ancien parti au pouvoir (dissous le 9 mars), le Rassemblement constitutionnel d\u00e9mocratique (RCD), ont indiqu\u00e9 mardi des sources militaires. Il s\u2019agirait d\u2019hommes d\u2019affaires originaires de Metlaoui, ainsi que d\u2019un ancien d\u00e9l\u00e9gu\u00e9 du r\u00e9gime du pr\u00e9sident d\u00e9chu Zine El Abidine Ben Ali. Les forces de police auraient saisi des armes \u00e0 feu et une grande quantit\u00e9 de munitions, ont pr\u00e9cis\u00e9 ces sources.<\/font><\/div>\n<div> <font>Les hostilit\u00e9s entre les deux tribus rivales, qui ont dur\u00e9 trois jours, de vendredi soir \u00e0 dimanche, ont fait au moins 12 morts et une centaine de bless\u00e9s. Les d\u00e9g\u00e2ts mat\u00e9riels ont \u00e9galement \u00e9t\u00e9 importants. Des maisons et commerces ont \u00e9t\u00e9 d\u00e9truits \u00e0 coup de bulldozer ou br\u00fbl\u00e9s. Les deux parties \u00e9taient arm\u00e9es de fusils de chasse, de barres de fer, et de cocktails molotov, a indiqu\u00e9 mardi le porte-parole du minist\u00e8re de la Justice, Zine El Abidine Kadhem, lors d\u2019une conf\u00e9rence de presse au si\u00e8ge du Gouvernement de transition \u00e0 la Kasbah. Il a pr\u00e9cis\u00e9 que les personnes arr\u00eat\u00e9es sont suspect\u00e9es de meurtre avec pr\u00e9m\u00e9ditation, incendie volontaire de domiciles, incitation au port d\u2019armes\u2026<\/font><\/div>\n<div> <font>A l\u2019origine de cette confrontation, une rumeur selon laquelle des tribus b\u00e9n\u00e9ficieraient d\u2019embauches au profit d\u2019autres au sein d\u2019une soci\u00e9t\u00e9 locale d\u2019exploitation du phosphate. L\u2019arm\u00e9e et la garde nationale ont mis en place un dispositif de s\u00e9curit\u00e9 pour tenter de r\u00e9tablir le calme. Le couvre-feu, qui \u00e9tait d\u00e9j\u00e0 \u00e9tabli, a \u00e9t\u00e9 fix\u00e9 dor\u00e9navant de 16h \u00e0 6h. Les tensions tribales dans cette ville min\u00e9e par le ch\u00f4mage ne datent pas d\u2019aujourd\u2019hui. Et elles se sont multipli\u00e9es depuis la chute du pr\u00e9sident d\u00e9chu Ben Ali, le 14 janvier. En mars dernier, deux personnes avaient p\u00e9ri dans des affrontements. De m\u00eame, dans la ville de Sened, pr\u00e8s de Gafsa, en avril, deux autres avaient connu le m\u00eame sort apr\u00e8s de violents combats opposant des lyc\u00e9ens de tribus rivales.<\/font><\/div>\n<div> <font>Des violences condamn\u00e9es<\/font><\/div>\n<div> <font>Les partis politiques ont vivement condamn\u00e9 ces violences. Notamment le Parti d\u00e9mocratique progressiste (Pdp), qui a mis en garde, pour sa part, contre la gravit\u00e9 du d\u00e9rapage dans les conflits tribaux et claniques \u00ab qui menacent l\u2019unit\u00e9 nationale et la font d\u00e9vier des objectifs de la r\u00e9volution pour b\u00e2tir une Tunisie nouvelle, libre, solidaire et d\u00e9mocratique \u00bb. Le parti de la Rencontre de la jeunesse libre (Prjl) s\u2019est propos\u00e9e d\u2019envoyer une d\u00e9l\u00e9gation de jeunes \u00e0 Metlaoui pour participer \u00e0 calmer les esprits afin d\u2019\u00e9viter tout d\u00e9rapage et r\u00e9tablir la s\u00e9curit\u00e9. La Ligue Tunisienne de D\u00e9fense des Droits de l\u2019Homme (LTDH) s\u2019est, quant \u00e0 elle, dite tr\u00e8s pr\u00e9occup\u00e9e par la situation et a exhort\u00e9 \u00ab les citoyens de Metaloui \u00e0 faire preuve d\u2019extr\u00eame retenue et les diff\u00e9rentes composantes de la soci\u00e9t\u00e9 civile \u00e0 s\u2019opposer \u00e0 toute action pouvant attiser la tension ou mener \u00e0 l\u2019escalade \u00bb. La Ligue, qui a appel\u00e9 le gouvernement \u00e0 \u00ab prendre toutes les dispositions pour r\u00e9tablir la s\u00e9curit\u00e9, et \u00e0 ouvrir une enqu\u00eate s\u00e9rieuse afin de r\u00e9v\u00e9ler toute la v\u00e9rit\u00e9 et d\u00e9terminer les responsables de ces \u00e9v\u00e8nement \u00bb, a soulign\u00e9 \u00ab la n\u00e9cessit\u00e9 de trouver des solutions urgentes accept\u00e9es par toutes les parties afin de restaurer la concorde parmi les habitants de Metlaoui, et \u00e9loigner le spectre de la discorde qui menace la r\u00e9gion \u00bb.<\/font><\/div>\n<div> <font>La crise \u00e0 laquelle est en proie Metlaoui pourrait bien se propager comme une gangr\u00e8ne dans d\u2019autres r\u00e9gions. Les Tunisiens, qui esp\u00e9raient un avenir meilleur apr\u00e8s la chute du r\u00e9gime de Zine El Abidine Ben Ali, ne sont pas au bout de leurs peines. Ils sont toujours confront\u00e9s \u00e0 un ch\u00f4mage grandissant et au co\u00fbt \u00e9lev\u00e9 de la vie. Sans compter l\u2019incertitude politique caract\u00e9ris\u00e9e par le report fr\u00e9quent des \u00e9lections de l\u2019Assembl\u00e9e constituante. Ces derni\u00e8res, initialement pr\u00e9vues le 24 juillet, sont d\u00e9sormais report\u00e9es au 23 octobre, a annonc\u00e9 ce mercredi le Premier ministre tunisien de la transition, B\u00e9ji Ca\u00efd Essebsi. Stabiliser le pays semble plus que jamais une urgence, pour \u00e9viter qu\u2019il ne sombre dans la violence.<\/font><\/div>\n<div> <strong><font>(Source : \u00ab afrik.com \u00bb, le 9 juin 2011)<\/font><\/strong><\/div>\n<div> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.afrik.com\/article23033.html<\/font><\/a><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h4 style=\"color: blue;\"><font size=\"3\">La veille strat\u00e9gique pour le maintien du tourisme en Tunisie<\/font><\/h4>\n<p><\/strong><\/div>\n<div>\n<hr\/>\n<\/div>\n<div> <font>La r\u00e9volution et l\u2019atmosph\u00e8re d\u2019ins\u00e9curit\u00e9 ont fragilis\u00e9 un secteur d\u2019activit\u00e9 essentiel du pays: le tourisme. D\u2019o\u00f9 la n\u00e9cessit\u00e9 d\u2019une veille strat\u00e9gique pour relancer le secteur. Par Sofian Parisi*   La Tunisie, longtemps victime de sa r\u00e9putation de destination \u00ablow cost\u00bb (ou pas ch\u00e8re), peine \u00e0 trouver de nouveaux axes de d\u00e9veloppement pour diversifier son tourisme, malgr\u00e9 des efforts \u00e9normes pour la promotion de nouveaux produits touristiques.<\/font><\/div>\n<div> <font>M\u00eame si la r\u00e9volution est finie en tant que telle, une crise de confiance des voyageurs pourrait co\u00fbter cher au pays qui fait figure de destination privil\u00e9gi\u00e9 des consommateurs recherchant un bas prix.<\/font><\/div>\n<div> <font>Le secteur du tourisme \u00e0 lui seul repr\u00e9sente 7% du Pib du pays en 2010.<\/font><\/div>\n<div> <font>En tant que premi\u00e8re destination touristique de la France, la Tunisie ne peut pas rester insensible \u00e0 ces al\u00e9as.<\/font><\/div>\n<div> <font>Il parait donc int\u00e9ressant d\u2019apporter un \u00e9clairage sur cette activit\u00e9 diffus et mal reconnue en Tunisie et pourtant \u00e9conomiquement strat\u00e9gique pour notre pays d\u2019autant plus que les pratiques de veille et de gestion de crises n\u2019existe carr\u00e9ment pas comme outils d\u2019aide au niveau du minist\u00e8re du Commerce et du Tourisme mais aussi les professionnels du secteur.<\/font><\/div>\n<div> <font>Aujourd\u2019hui, notre plan\u00e8te est un espace global de flux touristiques. Il n\u2019existe plus de territoire non ouvert \u00e0 la pr\u00e9sence de voyageurs sauf dans les dictatures les plus ferm\u00e9es. <\/font><\/div>\n<div> <font>Ph\u00e9nom\u00e8ne \u00e9conomique et g\u00e9opolitique sans pr\u00e9c\u00e9dent, cons\u00e9quence d\u2019une diminution du temps de travail et d\u2019un accroissement r\u00e9gulier du pouvoir d\u2019achat (en Europe), le tourisme est pass\u00e9, en une cinquantaine d\u2019ann\u00e9es, d\u2019un secteur artisanal r\u00e9serv\u00e9 \u00e0 des privil\u00e9gi\u00e9s \u00e0 une industrie dynamique qui s\u2019adresse \u00e0 un march\u00e9 de masse. <\/font><\/div>\n<div> <font>Ce d\u00e9veloppement en fait un secteur strat\u00e9gique pour l\u2019\u00e9conomie en devises du pays malgr\u00e9 les al\u00e9as conjoncturels (conflits, attentats, crise \u00e9cologique, r\u00e9volution, \u00e9conomique et sociales) qui affectent fortement et r\u00e9guli\u00e8rement le tourisme mondial. A ce titre il reste un puissant moyen de stimuler le d\u00e9veloppement territorial sur le long terme.<\/font><\/div>\n<div> <font>Pourquoi faire de la veille en tourisme?<\/font><\/div>\n<div> <font>L\u2019activit\u00e9 touristique est \u00e9minemment strat\u00e9gique pour la Tunisie puisque notre pays occupe une place de choix en termes de destination dans la M\u00e9diterran\u00e9e, ce qui induit un poids important dans l\u2019\u00e9conomie nationale. Malgr\u00e9 tout, elle g\u00e9n\u00e8re moins d\u2019emplois et de recettes que ces plus proches concurrentes: la Turquie et le Maroc.<\/font><\/div>\n<div> <font>Dans un secteur fortement concurrentiel, \u00e0 la fois en expansion mais \u00e9galement en profonde mutation, la Tunisie voit sa position grignot\u00e9e d\u2019ann\u00e9e en ann\u00e9e par les destinations concurrentes traditionnelles mais aussi par les nouveaux entrants des pays de l\u2019est.<\/font><\/div>\n<div> <font>Parall\u00e8lement, le march\u00e9 touristique tunisien int\u00e9rieur reste modeste et quasi inexistant, tr\u00e8s fragment\u00e9, et les produits touristiques continuent \u00e0 \u00eatre commercialis\u00e9s par des canaux traditionnels touchant peu de consommateurs. Enfin le tourisme repr\u00e9sente un enjeu de d\u00e9veloppement territorial puisqu\u2019il pourrait permettre d\u2019irriguer \u00e9conomiquement l\u2019ensemble du pays et notamment le milieu rural (80% du territoire) alors qu\u2019aujourd\u2019hui 70% des touristes se concentre sur 30% du territoire (le littoral).<\/font><\/div>\n<div> <font>Selon quels axes?<\/font><\/div>\n<div> <font>Le tourisme est un secteur en perp\u00e9tuel mouvement et mutation permanente et en crise depuis quelques ann\u00e9es, mais il est complexe. Ses produits sont composites car ils r\u00e9sultent d\u2019une combinaison de biens et de services tant publics que marchands. <\/font><\/div>\n<div> <font>En cons\u00e9quence, et plus encore que tout autre domaine, la veille doit se pratiquer comme un scanning permanent sur 360 degr\u00e9s avec une focalisation sur les axes strat\u00e9giques propres \u00e0 chaque op\u00e9rateur. <\/font><\/div>\n<div> <font>Pour \u00eatre juste, les grandes tendances de veille portent sur les domaines aussi vari\u00e9s que l\u2019innovation (technologique, organisationnelle, produits), le risque pays (touriste cible m\u00e9diatique des terroristes), le comportement des consommateurs (\u00e9thique, packaging, vieillissement, facteur prix), l\u2019apparition de nouvelles destinations (renforcement de la concurrence), la structuration du march\u00e9 de l\u2019offre ou encore la d\u00e9centralisation des comp\u00e9tence dans le futur (risque de comp\u00e9tition territorial).<\/font><\/div>\n<div> <font>Qui fait la veille dans le tourisme?<\/font><\/div>\n<div> <font>En Tunisie, personne! Il est de notre devoir de conserver une forte comp\u00e9titivit\u00e9 gr\u00e2ce \u00e0 une bonne analyse de la concurrence et de l\u2019\u00e9volution des march\u00e9s et des tendances de consommation. Les organismes publics en charge du secteur devraient avoir un secteur d\u00e9di\u00e9s.<\/font><\/div>\n<div> <font>Encore ignor\u00e9 et insuffisamment coordonn\u00e9e, la veille strat\u00e9gique est au c\u0153ur de cette d\u00e9marche en tant qu\u2019activit\u00e9 structurante dans son r\u00f4le de questionnement, d\u2019analyse et d\u2019outil d\u2019animation de r\u00e9seau. <\/font> \u00a0<\/div>\n<div><font>La gestion de l\u2019information strat\u00e9gique ne s\u2019est pas d\u00e9velopp\u00e9e dans nos institutions d\u2019autant plus qu\u2019il existe des bureaux \u00e9tranger qui s\u2019occupent de la promotion de la destination et qui pourraient faire une collecte d\u2019information continue. On peut attribuer ce retard \u00e9galement \u00e0 une prise de conscience r\u00e9cente au niveau politique de l\u2019information pour un r\u00e9el pilotage strat\u00e9gique ainsi qu\u2019une m\u00e9connaissance de la part des h\u00f4teliers.<\/font><\/div>\n<div> <font>Une place de premier choix \u00e0 conqu\u00e9rir<\/font><\/div>\n<div> <font>Malgr\u00e9 des discours et des d\u00e9bats entrepris dans le domaine de l\u2019intelligence \u00e9conomique, on peut constater qu\u2019\u00e0 l\u2019\u00e9vidence, la veille strat\u00e9gique n\u2019occupe pas encore la place qu\u2019elle m\u00e9rite parmi les outils de promotion et de d\u00e9fense dans le secteur du tourisme.  Un syst\u00e8me d\u2019information unique dans le futur permettrait la planification et la diffusion des connaissances serait peut-\u00eatre une impulsion pour att\u00e9nuer le d\u00e9calage par rapport \u00e0 nos concurrents. Cela peut rendre plus facile l\u2019accompagnement des entreprises dans leurs d\u00e9marches de prospections des march\u00e9s internationaux et dans leurs approches. Cr\u00e9er une culture partag\u00e9e du gagnant-gagnant visant \u00e0 anticiper l\u2019avenir et \u00e0 accro\u00eetre la comp\u00e9titivit\u00e9 nationale semble \u00eatre la juste place de l\u2019intelligence strat\u00e9gique dans le tourisme tunisien.<\/font><\/div>\n<div> <font>* Cabinet conseil d\u2019intelligence \u00e9conomique Fyeld Consulting <\/font><a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.fyeldconsulting.com<\/font><\/a><\/div>\n<div> <font>sofian@fyeldconsulting.com Cette adresse email est prot\u00e9g\u00e9e contre les robots des spammeurs, vous devez activer Javascript pour la voir. <\/font><\/div>\n<div>\u00a0<\/div>\n<div><strong><font>(Source : \u00ab Kapitalis \u00bb, le 9 juin 2011)<\/font><\/strong><\/div>\n<div> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.kapitalis.com\/kapital\/34-economie\/4295-la-veille-strategique-pour-le-maintien-du-tourisme-en-tunisie.html<\/font><\/a><\/div>\n<div dir=\"rtl\">\u00a0<\/div>\n<hr\/>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Reuters, le 9 juin 2011 \u00e0 04h17 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Kadhafi a encourag\u00e9 les viols d&rsquo;opposants &#8211; procureur de la CPI<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">NATIONS UNIES, 9 juin (Reuters) &#8211; Les enqu\u00eateurs de la Cour p\u00e9nale internationale (CPI) ont des preuves que Mouammar Kadhafi a encourag\u00e9 les viols d&rsquo;opposants en Libye, ce qui pourrait faire l&rsquo;objet d&rsquo;un nouveau chef d&rsquo;inculpation, a dit mercredi le procureur de la CPI.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Luis Moreno-Ocampo a requis en mai un mandat d&rsquo;arr\u00eat contre Mouammar Kadhafi pour crimes contre l&rsquo;humanit\u00e9, ainsi que contre son fils Sa\u00eff al Islam et le chef des renseignements libyens, Abdoullah al Senoussi.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les accusations de viols d&rsquo;opposants en Libye ne sont pas nouvelles. En avril, l&rsquo;ambassadrice am\u00e9ricaine aux Nations unies, Susan Rice, a affirm\u00e9 que les hommes de Kadhafi \u00e9taient aliment\u00e9s en Viagra, traitement indiqu\u00e9 contre l&rsquo;impuissance sexuelle.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Maintenant, nous recevons des informations indiquant que Kadhafi a lui-m\u00eame d\u00e9cid\u00e9 (d&rsquo;autoriser les viols) et cela est nouveau\u00a0\u00bb, a dit Moreno-Ocampo lors d&rsquo;une conf\u00e9rence de presse au si\u00e8ge de l&rsquo;Onu.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Cela n&rsquo;avait jamais fait partie de ses techniques de contr\u00f4le de la population. Le viol est un aspect nouveau de la r\u00e9pression\u00a0\u00bb, a d\u00e9clar\u00e9 le procureur de la CPI.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Moreno-Ocampo a indiqu\u00e9 que ses enqu\u00eateurs avaient trouv\u00e9 \u00ab\u00a0quelques \u00e9l\u00e9ments\u00a0\u00bb confirmant l&rsquo;achat de \u00ab\u00a0m\u00e9dicaments du type du Viagra\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il y a, a-t-il dit, des preuves que la Libye achetait des \u00ab\u00a0containers entiers\u00a0\u00bb de ces drogues \u00ab\u00a0pour augmenter la possibilit\u00e9 de violer des femmes\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il est difficile de savoir \u00e0 quel point le viol \u00e9tait r\u00e9pandu, a dit Moreno-Ocampo, ajoutant que, selon ses informations, il y avait plusieurs centaines de victimes dans certaines r\u00e9gions.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 9 juin 2011 \u00e0 07h26 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">La perspective d&rsquo;une guerre civile plane sur la Syrie<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Par Christophe SCHMIDT<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">WASHINGTON, 09 Jui 2011 (AFP) &#8211; La Syrie s&rsquo;achemine-t-elle, apr\u00e8s trois mois de r\u00e9pression, vers une guerre civile qui menacerait le r\u00e9gime tenant dans sa main de fer les communaut\u00e9s de ce pays tr\u00e8s composite? La question s&rsquo;impose aux analystes depuis l&rsquo;annonce de la mort de 120 policiers lundi.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Selon les autorit\u00e9s syriennes, ces membres des forces de l&rsquo;ordre ont \u00e9t\u00e9 tu\u00e9s \u00e0 Jisr al-Choughour (nord) par des \u00ab\u00a0groupes arm\u00e9s\u00a0\u00bb. Mais des militants des droits de l&rsquo;homme et diff\u00e9rents t\u00e9moins ont r\u00e9fut\u00e9 cette version, certains affirmant que les victimes \u00e9taient mortes lors d&rsquo;une mutinerie au QG de la S\u00e9curit\u00e9.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Dans l&rsquo;hypoth\u00e8se d&rsquo;une tentative de mutinerie ou de d\u00e9fections pour aider les manifestants, le r\u00e9gime du pr\u00e9sident Bachar al-Assad serait \u00ab\u00a0confront\u00e9 \u00e0 une r\u00e9bellion d&rsquo;ampleur diff\u00e9rente\u00a0\u00bb, commente pour l&rsquo;AFP Mohamad Bazzi, du Centre des affaires \u00e9trang\u00e8res (CFR) \u00e0 New York.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Cela pourrait amener le r\u00e9gime \u00e0 faire usage d&rsquo;une force encore plus brutale pour tenter d&rsquo;\u00e9craser la r\u00e9volte et ce pourrait \u00eatre le tournant amenant la Syrie \u00e0 une guerre civile, un conflit \u00e0 grande \u00e9chelle entre les sunnites et les alaouites\u00a0\u00bb, ces derniers \u00e9tant la minorit\u00e9 au pouvoir.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">M. Bazzi note toutefois que la t\u00eate de l&rsquo;arm\u00e9e est monopolis\u00e9e par des alaouites fid\u00e8les au clan Assad et que les minorit\u00e9s chr\u00e9tienne, druze et chiite (qui constituent environ 15% de la population) ont tendance \u00e0 \u00ab\u00a0consid\u00e9rer Assad comme une source de stabilit\u00e9\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;expert ajoute que les sunnites la\u00efcs, notamment \u00ab\u00a0la bourgeoisie commer\u00e7ante de Damas et Alep\u00a0\u00bb, ne semblent pas \u00eatre encore entr\u00e9s dans la contestation. \u00ab\u00a0Un d\u00e9but de scission dans l&rsquo;arm\u00e9e pourrait les faire basculer\u00a0\u00bb, juge-t-il, car \u00ab\u00a0Assad perdrait l&rsquo;argument selon lequel il est le seul \u00e0 pouvoir maintenir la stabilit\u00e9\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Tout le monde s&rsquo;inqui\u00e8te d&rsquo;une guerre civile qui se r\u00e9pandrait dans tout le pays\u00a0\u00bb, note de son c\u00f4t\u00e9 un diplomate europ\u00e9en \u00e0 Washington, en jugeant cette issue \u00ab\u00a0possible\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Selon les informations dont dispose cette source, l&rsquo;opposition syrienne est mieux organis\u00e9e qu&rsquo;au d\u00e9but des manifestations, sans qu&rsquo;on puisse encore parler \u00ab\u00a0d&rsquo;opposition structur\u00e9e\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pour le dissident Amr al-Azm, le r\u00e9gime d&rsquo;Assad redoute tout de m\u00eame que les opposants se constituent un fief aux fronti\u00e8res. Cela expliquerait la violence particuli\u00e8re de la r\u00e9pression, d&rsquo;abord \u00e0 Deraa, aux confins de la Jordanie, et \u00e0 Benyas, pr\u00e8s du Liban, puis ces derniers jours \u00e0 Jisr al-Choughour, \u00e0 la fronti\u00e8re turque.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les dirigeants syriens sont \u00ab\u00a0t\u00e9tanis\u00e9s \u00e0 l&rsquo;id\u00e9e que se forme un nouveau Benghazi\u00a0\u00bb, a affirm\u00e9 au New York Times cet enseignant en histoire de l&rsquo;universit\u00e9 Shawnee State, en r\u00e9f\u00e9rence \u00e0 la \u00ab\u00a0capitale\u00a0\u00bb rebelle dans l&rsquo;est de la Libye, fief de la contestation.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Parler de guerre civile est \u00ab\u00a0tr\u00e8s pr\u00e9matur\u00e9\u00a0\u00bb, conteste le blogueur et militant des droits de l&rsquo;homme Nasser Weddady, qui rappelle \u00e0 l&rsquo;AFP que \u00ab\u00a0la lutte pacifique et non-violente est l&rsquo;objectif d\u00e9clar\u00e9 des manifestants\u00a0\u00bb.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Selon lui, le r\u00e9gime d&rsquo;Assad est \u00ab\u00a0aux abois\u00a0\u00bb et \u00ab\u00a0sur la d\u00e9fensive\u00a0\u00bb. Il \u00ab\u00a0invente toutes sortes d&rsquo;histoires\u00a0\u00bb de conspiration et d&rsquo;attentats pour justifier sa violence et se pr\u00e9senter comme le garant de la stabilit\u00e9, notamment aupr\u00e8s de la communaut\u00e9 internationale.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 8 juin 2011 \u00e0 21h19 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Mosqu\u00e9e et Facebook : les deux vecteurs de la contestation en Syrie<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Par Nicolas CHEVIRON<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANTAKYA, 08 Jui 2011 (AFP) &#8211; Quand on veut contester le r\u00e9gime du pr\u00e9sident syrien Bachar al-Assad, on se rencontre d&rsquo;abord \u00e0 la mosqu\u00e9e, ou bien sur Facebook, expliquent des Syriens hospitalis\u00e9s \u00e0 Antakya, dans le sud de la Turquie, apr\u00e8s avoir \u00e9t\u00e9 bless\u00e9s par les forces de s\u00e9curit\u00e9 syriennes.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Chez nous, les manifestations ont lieu \u00e0 la sortie de la mosqu\u00e9e, apr\u00e8s la pri\u00e8re. Ca n&rsquo;est pas organis\u00e9, c&rsquo;est plut\u00f4t spontan\u00e9\u00a0\u00bb, affirme Akram, un \u00e9tudiant de 17 ans originaire d&rsquo;un village proche d&rsquo;Idlib, dans le nord-ouest de la Syrie.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Les jeunes, les vieux, les femmes, tout le monde participe\u00a0\u00bb, ajoute-t-il.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">C&rsquo;est \u00e0 la sortie de la pri\u00e8re du vendredi, le 20 mai, que les forces de s\u00e9curit\u00e9, parmi lesquelles figuraient d&rsquo;\u00e9tranges soldats v\u00eatus de noir &#8211;\u00ab\u00a0des Iraniens\u00a0\u00bb, assure Akram&#8211; ont investi le village avec des v\u00e9hicules blind\u00e9s, et ont tir\u00e9 dans la foule, se souvient le jeune homme.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;\u00e9tudiant a \u00e9t\u00e9 atteint \u00e0 la jambe gauche par une balle explosive aux effets ravageurs: deux semaines plus tard, une entaille de plusieurs centim\u00e8tres de large d\u00e9voile encore ses chairs \u00e0 vif.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il a cependant pu prendre la fuite \u00e0 travers les montagnes avant d&rsquo;\u00eatre recueilli par des inconnus qui l&rsquo;ont conduit \u00e0 la fronti\u00e8re turque.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">A Jisr al-Choughour aussi, les mosqu\u00e9es sont le point de d\u00e9part des manifestations.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0A la sortie de la pri\u00e8re, tous les gens se retrouvent sur une place centrale de la ville pour manifester. Tout le monde conna\u00eet le rendez-vous. M\u00eame les chr\u00e9tiens attendent les autres \u00e0 la sortie des mosqu\u00e9es\u00a0\u00bb, relate Rajah, un p\u00e2tissier de 23 ans originaire de cette ville du nord-ouest.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;artisan se croyait \u00e0 l&rsquo;abri des violences polici\u00e8res, plus fortes apr\u00e8s la pri\u00e8re du vendredi, alors qu&rsquo;il devisait samedi dernier avec un ami pr\u00e8s de la poste centrale de Jisr al-Choughour.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Manque de chance, la r\u00e9pression a atteint ce jour l\u00e0 un niveau in\u00e9gal\u00e9 dans la ville: elle a fait 35 morts selon l&rsquo;Observatoire syrien des droits de l&rsquo;Homme (OSDH).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">De ces violences, Rajah n&rsquo;a rien su. \u00ab\u00a0Je discutais avec un ami, et puis plus rien. Plus tard, on m&rsquo;a dit qu&rsquo;une bombe avait explos\u00e9 pr\u00e8s de moi\u00a0\u00bb, relate le jeune homme, dont le visage, le torse et les bras sont constell\u00e9s de br\u00fblures.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Si les mosqu\u00e9es sont le lieu de ralliement des manifestants, le p\u00e2tissier d\u00e9ment toute r\u00e9cup\u00e9ration de la contestation par les islamistes, et surtout par les Fr\u00e8res musulmans, dont Jisr al-Choughour constituait un fief dans les ann\u00e9es 1980.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Tous les Fr\u00e8res musulmans ont quitt\u00e9 le pays depuis longtemps, il n&rsquo;y en a plus en Syrie. S&rsquo;il y en avait, ils se feraient imm\u00e9diatement ex\u00e9cuter par le r\u00e9gime\u00a0\u00bb, assure-t-il.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La contestation n&rsquo;en a pas moins des leaders, \u00ab\u00a0des gens de la ville qu&rsquo;on respecte, des anciens, issus de diff\u00e9rents milieux\u00a0\u00bb, indique le jeune homme.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Avec sa barbe blanche et sa voix puissante, un des pensionnaires de l&rsquo;h\u00f4pital d&rsquo;Antakya, un enseignant d&rsquo;une cinquantaine d&rsquo;ann\u00e9es bless\u00e9 par balles aux deux jambes le 20 mai dans un village proche d&rsquo;Idlib, serait-il un de ces respectables anciens?<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Peut-\u00eatre. L&rsquo;homme ne d\u00e9daigne pas en tout cas les innovations technologiques pour pallier les limites de la \u00ab\u00a0spontan\u00e9it\u00e9\u00a0\u00bb en mati\u00e8re de contestation.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Les manifestations sont organis\u00e9es sur Facebook, parfois par t\u00e9l\u00e9phone quand on en a la possibilit\u00e9\u00a0\u00bb, affirme-t-il.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le r\u00e9gime syrien ne s&rsquo;y est pas tromp\u00e9, qui, selon les t\u00e9moignages de plusieurs bless\u00e9s, a coup\u00e9 le t\u00e9l\u00e9phone et l&rsquo;internet \u00e0 Jisr al-Choughour au cours des derniers jours de violences.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Fin mai, des militants pro-d\u00e9mocratie en Syrie ont d\u00e9di\u00e9 une page du r\u00e9seau social Facebook \u00e0 un gar\u00e7on de 13 ans \u00ab\u00a0tortur\u00e9 et tu\u00e9\u00a0\u00bb, selon eux, par les forces de s\u00e9curit\u00e9 \u00e0 Deraa (sud), o\u00f9 est n\u00e9e la contestation du r\u00e9gime, appelant \u00e0 des manifestations \u00e0 sa m\u00e9moire.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 9 juin 2011<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La Turquie<\/font><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANKARA, 09 Jui 2011 (AFP) &#8211; La Turquie, o\u00f9 auront lieu dimanche des \u00e9lections l\u00e9gislatives, est un pays musulman situ\u00e9 entre Europe et Asie, membre de l&rsquo;Otan, candidat \u00e0 l&rsquo;Union europ\u00e9enne, dirig\u00e9 par un gouvernement islamo-conservateur et qui a connu une croissance de 8,9 % en 2010.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; SITUATION GEOGRAPHIQUE: Pays de 779.452 km2, \u00e0 cheval entre l&rsquo;Asie et l&rsquo;Europe, baign\u00e9e par les mers Noire, de Marmara, Eg\u00e9e et M\u00e9diterran\u00e9e, la Turquie a des fronti\u00e8res avec l&rsquo;Arm\u00e9nie, la G\u00e9orgie, l&rsquo;Azerba\u00efdjan, l&rsquo;Iran, l&rsquo;Irak, la Syrie, la Gr\u00e8ce et la Bulgarie.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; POPULATION: 73,7 millions d&rsquo;habitants.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; CAPITALE: Ankara.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; LANGUE OFFICIELLE: Turc.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; RELIGION: 99% de musulmans, en majorit\u00e9 sunnites. Le pays compte aussi une importante minorit\u00e9 al\u00e9vie (15 \u00e0 20%), connue pour son interpr\u00e9tation tol\u00e9rante du Coran. La communaut\u00e9 juive compte quelque 23.000 personnes et la communaut\u00e9 arm\u00e9nienne environ 70.000.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; HISTOIRE: Chute de l&rsquo;Empire ottoman, lors de la Premi\u00e8re Guerre mondiale. Mustafa Kemal Atat\u00fcrk proclame le 29 octobre 1923 la R\u00e9publique turque, qu&rsquo;il dirigera jusqu&rsquo;\u00e0 sa mort en 1938, et modernise la Turquie.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le multipartisme est introduit en 1946, mais la vie politique est marqu\u00e9e par trois coups d&rsquo;Etat militaires suivis de dures r\u00e9pressions (1960, 1971 et 1980).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le Parti des travailleurs du Kurdistan (PKK) a lanc\u00e9 en 1984 une r\u00e9bellion arm\u00e9e qui a fait plus de 45.000 morts.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; SITUATION POLITIQUE: Le pr\u00e9sident de la R\u00e9publique (actuellement Abdullah G\u00fcl, \u00e9lu par le parlement en ao\u00fbt 2007) a des fonctions largement honorifiques.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Recep Tayyip Erdogan a \u00e9t\u00e9 nomm\u00e9 Premier ministre en mars 2003, succ\u00e9dant \u00e0 Abdullah G\u00fcl, tous deux \u00e9tant issus de la mouvance islamiste. Son Parti de la justice et du d\u00e9veloppement (AKP) avait remport\u00e9 une victoire \u00e9crasante aux l\u00e9gislatives anticip\u00e9es de novembre 2002, mettant fin \u00e0 plus d&rsquo;une d\u00e9cennie de gouvernements de coalition.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;AKP a \u00e9t\u00e9 reconduit au pouvoir avec une confortable majorit\u00e9 lors de l\u00e9gislatives anticip\u00e9es en juillet 2007.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La Turquie est dot\u00e9e d&rsquo;un Parlement monocam\u00e9ral constitu\u00e9 de 550 d\u00e9put\u00e9s.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; ECONOMIE: L&rsquo;\u00e9conomie turque a souffert fin 2008 et en 2009 de la crise \u00e9conomique mondiale, entrant en r\u00e9cession, avant de renouer avec une forte croissance (8,9 % en 2010).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le tourisme est l&rsquo;une des principales sources de devises du pays. Il a repr\u00e9sent\u00e9 22 milliards de dollars avec 32 millions de visiteurs en 2009.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La Turquie a entam\u00e9 en octobre 2005 de difficiles n\u00e9gociations d&rsquo;adh\u00e9sion \u00e0 l&rsquo;Union europ\u00e9enne.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Produit national brut (PNB) par habitant: 10.079 dollars en 2010 (institut officiel T\u00fcik).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Ch\u00f4mage: 14 % en 2009.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Monnaie: la livre turque (TL).<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; FORCES ARMEES: 510.600 hommes (IISS 2010).<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Reuters, le 9 juin 2011 \u00e0 12h51 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Les \u00e9lections l\u00e9gislatives en Turquie<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ISTANBUL, 9 juin (Reuters) &#8211; La Turquie organise dimanche des \u00e9lections l\u00e9gislatives.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les 550 d\u00e9put\u00e9s de la nouvelle Grande Assembl\u00e9e nationale, unique chambre du parlement, si\u00e8geront pour quatre ans. <\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le Parti de la Justice et du D\u00e9veloppement (AKP), formation conservatrice au pouvoir depuis 2002, devrait obtenir une nouvelle majorit\u00e9 absolue.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Voici quelques \u00e9l\u00e9ments sur ces \u00e9lections:<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Les bureaux de vote ouvriront \u00e0 07h00 (04h00 GMT) dans l&rsquo;est de la Turquie et \u00e0 08h00 (05h00 GMT) dans les r\u00e9gions occidentales, y compris Ankara, la capitale, et Istanbul, la plus grande ville du pays et son coeur \u00e9conomique.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Les bureaux de vote fermeront \u00e0 16h00 dans l&rsquo;Est et \u00e0 17h00 dans l&rsquo;Ouest.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Il n&rsquo;y a pas de projections effectu\u00e9es \u00e0 partir de sondages \u00e0 la sortie des urnes et il est interdit de communiquer le moindre r\u00e9sultat jusqu&rsquo;\u00e0 21h00 (18h00 GMT), heure \u00e0 laquelle sont attendus les premiers r\u00e9sultats non d\u00e9finitifs. La r\u00e9partition approximative des si\u00e8ges devrait \u00eatre connue dans la soir\u00e9e de dimanche. Le Haut Conseil \u00e9lectoral ne devrait pas annoncer les r\u00e9sultats officiels avant le 19 juin.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Environ 50 millions de Turcs vivant dans leur pays et 2,5 millions d&rsquo;autres r\u00e9sidant \u00e0 l&rsquo;\u00e9tranger sont autoris\u00e9s \u00e0 voter sur une population totale de 74 millions d&rsquo;habitants. Environ cinq millions de jeunes voteront pour la premi\u00e8re fois \u00e0 un scrutin national.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Quinze partis concourent \u00e0 ces \u00e9lections pour 7.695 candidats, y compris les ind\u00e9pendants.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Pour obtenir une repr\u00e9sentation au parlement, un parti doit obtenir au moins 10% des voix sur le plan national. Ce seuil, l&rsquo;un des plus \u00e9lev\u00e9s au monde, emp\u00eache beaucoup de petites formations d&rsquo;avoir des d\u00e9put\u00e9s. Certains, comme le parti pro-kurde Paix et D\u00e9mocratie, contournent la difficult\u00e9 en pr\u00e9sentant des candidats ind\u00e9pendants, qui peuvent ensuite les repr\u00e9senter au parlement s&rsquo;ils sont \u00e9lus.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">&#8211; Seuls trois partis devraient obtenir des d\u00e9put\u00e9s &#8211; l&rsquo;AKP, le Parti r\u00e9publicain du peuple (CHP) de centre gauche, et le parti du Mouvement nationaliste (MHP) &#8211; ainsi que 28 ind\u00e9pendants au moins, selon les instituts de sondage.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 9 juin 2011<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Turquie: un mode de scrutin qui favorise les grands partis<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANKARA, 09 Jui 2011 (AFP) &#8211; Le mode de scrutin qui sera appliqu\u00e9 dimanche en Turquie pour les \u00e9lections l\u00e9gislatives est bas\u00e9 sur la proportionnelle et favorise les grands partis.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le Parti de la justice et du d\u00e9veloppement (AKP, issu de la mouvance islamiste) au pouvoir, qui part grand favori pour un troisi\u00e8me mandat cons\u00e9cutif depuis 2002, selon les sondages, profite de ce syst\u00e8me.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L&rsquo;une des raisons tient \u00e0 la taille tr\u00e8s variable des circonscriptions, ce<span><\/span>qui favorise les zones rurales.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ainsi le d\u00e9put\u00e9 d&rsquo;une r\u00e9gion rurale de l&rsquo;est ou du sud-est repr\u00e9sente en moyenne 30.000 \u00e9lecteurs, contre 80.000 pour un d\u00e9put\u00e9 de l&rsquo;ouest urbanis\u00e9.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Istanbul, avec 13 millions d&rsquo;habitants recens\u00e9s, envoie 85 d\u00e9put\u00e9s (sur 550) au Parlement. Et la petite province de Tunceli (est, 77.000 habitants) en envoie deux. 108.000 voix sont n\u00e9cessaires \u00e0 Istanbul pour remporter un si\u00e8ge contre 28.000 \u00e0 Tunceli, soit quatre fois moins.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les si\u00e8ges sont attribu\u00e9s aux listes pr\u00e9sent\u00e9es par les partis, proportionnellement au nombre de voix obtenu, selon ce syst\u00e8me, appel\u00e9 \u00ab\u00a0syst\u00e8me d&rsquo;Hondt\u00a0\u00bb, du nom d&rsquo;un juriste belge.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">On divise le nombre total de voix par le nombre de si\u00e8ges \u00e0 pourvoir dans chaque circonscription. Le score r\u00e9alis\u00e9 par chaque parti est alors divis\u00e9 par ce quotient pour d\u00e9terminer le nombre de si\u00e8ges attribu\u00e9s \u00e0 chaque parti.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ce syst\u00e8me de calcul favorise les grands partis. Mais ceux-ci profitent plus encore du fait qu&rsquo;un parti n&rsquo;obtient aucun si\u00e8ge s&rsquo;il ne recueille pas au minimum 10% des suffrages exprim\u00e9s \u00e0 l&rsquo;\u00e9chelle nationale.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Cette disposition controvers\u00e9e n&rsquo;a pas \u00e9t\u00e9 abandonn\u00e9e, malgr\u00e9 des promesses en ce sens faites par l&rsquo;AKP, qui est le premier \u00e0 en profiter.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">De tels seuils existent dans plusieurs pays d&rsquo;Europe, mais ils ne d\u00e9passent pas les 5%.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">En 2002, l&rsquo;AKP a obtenu 34,2% des voix aux l\u00e9gislatives, enlevant 363 si\u00e8ges, soit 66% du Parlement. En 2007, l&rsquo;AKP a remport\u00e9 46,5% des voix et obtenu 341 si\u00e8ges (62% du Parlement).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">En 2002 et 2007 respectivement, 45% et 13% des suffrages exprim\u00e9s ont \u00e9t\u00e9 \u00e9cart\u00e9es du Parlement en raison du seuil des 10%.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les partis pro-kurdes, qui recueillent l&rsquo;essentiel de leurs votes dans le sud-est et les m\u00e9tropoles de l&rsquo;ouest \u00e0 fortes communaut\u00e9s kurdes, se retrouvent ainsi exclus du Parlement.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pour contourner ce barrage, la principale force politique kurde, le Parti de la paix et de la d\u00e9mocratie (BDP), pr\u00e9sente des candidats ind\u00e9pendants, qui une fois \u00e9lus, se retrouveront sous le drapeau de leur formation au Parlement.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 9 juin 2011<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Erdogan, recordman de long\u00e9vit\u00e9 politique, figure charismatique et controvers\u00e9e<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANKARA, 09 Jui 2011 (AFP) &#8211; Le Premier ministre turc Recep Tayyip Erdogan, qui vise un troisi\u00e8me mandat lors des l\u00e9gislatives dimanche, est une figure charismatique venue de l&rsquo;islamisme politique, dont les d\u00e9clarations de plus en plus virulentes font douter certains de l&rsquo;avenir de la d\u00e9mocratie turque.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Connu pour son franc parler et des sorties parfois brutales contre la presse ou ses opposants, cet ancien maire d&rsquo;Istanbul, 57 ans, est pass\u00e9 par l&rsquo;islamisme politique avant de se convertir \u00e0 la \u00ab\u00a0d\u00e9mocratie conservatrice\u00a0\u00bb, comme il d\u00e9finit lui-m\u00eame la ligne de son Parti de la Justice et du d\u00e9veloppement (AKP), au pouvoir depuis 2002.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Une \u00e9volution que ne convainc pas l&rsquo;opposition la\u00efque, attach\u00e9e aux principes de la R\u00e9publique d&rsquo;Atat\u00fcrk, qui lui reproche de vouloir islamiser la soci\u00e9t\u00e9 turque, \u00e0 tout le moins d&rsquo;accompagner une telle \u00e9volution.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Consid\u00e9r\u00e9 lors de son premier mandat comme un important r\u00e9formateur cherchant \u00e0 d\u00e9mocratiser la soci\u00e9t\u00e9 turque face \u00e0 l&rsquo;influence politique des militaires, il a obtenu en 2005 le lancement de n\u00e9gociations d&rsquo;adh\u00e9sion avec l&rsquo;Union europ\u00e9enne, qui sont aujourd&rsquo;hui au point mort.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il a \u00e9t\u00e9 salu\u00e9 lors de son deuxi\u00e8me mandat (2007-2011) pour avoir remis sur pied l&rsquo;\u00e9conomie, malgr\u00e9 la crise globale. En 2010, la Turquie a enregistr\u00e9 un taux de croissance \u00ab\u00a0\u00e0 la chinoise\u00a0\u00bb de 8,9 %.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Mais apr\u00e8s une victoire sans appel de son parti aux l\u00e9gislatives de 2007, nombre d&rsquo;analystes ont d\u00e9nonc\u00e9 chez M. Erdogan des tendances populistes et autocratiques, et la volont\u00e9 d&rsquo;orienter la diplomatie turque vers le Moyen Orient, notamment l&rsquo;Iran, au d\u00e9triment de l&rsquo;Europe et des traditionnels alli\u00e9s de l&rsquo;Otan, dont le pays fait partie. Accusations qu&rsquo;il a toujours r\u00e9fut\u00e9es.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pendant la campagne \u00e9lectorale, il a qualifi\u00e9 les manifestants anti-gouvernementaux de \u00ab\u00a0bandits\u00a0\u00bb, faisant peu de cas de la mort par crise cardiaque d&rsquo;un quinquag\u00e9naire, intoxiqu\u00e9 par les gaz lacrymog\u00e8nes de la police.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il a aussi d\u00e9fendu l&rsquo;arrestation de journalistes accus\u00e9s d&rsquo;implication dans des complots anti-gouvernement pr\u00e9sum\u00e9s, les comparant \u00e0 des \u00ab\u00a0bombes\u00a0\u00bb pr\u00eates \u00e0 exploser.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Issu des quartiers pauvres d&rsquo;Istanbul, M. Erdogan se vante d&rsquo;avoir dans son enfance vendu des bonbons pour payer ses \u00e9tudes coraniques.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il est devenu Premier ministre en mars 2003, plusieurs mois apr\u00e8s que l&rsquo;AKP eut acc\u00e9d\u00e9 au pouvoir et amend\u00e9 les lois qui l&rsquo;interdisaient, depuis 1997, d&rsquo;activit\u00e9 politique.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Alors qu&rsquo;il \u00e9tait maire d&rsquo;Istanbul, M. Erdogan avait en effet r\u00e9cit\u00e9 au cours d&rsquo;un meeting un po\u00e8me aux connotations islamistes qui lui avait valu quatre mois de prison et la perte de ses droits politiques.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ses d\u00e9buts dans le militantisme islamiste remontent \u00e0 ses ann\u00e9es d&rsquo;universit\u00e9, quand il avait rejoint le mouvement de Necmettin Erbakan, son mentor politique, d\u00e9c\u00e9d\u00e9 cette ann\u00e9e.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ce dernier \u00e9tait devenu en 1996 le premier chef de gouvernement islamiste de Turquie, avant d&rsquo;\u00eatre chass\u00e9 un an plus tard du pouvoir sous la pression de l&rsquo;arm\u00e9e et des milieux la\u00efcs.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Elu maire d&rsquo;Istanbul en 1994, M. Erdogan s&rsquo;\u00e9tait acquis une forte popularit\u00e9 gr\u00e2ce \u00e0 l&rsquo;efficacit\u00e9 de sa gestion des services municipaux.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Mais la d\u00e9mission forc\u00e9e en 1997 de M. Erbakan et l&rsquo;interdiction de son parti ont incit\u00e9 M. Erdogan et ses supporters \u00ab\u00a0modernistes\u00a0\u00bb \u00e0 revoir leur vision de la politique.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">A sa sortie de prison, il avait ainsi affirm\u00e9 avoir tir\u00e9 un trait sur son pass\u00e9 islamiste, clamant son attachement aux valeurs pro-occidentales et \u00e0 la la\u00efcit\u00e9.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il demeure n\u00e9anmoins un musulman pratiquant, qui ne boit pas d&rsquo;alcool et dont l&rsquo;\u00e9pouse et les filles portent le voile.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">AFP, le 9 juin 2011<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Erdogan brigue un troisi\u00e8me mandat, durcit le ton contre l&rsquo;opposition<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Par Burak AKINCI<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">ANKARA, 09 Jui 2011 (AFP) &#8211; Le parti islamo-conservateur du Premier ministre Recep Tayyip Erdogan compte bien sur une troisi\u00e8me victoire d&rsquo;affil\u00e9e, m\u00eame si l&rsquo;opposition grimpe dans les sondages, lors des \u00e9lections l\u00e9gislatives dimanche en Turquie.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Selon toutes les \u00e9tudes d&rsquo;opinion, la victoire du Parti de la justice et du d\u00e9veloppement (AKP), au pouvoir depuis 2002, ne fait pas de doute.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Dans ce contexte, le principal suspense du scrutin, qui vise \u00e0 renouveler les 550 membres du Parlement monocam\u00e9ral, est de savoir si l&rsquo;AKP obtiendra assez de si\u00e8ges pour faire adopter une Constitution plus lib\u00e9rale, en remplacement de celle r\u00e9dig\u00e9e apr\u00e8s le putsch militaire de 1980.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">M. Erdogan souhaite en effet poursuivre le travail commenc\u00e9 sur la Constitution, r\u00e9vis\u00e9e plusieurs fois, dont la derni\u00e8re en 2010.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Il affirme vouloir approfondir la d\u00e9mocratisation de la Turquie, candidate \u00e0 l&rsquo;Union europ\u00e9enne, o\u00f9 il voudrait voir instaurer un r\u00e9gime pr\u00e9sidentiel. Mais une partie de l&rsquo;opinion craint de voir le pays sombrer dans un autoritarisme \u00ab\u00a0\u00e0 la Poutine\u00a0\u00bb avec ces changements.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Un des trois sc\u00e9narios suivants est attendu dimanche: si l&rsquo;AKP d\u00e9passe la barre des 367 d\u00e9put\u00e9s, soit une majorit\u00e9 des deux-tiers, il pourra changer la constitution sans avoir recours \u00e0 un r\u00e9f\u00e9rendum. Avec au moins 330 si\u00e8ges, sans atteindre 367, le parti au pouvoir devra organiser un r\u00e9f\u00e9rendum. Enfin, \u00e0 moins de 330, il lui faudrait l&rsquo;aide d&rsquo;autres partis, ou abandonner son projet.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les sondages donnent l&rsquo;AKP gagnant avec environ 45% voix, voire 50% (47% aux derni\u00e8res l\u00e9gislatives de 2007).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Mais le principal parti d&rsquo;opposition pro-la\u00efque (CHP, Parti r\u00e9publicain du peuple), dirig\u00e9 par Kemal Kili\u00e7daroglu, semble capable d&rsquo;une perc\u00e9e, avec 30% des intentions de vote (21% en 2007). Les observateurs expliquent cette mont\u00e9e du CHP par le charisme de son leader, connu pour sa lutte anti-corruption, qui a cr\u00e9\u00e9 une nouvelle dynamique au sein du parti k\u00e9maliste.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La campagne \u00e9lectorale a \u00e9t\u00e9 marqu\u00e9e notamment par des scandales sexuels, plusieurs dirigeants du Parti de l&rsquo;action nationaliste (MHP), ayant d\u00e9missionn\u00e9 apr\u00e8s la diffusion sur internet de vid\u00e9os montrant ces hommes mari\u00e9s dans des situations compromettantes.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Cette formation sera tr\u00e8s probablement en troisi\u00e8me position dans la liste des 15 partis en lice, et elle devrait passer le seuil des 10% de voix \u00e0 l&rsquo;\u00e9chelle nationale, impos\u00e9 aux partis pour obtenir des d\u00e9put\u00e9s.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Une trentaine de candidats se pr\u00e9sentant en ind\u00e9pendants mais soutenus par le principal parti kurde, le Parti pour la paix et la d\u00e9mocratie (BDP), devraient aussi entrer \u00e0 l&rsquo;Assembl\u00e9e, contre 20 aujourd&rsquo;hui.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Ces derni\u00e8res semaines, M. Erdogan a accabl\u00e9 ses adversaires de vives critiques, visant parfois leur vie priv\u00e9e, s&rsquo;en prenant au passage \u00e0 des journalistes et hommes d&rsquo;affaires connus comme opposants.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pour Sedat Ergin, du journal H\u00fcrriyet, l&rsquo;AKP est parvenu \u00e0 s&rsquo;approprier toutes les institutions, au fil des ans, et M. Erdogan semble pris d&rsquo;une tentation h\u00e9g\u00e9monique.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Impitoyable \u00e0 l&rsquo;\u00e9gard des critiques, il affirme un style de plus en plus autoritaire (&#8230;) et avec les arrestations de journalistes d&rsquo;opposition, accus\u00e9s de comploter contre l&rsquo;Etat, un climat de censure s&rsquo;est install\u00e9 dans le pays\u00a0\u00bb, dit-il.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">La popularit\u00e9 du Premier ministre repose largement sur les succ\u00e8s \u00e9conomiques du pays: en 2010, la Turquie a enregistr\u00e9 le troisi\u00e8me meilleur taux de croissance du G20 (8,9%).<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Au del\u00e0 du boom \u00e9conomique, le nouveau gouvernement devra s&rsquo;atteler \u00e0 la question du conflit kurde, qui a fait 45.000 morts depuis le d\u00e9but de la r\u00e9bellion, en 1984.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">A l&rsquo;approche des \u00e9lections, les accrochages se sont multipli\u00e9s entre rebelles et forces de s\u00e9curit\u00e9, dans le sud-est du pays.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Reuters, le 9 juin 2011 \u00e0 08h28 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Erdogan: The boy bread vendor who changed Turkey<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Erdogan to win third term in Sunday&rsquo;s vote<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Political, economic reforms have transformed Turkey<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Concerns over Erdogan accumulating too much power<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">By Ece Toksabay and Ibon Villelabeitia<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">ISTANBUL, June 9 (Reuters) &#8211; When Tayyip Erdogan sold bread rolls as a boy on the old streets of Istanbul, Turkey was a country caught in a cycle of army coups. It languished on the fringes of Europe. Pious Turks were the underdogs of society.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">As Erdogan moves towards his second decade as prime minister, Turkey could not look more different.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">It has one of the world&rsquo;s fastest-growing economies, it is a European Union candidate and a regional heavyweight, and religious Turks have displaced the secularist elite from power.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">An autocrat and a dangerous Islamist to his enemies, a hero and a man of the people to his admirers, Erdogan has transformed this Muslim democracy since his AK Party swept to power in 2002, on a scale unseen since Kemal Ataturk founded the Turkish republic in 1923 out of the ruins of a defeated Ottoman Empire.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Opinion polls show Erdogan, 57, will comfortably win a third term of single-party rule in an election on June 12.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">While the only uncertainty at the ballot box is Erdogan&rsquo;s margin of victory, the outcome will determine the future of this complicated country of 74 million people.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Erdogan has said that if AK wins he will rewrite Turkey&rsquo;s constitution, drafted after a military coup in 1980, and there is speculation his next step could be to elevate himself to the presidency under a strengthened presidential system.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0Erdogan wants to be remembered as the man who made Turkey a global power,\u00a0\u00bb said Henri Barkey, a Turkey expert at the Carnegie Endowment for International Peace in Washington.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0And he wants to prove to the world that you can be a global player and a Muslim at the same time,\u00a0\u00bb Barkey said.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">A hot-tempered but charismatic politician, Erdogan has taken risks as he has challenged the secularist military and the judiciary, while power has shifted from the Westernised, urban elites to a new class of observant Muslims from the heartland.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Market-friendly reforms pushed by his socially conservative AK have tripled Turkey&rsquo;s per capita income in the last eight years. Bailout programmes to clean up financial meltdowns and banking collapses are now a thing of the past.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Erdogan, who does not drink or smoke and is known for chastising his aides when he catches them smoking, has also changed Turkey&rsquo;s place in the world. A long-time NATO member and U.S. ally, Turkey has deepened ties with the Middle East, including Iran, and opened new markets in Asia and Africa.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Fears by secularists that AK, which evolved from banned Islamist movements, would turn Turkey into Iran have not materialised and investors have rewarded Erdogan&rsquo;s pragmatism.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">His brief stay in prison for Islamist agitation when he was mayor of Istanbul came during his more ardent days.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">But despite this success story there are concerns about Turkey&rsquo;s future.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Critics accuse Erdogan of showing authoritarian tendencies and say he has accumulated too much power. Some fret a two-thirds AK majority would allow Erdogan to pass unilateral constitutional changes and give free rein to a man known for disliking dissent and used to having his way.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">The weakness of opposition parties, their continued disarray following the 2002 rout that first brought AK to power, only adds to the impression of Erdogan&rsquo;s complete domination.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">If elected, Erdogan would not be allowed to run for a fourth term. But campaign materials intimate that he plans to remain on the political scene well beyond then; in posters and brochures he strikes an unsmiling, paternal pose reminiscent of Turkey&rsquo;s revered founder Ataturk, and uses the slogan \u00ab\u00a0Objective 2023\u00a0\u00bb &#8212; the 100th anniversary of Turkey&rsquo;s foundation.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0Turkey is a more self-confident country with high growth, a banking sector and public finances looking good, with a consumer and housing boom, and young demographics, but there is clearly a concern about concentration of power,\u00a0\u00bb Timothy Ash, a London-based analyst from Royal Bank of Scotland, told Reuters.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">STREETS OF KASIMPASA<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">The son of a boat captain from the Black Sea, Erdogan migrated as a child to Istanbul, where biographers say he sold bread rolls and lemonade to help pay for his religious school.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Biographers say Erdogan&rsquo;s combative and populist traits can be traced to the idiosyncracies of Kasimpasa, an old Istanbul neighbourhood made up of workers from the countryside and shopkeepers, where men take pride in their swaggering ways.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">In Kasimpasa&rsquo;s steep, narrow streets, Erdogan is still seen as one of them. Tea houses and shops display his portraits, some on the campaign trail and others dressed in soccer attire from his days as a semi-professional player, and neighbours speak respectfully of \u00ab\u00a0Basbakanimiz\u00a0\u00bb (our prime minister).<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0He makes us feel proud,\u00a0\u00bb said Adnan Savas, 45, who runs a kebab shop. \u00ab\u00a0You can come fom Kasimpasa and become a prime minister so he encourages our children to work hard. You can be a good Muslim, preserve your values, and be very successful.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">A Reuters reporter who wandered into Kasimpasa one recent afternoon witnessed a shooting in broad daylight: A crowd gathered around a man lying wounded on the ground as police chased down and arrested his assailant.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0We are used to it: stabbings, fist-fights, shootings. People from Kasimpasa are actually very good inside, but they happen to be quick-tempered,\u00a0\u00bb said waiter Elif Gorgulu.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0They are very protective of their honour and can&rsquo;t take insults calmly. You have to watch your back around here.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0POLITICAL ANIMAL\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Although he is a divisive figure, even Erdogan&rsquo;s most militant enemies would contend he is force to be reckoned with.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Microphone in hand and pacing the stage at rallies of enthusiastic supporters, Erdogan knows how to work a crowd.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">He quotes local religious philosophers, slams his enemies as \u00ab\u00a0dark forces\u00a0\u00bb resisting change, lists public works completed under his government and adorns his speeches with streetwise vernacular the secular elite in the capital Ankara frowns upon.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Lately, he has been reciting the lyrics of a popular Turkish folk song to frenzied audiences who roar the words back to him as if in a declaration of love.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0We walked together on this path, we got wet together under this rain, now whenever I listen to a song, everything reminds me of you,\u00a0\u00bb Erdogan and the crowd chant at each other.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0He is a political animal, but the drawback is that he has become the unique decision maker in the country,\u00a0\u00bb said Cengiz Aktar, a professor at Istanbul&rsquo;s Bahcesehir University.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0The presidential system looks like a very autocratic idea. He would like to consolidate his power with more power, but without checks and balances. Turkey might face serious challenges in the future if we go down that path.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Many Turks respect Erdogan for restoring stability in a country plagued by decades of chaotic coalitions, coups and failed international financial bailouts, and for giving them confidence in their country.<\/font><\/span><\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0He is still in a way the soccer player from Kasimpasa and that is part of Turkey&rsquo;s success. His story is that upward mobility can happen in Turkey,\u00a0\u00bb Barkey said.<\/font><\/span><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><i><u><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Reuters, le 9 juin 2011 \u00e0 08h01 GMT<\/font><\/span><\/u><\/i><\/div>\n<div align=\"center\"><b><span><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\">Islamic trade finance seen lifting growth of sector<\/font><\/h4>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Islamic trade finance may grab 20 pct of OIC trade finance<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Islamic finance innovations aid growth in industry<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">* Asia-Middle East trade flows to lift Islamic trade finance<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">By Shaheen Pasha<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">DUBAI, June 9 (Reuters) &#8211; Islamic trade finance has benefitted from shifting preferences towards Sharia-compliant banking and could serve as one of the key growth drivers to help the nearly $1 trillion Islamic finance industry double in size.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">The global Islamic finance industry, which has been growing between 15 to 20 percent a year, is widely expected to reach $2 trillion in the next three to five years.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">While Islamic banking and Islamic bonds, or sukuk, are expected to lead growth, bankers say Islamic trade finance could serve as the dark horse emerging to propel the industry further.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Trade finance, the lifeblood of global commerce, underpins 60-80 percent of the $12-13 trillion trade in global merchandise and practitioners say it is safer than other forms of lending.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Total trade finance among the 57 members of the Organization of the Islamic Conference, which includes Saudi Arabia, Malaysia and Turkey, is expected to reach $4 trillion by 2012, said Mohamad Nedal Alchaar, secretary-general of the Accounting &amp; Auditing Organization for Islamic Financial Institutions (AAOIFI).<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0(Islamic finance) could tap 20 percent of the total trading financing, that&rsquo;s very reasonable,\u00a0\u00bb Alchaar said, adding that while the current Islamic trade finance market remains fragmented and non-competitive, there has been a shift towards pushing trade finance among Islamic practitioners.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Part of the increased interest in Islamic trade finance is that the Islamic finance industry, which prohibits interest, has matured and can provide complicated instruments, such as Sharia-compliant hedging products to protect trade transactions, said Yakub Bobat, global head of HSBC Amanah commercial banking.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0If you don&rsquo;t have access to Islamic hedging, there will be a currency conversion impact. In the absence of those solutions, people go for conventional,\u00a0\u00bb Bobat said. \u00ab\u00a0But the proposition is now complete and you can now use Islamic hedges for trade transactions.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Bobat said such innovations in the industry will help persuade people inclined toward Sharia-compliant business to opt for Islamic trade finance over conventional forms.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">In Islamic trade finance, a bank will provide a letter of credit, guaranteeing import payments using its own funds, for a client based on sharing the profit from the sale of the item.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">But some banks are still wary of providing Islamic trade finance services, citing it as more costly and time consuming.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">In addition, some see little difference between conventional and Islamic trade finance as both are fee-based products, resulting in lower demand for the Islamic product.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Changing that view will be key for the industry, said Shabir Randeree, chairman of the European Islamic Investment Bank.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">EAST-EAST TRADE FLOWS GROW<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0There is a very compelling reason to promote this product given that the returns of trade financing can be very attractive, much more than real estate financing, for example,\u00a0\u00bb he said. \u00ab\u00a0Providers of this product have not been as aggressive in promoting it.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">But with increasing cross-border trade among Asian and Middle Eastern countries, demand for more Sharia-compliant financing from Muslims is still expected to increase.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Asia to Middle East trade flows more than doubled between 2005 and 2008, according to the World Trade Organization.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0If I compare three years back, volumes have gone up overall in the Islamic trade finance market,\u00a0\u00bb said Ghazanfar Naqvi, managing director, Islamic origination and client coverage at Standard Chartered Saadiq. <\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0It&rsquo;s a function of more awareness and more offerings. Today we are seeing customer preference changing and trade finance is a key component of growth in Islamic finance.\u00a0\u00bb<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">Naqvi said it was difficult to pin down tangible global figures for Islamic trade finance as the majority of deals are not public transactions. <\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">The International Islamic Trade Finance Corp. (ITFC), an independent entity within the Islamic Development Bank, said in its annual report that it approved $2.17 billion in Islamic trade finance transactions at the end of 2009.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">That grew to around $2.55 billion in 2010, with a majority of transactions taking place in OIC member nations.<\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">HSBC Amanah&rsquo;s Bobat said Islamic trade finance will be a significant contributor to growth in Islamic finance but the industry will have to look beyond asset finance.<span><\/span><\/font><\/span><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><span><font face=\"Arial\" size=\"2\">\u00ab\u00a0The industry today is pretty much focused on asset finance and it needs to have the ability to capitalise on trade,\u00a0\u00bb he said. \u00ab\u00a0(Islamic trade finance) should be as much bread and butter business as it is for conventional trade flows.\u00a0\u00bb<\/font><\/span><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h4 style=\"color: blue;\"><font size=\"3\">Les r\u00e9volutions arabes et la d\u00e9soccidentalisation du monde<\/font><\/h4>\n<p><\/strong><\/div>\n<div>\n<hr\/>\n<\/div>\n<div><font>Les journ\u00e9es fatidiques qui ont vu en Tunisie, la chute d&rsquo;un dictateur prot\u00e9g\u00e9 et soutenu par l&rsquo;Occident, marquent une nouvelle \u00e9tape dans les relations entre le Nord et le Sud. Europ\u00e9ens et Am\u00e9ricains ont construit leurs alliances avec des r\u00e9gimes arabes qui, les uns apr\u00e8s les autres sont menac\u00e9s ou en voie de disparition. De cette nouvelle donne on peut d&rsquo;ores et d\u00e9j\u00e0 tirer deux enseignements :  Les bouleversements en cours marque la fin de l&rsquo;h\u00e9g\u00e9monie am\u00e9ricaine dans la r\u00e9gion, n\u00e9e de la crie de Suez en 1956.  Ensuite elle nous rappelle, pour ceux qui doutaient encore, que l&rsquo;histoire continue et qu&rsquo;il n&rsquo;y a pas de d\u00e9terminisme culturel.  Les jeunes ch\u00f4meurs de Casablanca, les classes moyennes urbanis\u00e9es du Caire ou les paysans y\u00e9m\u00e9nites, expriment la m\u00eame revendication. Non seulement ils sont revenus dans l&rsquo;Histoire, mais ils l&rsquo;ont \u00e9crite. Avec leurs r\u00e9f\u00e9rents culturels, leurs slogans (\u00ab d\u00e9gage \u00bb) et une farouche d\u00e9termination politique. Le fil d&rsquo;Ariane  Ce vaste mouvement a rassembl\u00e9 des couches sociales tr\u00e8s diff\u00e9rentes, anim\u00e9es par des int\u00e9r\u00eats, parfois divergents, mais agit\u00e9es par des id\u00e9es si famili\u00e8res \u00e0 nos \u00e9lites germanopratines. Qu&rsquo;elles en rest\u00e8rent sans voix.  Ces mobilisations auraient pu sonner comme un hommage, au Vieux Continent, \u00e0 ses valeurs, \u00e0 ses principes. Le peuple mobilis\u00e9, le peuple rassembl\u00e9, le peuple lib\u00e9r\u00e9, un petit air de 1789\u2026  La France, refuse l&rsquo;obstacle, elle n&rsquo;a jou\u00e9 aucun r\u00f4le positif, elle n&rsquo;est plus au centre du jeu. L&rsquo;histoire retiendra que c&rsquo;est \u00e0 Tunis que s&rsquo;est bris\u00e9 le fil d&rsquo;Ariane qui relie, depuis les conqu\u00eates coloniales, le Maghreb \u00e0 l&rsquo;Europe. Toutefois il convient de souligner, que ces r\u00e9volutions ne se font ni avec l&rsquo;Occident, ni contre lui, signe d&rsquo;un recul de son influence et de son d\u00e9clin face \u00e0 l&rsquo;\u00e9mergence de la puissance chinoise. Au Maghreb comme au Moyen orient, en Afrique, comme en Asie du sud. Am\u00e9ricains et Europ\u00e9ens doivent composer avec une Chine conqu\u00e9rante  Les trois Grands La Chine, qui n&rsquo;a jamais eu de vocation expansionniste, impose plus qu&rsquo;elle ne n\u00e9gocie sa place. Elle propose une vision d\u00e9sid\u00e9ologis\u00e9e de la mondialisation. La Chine ne vend pas de mod\u00e8le culturel, elle assure sa position pour le demi-si\u00e8cle \u00e0 venir. Un nouvel ordre mondial prend forme sous nos yeux, les Empires issus des guerres coloniales du 19\u00e8 si\u00e8cle sont affaiblis, mais ils ne dispara\u00eetront pas. Les Etats-Unis sous la f\u00e9rule de Barak Obama tentent de red\u00e9finir une doctrine diplomatique. L&rsquo;Inde se cherche un r\u00f4le, mais ne semble pas avoir d&rsquo;app\u00e9tit strat\u00e9gique. Ce sont trois grands p\u00f4les g\u00e9opolitiques qui \u00e9mergent : Etats-Unis, Union Europ\u00e9enne et Chine. La Russie vaste pays en voie de d\u00e9peuplement, vit dans le souvenir de la puissance sovi\u00e9tique, sans avoir pu, depuis la dislocation de l&rsquo;URSS, d\u00e9finir un projet viable. La g\u00e9opolitique du XXI\u00e8 si\u00e8cle ressemble au 1984 de George Orwell , si ce n&rsquo;est que le d\u00e9coupage (Oc\u00e9ania, Eurasia et Eastasia) est ici remplac\u00e9 par un d\u00e9coupage Am\u00e9rique, Europe et Chine. P\u00e9kin \u00e0 la manoeuvre  Dans le monde entier P\u00e9kin d\u00e9ploie ses ing\u00e9nieurs, ses hommes d&rsquo;affaires, ses architectes ou ses ouvriers. En Afrique elle garantie son approvisionnement \u00e9nerg\u00e9tique et r\u00e9alise d&rsquo;importants investissements dans le secteur de la finance. En Am\u00e9rique latine, au Canada, dans les Cara\u00efbes, la Chine conclut des accords commerciaux et planifie sa s\u00e9curit\u00e9 alimentaire. Si les \u00e9conomistes s&rsquo;accordent \u00e0 admettre que l&rsquo;Europe constitue une attraction, qui attire dans son orbite des pays p\u00e9riph\u00e9riques, elle reste politiquement tr\u00e8s divis\u00e9e. Les Etats-Unis projette l&rsquo;image de l \u00bb \u00ab Empire du Chaos \u00bb , et la p\u00e9riode Bush n&rsquo;a pas contribu\u00e9 \u00e0 combler le foss\u00e9.  Dans le vaste march\u00e9 g\u00e9opolitique du si\u00e8cle qui commence, ce sont les blocs r\u00e9gionaux, organis\u00e9s ou en voie de l&rsquo;\u00eatre (Asie centrale, Afrique australe, Asie du sud, Moyen orient, Maghreb), qui d\u00e9termineront l&rsquo;influence de chacun des \u00ab Trois Grands \u00bb. Ni la Chine, ni l&rsquo;Union europ\u00e9enne ne reprendront le r\u00f4le de super-puissance des Etats-Unis. Les trois puissances s&rsquo;affronteront pour \u00e9tendre leur influence. In fine dans ce vaste mouvement de redistribution g\u00e9opolitique, c&rsquo;es la Chine que l&rsquo;histoire replace au milieu d&rsquo;un nouveau jeu plan\u00e9taire. Les Tunisiens ont ouvert une br\u00e8che, ils ont montr\u00e9 une voie, elle n&rsquo;est pas exclusive. L&rsquo;Occident a mal interpr\u00e9t\u00e9 les aspirations populaires arabes. Une antienne marxiste assure que \u00ab la pratique est l&rsquo;unique crit\u00e8re de v\u00e9rification de la v\u00e9rit\u00e9 \u00bb. Les nouvelles relations internationales qui se dessinent, ne peuvent d\u00e9roger \u00e0 ce principe.<\/font><\/div>\n<div>\u00a0<\/div>\n<div><font><strong>(Source : \u00ab<font>rue89<\/font> \u00bb, le 9 juin 2011)<\/strong><\/font><\/div>\n<div> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.rue89.com\/2011\/06\/09\/les-revolutions-arabes-et-la-desoccidentalisation-du-monde-208595<\/font><\/a> \u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">R\u00e9volutions arabes et tourisme sexuel<\/font><\/h5>\n<p><\/strong><\/div>\n<div>\n<hr\/>\n<\/div>\n<div><strong><font>Par Pierre Vermeren, publi\u00e9 le 09\/06\/2011 \u00e0 10:41 AFP ABDELHAK SENNA<\/font><\/strong><\/div>\n<div> <font>Le \u00ab\u00a0printemps arabe\u00a0\u00bb est une insurrection pour la dignit\u00e9. Au nom de cette derni\u00e8re, l&rsquo;historien du Maghreb Pierre Vermeren* estime qu&rsquo;il faut aussi d\u00e9noncer des affaires de moeurs et des pratiques trop longtemps impunies.<\/font><\/div>\n<div> <font>A l&rsquo;heure o\u00f9 l&rsquo;affaire DSK d\u00e9fraie la chronique, il est utile de rappeler le lien entre des \u00e9v\u00e9nements qui n&rsquo;ont, a priori, rien \u00e0 voir : le \u00ab\u00a0printemps arabe\u00a0\u00bb et le tourisme sexuel. Pourtant, un fil t\u00e9nu les unit. <\/font><\/div>\n<div> <font>Le \u00ab\u00a0printemps arabe\u00a0\u00bb est une insurrection contre le m\u00e9pris et l&rsquo;humiliation, la fameuse hogra maghr\u00e9bine. Le soul\u00e8vement d\u00e9mocratique observ\u00e9 d&rsquo;un bout \u00e0 l&rsquo;autre du monde arabe d\u00e9nonce la violence contre les faibles, l&rsquo;injustice, le m\u00e9pris, la corruption, le n\u00e9potisme. Or c&rsquo;est en Egypte et en Tunisie, les deux plus grandes destinations touristiques de la r\u00e9gion, qu&rsquo;il a \u00e9t\u00e9 \u00e0 la fois le plus pr\u00e9coce et le plus abouti. Et c&rsquo;est \u00e0 Marrakech qu&rsquo;un attentat a d\u00e9lib\u00e9r\u00e9ment cibl\u00e9 en avril des touristes europ\u00e9ens. Est-ce fortuit ?<\/font><\/div>\n<div> <font>D\u00e8s l&rsquo;\u00e9poque coloniale, l&rsquo;Afrique du Nord \u00e9tait terre d&rsquo;\u00e9lection pour les amours viriles, alors criminalis\u00e9es en Europe<\/font><\/div>\n<div> <font>Ces pays sont class\u00e9s par l&rsquo;ONU sur la liste des destinations du tourisme sexuel. D\u00e8s l&rsquo;\u00e9poque coloniale, l&rsquo;Afrique du Nord \u00e9tait terre d&rsquo;\u00e9lection pour les amours viriles, alors criminalis\u00e9es en Europe; de nos jours, certains Occidentaux et de riches \u00e9mirs du Golfe profitent de cet espace de tol\u00e9rance. <\/font><\/div>\n<div> <font>Les dirigeants avis\u00e9s du Sud et leurs services de s\u00e9curit\u00e9 assurent leurs h\u00f4tes de toute la discr\u00e9tion n\u00e9cessaire, dans l&rsquo;espoir de contreparties futures <\/font><\/div>\n<div> <font>Car les affaires de moeurs sont aussi politiques et financi\u00e8res. Les dirigeants avis\u00e9s du Sud et leurs services de s\u00e9curit\u00e9 assurent leurs h\u00f4tes de toute la discr\u00e9tion n\u00e9cessaire, dans l&rsquo;espoir de contreparties futures. Ce n&rsquo;est pas au Caire, \u00e0 Djerba ou \u00e0 Marrakech que la police risque de vous sortir d&rsquo;un avion en partance pour Paris ! Bien avant Luc Ferry, de nombreux livres et \u00e9chos de presse ont rapport\u00e9 les frasques d&rsquo;hommes politiques fran\u00e7ais. Tel ministre fait ainsi scandale dans un grand h\u00f4tel du Maroc quand sa compagne d\u00e9couvre son inconduite. La passion nationale pour les riads marocains et les villas tunisiennes n&rsquo;est pas due qu&rsquo;\u00e0 l&rsquo;amour du tagine et des bricks. Tout cela est discr\u00e8tement su et tu. Or, avec la p\u00e9dophilie, c&rsquo;est de crime dont il s&rsquo;agit. <\/font><\/div>\n<div> <font>Parties fines \u00e0 l&rsquo;abri de certains riads<\/font><\/div>\n<div> <font>A Marrakech ou ailleurs, des parties fines se d\u00e9roulent \u00e0 l&rsquo;abri de certains riads, sous le regard des autorit\u00e9s, et gr\u00e2ce \u00e0 l&rsquo;abondance d&rsquo;une main-d&rsquo;oeuvre servile. C&rsquo;est ici que s&rsquo;op\u00e8re la jonction avec le \u00ab\u00a0printemps arabe\u00a0\u00bb. Insurrection pour la dignit\u00e9, il rejette aussi le cynisme des autorit\u00e9s dans ce domaine. Et refuse l&rsquo;impunit\u00e9 d&rsquo;\u00e9lites europ\u00e9ennes ou arabes qui s&rsquo;adonnent \u00e0 leur bon plaisir&#8230; \u00ab\u00a0Sur le Maroc, on est g\u00ean\u00e9s, ils nous tiennent\u00a0\u00bb, d\u00e9clarait au Monde un diplomate fran\u00e7ais en f\u00e9vrier 2011. <\/font><\/div>\n<div> <font>L&rsquo;affaire DSK a r\u00e9veill\u00e9 la vigilance de l&rsquo;opinion pour les d\u00e9lits sexuels. Ils ne sont pourtant pas nouveaux. La p\u00e9dophilie au-del\u00e0 des fronti\u00e8res, a, par deux fois, d\u00e9fray\u00e9 la chronique en 2010, mettant en cause un ministre (Fr\u00e9d\u00e9ric Mitterrand) &#8211; dans un livre &#8211; et un cin\u00e9aste (Roman Polanski) &#8211; dans un pays o\u00f9 la justice juge les crimes. Mais, quand l&rsquo;affaire frappe nos voisins du Sud, un grand rideau tombe sur la r\u00e9alit\u00e9. Il y a quelques ann\u00e9es, j&rsquo;ai \u00e9t\u00e9 contact\u00e9 par une journaliste d&rsquo;un grand quotidien. Un Fran\u00e7ais tr\u00e8s puissant \u00e9tait dans de vilains draps, un article sur la p\u00e9dophilie au Maroc s&rsquo;imposait selon elle. Mais ordre de la r\u00e9daction: silence absolu.<\/font><\/div>\n<div> <font>Il serait d\u00e9testable que l&rsquo;Afrique du Nord demeure un lieu de qui\u00e9tude pour le tourisme sexuel. Le tremblement de terre provoqu\u00e9 par l&rsquo;affaire DSK pourrait ouvrir la voie \u00e0 une normalisation. Il s&rsquo;agirait l\u00e0 d&rsquo;une autre r\u00e9volution, aussi bienvenue que le r\u00e9veil des peuples arabes et berb\u00e8res. <\/font><\/div>\n<div>\u00a0<\/div>\n<div><strong><font>(Source: \u201clexpress.fr\u201d le 9 juin 2011)<\/font><\/strong><\/div>\n<div> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/www.lexpress.fr\/actualite\/monde\/revolutions-arabes-et-tourisme-sexuel_1000223.html\\<\/font><\/a> \u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h5 style=\"color: blue;\"><font size=\"3\"><strong>Cameron d\u00e9fend les \u00ab\u00a0valeurs traditionnelles\u00a0\u00bb contre l&rsquo;islam radical<\/strong><\/font><\/h5>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div><strong><font>08.06.2011 | 16:34 Par  Tristan de Bourbon (Londres)<\/font><\/strong><\/div>\n<div> <font>Le gouvernement britannique a durci son discours sur les questions de s\u00e9curit\u00e9, sans h\u00e9siter \u00e0 jouer sur le registre de la peur. Les parall\u00e8les entre extr\u00e9misme religieux, Islam et immigration ill\u00e9gale, engendre un certain malaise dans les rangs m\u00eame du parti conservateur.  La ministre de l\u2019Int\u00e9rieur britannique, Theresa May, durcit son discours et sa politique nationale vis-\u00e0-vis des immigr\u00e9s et de l\u2019extr\u00e9misme religieux.<\/font><\/div>\n<div> <font>Stopper l&rsquo;immigration ill\u00e9gale pour les JO<\/font><\/div>\n<div> <font>Lundi, la ministre a eu une journ\u00e9e tr\u00e8s charg\u00e9e. Le matin, visite \u00e0 Calais avec son homologue fran\u00e7ais Claude Gu\u00e9ant. L&rsquo;entente cordiale \u00e9tait de mise. Les deux ministres se sont f\u00e9licit\u00e9 qu&rsquo;\u00e0 la suite des op\u00e9rations men\u00e9es conjointement entre les deux pays, le nombre d\u2019ill\u00e9gaux tentant d\u2019entrer au Royaume-Uni depuis le port fran\u00e7ais aurait baiss\u00e9 de 70%.<\/font><\/div>\n<div> <font>Nous avons une cause commune pour nous assurer que nous stopperons l\u2019immigration ill\u00e9gale et que l\u2019acc\u00e8s aux Jeux Olympiques est s\u00fbr\u00a0\u00bb. Le gouvernement britannique joue depuis plusieurs mois sur la crainte d\u2019une vague migratoire en provenance des pays touch\u00e9s par la r\u00e9volution arabe, et notamment sur la d\u00e9livrance \u00e0 plusieurs \u00ab\u00a0centaines de milliers de Tunisiens\u00a0\u00bb d\u2019un permis de voyage temporaire des autorit\u00e9s italiennes. La ministre a ensuite critiqu\u00e9 le laisser-faire des universit\u00e9s face \u00e0 la mont\u00e9e des extr\u00e9mismes religieux, faisant r\u00e9f\u00e9rence \u00e0 l&rsquo;attentat rat\u00e9 du vol Amsterdam-Detroit par un jeune Nigerian, ancien \u00e9tudiant de la prestigieuse University College of London (UCL), en d\u00e9cembre 2009. Je ne crois pas qu\u2019elles [les universit\u00e9s] aient suffisamment voulu reconna\u00eetre ce qui pouvait arriver sur leur campus et la radicalisation qui peut y avoir lieu\u00a0\u00bb.<\/font><\/div>\n<div> <font>Anti-terrorisme renforc\u00e9<\/font><\/div>\n<div> <font>Nouvelle offensive le lendemain, mardi, lors de la publication par le Parlement d\u2019une mise \u00e0 jour de la Strat\u00e9gie Prevent, lanc\u00e9e apr\u00e8s les attentats de Londres du 7 juillet 2005 pour arr\u00eater la progression de l\u2019extr\u00e9misme et du terroriste dans le pays.<\/font><\/div>\n<div> <font>Premi\u00e8re mesure : les organisations extr\u00e9mistes qui pr\u00f4nent un discours anti-gouvernemental\/anti-occidental pouvaient jusqu&rsquo;alors recevoir des subventions gouvernementales &#8211; tant qu&rsquo;elles n&rsquo;appelaient pas \u00e0 l&rsquo;action terroriste. Elles ne toucheront d\u00e9sormais plus rien aussi longtemps qu\u2019elles \u00ab\u00a0tiendront des vues extr\u00eames ou soutiendront des activit\u00e9s li\u00e9es de quelque mani\u00e8re que ce soit au terrorisme\u00a0\u00bb et qu&rsquo;elles ne \u00ab\u00a0refl\u00e8teront pas les valeurs britanniques traditionnelles\u00a0\u00bb.<\/font><\/div>\n<div> <font>Une vingtaine d&rsquo;organisations qui pr\u00f4nent l&rsquo;instauration de la charia (la loi islamique) pourraient perdre le soutien de l&rsquo;\u00c9tat.<\/font><\/div>\n<div> <font>Cette id\u00e9e d\u00e9coule directement du discours du mois d\u2019avril de David Cameron sur l\u2019\u00e9chec du multiculturalisme : il avait parl\u00e9 de \u00ab\u00a0gens qui peuvent rejeter la violence mais acceptent certains points de vue extr\u00e9mistes, notamment ceux qui ont une r\u00e9elle hostilit\u00e9 envers les d\u00e9mocraties occidentales et les valeurs lib\u00e9rales\u00a0\u00bb, avant de demander :<\/font><\/div>\n<div> <font>Donneriez-vous \u00e0 un parti d\u2019extr\u00eame droite des fonds publics s\u2019ils promettent d\u2019aider des jeunes hommes blancs \u00e0 s\u2019\u00e9loigner du terrorisme fasciste ? Evidemment non !\u00a0\u00bb<\/font><\/div>\n<div> <font>Deuxi\u00e8me mesure : une importante partie des 63 millions de livres sterling (72 millions d\u2019euros) utilis\u00e9s chaque ann\u00e9e pour aider les actions anti-terroristes \u00e0 l\u2019\u00e9tranger servira \u00e0 combattre la radicalisation dans les prisons britanniques et \u00e0 suivre les prisonniers lib\u00e9r\u00e9s mais suspect\u00e9s d\u2019extr\u00e9misme. Un nouvel axe strat\u00e9gique visant \u00e0 toucher, comme dans les universit\u00e9s, les pros\u00e9lytes l\u00e0 o\u00f9 ils sont suppos\u00e9s \u00eatre particuli\u00e8rement efficaces.<\/font><\/div>\n<div> <font>Une stigmatisation des musulmans<\/font><\/div>\n<div> <font>Si le gouvernement ne cite jamais explicitement les musulmans, prenant au contraire comme exemple \u00ab\u00a0l\u2019extr\u00eame droite blanche\u00a0\u00bb pour ne pas \u00eatre tax\u00e9 de racisme, ces d\u00e9cisions interpellent certains d&rsquo;entre eux, comme Azad Ali, le pr\u00e9sident du Forum s\u00e9curitaire musulman, conseiller du pr\u00e9c\u00e9dent gouvernement sur l\u2019extr\u00e9misme.<\/font><\/div>\n<div> <font>Tout le monde est heureux d\u2019aider \u00e0 attraper les criminels qui veulent perp\u00e9tuer des crimes, m\u00eame la communaut\u00e9 musulmane. Mais il s&rsquo;agit bien l\u00e0 de plus en plus d&rsquo;une surveillance de la pens\u00e9e et des id\u00e9es des gens. Qu\u2019est-ce que l\u2019extr\u00e9misme ? Nous parlons de la communaut\u00e9 musulmane en particulier, soyons honn\u00eates, \u00e0 travers du prisme de la s\u00e9curit\u00e9. Pourquoi ?\u00a0\u00bb<\/font><\/div>\n<div> <font>De son c\u00f4t\u00e9, Haras Rafiq, le directeur du centre d\u2019\u00e9tude anti-extr\u00e9misme Centri, estime qu&rsquo;il est normal que les autorit\u00e9s \u00ab\u00a0doivent construire un crit\u00e8re qui \u00e9tablit quelle organisation a des id\u00e9es extr\u00e9mistes, laquelle n\u2019en a pas, et s\u2019assurer que les groupes extr\u00e9mistes ne re\u00e7oivent pas de fonds de groupes qui re\u00e7oivent des subventions\u00a0\u00bb.<\/font><\/div>\n<div> <font>Le d\u00e9bat agite \u00e9galement le parti conservateur lui-m\u00eame : Sayeeda Hussain Warsi, sa vice-pr\u00e9sidente, serait totalement oppos\u00e9e \u00e0 cette nouvelle politique, mais aurait accept\u00e9 de ne pas \u00e9voquer publiquement son d\u00e9saccord.<\/font> <a target=\"_blank\" rel=\"noopener\"><font>http:\/\/fr.myeurop.info\/2011\/06\/08\/cameron-defend-les-valeurs-traditionnelles-contre-l-islam-radical-2669<\/font><\/a><\/div>\n<hr\/>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<h5 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><font size=\"3\">Les Russes d\u00e9couvrent avec incr\u00e9dulit\u00e9 les origines juives de L\u00e9nine<\/font> <\/font><\/h5>\n<p><\/span><\/b><\/div>\n<div align=\"center\"><b><span lang=\"FR-CH\"><\/p>\n<hr\/>\n<p><\/span><\/b><\/div>\n<div align=\"justify\"><i><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le leader de la r\u00e9volution pourrait perdre son mausol\u00e9e de la place Rouge et le soutien des nostalgiques du sovi\u00e9tisme, dont beaucoup v\u00e9hiculent un antis\u00e9mitisme latent <\/font><\/span><\/i><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Emmanuel Grynszpan Moscou<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les archives du KGB concernant les origines ethniques du premier chef d\u2019Etat sovi\u00e9tique ont \u00e9t\u00e9 pour la premi\u00e8re fois expos\u00e9es au public russe la semaine derni\u00e8re. Une importante exposition consacr\u00e9e \u00e0 Vladimir Ilitch Oulianov (le vrai nom de L\u00e9nine) au Mus\u00e9e historique de l\u2019Etat r\u00e9v\u00e8le que son grand-p\u00e8re maternel \u00e9tait un juif converti. L\u2019information n\u2019a rien d\u2019anecdotique dans un pays o\u00f9 l\u2019antis\u00e9mitisme d\u2019Etat fut de r\u00e8gle pendant plusieurs d\u00e9cennies. Le r\u00e9gime sovi\u00e9tique, \u00e0 partir du d\u00e9but des ann\u00e9es<span><\/span>1930, a men\u00e9 sous l\u2019impulsion de Staline une politique violemment discriminatoire \u00e0 l\u2019\u00e9gard de ses citoyens d\u2019origine juive. <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">N\u00e9 en 1870, L\u00e9nine se d\u00e9finissait simplement comme \u00abrusse\u00bb d\u2019un point de vue ethnique. Sa biographie officielle mentionne seulement des origines russe, allemande et su\u00e9doise. Mais une des pi\u00e8ces ma\u00eetresses de l\u2019exposition \u00e9corne ce mythe. Une lettre \u00e0 Staline \u00e9crite en 1932 (six ans apr\u00e8s la mort de L\u00e9nine) par sa s\u0153ur a\u00een\u00e9e Anna Oulianova r\u00e9v\u00e8le que leur grand-p\u00e8re maternel \u00abvenait d\u2019une famille juive pauvre, et qu\u2019il \u00e9tait, d\u2019apr\u00e8s son certificat de bapt\u00eame, le fils de Moses Blank\u00bb, n\u00e9 \u00e0 Jitomir, en Ukraine. Anna Oulianova souligne que son fr\u00e8re \u00aba toujours eu une haute opinion des juifs\u00bb, d\u00e9sapprouve \u00abl\u2019essor r\u00e9cent de l\u2019antis\u00e9mitisme, y compris parmi les communistes\u00bb et enjoint \u00e0 Staline de faire conna\u00eetre les origines juives de L\u00e9nine. \u00abCe serait une erreur que de cacher ce fait aux masses\u00bb, conclut la lettre. <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Staline r\u00e9pondit en ordonnant \u00e0 Anna Oulianova de se taire. Quelques ann\u00e9es plus tard, il liquidait physiquement tous les juifs parmi les meneurs de la r\u00e9volution. Il pr\u00e9parait la d\u00e9portation de toute la population juive d\u2019URSS au fin fond de la Sib\u00e9rie quand la mort l\u2019a emport\u00e9 en 1953.<\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Dans pratiquement toutes les villes de province, l\u2019art\u00e8re centrale se nomme \u00abrue L\u00e9nine\u00bb, celle-l\u00e0 m\u00eame qui est couverte de magasins de luxe, de succursales bancaires et de tous les signes les plus tapageurs de la soci\u00e9t\u00e9 capitaliste. Au milieu de toutes les places centrales (y compris en Bi\u00e9lorussie et en Ukraine) une haute statue du leader toise l\u2019agitation commer\u00e7ante. Le paradoxe L\u00e9nine ne s\u2019arr\u00eate pas l\u00e0. Il est r\u00e9v\u00e9r\u00e9 par la frange la plus dure des communistes russes, ceux qui sont nostalgiques du r\u00e9gime sovi\u00e9tique et impr\u00e9gn\u00e9s non d\u2019internationalisme mais d\u2019un stalinisme impr\u00e9gn\u00e9 d\u2019antis\u00e9mitisme. <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Le d\u00e9bat autour de sa personnalit\u00e9 s\u2019est aujourd\u2019hui cristallis\u00e9 autour de sa momie, toujours expos\u00e9e \u00e0 l\u2019int\u00e9rieur du mausol\u00e9e de la place Rouge, \u00e0 Moscou. Chaque citoyen sovi\u00e9tique devait faire son \u00abp\u00e8lerinage\u00bb aupr\u00e8s du communiste sanctifi\u00e9. D\u00e9sormais, le d\u00e9bat fait rage entre les communistes, qui veulent voir le culte se perp\u00e9tuer ind\u00e9finiment, et les orthodoxes, qui abhorrent le destructeur du tsarisme et l\u2019homme d\u2019Etat qui a fait de l\u2019ath\u00e9isme un pilier de l\u2019id\u00e9ologie officielle. Ces derniers, comme beaucoup de Russes ordinaires, souhaitent que l\u2019homme soit enterr\u00e9, avec ou sans les honneurs r\u00e9serv\u00e9s \u00e0 un homme d\u2019Etat. <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Les Russes entr\u00e9s dans la vie active apr\u00e8s la chute du communisme ont souvent une perception tout aussi ambivalente du r\u00e9volutionnaire: \u00abGrand-p\u00e8re L\u00e9nine \u00e9tait un peu comme un P\u00e8re No\u00ebl pour les enfants sovi\u00e9tiques\u00bb, se souvient avec nostalgie Daria Beliaeva, une analyste bancaire \u00e2g\u00e9e d\u2019une trentaine d\u2019ann\u00e9es. \u00abMais j\u2019ai appris plus tard qu\u2019il avait \u00e9t\u00e9 envoy\u00e9 par les Allemands dans un train blind\u00e9 pour provoquer la r\u00e9volution en Russie et qu\u2019il a fait d\u00e9truire des centaines d\u2019\u00e9glises\u00bb, d\u00e9sapprouve cette orthodoxe pratiquante. Daria n\u2019est gu\u00e8re troubl\u00e9e d\u2019apprendre que l\u2019idole sovi\u00e9tique avait des origines juives. \u00abIl y a du bon et du mauvais en lui. Il a marqu\u00e9 notre histoire. Maintenant il faut l\u2019enterrer.\u00bb <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">Pour le politologue Boris Kagarlitski, un ancien dissident qui se revendique du l\u00e9ninisme, \u00able d\u00e9bat autour de la jud\u00e9it\u00e9 ou non et de l\u2019enterrement ou non de L\u00e9nine sert juste de pr\u00e9texte au pouvoir pour d\u00e9tourner les esprits des vrais probl\u00e8mes et enjeux de notre soci\u00e9t\u00e9\u00bb. <\/font><\/span><\/div>\n<div align=\"justify\"><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">L\u2019exposition vient donc \u00e0 point nomm\u00e9, m\u00eame si l\u2019antis\u00e9mitisme latent ne joue plus de r\u00f4le d\u00e9terminant dans la grande politique russe. En revanche, elle pourrait jouer un mauvais tour au leader communiste, le privant d\u2019une partie de ses d\u00e9fenseurs acharn\u00e9s. Peut-\u00eatre que les origines juives de L\u00e9nine h\u00e2teront sa mise en terre ou feront fleurir des \u00e9toiles de David sur d\u2019innombrables statues auxquelles plus personne ne pr\u00eate attention.<\/font><\/span><\/div>\n<div align=\"justify\"><b><span lang=\"FR-CH\"><font face=\"Arial\" size=\"2\">(Source : \u00ab Le Temps \u00bb (Quotidien \u2013 Suisse), le<span> <\/span>7 juin 2011)<\/font><\/span><\/b><\/div>\n<p><\/font><\/p>\n<p><\/font><\/p>\n<p><\/span><\/div>\n<p><\/body><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TUNISNEWS 11 \u00e8me ann\u00e9e, N\u00b04034 du 09.06.2011 archives : www.tunisnews.net Reuters: Biens de Ben Ali: deux ONG veulent la d\u00e9signation d&rsquo;une juge d&rsquo;instruction ANSA: Tunisia: ammontano a 55 milioni di franchi beni Ben Ali in Svizzera AFP: Tunisie: le fort afflux de r\u00e9fugi\u00e9s libyens se poursuit Conseil JAI : lettre ouverte de d\u00e9put\u00e9s europ\u00e9ens aux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[58,42,29],"class_list":["post-18598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-58","tag-42","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/18598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=18598"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/18598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=18598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=18598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=18598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}