{"id":18099,"date":"2010-11-18T00:00:00","date_gmt":"2010-11-18T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/18-novembre-2010\/"},"modified":"2010-11-18T00:00:00","modified_gmt":"2010-11-18T00:00:00","slug":"18-novembre-2010","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/18-novembre-2010\/","title":{"rendered":"18 novembre 2010"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\"Saber Ragoubi a \u00e9t\u00e9 condamn\u00e9 \u00e0 \n\t\t\t\t\t\t\t\t\t\t\t\tmort en Tunisie apr\u00e8s avoir \u00e9t\u00e9 \n\t\t\t\t\t\t\t\t\t\t\t\treconnu coupable d'infractions \n\t\t\t\t\t\t\t\t\t\t\t\tli\u00e9es \u00e0 la s\u00e9curit\u00e9 nationale et \n\t\t\t\t\t\t\t\t\t\t\t\tau terrorisme. Il clame son \n\t\t\t\t\t\t\t\t\t\t\t\tinnocence. Il n'a pas b\u00e9n\u00e9fici\u00e9 \n\t\t\t\t\t\t\t\t\t\t\t\td'un proc\u00e8s \u00e9quitable et il a \n\t\t\t\t\t\t\t\t\t\t\t\t\u00e9t\u00e9 d\u00e9clar\u00e9 coupable sur la base \n\t\t\t\t\t\t\t\t\t\t\t\td'\u00ab aveux \u00bb qui, selon son \n\t\t\t\t\t\t\t\t\t\t\t\tt\u00e9moignage, lui ont \u00e9t\u00e9 arrach\u00e9s \n\t\t\t\t\t\t\t\t\t\t\t\tsous la torture.\" http-equiv=\"Content-Type\"\/><\/head><body><body><\/p>\n<p align=\"center\" dir=\"ltr\"><font face=\"Arial\" size=\"2\"><b><a href=\"http:\/\/www.tunisnews.net\/\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accuei<\/span><\/a><span lang=\"FR-CH\">l<\/span><\/b><\/font><\/p>\n<div>\n<div align=\"justify\">\n<div>\n<div>\n<div>\n<div><font face=\"Arial\" size=\"2\"><\/p>\n<div><span><span><\/p>\n<div><font face=\"Calibri\"><\/font><\/div>\n<div><\/div>\n<p><span><\/p>\n<div><font size=\"4\"><\/p>\n<div dir=\"rtl\"><font face=\"Arial\" size=\"4\"><\/p>\n<div dir=\"rtl\"><b><span lang=\"AR-SA\"><\/p>\n<div dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"center\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"center\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"center\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div>\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"center\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div>\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div align=\"center\" dir=\"rtl\">\n<div align=\"justify\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div align=\"right\" dir=\"rtl\">\n<div dir=\"rtl\">\n<div align=\"center\" dir=\"ltr\">\u00a0<\/div>\n<div align=\"center\" dir=\"ltr\">\u00a0 <font face=\"Arial\" size=\"3\"><strong><font face=\"Bookman Old Style\" size=\"7\">TUNISNEWS<\/font><\/strong><\/font><b><font face=\"Arial\"><span lang=\"AR-SA\"><\/span><\/font><\/b><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/span><\/b><\/div>\n<p><\/font><\/div>\n<p><\/font><\/div>\n<div align=\"center\"><strong><font>\u00a0 <\/font><\/strong><\/div>\n<div align=\"center\"><strong><font><font size=\"3\">10 \u00e8me ann\u00e9e,<span>\u00a0<\/span><\/font><span lang=\"FR\"><font size=\"3\">N\u00b0 3831 du 18.11.2010<br \/><\/font><\/span><\/font><\/strong><span><font face=\"Arial\" size=\"2\"><strong>\u00a0archives :<span>\u00a0<\/span><\/strong><\/font><a target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\"><strong>www.tunisnews.net<\/strong><\/font><\/a><\/span><span lang=\"FR\">\u00a0<\/span><font face=\"Arial\" size=\"2\"><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>Amnesty International: Agissez en faveur de Saber Ragoubi (Tunisie)<\/strong><\/font><\/h2>\n<\/div>\n<div>\n<p><font face=\"Arial\" size=\"2\"><strong><font>Libert\u00e9 et Equit\u00e9: Adam Boukedida, ex prisonnier politique &#8211; Une descente de police qui se solde par un coma \u00e0 l\u2019h\u00f4pital<br \/><\/font>Luiza Toscane: Quaranti\u00e8me\u00a0 journ\u00e9e de gr\u00e8ve : Abdellatif Bouhjila aussi d\u00e9termin\u00e9 qu&rsquo;au premier jour<br \/><font>TTU-Monde Arabe: Tunisie &#8211; Grogne dans la r\u00e9gion du Sahel<br \/><\/font>Atlasinfo: AQMI veut faire du Sahara \u00ab\u00a0le prochain Afghanistan\u00a0\u00bb selon un expert US des questions terroristes<span>\u00a0<\/span><br \/><\/strong><font><strong>AFP: Maroc: mort d&rsquo;Abraham Serfaty, c\u00e9l\u00e8bre opposant au roi Hassan II<\/strong><\/font><\/font><\/p>\n<\/div>\n<p><font face=\"Arial\" size=\"2\"><\/p>\n<div><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div>\n<div><font face=\"Calibri\"><\/p>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong>Amnesty International<\/strong><\/font><\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><\/p>\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Agissez en faveur de Saber Ragoubi (Tunisie)<span>\u00a0<\/span><br \/>\u00a0<\/strong><\/font><\/h2>\n<p><font><\/p>\n<hr\/>\n<p>\u00a0<\/font><\/font><\/div>\n<div><font face=\"Arial\" size=\"2\">10 novembre 2010<span>\u00a0<\/span><br \/>Saber Ragoubi a \u00e9t\u00e9 condamn\u00e9 \u00e0 mort en Tunisie apr\u00e8s avoir \u00e9t\u00e9 reconnu coupable d&rsquo;infractions li\u00e9es \u00e0 la s\u00e9curit\u00e9 nationale et au terrorisme. Il clame son innocence. Il n&rsquo;a pas b\u00e9n\u00e9fici\u00e9 d&rsquo;un proc\u00e8s \u00e9quitable et il a \u00e9t\u00e9 d\u00e9clar\u00e9 coupable sur la base d&rsquo;\u00ab aveux \u00bb qui, selon son t\u00e9moignage, lui ont \u00e9t\u00e9 arrach\u00e9s sous la torture.<\/p>\n<p>Saber Ragoubi a \u00e9t\u00e9 arr\u00eat\u00e9 en m\u00eame temps que 29 autres hommes en d\u00e9cembre 2006, dans les environs de Soliman, une ville situ\u00e9e \u00e0 une quarantaine de kilom\u00e8tres au sud de Tunis. Ils ont \u00e9t\u00e9 inculp\u00e9s d&rsquo;infractions li\u00e9es au terrorisme, notamment de complot en vue de renverser le gouvernement et d&rsquo;appartenance \u00e0 une organisation terroriste. Malgr\u00e9 leurs d\u00e9n\u00e9gations, ils ont \u00e9t\u00e9 d\u00e9clar\u00e9s coupables au terme d&rsquo;un proc\u00e8s inique. Saber Ragoubi est le seul d&rsquo;entre eux \u00e0 avoir \u00e9t\u00e9 condamn\u00e9 \u00e0 mort.<\/p>\n<p>Saber Ragoubi a \u00e9t\u00e9 appr\u00e9hend\u00e9 \u00e0 la suite d&rsquo;affrontements entre les forces de s\u00e9curit\u00e9 et un groupe arm\u00e9. Il a indiqu\u00e9 \u00e0 ses avocats qu&rsquo;il avait \u00e9t\u00e9 tortur\u00e9 dans les locaux de la Direction de la s\u00fbret\u00e9 de l&rsquo;\u00c9tat du minist\u00e8re de l&rsquo;Int\u00e9rieur, \u00e0 Tunis, puis en prison avant d&rsquo;\u00eatre jug\u00e9. Au cours de son proc\u00e8s, il a d\u00e9clar\u00e9 au juge : \u00ab J&rsquo;ai subi une agression \u00e0 l&rsquo;int\u00e9rieur de la prison de Mornaguia et j&rsquo;ai perdu trois de mes dents de devant. \u00bb Cependant, le tribunal n&rsquo;a pas men\u00e9 d&rsquo;enqu\u00eate en bonne et due forme sur les all\u00e9gations selon lesquelles les \u00ab aveux \u00bb de Saber Ragoubi et de ses coaccus\u00e9s avaient \u00e9t\u00e9 extorqu\u00e9s sous la torture. Amnesty International estime que cet homme n&rsquo;a pas \u00e9t\u00e9 jug\u00e9 de mani\u00e8re \u00e9quitable, notamment parce qu&rsquo;il a \u00e9t\u00e9 condamn\u00e9 sur la base d&rsquo;\u00e9l\u00e9ments que d&rsquo;autres accus\u00e9s et lui avaient fournis sous la torture.<\/p>\n<p>La condamnation \u00e0 mort de Saber Ragoubi a \u00e9t\u00e9 confirm\u00e9e par une juridiction sup\u00e9rieure en 2008. La Tunisie n&rsquo;a proc\u00e9d\u00e9 \u00e0 aucune ex\u00e9cution depuis 1991, mais des condamn\u00e9s \u00e0 mort sont toujours incarc\u00e9r\u00e9s dans ce pays dans des conditions tr\u00e8s difficiles. Saber Ragoubi est d\u00e9tenu \u00e0 l&rsquo;isolement. Il n&rsquo;est autoris\u00e9 ni \u00e0 voir ses proches, ni \u00e0 recevoir du courrier.<\/p>\n<p>Le p\u00e8re de Saber Ragoubi a dit \u00e0 Amnesty International : \u00ab On ne me permet pas de voir mon fils [\u2026] Je voudrais lui rendre visite pour voir comment il va. \u00bb. Il a ajout\u00e9 qu&rsquo;il \u00e9tait terrible pour lui d&rsquo;\u00eatre ainsi priv\u00e9 de nouvelles de son fils.<\/p>\n<p><strong>Passez \u00e0 l&rsquo;action<br \/>Envoyez un courriel au Comit\u00e9 sup\u00e9rieur des droits de l&rsquo;homme et des libert\u00e9s fondamentales en Tunisie. Cette instance est habilit\u00e9e \u00e0 porter directement le cas de Saber Ragoubi \u00e0 l&rsquo;attention du pr\u00e9sident tunisien.<br \/>Saber Ragoubi doit b\u00e9n\u00e9ficier d&rsquo;une commutation de sa sentence capitale et \u00eatre rejug\u00e9<br \/><\/strong><br \/>Saber Ragoubi a \u00e9t\u00e9 condamn\u00e9 \u00e0 mort \u00e0 l&rsquo;issue d&rsquo;un proc\u00e8s in\u00e9quitable. Bien qu&rsquo;il ait indiqu\u00e9 au juge que ses \u00ab aveux \u00bb lui avaient \u00e9t\u00e9 arrach\u00e9s sous la torture, le tribunal n&rsquo;a pas tenu compte de cette information. Je vous prie instamment de porter cet appel \u00e0 l&rsquo;attention du pr\u00e9sident Zine el Abidine Ben Ali et d&rsquo;interc\u00e9der aupr\u00e8s de lui pour obtenir la commutation de la peine de Saber Ragoubi. Dans l&rsquo;intervalle, les autorit\u00e9s carc\u00e9rales doivent traiter Saber Ragoubi avec humanit\u00e9, mettre fin au r\u00e9gime d&rsquo;isolement auquel il est soumis et lui permettre de recevoir r\u00e9guli\u00e8rement la visite de ses proches. Je vous engage \u00e9galement \u00e0 intervenir afin qu&rsquo;il b\u00e9n\u00e9ficie d&rsquo;un nouveau proc\u00e8s, conforme aux normes internationales d&rsquo;\u00e9quit\u00e9, dans le cadre duquel aucun \u00e9l\u00e9ment obtenu au moyen de la torture ou d&rsquo;autres formes de mauvais traitements ne pourra \u00eatre retenu \u00e0 titre de preuve. Veuillez agr\u00e9er, Mesdames et Messieurs les membres du Comit\u00e9 sup\u00e9rieur des droits de l&rsquo;homme et des libert\u00e9s fondamentales en Tunisie, l&rsquo;expression de ma haute consid\u00e9ration.<\/font><\/div>\n<p><\/font><\/div>\n<\/div>\n<p><\/font><\/p>\n<div>\n<hr\/>\n<\/div>\n<div><font face=\"Calibri\"><\/p>\n<div align=\"center\"><font face=\"Arial\" size=\"2\">Libert\u00e9 pour tous les prisonniers politiques<br \/><strong><font>Libert\u00e9 et Equit\u00e9<br \/><\/font><\/strong>Organisation Ind\u00e9pendante de Droits Humains<br \/>33 rue Mokhtar Atya, 1001, Tunis<br \/>Liberte.equite@gmail.com<br \/>Tunis, le 17 novembre 2010<br \/><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Adam Boukedida, ex prisonnier politique<br \/>Une descente de police qui se solde par un coma \u00e0 l\u2019h\u00f4pital<\/font><\/h2>\n<p><\/strong><\/font><\/div>\n<p><\/font><\/p>\n<div><font face=\"Calibri\"><\/p>\n<hr\/>\n<p><font face=\"Arial\" size=\"2\">Le 16 novembre, jour de la f\u00eate du sacrifice, l\u2019ex prisonnier d\u2019opinion Adam Boukedida, a \u00e9t\u00e9 pris en chasse \u00e0 Sousse par des agents de la police politique qui ont fait une descente \u00e0 son domicile, le poussant \u00e0 tenter de prendre la fuite. Il est tomb\u00e9 du deuxi\u00e8me \u00e9tage, il en est r\u00e9sult\u00e9 des fractures aux mains et \u00e0 l\u2019un des genoux, une h\u00e9morragie abdominale. Il est actuellement dans le coma en r\u00e9animation \u00e0 l\u2019h\u00f4pital Sahloul, sous \u00e9troite surveillance s\u00e9curitaire. Des membres de sa famille qui lui ont rendu visite se sont entendus dire par les m\u00e9decins que ce n\u2019\u00e9tait pas \u00e0 l\u2019administration de l\u2019h\u00f4pital, mais \u00e0 la police politique de d\u00e9cider de son maintien \u00e0 l\u2019h\u00f4pital. Adam Boukedida \u00e9tait \u00e9tudiant \u00e0 l\u2019universit\u00e9 Alazhar lorsque les autorit\u00e9s \u00e9gyptiennes l\u2019ont livr\u00e9 \u00e0 la Tunisie o\u00f9 il a \u00e9t\u00e9 d\u00e9f\u00e9r\u00e9 en justice. Il a pass\u00e9 plus de trois ans en prison en vertu de la loi antiterroriste, loi non constitutionnelle, et depuis sa lib\u00e9ration il est soumis au harc\u00e8lement, aux descentes et aux arrestations de la police politique. Il est mari\u00e9 et p\u00e8re d\u2019une fillette. [\u2026]<br \/>Libert\u00e9 et Equit\u00e9<br \/>(traduction ni revue ni corrig\u00e9e par les auteurs de la version en arabe, LT)<br \/>\u00a0<br \/>\u00a0[\u2026]<br \/>Pour le Bureau Ex\u00e9cutif<br \/>La Charg\u00e9e du dossier des \u00e9migr\u00e9s et des exil\u00e9s<br \/><strong><font>Ma\u00eetre Najet Laabidi<br \/><\/font><\/strong><font>(traduction d\u2019extraits ni revue ni corrig\u00e9e par les auteurs de la version en arabe, LT)<\/font><\/font><\/font><\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div><font face=\"Calibri\"><\/p>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\"><strong>Quaranti\u00e8me\u00a0 journ\u00e9e de gr\u00e8ve : Abdellatif Bouhjila aussi d\u00e9termin\u00e9 qu&rsquo;au premier jour<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<p><\/font><\/div>\n<div><font face=\"Calibri\"><\/p>\n<p align=\"left\">\n<p><font><span><font face=\"Arial\">Abdellatif Bouhjila, prisonnier d&rsquo;opinion,\u00a0<span>a \u00e9t\u00e9 lib\u00e9r\u00e9 \u00e0 titre conditionnel en 2007 au terme de neuf ann\u00e9es et demie pass\u00e9es derri\u00e8re les barreaux. Il n\u2019a pas eu la possibilit\u00e9 de r\u00e9cup\u00e9rer son dossier m\u00e9dical \u00e0 l\u2019h\u00f4pital o\u00f9 il avait \u00e9t\u00e9 soign\u00e9 lors de son incarc\u00e9ration. Ses demandes de rendez-vous des soins ont par ailleurs \u00e9t\u00e9 ignor\u00e9es. Il a men\u00e9 une premi\u00e8re gr\u00e8ve de la faim pendant pr\u00e8s de deux mois en 2008 pour r\u00e9clamer un acc\u00e8s aux soins et son droit \u00e0 un passeport. Sans r\u00e9sultat. Un an plus tard, en septembre 2009, il a men\u00e9 une seconde gr\u00e8ve de la faim pour les m\u00eames raisons. Il a re\u00e7u un soutien unanime, tant au plan national qu\u2019international, mais aucune r\u00e9ponse des autorit\u00e9s tunisiennes que ce soit au niveau du droit \u00e0 la sant\u00e9 ou pour son passeport.<\/span><\/font><\/span><\/font><\/p>\n<\/p>\n<p align=\"left\">\n<p><font><span><font face=\"Arial\"><span>Pour la troisi\u00e8me ann\u00e9e cons\u00e9cutive, Abdellatif Bouhjila r\u00e9clame ses droits \u00e9l\u00e9mentaires.<span>\u00a0<\/span><br \/><\/span><\/font><font><span><font face=\"Arial\">Il est en gr\u00e8ve de la faim depuis le 11 octobre dernier. Affaibli, malade, \u00e9prouvant des douleurs au niveau des reins et du coeur, et pourtant il reste aussi d\u00e9termin\u00e9 qu&rsquo;au premier jour. Son domicile est surveill\u00e9 en permanence par des agents de la police politique. il attend un signe des autorit\u00e9s pouvant lui permettre d&rsquo;augurer que son passeport est pr\u00eat.<br \/>\u00a0<\/font><\/span><\/font><\/span><\/font><\/p>\n<\/p>\n<p><font><\/p>\n<p align=\"left\" lang=\"fr-FR\"><font face=\"Arial\"><em>Amnesty International<\/em>, d\u00e9clarait, \u00e0 son propos notamment, le 29 octobre\u00a0: \u00a0\u00bb\u00a0<em>les gr\u00e8ves de la faim qui se poursuivent constituent un rappel brutal du harc\u00e8lement auquel sont confront\u00e9s tous ceux qui s&rsquo;opposent aux autorit\u00e9s tunisiennes et de la mise en marge syst\u00e9matique des anciens prisonniers politiques en Tunisie<\/em>\u00a0\u00bb . Et c&rsquo;est en solidarit\u00e9 que le Syndicat de la M\u00e9decine G\u00e9n\u00e9rale (SMG; France) a \u00e9crit le 4 novembre dernier aux autorit\u00e9s tunisiennes.<\/font><\/p>\n<p><\/font><\/p>\n<p align=\"left\" lang=\"fr-FR\"><font face=\"Arial\">Abdellatif Bouhjila reste s\u00fbr de son bon droit, et\u00a0certain de pouvoir compter sur la solidarit\u00e9 nationale et internationale.<span>\u00a0<\/span><br \/><\/font><\/p>\n<h2 style=\"color: red;\"><font><span><font face=\"Arial\"><span>Pour lui en faire part, lui t\u00e9l\u00e9phoner au (00\u00a0216) 23\u00a0048 533.<\/span><\/font><\/span><\/font><\/h2>\n<\/p>\n<p><b><span><font face=\"Arial\">Luiza Toscane<\/font><\/span><\/b><\/p>\n<p><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><\/p>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">TUNISIE : GROGNE DANS LA R\u00c9GION DU SAHEL<\/font><\/h2>\n<p><span>\u00a0<\/span><\/strong><\/font><\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong><span><\/p>\n<hr\/>\n<p><\/span><br \/>\u00a0<\/strong><\/font><\/div>\n<p><\/font><\/p>\n<div align=\"left\"><font face=\"Arial\" size=\"2\"><font>\u00a0 La r\u00e9gion tunisienne du Sahel, notamment les villes de Ksar Hellal et\u00a0 Moknine, a \u00e9t\u00e9 le th\u00e9\u00e2tre de rassemblements et de manifestations violentes la semaine derni\u00e8re. Cette r\u00e9gion est un fief historique du PSD, le parti fond\u00e9 \u00e0 Ksar Hellal, en 1934, par le pr\u00e9sident Habib Bourguiba, et devenu le RCD, parti aujourd\u2019hui au pouvoir. Ces manifestations, au cours desquelles des coups de feu ont \u00e9t\u00e9 tir\u00e9s, visaient \u00e0 protester contre la mont\u00e9e en puissance de certaines personnalit\u00e9s au sein du parti, notamment Sakhr Materi, le gendre du pr\u00e9sident Ben Ali. La col\u00e8re dans la r\u00e9gion du Sahel, dont sont issus la plupart des responsables du pouvoir en Tunisie depuis plus de soixante ans, \u00e9tait d\u00e9j\u00e0<span>\u00a0<\/span><br \/>mont\u00e9e d&rsquo;un cran \u00e0 l&rsquo;occasion de la r\u00e9cente visite aux Etats-Unis de Sakhr Materi (voir TTU n\u00b0 664). Ce dernier ayant \u00e9cart\u00e9 la d\u00e9l\u00e9gation de parlementaires invit\u00e9s, dont beaucoup repr\u00e9sentaient la r\u00e9gion, imposant \u00e0 leur place<span>\u00a0<\/span><br \/>une liste de personnalit\u00e9s de son choix. De l\u2019avis de certains commentateurs, les Sah\u00e9liens entendent faire barrage \u00e0 la famille Materi et, plus g\u00e9n\u00e9ralement, \u00e0 l\u2019entourage de l\u2019\u00e9pouse du pr\u00e9sident, Leila Trabelsi, qui s\u2019emploierait \u00e0 renforcer son influence sur le plan politique, apr\u00e8s s\u2019\u00eatre assur\u00e9e du contr\u00f4le de nombreux leviers du pouvoir \u00e9conomique dans le pays.<span>\u00a0<\/span><br \/><\/font><strong>\u00a0<br \/><\/strong><font><strong>(Source: \u00ab\u00a0TTU-Monde Arabe\u00a0\u00bb\u00a0 Hebdomadaire d&rsquo;informations politiques et strat\u00e9giques num\u00e9ro 667 Jeudi 18 Novembre 2010)<br \/>\u00a0<\/strong><\/p>\n<hr\/>\n<p><\/font><\/font><\/div>\n<\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\"><strong><font>Maghreb<br \/><\/font><font>\u00a0<\/font>AQMI veut faire du Sahara \u00ab\u00a0le prochain<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\"><strong>Afghanistan\u00a0\u00bb selon un expert US des questions terroristes<\/strong><\/font><\/h2>\n<\/div>\n<div>\n<hr\/>\n<p><font face=\"Arial\" size=\"2\">Le groupe terroriste d&rsquo;Al-Qaeda dans le Maghreb Islamique, qui s\u00e9vit dans les vastes \u00e9tendues d\u00e9sertiques allant de l&rsquo;Alg\u00e9rie en passant par le Mali, le Niger et la Mauritanie, veut faire du Sahara \u00ab\u00a0le prochain Afghanistan\u00a0\u00bb, a mis en garde mercredi Richard Miniter, un expert US des questions terroristes.<span>\u00a0<\/span><\/p>\n<p>\u00a0\u00ab\u00a0AQMI, qui a jur\u00e9 de s&rsquo;attaquer aux int\u00e9r\u00eats am\u00e9ricains, s&rsquo;est repli\u00e9e dans les vastes \u00e9tendues d\u00e9sertiques du Sahara fuyant la pression des forces arm\u00e9es US au Pakistan, en Irak et au Y\u00e9men\u00a0\u00bb, souligne Richard Miniter, qui \u00e9tait l&rsquo;invit\u00e9 de la cha\u00eene de t\u00e9l\u00e9vision US CBN News.<span>\u00a0<\/span><\/p>\n<p>Miniter, qui a fourni \u00e0 CBN News des enregistrements vid\u00e9os exclusifs montrant des militants d&rsquo;AQMI dans leurs camps d&rsquo;entra\u00eenement au Mali, a tenu \u00e0 rappeler que ce groupe terroriste avait par le pass\u00e9 nourri des complots visant des b\u00e2timents de guerre US qui croisaient dans le D\u00e9troit de Gibraltar, ainsi que l&rsquo;ambassade des Etats-Unis \u00e0 Bamako.<span>\u00a0<\/span><\/p>\n<p>\u00ab\u00a0Ils s&rsquo;entra\u00eenent dans le d\u00e9sert dans le but de mener des assauts arm\u00e9s\u00a0\u00bb, a-t-il averti, notant que ce groupe s&rsquo;\u00e9tait d\u00e9j\u00e0 attaqu\u00e9 aux arm\u00e9es de la r\u00e9gion, notamment celles du Mali et du Niger \u00ab\u00a0dans ce qui s&rsquo;apparente \u00e0 des exercices pour s&rsquo;en prendre plus tard aux int\u00e9r\u00eats am\u00e9ricains\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p>Un des enregistrements vid\u00e9o mis par Miniter \u00e0 la disposition de CBN News montre, en effet, les militants d&rsquo;AQMI partageant entre eux le butin apr\u00e8s un raid men\u00e9 contre l&rsquo;arm\u00e9e r\u00e9guli\u00e8re malienne.<span>\u00a0<\/span><\/p>\n<p>Commentant ledit enregistrement, Miniter a expliqu\u00e9 \u00ab\u00a0que derri\u00e8re les militants enturbann\u00e9s, on peut voir des armes lourdes, des munitions, des tentes et d&rsquo;autres \u00e9quipements pour le d\u00e9sert\u00a0\u00bb, notant que l&rsquo;un des jihadistes montr\u00e9s dans la vid\u00e9o \u00e9tait \u00ab\u00a0derri\u00e8re le meurtre, en 2009, du ressortissant britannique Edwin Dyer\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p>AQMI, a-t-il par ailleurs d\u00e9plor\u00e9, utilise les ran\u00e7ons des kidnappings de ressortissants occidentaux et les entr\u00e9es d&rsquo;argent d&rsquo;activit\u00e9s criminelles et de trafic de drogues pour le financement de ses activit\u00e9s terroristes.<span>\u00a0<\/span><\/p>\n<p>Citant des services de renseignement de la r\u00e9gion, CBN News souligne que le groupe terroriste d&rsquo;AQMI \u00ab\u00a0dispose d&rsquo;un vaste r\u00e9seau en Europe occidentale\u00a0\u00bb, notant que ces services craignent que l&rsquo;Administration Obama ne soit trop accapar\u00e9e par ce qui ce se passe au Pakistan et au Y\u00e9men, au moment m\u00eame o\u00f9 \u00ab\u00a0une temp\u00eate d&rsquo;Al-Qaeda est en pleine gestation dans le Sahara\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p>Dans un article publi\u00e9 par le New York Post, Richard Minier, qui a r\u00e9cemment visit\u00e9 les camps de Tindouf \u00e0 l&rsquo;invitation des s\u00e9paratistes, avait soutenu que plusieurs dirigeants et membres du front polisario ont \u00ab\u00a0des liens avec le groupe terroriste d&rsquo;Al-Qaeda dans le Maghreb Islamique\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p>\u00ab\u00a0Quelque 56 individus entre dirigeants et membres du polisario ont des liens avec Al-Qaeda\u00a0\u00bb, avait-il soulign\u00e9 dans un article dat\u00e9 de Tindouf, sous le titre: \u00ab\u00a0Un bastion d&rsquo;Al-Qaeda en devenir\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p>Richard Miniter, est l&rsquo;auteur de deux bestsellers sur la liste du New York Times intitul\u00e9s \u00ab\u00a0Losing bin Laden\u00a0\u00bb (Perdre bin Laden) et \u00ab\u00a0Shadow War\u00a0\u00bb, (Guerre d&rsquo;ombre).<span>\u00a0<\/span><\/p>\n<p><\/font><font><strong><font face=\"Arial\" size=\"2\">(Source: Atlasinfo\u00a0 le 18 novembre 2010)<br \/>Lien:<span>\u00a0<\/span><\/font><\/strong><a target=\"_blank\" rel=\"noopener\"><strong title=\"http:\/\/www.atlasinfo.fr\/AQMI-veut-faire-du-Sahara-le-prochain-Afghanistan-un-expert-US-des-questions-terroristes_a11565.htmlF\u00f6lj l\u00e4nken genom att trycka p\u00e5 CTRL och klicka\"><font face=\"Arial\" size=\"2\" title=\"http:\/\/www.atlasinfo.fr\/AQMI-veut-faire-du-Sahara-le-prochain-Afghanistan-un-expert-US-des-questions-terroristes_a11565.htmlF\u00f6lj l\u00e4nken genom att trycka p\u00e5 CTRL och klicka\">http:\/\/www.atlasinfo.fr\/AQMI-veut-faire-du-Sahara-le-prochain-Afghanistan-un-expert-US-des-questions-terroristes_a11565.html<\/font><\/strong><\/a><\/font><\/div>\n<p><font><\/p>\n<div><strong><font face=\"Arial\" size=\"2\"><\/p>\n<hr\/>\n<p><\/font><\/strong><\/div>\n<div align=\"center\"><font><\/p>\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Maroc: mort d&rsquo;Abraham Serfaty, c\u00e9l\u00e8bre opposant au roi Hassan II<\/strong><\/font><\/h3>\n<p><\/font><\/div>\n<div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div><font face=\"Arial\" size=\"2\">(AFP) \u2013<span>\u00a0<\/span><span>le 18 novembre 2010<\/span><\/font><\/div>\n<p><span><\/span><font face=\"Arial\" size=\"2\">RABAT \u2014 Abraham Serfaty, l&rsquo;un des plus c\u00e9l\u00e8bres opposants de gauche au r\u00e9gime du roi Hassan II, est d\u00e9c\u00e9d\u00e9 jeudi \u00e0 Marrakech (sud) \u00e0 l&rsquo;\u00e2ge de 84 ans, apr\u00e8s avoir consacr\u00e9 sa vie \u00e0 militer contre l&rsquo;absolutisme monarchique.<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">Cet ancien opposant, qualifi\u00e9 par ses proches de \u00ab\u00a0patriote marocain\u00a0\u00bb, s&rsquo;est \u00e9teint dans une clinique de Marrakech, a indiqu\u00e9 Christine-Daure Serfaty, son \u00e9pouse, et sera inhum\u00e9 vendredi au cimeti\u00e8re juif de Casablanca, pr\u00e8s de ses parents.<\/font><br \/><font face=\"Arial\" size=\"2\">\u00ab\u00a0J&rsquo;ai perdu un ami et quelqu&rsquo;un qui avait le courage de dire ses id\u00e9es par rapport au changement de la politique et des institutions\u00a0\u00bb, a d\u00e9clar\u00e9 Amina Bouaych, pr\u00e9sidente de l&rsquo;Organisation marocaine des droits de l&rsquo;Homme (OMDH).<\/font><br \/><font face=\"Arial\" size=\"2\">Le ministre de la Communication Khalid Naciri, qui avait milit\u00e9 avec Abraham Serfaty au sein du Parti communiste marocain, a lui aussi rendu hommage, dans une d\u00e9claration \u00e0 l&rsquo;AFP, \u00e0 un militant \u00ab\u00a0de la premi\u00e8re heure qui s&rsquo;est battu d&rsquo;abord pour l&rsquo;ind\u00e9pendance de son pays\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">\u00ab\u00a0Progressiste convaincu, a ajout\u00e9 le ministre, Abraham Serfaty a pu diverger avec ses camarades de combat mais, personnage honn\u00eate, il a pu porter un regard positif sur le nouveau Maroc qui se construit\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">Ancien membre du parti communiste marocain, Serfaty &#8211; n\u00e9 \u00e0 Casablanca dans une famille juive originaire de Tanger -, avait particip\u00e9 \u00e0 la fondation dans les ann\u00e9es 1970 de l&rsquo;organisation d&rsquo;extr\u00eame gauche Ila Al Amam (En Avant).<\/font><br \/><font face=\"Arial\" size=\"2\">En 1972, il avait \u00e9t\u00e9 arr\u00eat\u00e9 une premi\u00e8re fois et accus\u00e9 les autorit\u00e9s de l&rsquo;avoir \u00ab\u00a0sauvagement tortur\u00e9\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">Apr\u00e8s plusieurs mois de clandestinit\u00e9, arr\u00eat\u00e9 \u00e0 nouveau en 1974, il avait \u00e9t\u00e9 condamn\u00e9 en octobre 1977 \u00e0 la prison \u00e0 perp\u00e9tuit\u00e9 sous l&rsquo;accusation de \u00ab\u00a0complot contre la s\u00fbret\u00e9 de l&rsquo;Etat\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">Proche \u00e0 l&rsquo;\u00e9poque des th\u00e8ses ind\u00e9pendantistes du Front Polisario sur le Sahara occidental, il aura pass\u00e9 au total 17 ans en prison \u00e0 K\u00e9nitra (nord de Rabat).<\/font><br \/><font face=\"Arial\" size=\"2\">Lib\u00e9r\u00e9 en 1991 par roi Hassan II, p\u00e8re de l&rsquo;actuel roi Mohammed VI, apr\u00e8s une importance campagne internationale en sa faveur, il fut aussit\u00f4t expuls\u00e9 du Maroc vers la France par le ministre de l&rsquo;Int\u00e9rieur de l&rsquo;\u00e9poque, Driss Basri, au motif qu&rsquo;il \u00e9tait un \u00ab\u00a0ressortissant br\u00e9silien\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">Tr\u00e8s connu dans les milieux politiques en France, Serfaty b\u00e9n\u00e9ficia d&rsquo;une intervention de Dani\u00e8le Mitterrand, \u00e9pouse de l&rsquo;ancien pr\u00e9sident fran\u00e7ais, aupr\u00e8s du palais royal.<\/font><br \/><font face=\"Arial\" size=\"2\">En 2000 apr\u00e8s l&rsquo;intronisation de Mohammed VI, l&rsquo;opposant a \u00e9t\u00e9 autoris\u00e9 \u00e0 rentrer au Maroc avec un passeport marocain. Il s&rsquo;\u00e9tait alors install\u00e9 \u00e0 Mohammedia (sud de Rabat) avec son \u00e9pouse Christine Daure, qui l&rsquo;avait toujours soutenu.<\/font><br \/><font face=\"Arial\" size=\"2\">\u00ab\u00a0M. Serfaty \u00e9tait un militant qui avait consacr\u00e9 sa vie d&rsquo;abord \u00e0 la lutte anticoloniale puis contre le r\u00e9gime antid\u00e9mocratique du roi Hassan II\u00a0\u00bb, a d\u00e9clar\u00e9 \u00e0 l&rsquo;AFP Amine Abdelhamid, vice-pr\u00e9sident de l&rsquo;Association marocaine des droits humains (AMDH, ind\u00e9pendant).<\/font><br \/><font face=\"Arial\" size=\"2\">\u00ab\u00a0Abraham Serfaty \u00e9tait un compagnon de route entre 1971 et 1991. Il avait \u00e9t\u00e9 un fervent d\u00e9fenseur de la cause des travailleurs et des droits de l&rsquo;homme\u00a0\u00bb, a-t-il ajout\u00e9.<\/font><br \/><font face=\"Arial\" size=\"2\">Pour le militant de gauche Mohamed Sebbar, membre du Forum justice et v\u00e9rit\u00e9 (FJV), \u00ab\u00a0nous ne pouvons parler de l&rsquo;exp\u00e9rience des groupes de gauche clandestins au Maroc sans \u00e9voquer cet opposant au r\u00e9gime du roi Hassan II\u00a0\u00bb.<\/font><br \/><font face=\"Arial\" size=\"2\">Cet ing\u00e9nieur fut l&rsquo;un des promoteurs de la politique mini\u00e8re du Maroc ind\u00e9pendant, en tant que directeur \u00e0 l&rsquo;Office ch\u00e9rifien des phosphates.<\/font><br \/><font face=\"Arial\" size=\"2\">Issu d&rsquo;une famille de juifs chass\u00e9s d&rsquo;Espagne en 1492, Abraham Serfaty, restait un antisioniste convaincu. \u00ab\u00a0J&rsquo;irai d&rsquo;abord en Palestine lorsqu&rsquo;il y aura un Etat puis je passerai voir des amis juifs qui se trouvent eu Isra\u00ebl\u00a0\u00bb, avait-il confi\u00e9 \u00e0 l&rsquo;AFP dans une interview en 2005.<\/font><br \/>\u00a0<\/div>\n<p><\/font><\/p>\n<div><font face=\"Arial\" size=\"2\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<p><font face=\"Arial\" size=\"2\"><strong>Condol\u00e9ances<br \/><\/strong><\/font><font face=\"Arial\" size=\"2\">Au nom des militantEs de la FTCR, je pr\u00e9sente mes sinc\u00e8res condol\u00e9ances \u00e0 la famille, aux proches et aux camarades de<span>\u00a0<\/span><strong>Abraham SARFATY<\/strong>, infatigable militant d\u00e9mocrate et progressiste marocain.<br \/>Le Maghreb perd un de ses fils prestigieux, un authentique d\u00e9mocrate qui a d\u00e9di\u00e9 toute sa vie \u00e0 la lutte contre les injustices. Nous te t&rsquo;oublierons pas Abraham, tu reste un exemple de courage et de justesse.<br \/>Repose en paix<br \/><\/font><font face=\"Arial\" size=\"2\"><strong>Tarek BEN HIBA<br \/><\/strong>pr\u00e9sident de la FTCR<\/font><\/span><\/span><\/span><\/div>\n<p><font face=\"Arial\" size=\"2\"><br \/>\u00a0<\/font><\/p>\n<p><\/font><\/div>\n<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p align=\"center\" dir=\"ltr\">\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong><b><a href=\"http:\/\/www.tunisnews.net\/\"><font face=\"Arial\"><span><font size=\"2\">Home<\/font><\/span><font size=\"2\"><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><\/font><\/font><span dir=\"rtl\" lang=\"AR-SA\"><font size=\"2\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/font><\/span><\/a><\/b><\/strong><\/font><\/h3>\n<\/p>\n<p align=\"center\" dir=\"ltr\">\u00a0<\/p>\n<p><\/body><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Accueil \u00a0 \u00a0 TUNISNEWS \u00a0 10 \u00e8me ann\u00e9e,\u00a0N\u00b0 3831 du 18.11.2010\u00a0archives :\u00a0www.tunisnews.net\u00a0 Amnesty International: Agissez en faveur de Saber Ragoubi (Tunisie) Libert\u00e9 et Equit\u00e9: Adam Boukedida, ex prisonnier politique &#8211; Une descente de police qui se solde par un coma \u00e0 l\u2019h\u00f4pitalLuiza Toscane: Quaranti\u00e8me\u00a0 journ\u00e9e de gr\u00e8ve : Abdellatif Bouhjila aussi d\u00e9termin\u00e9 qu&rsquo;au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[63,41,29],"class_list":["post-18099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-63","tag-41","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/18099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=18099"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/18099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=18099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=18099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=18099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}