{"id":17502,"date":"2007-08-24T00:00:00","date_gmt":"2007-08-24T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/24-aout-2007\/"},"modified":"2007-08-24T00:00:00","modified_gmt":"2007-08-24T00:00:00","slug":"24-aout-2007","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/24-aout-2007\/","title":{"rendered":"24 ao\u00fbt 2007"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\"Ma\u00eetre Mohamed ABBOU, avocat et d\u00e9fenseur des \n        droits humains, lib\u00e9r\u00e9 depuis quelques semaines apr\u00e8s 30 mois \n        d\u2019incarc\u00e9ration arbitraire, vient d\u2019\u00eatre refoul\u00e9 et interdit de voyager \n        \u00e0 Londres o\u00f9 il doit se rendre, aujourd\u2019hui, le vendredi 24 ao\u00fbt 2007, \n        pour enregistrer une \u00e9mission dans les studios londoniens de la Cha\u00eene \n        satellitaire Al-Jazira\u00a0 sur la libert\u00e9 d\u2019expression et les droits de \n        l\u2019homme.\" http-equiv=\"Content-Type\"\/><\/head><body><body><\/p>\n<p align=\"center\" dir=\"ltr\"><b><a href=\"http:\/\/www.tunisnews.net\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><span dir=\"rtl\" lang=\"AR-SA\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/span><\/a><\/b><\/p>\n<p> <font face=\"Arial\" size=\"2\"><span lang=\"FR\"><\/p>\n<div align=\"justify\">\n<div>  <span lang=\"FR\"> <\/p>\n<div align=\"center\" dir=\"ltr\"> <font face=\"Arial\"><font size=\"2\"> <span lang=\"SV\"> <strong>TUNISNEWS<\/strong><\/span> <\/font><\/font> <\/div>\n<div align=\"center\" dir=\"ltr\"> <strong><font size=\"2\">8\u00a0\u00e8me\u00a0ann\u00e9e, N\u00b0\u00a02649 du 24.08.2007<\/font><\/strong><\/div>\n<p> <strong> <\/p>\n<div align=\"center\" dir=\"ltr\"> <b><span><blink> <font size=\"2\">\u00a0archives : <\/font><a href=\"\" target=\"_blank\" rel=\"noopener\"> <font size=\"2\" target=\"_blank\">www.tunisnews.net<\/font><\/a><\/blink><\/span><\/b><font size=\"2\"> <\/font> <\/div>\n<div>\n<hr\/><\/div>\n<p> <font size=\"2\"> <span lang=\"FR-CH\"> <span lang=\"FR-CH\"> <span> <span lang=\"DE-CH\"> <span lang=\"FR-CH\"> <\/p>\n<div>\u00a0<\/div>\n<p> <font size=\"3\"> <\/p>\n<div align=\"left\">\n<div> <span lang=\"FR-CH\"> <span lang=\"FR-CH\"> <font face=\"Arial\"><font size=\"2\"> <\/p>\n<div> <font face=\"Arial\" size=\"2\"><font size=\"3\"><strong> <font size=\"2\"> <\/p>\n<div> <font face=\"Arial\"> <\/p>\n<div align=\"justify\">\n<p><font face=\"Arial\" size=\"2\">C.R.L.D.H. Tunisie:               Refoulement de Ma\u00eetre Mohamed ABBOU de l\u2019a\u00e9roport de Tunis-               Carthage               <font>Reporters sans fronti\u00e8res: Tunisie:Un               journaliste d&rsquo;une cha\u00eene de t\u00e9l\u00e9vision priv\u00e9e agress\u00e9 par des               policiers en civil<\/font>               Communiqu\u00e9 de la FTCR aux sans-papiers \u00e0 Lille                <font>AP: Le pr\u00e9sident tunisien pour une \u00ab\u00a0approche               globale\u00a0\u00bb dans la lutte contre le terrorisme<\/font>               AP: Un parti d&rsquo;opposition d\u00e9nonce les \u00ab\u00a0entraves\u00a0\u00bb des autorit\u00e9s               tunisiennes               <font>le blog \u00ab Mouwaten Tounsi \u00bb : Allocution du               6 avril 2004 de Bertrand Delano\u00eb lors de l\u2019inauguration de               l\u2019esplanade Habib Bourguiba.<\/font>               Qantara.: Interview mit Mohammad Abbou:               <font>AFP: Peres rassure Erdogan apr\u00e8s qu&rsquo;un lobby               juif \u00e9voque le \u00ab\u00a0g\u00e9nocide\u00a0\u00bb arm\u00e9nien<\/font>               Belfast Telegraph: Belfast mum dies in hols swimming pool tragedy                             <font>R\u00e9alit\u00e9s : Rumeurs sur la vente de Hannibal               TV : Larbi Nasra rompt le silence<\/font>               R\u00e9alit\u00e9s : Grande pol\u00e9mique autour d\u2019un concours : La paix pourra               attendre \u2026<\/font><\/p>\n<\/div>\n<p> <font face=\"Arial\" size=\"2\"> <\/p>\n<div align=\"justify\">\n<hr\/><\/div>\n<p> <\/font><\/font> <\/div>\n<p> <\/font><\/strong><\/font> <\/font><\/div>\n<p> <\/font><\/font><\/span><\/span> <\/div>\n<\/p><\/div>\n<p> <\/font><\/span><\/span><\/span><\/span><\/span><\/font> <font face=\"Arial\" size=\"2\"> <\/p>\n<div>\n<div align=\"center\"> <font face=\"Arial\" size=\"2\"><strong><font>C.R.L.D.H.         Tunisie<\/font> <\/strong>Comit\u00e9 pour le Respect des Libert\u00e9s et des Droits de l\u2019Homme en         Tunisie         membre du R\u00e9seau Euro-m\u00e9diterran\u00e9en des Droits de l\u2019Homme                  21ter rue Voltaire \u2013 FR-75011 PARIS\u00a0 &#8211; Tel\/Fax : 00.33.(0)1.43.72.97.34         contact@crldht.org \/ <a href=\"http:\/\/www.crldht.org\" target=\"_blank\" rel=\"noopener\">www.crldht.org<\/a><\/font><\/div>\n<div align=\"center\"> <font face=\"Arial\" size=\"2\"> <\/p>\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Refoulement de Ma\u00eetre Mohamed         ABBOU de l\u2019a\u00e9roport de Tunis- Carthage<\/strong><\/font><\/h2>\n<p><\/font><\/div>\n<div align=\"justify\"> <font>Ma\u00eetre Mohamed ABBOU, avocat et d\u00e9fenseur des         droits humains, lib\u00e9r\u00e9 depuis quelques semaines apr\u00e8s 30 mois         d\u2019incarc\u00e9ration arbitraire, vient d\u2019\u00eatre refoul\u00e9 et interdit de voyager         \u00e0 Londres o\u00f9 il doit se rendre, aujourd\u2019hui, le vendredi 24 ao\u00fbt 2007,         pour enregistrer une \u00e9mission dans les studios londoniens de la Cha\u00eene         satellitaire Al-Jazira\u00a0 sur la libert\u00e9 d\u2019expression et les droits de         l\u2019homme.         Au moment de passer les douanes, la police de l\u2019air et des fronti\u00e8res         l\u2019a pr\u00e9venu de l\u2019impossibilit\u00e9 de quitter le pays sous pr\u00e9texte que sa         lib\u00e9ration \u00e9tait conditionnelle et qu\u2019il ne peut voyager sans l\u2018accord         du juge et du tribunal qui l\u2019ont condamn\u00e9s !         Quelques jours avant, le couple ABBOU a \u00e9t\u00e9 victime d\u2019un d\u00e9tournement de         fonds lorsque Front Line, une fondation internationale pour la         protection des d\u00e9fenseurs des droits humains, effectue un virement d\u2019un         montant de 3700 Dinars tunisiens destin\u00e9s \u00e0 couvrir les frais du voyage\u00a0         pour un s\u00e9jour \u00e0 Paris. Le couple ABBOU s\u2019es pr\u00e9sent\u00e9 le 21 ao\u00fbt au         bureau de poste principal de Tunis pour entendre dire que la somme a         d\u00e9j\u00e0 \u00e9t\u00e9 retir\u00e9e le samedi 18 ao\u00fbt\u00a0 \u00e0 8h05 du matin !         Le CRLDT s\u2019\u00e9l\u00e8ve contre l\u2019atteinte au droit fondamental \u00e0 la circulation         qui vient de frapper Ma\u00eetre ABOU apr\u00e8s avoir \u00e9t\u00e9 lourdement puni pour         son engagement en faveur des libert\u00e9s et la d\u00e9fense des droits. Il         s\u2019indigne contre de telles m\u00e9thodes visant \u00e0 priver des d\u00e9fenseurs de         leur libert\u00e9 d\u2019expression et assure Me ABBOU et son \u00e9pouse Samia de son         soutien et de son engagement total\u00a0 pour d\u00e9fendre, \u00e0 leurs cot\u00e9s, la         libert\u00e9 et la dignit\u00e9 des tunisiens.<\/font> <strong>Paris, le 24 ao\u00fbt 2007.<\/strong><\/div>\n<\/p><\/div>\n<div>\n<hr\/><\/div>\n<p> <\/font> <\/strong><\/span><\/div>\n<div>    \u00a0<\/div>\n<div>\n<div align=\"center\"> <font size=\"3\"><font size=\"2\"><font><strong>Reporters sans       fronti\u00e8res<\/strong>       Communiqu\u00e9<\/font> <font>24 ao\u00fbt 2007       <\/font><font>Tunisie<\/font><\/font> <\/p>\n<p><font><strong>Un journaliste d&rsquo;une cha\u00eene de t\u00e9l\u00e9vision       priv\u00e9e agress\u00e9 par des policiers en civil       Mohammed Abbou emp\u00each\u00e9 de quitter le territoire et vol\u00e9<\/strong><\/font><\/p>\n<p><\/font><\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\">             Reporters sans fronti\u00e8res est indign\u00e9e par l&rsquo;agression dont a \u00e9t\u00e9 victime      <strong>Aymen Rezgui<\/strong>, journaliste de la cha\u00eene de t\u00e9l\u00e9vision       satellitaire priv\u00e9e Al-Hiwar Attounsi, le 24 ao\u00fbt 2007, en plein       centre-ville de Tunis. Le jour m\u00eame, l&rsquo;avocat Mohammed Abbou n&rsquo;a pas \u00e9t\u00e9       autoris\u00e9 \u00e0 se rendre \u00e0 Londres, o\u00f9 il devait \u00eatre interview\u00e9 par la cha\u00eene       Al-Jazira.               \u00ab\u00a0Cette nouvelle agression t\u00e9moigne de la volont\u00e9 r\u00e9elle des autorit\u00e9s       tunisiennes d&#8217;emp\u00eacher les journalistes ind\u00e9pendants de travailler. A       l\u2019instar d\u2019Aymen Rezgui, ces journalistes sont sans cesse surveill\u00e9s et       harcel\u00e9s. Ce n&rsquo;est pas la premi\u00e8re fois qu\u2019il se fait agresser et       confisquer son mat\u00e9riel. C&rsquo;est d&rsquo;autant plus r\u00e9voltant que cet incident       s&rsquo;est produit en plein jour, devant de nombreux t\u00e9moins\u00a0\u00bb, a d\u00e9nonc\u00e9       l&rsquo;organisation.              \u00ab\u00a0Par ailleurs, nous demandons aux autorit\u00e9s tunisiennes de mettre fin \u00e0       leur acharnement contre l&rsquo;avocat Mohammed Abbou, lib\u00e9r\u00e9 il y a un mois       apr\u00e8s avoir injustement pass\u00e9 pr\u00e8s de deux ans et demi en prison. Cet       homme continue d&rsquo;\u00eatre puni pour sa libert\u00e9 de ton\u00a0\u00bb, a ajout\u00e9 Reporters       sans fronti\u00e8res.              Aymen Rezgui sortait d&rsquo;une conf\u00e9rence de presse tenue par le Parti       d\u00e9mocrate progressiste (PDP) dans ses locaux en plein centre-ville,       lorsqu&rsquo;il a \u00e9t\u00e9 agress\u00e9 par une dizaine de policiers en civil. Il a \u00e9t\u00e9       bless\u00e9 \u00e0 la main. Sa cam\u00e9ra ainsi que toutes ses notes ont \u00e9t\u00e9       confisqu\u00e9es. Le PDP d\u00e9non\u00e7ait la volont\u00e9 des autorit\u00e9s tunisiennes       d&rsquo;entraver ses activit\u00e9s l\u00e9gales, en particulier le rassemblement des       jeunes du parti pr\u00e9vu les 25 et 26 ao\u00fbt prochain, en lui interdisant       l\u2019acc\u00e8s et l\u2019utilisation des espaces publics.               Le directeur d&rsquo;Al-Hiwar Attounsi, Tahar Ben Hassine, avait confi\u00e9, il y a       peu, \u00e0 Reporters sans fronti\u00e8res, ses craintes quant \u00e0 une \u00e9ventuelle       agression. Les 15 et 16 ao\u00fbt 2007, des policiers s&rsquo;\u00e9taient rendus \u00e0 son       domicile et avaient interrog\u00e9 sa femme de m\u00e9nage. M. Ben Hassine       souhaitait porter plainte pour \u00ab\u00a0tentative d&rsquo;intrusion\u00a0\u00bb.               Dans une autre affaire, l\u2019avocat Mohammed Abbou s\u2019est rendu, le 24 ao\u00fbt       2007, \u00e0 l\u2019a\u00e9roport de Tunis-Carthage pour embarquer vers la       Grande-Bretagne afin d\u2019enregistrer une \u00e9mission sur la libert\u00e9       d\u2019expression et les droits de l\u2019homme en Tunisie, dans les studios       londoniens de la cha\u00eene satellitaire Al-Jazira. L\u2019avocat, en libert\u00e9       conditionnelle, a \u00e9t\u00e9 inform\u00e9 par les autorit\u00e9s qu\u2019il \u00e9tait \u201cinterdit de       voyage\u201d. Selon Me Abbou, aucune disposition l\u00e9gale ne justifie cette       interdiction. Dans une d\u00e9claration \u00e0 l\u2019Agence France-Presse, le 22 ao\u00fbt       dernier, l\u2019avocat avait r\u00e9v\u00e9l\u00e9 ses craintes de ne pas \u00eatre autoris\u00e9 \u00e0       quitter le territoire apr\u00e8s qu\u2019une importante somme d\u2019argent, qui lui       \u00e9tait destin\u00e9e pour un prochain d\u00e9placement en France, envoy\u00e9e par       l\u2019organisation de d\u00e9fense des droits de l\u2019homme Frontline, via Western       union, avait myst\u00e9rieusement disparu.               Reporters sans fronti\u00e8res rappelle que le pr\u00e9sident Zine el-Abidine Ben       Ali est l&rsquo;un des 34 pr\u00e9dateurs de la libert\u00e9 de la presse.<\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Communiqu\u00e9 de la FTCR aux       sans-papiers \u00e0 Lille<\/strong>  \u00a0<\/font><\/h2>\n<\/div>\n<div align=\"justify\">      La f\u00e9d\u00e9ration des tunisiens pour une citoyennet\u00e9 des deux rives suit avec       beaucoup d\u2019inqui\u00e9tude\u00a0 l\u2019\u00e9volution de la gr\u00e8ve de la faim entam\u00e9e depuis       le 15 juin dernier par les sans-papiers \u00e0 Lille.       La FTCR qui n\u2019a cess\u00e9 d\u2019appeler \u00e0 la r\u00e9gularisation de tous les sans       papiers, apporte un soutien ind\u00e9fectible aux sans-papiers gr\u00e9vistes de la       faim, au CSP 59 et \u00e0 tous les militants engag\u00e9s dans cette cause.        Elle s\u2019insurge contre les pratiques d\u00e9gradantes subies par les gr\u00e9vistes       de la faim et les m\u00e9thodes muscl\u00e9es et inhumaines employ\u00e9es par les forces       de police \u00e0 Lille sous l\u2019\u00e9gide du pr\u00e9fet Daniel CANEPA, conform\u00e9ment \u00e0 la       politique du pr\u00e9sident Sarkozy et de son gouvernement.       La FTCR exige l\u2019arr\u00eat des interpellations des gr\u00e9vistes de la faim, la       lib\u00e9ration de ceux qui ont \u00e9t\u00e9 conduits dans des lieux d\u2019enfermement aisi       que l\u2019arr\u00eat des expulsions.       La FTCR consid\u00e8re que la seule issue \u00e0 m\u00eame d\u2019\u00e9viter des cons\u00e9quences       dramatiques est la r\u00e9gularisation de tous les sans papiers concern\u00e9s et en       particulier les gr\u00e9vistes de la faim. Elle fait porter la responsabilit\u00e9       de toute \u00e9volution n\u00e9gative \u00e0 l\u2019ent\u00eatement des autorit\u00e9s pr\u00e9fectorales.       La FTCR r\u00e9it\u00e8re son\u00a0 soutien aux gr\u00e9vistes de la faim et appelle \u00e0 une       r\u00e9gularisation de tous les sans papiers.               <font>Paris le 22.8.07<\/font> <\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Le pr\u00e9sident tunisien pour une       \u00ab\u00a0approche globale\u00a0\u00bb dans la lutte contre le terrorisme<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"justify\"> <font>Associated Press, le 23 ao\u00fbt 2007 \u00e0 19h47<\/font><\/div>\n<div align=\"justify\"> <font>TUNIS (AP)&#8211;<\/font> Le pr\u00e9sident tunisien Zine El       Abidine Ben Ali a appel\u00e9 jeudi \u00e0 \u00ab\u00a0h\u00e2ter la tenue d&rsquo;une conf\u00e9rence       internationale, sous l&rsquo;\u00e9gide de l&rsquo;ONU, en vue de l&rsquo;adoption d&rsquo;un code de       conduite en mati\u00e8re de lutte contre le terrorisme qui soit contraignant       pour tous les Etats\u00a0\u00bb.              Dans une interview accord\u00e9e \u00e0 la revue libanaise \u00ab\u00a0Al-Hawadeth\u00a0\u00bb et diffus\u00e9e       par l&rsquo;agence de presse tunisienne TAP, il estime imp\u00e9ratif pour la       communaut\u00e9 internationale de redoubler d&rsquo;efforts pour apporter \u00ab\u00a0des       solutions communes \u00e0 l&rsquo;ensemble des probl\u00e8mes\u00a0\u00bb engendr\u00e9s par       \u00ab\u00a0l&rsquo;aggravation des p\u00e9rils de l&rsquo;extr\u00e9misme et du terrorisme\u00a0\u00bb.              Face \u00e0 ce fl\u00e9au, le pr\u00e9sident tunisien plaide pour \u00ab\u00a0une approche globale       qui ne se limiterait pas aux seules dimensions s\u00e9curitaires, mais qui       engloberait les dimensions \u00e9conomiques, sociales, culturelles, \u00e9ducatives       et politiques\u00a0\u00bb.              Selon lui, \u00ab\u00a0tout dysfonctionnement qui affecterait l&rsquo;une de ces dimensions       ne pourrait qu&rsquo;alimenter l&rsquo;extr\u00e9misme et le terrorisme\u00a0\u00bb.              A ses yeux, la lutte contre ce ph\u00e9nom\u00e8ne \u00ab\u00a0commande d&rsquo;\u00e9radiquer la pauvret\u00e9       dans le monde et d&rsquo;\u0153uvrer \u00e0 combler la fracture \u00e9conomique et cognitive       entre les Etats du Nord et ceux du Sud et \u00e0 diffuser les valeurs de       tol\u00e9rance et de concorde\u00a0\u00bb.              Au plan politique, il juge n\u00e9cessaire de rechercher des \u00ab\u00a0solutions       \u00e9quitables aux probl\u00e8mes en suspens (&#8230;) \u00e0 l&rsquo;origine de tant de foyers de       tension et de conflits g\u00e9n\u00e9rateurs de sentiments d&rsquo;impuissance et       d&rsquo;humiliation de nombreux peuples\u00a0\u00bb, allusion au conflit isra\u00e9lo-arabe et \u00e0       l&rsquo;Irak.              \u00ab\u00a0Il est temps de d\u00e9passer le sc\u00e9nario de l&rsquo;antagonisme entre l&rsquo;Orient et       l&rsquo;Occident et rompre avec les malentendus accumul\u00e9s entre les       civilisations et les religions\u00a0\u00bb, ajoute le pr\u00e9sident Ben Ali.              Un tel dialogue \u00ab\u00a0est n\u00e9cessaire pour corriger notre image en tant       qu&rsquo;arabes et musulmans et de la d\u00e9barrasser des s\u00e9quelles d&rsquo;une       m\u00e9connaissance de notre civilisation, de notre culture et de notre       religion, laquelle s&rsquo;accompagne parfois de comportements et d&rsquo;attitudes       qui heurtent notre sensibilit\u00e9\u00a0\u00bb, d\u00e9plore-t-il.               <font><strong>Associated Press <\/p>\n<hr\/>\n<p><\/strong><\/font> <\/div>\n<div align=\"justify\"> <font> <\/p>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Un parti d&rsquo;opposition d\u00e9nonce les         \u00ab\u00a0entraves\u00a0\u00bb des autorit\u00e9s tunisiennes<\/strong><\/font><\/h2>\n<\/div>\n<p> <font>\u00a0AP &#8211; Vendredi 24 ao\u00fbt, 19h44        TUNIS &#8211; Un parti de l&rsquo;opposition l\u00e9gale en Tunisie a accus\u00e9 vendredi le       gouvernement d&rsquo;avoir entrav\u00e9 l&rsquo;organisation d&rsquo;un s\u00e9minaire de jeunes qui       devait se tenir dans un village touristique dans la banlieue sud de Tunis.              Lors d&rsquo;une conf\u00e9rence de presse, Maya Jribi, secr\u00e9taire g\u00e9n\u00e9rale du parti       d\u00e9mocratique progressiste (PDP), a fait \u00e9tat de \u00ab\u00a0pressions\u00a0\u00bb exerc\u00e9es sur       la soci\u00e9t\u00e9 propri\u00e9taire de cet espace, qui ont conduit \u00e0 l&rsquo;annulation du       contrat sign\u00e9 avec le PDP, sous pr\u00e9texte de travaux devant \u00eatre effectu\u00e9s       sur les lieux.       Elle a mis en garde contre \u00ab\u00a0la gravit\u00e9\u00a0\u00bb de telles entraves et contre les       cons\u00e9quences qui peuvent en d\u00e9couler en entra\u00eenant les jeunes vers les       courants de l&rsquo;extr\u00e9misme et de la violence.       Selon elle, de telles \u00ab\u00a0mesures oppressives\u00a0\u00bb qui ont affect\u00e9 d&rsquo;autres       structures de la soci\u00e9t\u00e9 civile, telle que l&rsquo;Association tunisienne des       femmes d\u00e9mocrates (ATFD), \u00ab\u00a0visent \u00e0 \u00e9touffer toute voix ind\u00e9pendante\u00a0\u00bb.       \u00ab\u00a0Nous \u00e9levons une protestation \u00e9nergique contre ces pratiques\u00a0\u00bb, a-t-elle       d\u00e9clar\u00e9.       Les autorit\u00e9s rejettent ces accusations, en assurant que \u00ab\u00a0les huit partis       l\u00e9gaux ne font l&rsquo;objet d&rsquo;aucune restriction dans leurs activit\u00e9s dans       leurs si\u00e8ges ou dans leurs m\u00e9dias\u00a0\u00bb. AP<\/font><\/p>\n<p><\/font><\/div>\n<div align=\"justify\"> <font>\u00a0<\/font><\/div>\n<div align=\"justify\"> <strong><\/p>\n<hr\/>\n<p><\/strong> <\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Tunisie: visite priv\u00e9e de Silvio       Berlusconi chez le pr\u00e9sident Ben Ali (Ansa)<\/strong><\/font><\/h2>\n<\/p><\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\"> <font>AFP, jeudi 23 ao\u00fbt 2007 <\/font> <\/div>\n<div align=\"justify\">      ROME &#8211; L&rsquo;ancien premier ministre italien Silvio Berlusconi a quitt\u00e9 jeudi       matin la Sardaigne o\u00f9 il passait ses vacances pour se rendre en Tunisie       afin d&rsquo;y rencontrer le pr\u00e9sident Zine El Abidine Ben Ali, a indiqu\u00e9       l&rsquo;agence italienne Ansa.\u00a0       \u00a0 Selon l&rsquo;agence il s&rsquo;agirait d&rsquo;une visite priv\u00e9e, M. Berlusconi \u00e9tant un       ami de longue date du pr\u00e9sident tunisien.        L&rsquo;actuel chef de l&rsquo;opposition italienne a \u00e9t\u00e9 au pouvoir \u00e0 deux reprises       en 1994 puis de 2001 \u00e0 avril 2006.              <font><strong>AFP<\/strong><\/font><\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<p><font size=\"3\"><strong>Allocution du 6 avril 2004 de       Bertrand Delano\u00eb lors de l\u2019inauguration de l\u2019esplanade Habib Bourguiba.<\/strong><\/font><\/p>\n<\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\">      \u00ab Il y a quatre ans disparaissait celui que l\u2019Histoire a, de son vivant,       \u00e9rig\u00e9 en fondateur de la nation tunisienne. Nous reviennent \u00e0 l\u2019esprit les       mots prononc\u00e9s en 1973 par Habib Bourguiba : \u201cD\u2019une poussi\u00e8re d\u2019individus,       d\u2019un magma de tribus, de sous tribus, tous courb\u00e9s sous le joug de la       r\u00e9signation et du fatalisme, j\u2019ai fait un peuple de citoyens.\u201d Des paroles       fortes qui identifient un r\u00f4le, une oeuvre et un parcours uniques dans le       si\u00e8cle.              Retracer le destin d\u2019Habib Bourguiba, c\u2019est \u00e9voquer la figure du leader       charismatique, celui qui fait l\u2019Histoire. Et, dans ce cheminement hors du       commun, Paris occupe une place particuli\u00e8re. C\u2019est en effet dans notre       capitale que le jeune \u00e9tudiant \u00e0 la Sorbonne et \u00e0 l\u2019\u00c9cole libre des       sciences politiques a acquis les armes intellectuelles et id\u00e9ologiques       propres \u00e0 nourrir le futur homme d\u2019\u00c9tat. Venu avec l\u2019ambition d\u00e9clar\u00e9e \u00ab       d\u2019\u00e9tudier le droit en vue de combattre le protectorat \u00bb, Habib Bourguiba,       \u00e0 20 ans, s\u2019est donn\u00e9 les moyens de son r\u00eave d\u2019ind\u00e9pendance.              C\u2019est aussi \u00e0 Paris qu\u2019il rencontra Mathilde, sa premi\u00e8re \u00e9pouse. Et       comment oublier que ce s\u00e9jour parisien lui offrit l\u2019occasion de cultiver       sa passion pour les auteurs fran\u00e7ais, Vigny, Hugo ou Bergson ? Sans doute,       d\u00e9j\u00e0, peut-on d\u00e9celer les ressorts de la dualit\u00e9 qui caract\u00e9rise son       rapport \u00e0 notre pays : il sera un militant inlassable de la       d\u00e9colonisation, mais demeurera un admirateur sinc\u00e8re et enthousiaste de la       France universelle, \u00e9pris de ses po\u00e8tes, de ses \u00e9crivains, de sa culture.              Ainsi, lorsqu\u2019il retrouve son pays natal, en 1927, il ne peut que mesurer       le d\u00e9calage cruel entre les principes enseign\u00e9s \u00e0 Paris et la pratique       effective du protectorat. Ce constat stimule, plus que jamais, le dessein       qu\u2019il nourrit : servir l\u2019\u00e9mancipation de son peuple. Tr\u00e8s t\u00f4t, en effet,       il acquiert la conviction que l\u2019ind\u00e9pendance de la Tunisie est       in\u00e9luctable, m\u00eame si son horizon para\u00eet alors lointain. Lucide, intuitif,       il per\u00e7oit aussi tr\u00e8s vite l\u2019inefficacit\u00e9 du \u00ab Destour \u00bb, le parti lib\u00e9ral       constitutionnel, qu\u2019il juge inadapt\u00e9 \u00e0 cette ambition. Assumant la       dissidence, il fonde donc le N\u00e9o-Destour.              Cette jeune formation est moins \u00e9litiste, plus populaire. Elle n\u2019est plus       seulement urbaine, mais s\u2019ouvre aux campagnes. Surtout, et c\u2019est la marque       fondamentale du bourguibisme, elle rejette la logique du \u201ctout ou rien\u201d et       s\u2019inscrit dans une d\u00e9marche par \u00e9tapes, en acceptant la n\u00e9gociation avec       la puissance coloniale.              D\u00e8s 1931, le \u201cCombattant supr\u00eame\u201d r\u00e9sumait cette strat\u00e9gie dans le journal       La Voix du Tunisien : \u201cLe contact d\u2019une civilisation plus avanc\u00e9e       d\u00e9termine pour le peuple tunisien une r\u00e9action salutaire. Une v\u00e9ritable       r\u00e9g\u00e9n\u00e9 ration se produit. Gr\u00e2ce \u00e0 une judicieuse assimilation des       principes et des m\u00e9thodes de cette civilisation, il arrive fatalement \u00e0       r\u00e9aliser par \u00e9tapes son \u00e9mancipation d\u00e9finitive.\u201d              La marche vers l\u2019ind\u00e9pendance est ainsi pens\u00e9e tr\u00e8s t\u00f4t : elle sera       l\u2019oeuvre du peuple, progressant pas \u00e0 pas, au rythme des compromis, de la       lutte et m\u00eame des sacrifices. Durant vingt ans, en effet, Bourguiba       affrontera toutes les exigences du combat. Assign\u00e9 \u00e0 r\u00e9sidence d\u00e8s le       milieu des ann\u00e9es 1930, lib\u00e9r\u00e9 sous le Front populaire puis de nouveau       emprisonn\u00e9 en 1938, il est livr\u00e9 par le gouvernement de Vichy \u00e0 Mussolini,       qui esp\u00e9rait ainsi affaiblir la r\u00e9sistance en Afrique du Nord.              Terribles ann\u00e9es, domin\u00e9es par l\u2019intensit\u00e9 de l\u2019affrontement, mais aussi       par le sens des valeurs et de l\u2019Histoire. En d\u00e9pit de son opposition \u00e0 la       colonisation, Bourguiba condamne les fascismes et, d\u00e8s le 8 ao\u00fbt 1942,       lance un appel \u00e0 soutenir les troupes alli\u00e9es contre les forces de l\u2019Axe.              De sa prison, il \u00e9crit : \u201cL\u2019Allemagne ne gagnera pas et ne peut gagner la       guerre. L\u2019ordre est donn\u00e9 aux militants d\u2019entrer en relation avec les       Fran\u00e7ais gaullistes en vue de conjuguer notre action clandestine. Notre       soutien doit \u00eatre inconditionnel. C\u2019est une question de vie ou de mort       pour la Tunisie.\u201d Et ces propos prennent un relief particulier en ce lieu       o\u00f9 se trouve le monument \u00e0 la m\u00e9moire des soldats tomb\u00e9s pendant la       campagne de Tunisie, en 1942-1943.              Une fois la guerre termin\u00e9e, le combat reprend. D\u2019abord sur la sc\u00e8ne       internationale. Du Caire, o\u00f9 il r\u00e9side, jusqu\u2019au si\u00e8ge des Nations unies,       Bourguiba s\u2019impose comme le porte-parole et le th\u00e9oricien inspir\u00e9 de la       cause tunisienne. Mais, conscient que la libert\u00e9 ne se gagne que de       l\u2019int\u00e9rieur, il rentre en Tunisie en 1949. Apr\u00e8s les r\u00e9voltes de 1952, son       parti est interdit, et lui-m\u00eame condamn\u00e9 \u00e0 l\u2019exil.              Alors que la marche vers l\u2019ind\u00e9pendance semble brutalement interrompue,       une rencontre d\u00e9cisive va restaurer l\u2019espoir. Car \u00e0 la conviction de       Bourguiba fait \u00e9cho l\u2019esprit \u00e9clair\u00e9 de Pierre Mend\u00e8s France. Le 31       juillet 1954, celui-ci annonce que la France reconna\u00eet l\u2019autonomie interne       de la Tunisie. L\u2019Histoire s\u2019acc\u00e9l\u00e8re alors. Le gouvernement tunisien       engage des pourparlers avec la France qui d\u00e9bouchent sur le protocole       d\u2019accord du 20 mars 1956. La Tunisie est ind\u00e9pendante et souveraine. Le 25       juillet 1957, Bourguiba en devient le premier pr\u00e9sident de la R\u00e9publique.              Victoire de la raison arrach\u00e9e dans le tourbillon enflamm\u00e9 des       \u00e9v\u00e9nements&#8230; En contournant les haines et les blessures irr\u00e9versibles, en       \u00e9cartant les logiques de vengeance, Bourguiba a ouvert \u00e0 son pays la porte       de l\u2019avenir, tout en pr\u00e9servant ses liens avec la France. Des liens, en       v\u00e9rit\u00e9, essentiels \u00e0 ses yeux. Et un h\u00e9ritage pr\u00e9cieux que r\u00e9sume       magnifiquement Jean Lacouture : \u201cHabib Bourguiba, dit- il, ce sage aux       mani\u00e8res d\u2019agit\u00e9 m\u00e9diterran\u00e9en, dont le possibilisme lyrique fonda un \u00c9tat       et aurait peut-\u00eatre pu, pris pour mod\u00e8le, \u00e9viter la guerre d\u2019Alg\u00e9rie.\u201d Des       liens que Bourguiba s\u2019attachera toujours \u00e0 faire vivre. Il deviendra       ainsi, \u00e0 l\u2019instar d\u2019un L\u00e9opold S\u00e9dar Senghor, son ami, l\u2019un des plus       ardents d\u00e9fenseurs de la Francophonie, veillant \u00e0 maintenir l\u2019enseignement       de notre langue dans les \u00e9coles tunisiennes.              D\u00e8s son accession au pouvoir, Bourguiba s\u2019applique \u00e0 parachever la       souverainet\u00e9 nationale et \u00e0 faire entrer la Tunisie dans la modernit\u00e9. Ses       convictions, sa volont\u00e9, son prestige lui permettent de bousculer tabous       et conservatismes. Les r\u00e9formes se succ\u00e8dent : affirmation d\u2019un \u00c9tat la\u00efc       ; g\u00e9n\u00e9ralisation de l\u2019enseignement comme levier contre le       sous-d\u00e9veloppement ; am\u00e9lioration de la sant\u00e9 publique ; et, surtout,       \u00e9mancipation des femmes. \u201cCe que j\u2019ai fait pour la femme, dira-t-il en       1972, demeure la fiert\u00e9 de mon oeuvre.\u201d              Seize ans auparavant, il avait en effet promulgu\u00e9 un code du statut       personnel tr\u00e8s avant-gardiste, interdisant la polygamie, rempla\u00e7ant la       r\u00e9pudiation par une proc\u00e9dure de divorce et fondant le mariage sur le       consentement mutuel. Un an apr\u00e8s, il accordait le droit de vote aux       femmes, l\u00e9galisait la contraception en 1961, puis l\u2019interruption       volontaire de grossesse, en 1967 \u2013 longtemps, donc, avant de nombreux pays       europ\u00e9ens, dont le n\u00f4tre.              C\u2019est une v\u00e9ritable r\u00e9volution pour le statut des Tunisiennes qui fut       ainsi engag\u00e9e. Et un progr\u00e8s dont beaucoup de femmes \u00e0 travers le mo nde       sont encore, cinquante ans plus tard, tenues \u00e0 l\u2019\u00e9cart. C\u2019est aussi un       formidable h\u00e9ritage qu\u2019il l\u00e8gue \u00e0 notre \u00e9poque, sous forme d\u2019un message       adress\u00e9 \u00e0 travers le temps aux faussaires de la religion, aux tenants de       l\u2019obscurantisme.              Pionnier et visionnaire, Bourguiba le fut aussi comme grande figure du       monde arabe. Il utilise ce statut et son prestige au service d\u2019une       id\u00e9e-force : conqu\u00e9rir la paix au Proche-Orient comme la Tunisie avait       conquis son ind\u00e9pendance. Dans le fracas des passions, il est le premier \u00e0       pr\u00f4ner la sagesse et le r\u00e9alisme. \u00c0 J\u00e9richo, en 1965, il affirme ainsi,       contre Nasser, que \u201cla politique du tout ou rien n\u2019a men\u00e9 la Palestine       qu\u2019\u00e0 la d\u00e9faite\u201d. Il ose les mots de paix et de coexistence.              Vision empreinte de pragmatisme et d\u2019intelligence. Mais conception, aussi,       ins\u00e9parable d\u2019une ind\u00e9fectible fid\u00e9lit\u00e9 \u00e0 la cause palestinienne,       symbolis\u00e9e par l\u2019arriv\u00e9e, en ao\u00fbt 1982 \u2013 apr\u00e8s l\u2019invasion du Liban par       Isra\u00ebl \u2013, de bateaux militaires fran\u00e7ais conduisant Yasser Arafat et ses       partisans jusqu\u2019au port de Bizerte. Ind\u00e9pendance, paix et progr\u00e8s : telles       sont les ambitions qui ont inspir\u00e9 une vision sans cesse en mouvement, et       des actes m\u00e9morables, m\u00eame si la longue pr\u00e9sidence de Bourguiba s\u2019acheva       malheureusement dans la confusion. Rarement l\u2019identification entre un chef       d\u2019\u00c9tat et une nation n\u2019est apparue aussi forte. Bourguiba a \u00e9t\u00e9 la       Tunisie, il a incarn\u00e9 sa naissance, sa souverainet\u00e9, son d\u00e9veloppement.       Aujourd\u2019hui, en ce jour anniversaire de sa mort, c\u2019est donc \u00e0 cet homme       d\u2019\u00c9tat d\u2019exception que Paris rend hommage.              Parce qu\u2019il fut l\u2019un des acteurs majeurs du si\u00e8cle dernier ; parce qu\u2019il       sut \u00e9viter une cruelle trag\u00e9die dans notre histoire commune ; parce que       nous lui devons les liens amicaux, fraternels et pacifiques institu\u00e9s       entre nos peuples ; parce que les Tunisiens, au sein de notre communaut\u00e9       parisienne, apportent une richesse pr\u00e9cieuse \u00e0 l\u2019identit\u00e9 de notre ville,       il nous revenait d\u2019inscrire son nom dans la m\u00e9moire collective de notre       cit\u00e9.              Paris l\u2019honore aujourd\u2019hui, et, au-del\u00e0, marque son profond attachement \u00e0       la Tunisie, \u00e0 son peuple, \u00e0 son avenir. [\u2026] Puisse sur cette esplanade       r\u00e9sonner la modernit\u00e9 des mots que Bourguiba pronon\u00e7ait, il y a cinquante       ans : \u201cMon v\u0153u le plus cher est que les musulmans vivent dans une       communion des c\u0153urs encore plus \u00e9troite, que les dirigeants r\u00e9alisent       entre eux une meilleure compr\u00e9hension et combattent tous les complexes \u2013       d\u2019inf\u00e9riorit\u00e9 ou de sup\u00e9riorit\u00e9 \u2013 qui risqueraient de nous pr\u00e9cipiter dans       une catastrophe, ce que nous pouvons s\u00fbrement \u00e9viter gr\u00e2ce \u00e0 un recours       incessant \u00e0 la raison et \u00e0 l\u2019intelligence.\u201d              Que tous les promeneurs de ce lieu sachent que, irrigu\u00e9 de ces sages       principes, bat ici, avec confiance, le c\u0153ur de l\u2019amiti\u00e9 entre les peuples       de Tunisie et de France. \u00bb              <font><strong>(Source : le blog \u00ab Mouwaten Tounsi \u00bb, le 22       ao\u00fbt 2007)<\/strong><\/font> <font>Lien : <a href=\"http:\/\/mouwatentounsi.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">      http:\/\/mouwatentounsi.blogspot.com\/<\/a> <\/p>\n<hr\/>\n<p><\/font> <\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\"> <font><font> <\/p>\n<p align=\"center\"> <font size=\"3\"><span><b> <span lang=\"DE\">Interview mit       Mohammad Abbou:<\/span><\/b><\/span><\/font><\/p>\n<p> <span lang=\"SV\"><font size=\"3\">\u00a0<\/font><\/span><\/p>\n<p align=\"center\"> <font size=\"3\"><b><span lang=\"DE\">      \u00ab\u00a0Das tunesische Volk setzt auf Vers\u00f6hnung!<\/span><\/b><\/font><\/p>\n<p> <span lang=\"DE\"> <\/span><b> <span lang=\"DE\">      Der Menschenrechtler und Rechtsanwalt Mohammad Abbou wurde im April 2005       zu dreieinhalb Jahren Haft verurteilt, nachdem er hatte die Praxis der       Folter in Tunesien kritisiert hatte. Jetzt kam er nach der Intervention       des US-Au\u00dfenministeriums und des franz\u00f6sischen Pr\u00e4sidenten frei.<\/span><span lang=\"DE\"> <\/span><\/b> <span lang=\"DE\"> <\/span><i> <span lang=\"DE\">      Zun\u00e4chst einmal: Wie haben Sie die Begnadigung durch den tunesischen       Pr\u00e4sidenten und die Haftentlassung aufgenommen?<\/span><\/i><span lang=\"DE\"> <b>Mohammad Abbou:<\/b> Das war keine Begnadigung durch den Pr\u00e4sidenten,       wie es von einigen behauptet wird. Der Haftentlassung lag ein       polizeilicher Beschluss zugrunde. Au\u00dferdem wurde dieser Beschluss       erlassen, nachdem ich mehr als zwei Drittel der Haftzeit verb\u00fc\u00dft habe.               Meine Haftentlassung verdanke ich nicht den tunesischen Beh\u00f6rden, die mich       weiterhin in Haft behalten wollten, um sich an mir und an all den       unabh\u00e4ngigen Menschen, die f\u00fcr meine Freiheit gek\u00e4mpft hatten, zu r\u00e4chen.       Es sind meine Anwaltskollegen, die gleich nach meiner Verschleppung und       meiner \u00dcberstellung ins Gef\u00e4ngnis am 1. M\u00e4rz 2005 eine gro\u00dfe Kampagne f\u00fcr       meine Entlassung lostraten. Die hatte sich auf weite Teile der tunesischen       und der internationalen Zivilgesellschaft ausgeweitet. Viele tunesische       und internationale Organisationen hatten sich \u00fcber zwei Jahre f\u00fcr meinen       Fall eingesetzt, bis ich meine Freiheit wieder bekam.              <i>Haben Sie davon erfahren, dass sich am Ende der franz\u00f6sische Pr\u00e4sident       f\u00fcr Ihre Freilassung einsetzte?<\/i> <b>Abbou:<\/b> Ich habe dies erfahren. Deshalb nutze ich diese Gelegenheit,       ihm, all den franz\u00f6sischen Organisationen und dem franz\u00f6sischen Volk       meinen Dank auszusprechen. Au\u00dferdem m\u00f6chte ich dem US-Au\u00dfenministerium       danken, das in einem offiziellen Schreiben meine Entlassung forderte. Die       US-Botschaft in Tunesien hatte sich intensiv f\u00fcr mich eingesetzt. Zudem       gilt mein Dank den internationalen Rechtsorganisationen, die mich       vorbehaltlos verteidigt haben. Weiter m\u00f6chte ich den gewissenhaften       Menschen aus vielen Medienanstalten weltweit danken, die geholfen haben,       den verf\u00e4lschten Diskurs der tunesischen Regierung aufzudecken.              <i>Bef\u00fcrchten Sie nicht, dass die tunesische Regierung Sie &#8211; wie viele       andere Oppositionelle &#8211; beschuldigt, im Ausland um Unterst\u00fctzung       nachgesucht zu haben?<\/i> <b>Abbou: <\/b>Ich m\u00f6chte eins klarstellen: Wenn tunesische B\u00fcrger keine       staatliche Institutionen anrufen k\u00f6nnen, um ihre Rechte sch\u00fctzen und       Gerechtigkeit walten zu lassen, und wenn besagte Institutionen       instrumentalisiert werden, um politische Gegner kalt zu stellen und die       B\u00fcrger ihrer Rechte zu berauben, dann muss es einen Ausweg aus einem       solchen Missstand geben.              In solch einer Situation befanden schon Philosophen, dass ein Volk das       Recht habe, Widerstand gegen die Diktatur zu leisten.              Wir wollten aber nicht, dass Tunesien in Gewalt und Anarchie versinkt. Das       tunesische Volk setzt bekannterma\u00dfen auf Vers\u00f6hnung, auch wenn ihm die       Demokratie vorenthalten wird, und dies obwohl es alle Voraussetzungen       erf\u00fcllt, um in einer Demokratie zu leben.              F\u00fcr uns kommt keine andere Alternative als der friedliche Widerstand in       Frage. Allerdings unterdr\u00fcckt die tunesische Regierung jedwede Form des       friedlichen Widerstands.              Vor diesem Hintergrund bin ich keineswegs besch\u00e4mt dar\u00fcber, dass die       Partner Tunesiens Druck aus\u00fcben, um einen Ausweg herbeizuf\u00fchren. In diesem       Fall geht es darum, die tunesische Regierung zu verpflichten, ihren       B\u00fcrgern die ihnen zustehenden Rechte zu garantieren, die Verfassung und       die damit einhergehenden Freiheiten zu respektieren sowie die       internationalen Vertr\u00e4ge einzuhalten, die Tunesien unterzeichnete.              Ich muss aber deutlich machen, dass besagter Druck seitens der Partner       Tunesiens darauf beschr\u00e4nkt bleiben muss, Verfassungs- und Gesetzesbr\u00fcche       sowie die Verletzung der W\u00fcrde der Tunesier zu unterbinden.              Wir lehnen jede m\u00f6gliche ausl\u00e4ndische Einmischung ab, die der tunesischen       Regierung etwas vorschreiben k\u00f6nnte, was der tunesischen Politik       zuwiderl\u00e4uft, unter der Voraussetzung, dass sie den Interessen des       tunesischen Volkes entspricht.              <i>K\u00f6nnen Sie uns einen Eindruck von den Haftbedingungen geben?<\/i> <b>Abbou:<\/b> Ich habe schwierige Zeiten durchgemacht. Am 19. M\u00e4rz 2006       trat ich in den Hungerstreik und forderte, dass man mich in eine       Gef\u00e4ngniszelle zusammen mit den gew\u00f6hnlichen H\u00e4ftlingen verlegt, weil die       Regierung behauptete, dass es in Tunesien keine politischen H\u00e4ftlinge       gebe. Deshalb wollte ich wie jeder andere H\u00e4ftling behandelt werden.              Meiner Forderung wurde jedoch nicht entsprochen. Stattdessen wurde ich       damit bestraft, dass man mich mit Gewalt in die gleiche Zelle       zur\u00fcckbrachte. Am 9. Tag des 25-t\u00e4gigen Hungerstreiks wurde ich trotz       meines sich verschlechternden Gesundheitszustandes gezwungen, die Zelle zu       verlassen, um bei der t\u00e4glichen Z\u00e4hlung der H\u00e4ftlinge anwesend zu sein.              Auch der Gef\u00e4ngnisarzt, an den ich mich deswegen gewandt hatte, behauptete       in Anwesenheit der Gef\u00e4ngnisw\u00e4rter, dass mein Gesundheitszustand dadurch       nicht beeintr\u00e4chtigt werde. Dies war unethisch und \u00e4u\u00dferst inhuman.               Au\u00dferdem verzichtete ich aus Solidarit\u00e4t mit den \u00fcbrigen H\u00e4ftlingen, die       in Zellen ohne Matratzen einsa\u00dfen, auf meine eigene Matratze, was mir       jedoch Nierenbeschwerden verursachte.              Dieses Problem w\u00e4re ziemlich einfach zu beheben gewesen, wenn man meiner       Bitte gefolgt w\u00e4re. Doch mein Gesuch wurde abgeschmettert. So musste ich       auf diese schmerzhafte und ungesunde Weise ein Jahr und vier Monate       schlafen.              Ich w\u00fcnsche mir, dass derartige Praktiken gegen\u00fcber der tunesischen       Bev\u00f6lkerung aufh\u00f6ren. Sie verdient einen w\u00fcrdevolleren Umgang.              <i>Gab es w\u00e4hrend Ihrer Haft Versuche seitens der Beh\u00f6rden, Sie zur       Stellung eines Gnadengesuchs zu bewegen und Ihnen den Artikel, der       letztlich der Grund f\u00fcr Ihre Verhaftung war, zu verzeihen?<\/i> <b>Abbou:<\/b> Solche Versuche unternahmen Personen, die den Beh\u00f6rden nahe       standen. Auch ein Mith\u00e4ftling war von den Beh\u00f6rden damit beauftragt       worden. Es gab auch weitere niedertr\u00e4chtige Versuche, die stets an meine       Haftentlassung gekn\u00fcpft wurden. Ich lehnte alle ab, und zwar nicht nur, um       meine W\u00fcrde zu wahren und auf mein Recht auf Meinungs\u00e4u\u00dferung zu pochen,       sondern auch um das tunesische Volk durch mich nicht zu dem\u00fctigen.              <i>Was halten Sie vom Appell des tunesischen Pr\u00e4sidenten Ben Ali an das       tunesische Volk, seine Amtszeit ab 2009 um weitere f\u00fcnf Jahre zu       verl\u00e4ngern?<\/i> <b>Abbou:<\/b> Ich bin der Meinung, dass Machtwechsel zu den tragenden       S\u00e4ulen eines demokratischen Systems geh\u00f6rt. Die Machtergreifung im Jahre       1987 durch Pr\u00e4sident Ben Ali wurde von den Menschen, die unter dem       Diktator Bourguiba und der lebenslangen Pr\u00e4sidentschaft gelitten hatten,       deshalb begr\u00fc\u00dft, weil der Pr\u00e4sident in der Erkl\u00e4rung vom 7. November 1987       den Bruch mit der bisherigen Diktatur versprach.              Das Versprechen wurde aber nicht gehalten, obwohl die tunesische       Verfassung seit 1988 vorsieht, dass der Staatspr\u00e4sident nicht \u00f6fter als       zweimal f\u00fcr die Pr\u00e4sidentschaftswahlen kandidieren darf. Nach der       Volksabstimmung im Jahre 2002 wurde jedoch die Verfassung dahingehend       ge\u00e4ndert, dass der 73-j\u00e4hrige Pr\u00e4sident f\u00fcr die Pr\u00e4sidentschaftswahlen       2009 nach einer 22-j\u00e4hrigen Amtszeit wieder kandidieren darf.              Das ist ein Zustand wie zu Zeiten von Bourguiba. Jeder kennt die Gefahren,       denen das Land in den achtziger Jahren aufgrund der damaligen Situation       ausgesetzt war. Daher glaube ich, dass keine demokratischen Strukturen \u2013       weder in Tunesien noch in irgendeinem anderen Land \u2013 aufgebaut werden       k\u00f6nnen, solange es eine lebenslange Pr\u00e4sidentschaft gibt.              <\/span><b><i> <span lang=\"DE\">      Interview: Salim Boukhdhir<\/span><\/i><span lang=\"DE\"> <\/span><\/b> <span lang=\"DE\"> <\/span><b><i> <span lang=\"DE\">      Aus dem Arabischen von Raoua Allaoui<\/span><\/i><\/b><i><span lang=\"DE\"> <b>\u00a9 Qantara.de 2007<\/b> <\/span><\/i><b><i> <span lang=\"DE\">      Salim Boukhdhir ist tunesischer Schriftsteller und Journalist.<\/span><\/i><\/b><\/p>\n<p> <b><i> <span lang=\"DE\">      \u00a0<\/span><\/i><\/b><\/p>\n<p> <b><i><span>      Source:<\/span><\/i><\/b><\/p>\n<p> <b><i><span>      Site\u201cQantara\u201c( site appartient au canal DW deutsche welle) \u00a0le 23 aout       2007 .<\/span><\/i><\/b><\/p>\n<p> <b><i><span>\u00a0<\/span><\/i><\/b><\/p>\n<p> <b><i><span>      Lien\u00a0:<\/span><\/i><\/b><\/p>\n<p> <i> <span lang=\"SV\"> <a href=\"http:\/\/www.qantara.de\/webcom\/show_article.php\/_c-468\/_nr-803\/i.html\" rel=\"nofollow noopener\" target=\"_blank\"> <span lang=\"EN-US\"><font>      http:\/\/www.qantara.de\/webcom\/show_article.php\/_c-468\/_nr-803\/i.html<\/font><\/span><\/a><\/span><\/i><\/p>\n<p> <span>\u00a0<\/span><\/p>\n<p><\/font><\/font><\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Peres rassure Erdogan apr\u00e8s qu&rsquo;un       lobby juif \u00e9voque le \u00ab\u00a0g\u00e9nocide\u00a0\u00bb arm\u00e9nien<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"justify\"> <font>AFP, le 23 ao\u00fbt 2007 \u00e0 19h29<\/font><\/div>\n<div align=\"justify\"> <font>ANKARA, 23 ao\u00fbt 2007 (AFP) &#8211;<\/font> Le pr\u00e9sident       isra\u00e9lien Shimon Peres a appel\u00e9 le Premier ministre turc Recep Tayyip       Erdogan jeudi au t\u00e9l\u00e9phone pour le rassurer sur la volont\u00e9 d&rsquo;Isra\u00ebl de       maintenir des relations \u00e9troites avec la Turquie, a annonc\u00e9 un conseiller       de M. Erdogan.              Cet appel intervient apr\u00e8s qu&rsquo;un important lobby juif am\u00e9ricain, la Ligue       anti-diffamation (ADL), a d\u00e9cid\u00e9 de qualifier de \u00ab\u00a0g\u00e9nocide\u00a0\u00bb le massacre       des Arm\u00e9niens \u00e0 l&rsquo;\u00e9poque de l&#8217;empire ottoman, ce que rejettent       cat\u00e9goriquement les autorit\u00e9s turques.              A Ankara, cette d\u00e9cision fait craindre la fin du soutien du puissant lobby       juif am\u00e9ricain contre ceux qui pressent Washington de reconna\u00eetre le       massacre des Arm\u00e9niens comme g\u00e9nocide et de faire voter une loi dans ce       sens au Congr\u00e8s.              \u00ab\u00a0Peres a insist\u00e9 sur l&rsquo;importance pour Isra\u00ebl de ses relations avec la       Turquie\u00a0\u00bb, a d\u00e9clar\u00e9 le conseiller du Premier ministre turc \u00e0 l&rsquo;AFP. \u00ab\u00a0Ce       fut une discussion fructueuse\u00a0\u00bb, a-t-il ajout\u00e9.              Mercredi, l&rsquo;ambassade d&rsquo;Isra\u00ebl \u00e0 Ankara a d\u00e9clar\u00e9 que l&rsquo;Etat h\u00e9breu avait       connaissance des \u00ab\u00a0terribles \u00e9v\u00e9nements\u00a0\u00bb et des \u00ab\u00a0horribles souffrances\u00a0\u00bb       endur\u00e9s par les Arm\u00e9niens, tout en exhortant les Isra\u00e9liens \u00e0 ne pas       prendre partie.              \u00ab\u00a0Isra\u00ebl demande \u00e0 ce qu&rsquo;aucune des deux parties ne soit privil\u00e9gi\u00e9e et       qu&rsquo;aucune qualification ne soit faite concernant ce qui est arriv\u00e9. Nous       esp\u00e9rons que les deux parties parviendront \u00e0 un dialogue ouvert qui       permettra de refermer les blessures\u00a0\u00bb, a-t-elle ajout\u00e9.              L&rsquo;ADL a d\u00e9clar\u00e9 mardi qu&rsquo;elle avait r\u00e9examin\u00e9 le cas du massacre des       Arm\u00e9niens et, apr\u00e8s consultation de sp\u00e9cialistes, avait jug\u00e9 qu&rsquo;il       \u00ab\u00a0correspondait \u00e0 un g\u00e9nocide\u00a0\u00bb.              L&rsquo;organisation am\u00e9ricaine a n\u00e9anmoins ajout\u00e9 qu&rsquo;une loi du Congr\u00e8s, qui       reconna\u00eetrait ce massacre comme un g\u00e9nocide, ne \u00ab\u00a0faciliterait pas la       r\u00e9conciliation entre Turcs et Arm\u00e9niens, et pourrait mettre en p\u00e9ril&#8230;       les importantes relations bilat\u00e9rales entre la Turquie, Isra\u00ebl et les       Etats-Unis\u00a0\u00bb.              La Turquie est le principal alli\u00e9 d&rsquo;Isra\u00ebl dans la r\u00e9gion depuis la       signature en 1996 d&rsquo;un accord de coop\u00e9ration militaire, qui avait provoqu\u00e9       la col\u00e8re des pays arabes et de l&rsquo;Iran.              L&rsquo;intervention am\u00e9ricaine en Irak et la politique isra\u00e9lienne envers les       Palestiniens ont favoris\u00e9 l&rsquo;\u00e9mergence de sentiments anti-am\u00e9ricains et       anti-isra\u00e9liens dans l&rsquo;opinion turque.              Le gouvernement de M. Erdogan, issu de la mouvance islamiste, avait se son       c\u00f4t\u00e9 provoqu\u00e9 la col\u00e8re d&rsquo;Isra\u00ebl en 2006 en accueillant \u00e0 Ankara des       responsables du Hamas pour, selon la Turquie, tenter de convaincre le       groupe islamiste palestinien de renoncer \u00e0 la violence.              <font><strong>AFP    <\/strong><\/font><\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\"> <strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Belfast mum dies in hols swimming       pool tragedy<\/font><\/h2>\n<p> <\/strong> <\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\"> <font>By Claire McNeilly<\/font>               A devastated Ulster family were today coming to terms with their grief       after a 57-year-old mother-of-three tragically died on holiday abroad.              Meta Forsythe, from Twinbrook in west Belfast, was found dead in a       swimming pool in Tunisia on Sunday &#8211; just two days into her summer break.              Mrs Forsythe&rsquo;s body was discovered in the pool by her 24-year-old daughter       Lisa, who was then forced break the terrible news to the rest of the       family by telephone.              A post mortem examination is due to be carried out and it is understood       that the Department of Foreign Affairs in Dublin are helping to arrange       for the body to be flown home.              Mrs Forsythe&rsquo;s distraught husband Eric told the Irish News that he would       remember her as a woman of strong faith and charity.              Speaking to the Belfast Telegraph, Father Darach, a curate at St Luke&rsquo;s       Twinbrook, said that Mrs Forsythe, who was a florist at the church, would       be sorely missed.              \u00a0\u00bb Everyone is still very much shocked,\u00a0\u00bb he said.               <font><strong>(Source:\u00a0 \u00ab\u00a0Belfast Telegraph\u201d (Quotidien \u2013       Irlande), le 22 ao\u00fbt 2007 \u00e0 11h07)<\/strong><\/font> <font>Lien :      <a href=\"http:\/\/www.belfasttelegraph.co.uk\/news\/local-national\/article2884209.ece\" target=\"_blank\" rel=\"noopener\">      http:\/\/www.belfasttelegraph.co.uk\/news\/local-national\/article2884209.ece<\/a><\/font> \u00a0<\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Rumeurs sur la vente de Hannibal TV       :        <font>Larbi Nasra rompt le silence<\/font><\/strong><\/font><\/h2>\n<\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\"> <font>Nizar Bahloul\u00a0\u00a0        <\/font>       Les entretiens avec Larbi Nasra, patron de Hannibal TV, ne sont pas       faciles. Imposant, peut-\u00eatre h\u00e9g\u00e9monique, le bonhomme n\u2019aime pas qu\u2019on le       contrarie trop. Les rumeurs? Il s\u2019en moque. Ce qu\u2019on \u00e9crit sur lui et sur       Sa cha\u00eene ? Bof ! Ce qu\u2019on dit \u00e0 son encontre ? Les chiens aboient\u2026 Larbi       Nasra est persuad\u00e9 qu\u2019il est au-dessus de tout cela. Il a fond\u00e9 cette       cha\u00eene pour le plaisir et non pour l\u2019argent. Tout le reste n\u2019est que       litt\u00e9rature.              Larbi Nasra d\u00e9ment tout. Il nie en bloc. Personne ne l\u2019a contact\u00e9 pour       l\u2019achat de sa cha\u00eene et il n\u2019a contact\u00e9 personne \u00e0 ce sujet. Il n\u2019a pas de       dettes et la cha\u00eene fonctionne parfaitement. \u00ab Je ne suis quand m\u00eame pas       le cocu qui est le dernier \u00e0 apprendre que sa femme le trompe\u00bb, nous       dit-il en dialectal tunisien d\u00e8s l\u2019entame de l\u2019entretien qu\u2019il a accord\u00e9e       \u00e0 nos confr\u00e8res de Haqa\u00efq et auquel nous avons assist\u00e9. Il nous le fera       comprendre d\u2019ailleurs plus tard, car ses relations avec les journalistes       qu\u2019il ne conna\u00eet pas directement ne sont pas vraiment au beau fixe.              Les plus folles rumeurs n\u2019ont pas arr\u00eat\u00e9 de circuler ces derniers temps       autour du fondateur de la premi\u00e8re cha\u00eene priv\u00e9e tunisienne. Une cha\u00eene       qui est mont\u00e9e en fl\u00e8che \u00e0 partir de rien pour occuper en un temps record       (deux ans!) la premi\u00e8re place de l\u2019audimat sans jamais en redescendre.       \u201cHannibal est en vente et un groupe tunisien d\u00e9sire la racheter. Larbi       Nasra s\u2019est \u00e9vad\u00e9 en Arabie Saoudite. Larbi Nasra n\u2019a pas de quoi r\u00e9gler       ses factures et il a les banques, les cr\u00e9anciers, le fisc et la CNSS sur       le dos\u201d. Il nous fallait v\u00e9rifier tout cela et l\u2019unique personne pour       infirmer ou confirmer ne pouvait \u00eatre autre que Nasra lui-m\u00eame.              L\u2019exercice ne plait pas vraiment \u00e0 l\u2019int\u00e9ress\u00e9, mais il accepte de jouer       le jeu en nous ouvrant les portes de sa grande villa qui lui sert de       bureaux dans le vaste terrain abritant les locaux de la cha\u00eene priv\u00e9e.              \u00ab Certains consid\u00e8rent Hannibal TV comme un jouet, dit-il. Une sorte de       gadget. Certains pensaient qu\u2019on \u00e9tait une petite cha\u00eene et qu\u2019on allait       le rester. Non ! Hannibal TV va bien et le demeurera. La programmation de       ramadan est pr\u00eate dans les cartons depuis des mois. \u00bb              Convaincu de sa position et de l\u2019effet qu\u2019il a sur les Tunisiens, il       brandit les derniers chiffres de Sigma Conseil, qu\u2019il ne consid\u00e8re       toujours pas comme \u00ab ami \u00bb, montrant ses 35% d\u2019audimat. \u00ab Je suis certain       qu\u2019on a plus de 40%. De toute fa\u00e7on, on les aura \u00bb.              Concernant les rumeurs colport\u00e9es un peu partout, Larbi Nasra, comme ses       lieutenants il y a quelques semaines, \u00e9voque la jalousie de certains pour       en expliquer les raisons. \u00ab Nous d\u00e9rangeons, alors on m\u00e8ne contre moi-m\u00eame       et mon staff une guerre des nerfs dont l\u2019objectif est de nous d\u00e9stabiliser       \u00bb. Quelles sont les raisons de cette campagne de \u00ab d\u00e9stabilisation \u00bb ? La       jalousie, dit-il, \u00e9tonn\u00e9 que l\u2019on ne comprenne pas du premier coup. \u00ab Tout       succ\u00e8s a un prix. On me consid\u00e8re comme un intrus dans le domaine et on ne       comprend pas pourquoi on r\u00e9ussit. Ils ne comprennent pas comment j\u2019ai pu       apprendre le m\u00e9tier en quarante jours\u00bb. Larbi Nasra est convaincu, et les       r\u00e9sultats de sa cha\u00eene ne peuvent que le confirmer dans sa position, qu\u2019il       est un excellent gestionnaire et qu\u2019il m\u00e8ne la barque Hannibal comme elle       doit \u00eatre men\u00e9e.              Il nous racontera les t\u00e9moignages des t\u00e9l\u00e9spectateurs qu\u2019il recueille ici       et l\u00e0, en Tunisie et \u00e0 l\u2019\u00e9tranger. \u00ab Dans le paysage m\u00e9diatique, nous ne       sommes qu\u2019une goutte dans un oc\u00e9an face aux cha\u00eenes du Golfe financ\u00e9es par       les puissances p\u00e9troli\u00e8res. Pourtant, l\u00e0 o\u00f9 je vais, on conna\u00eet Hannibal.       Nous sommes class\u00e9s parmi les 40-50 premi\u00e8res cha\u00eenes de la r\u00e9gion malgr\u00e9       nos moyens. C\u2019est comme si nous \u00e9tions une famille de 8-10 personnes       d\u00eenant avec une baguette.\u00bb              Autant d\u2019\u00e9l\u00e9ments qui le confortent dans la position de quelqu\u2019un qui a       fortement r\u00e9ussi son projet. Un projet qu\u2019il d\u00e9veloppe pour le plaisir et       uniquement le plaisir. \u00ab Je suis milliardaire, j\u2019ai fait d\u00e9j\u00e0 mes preuves       et amass\u00e9 ma fortune, bien avant de cr\u00e9er Hannibal.              Cette cha\u00eene n\u2019est pas l\u00e0 pour que je gagne de l\u2019argent, mais pour le       plaisir et l\u2019unique plaisir. D\u2019ailleurs, elle ne gagne pas d\u2019argent et nos       recettes ne couvrent m\u00eame pas les 2\/3 de nos d\u00e9penses.\u00bb              On revient \u00e0 la charge sur la question des rumeurs et de ce qu\u2019il a       qualifi\u00e9 de pressions. Il commence \u00e0 se f\u00e2cher, mais r\u00e9pond. \u00ab Oui, j\u2019ai       eu des pressions. J\u2019ai eu les banques, le fisc et la CNSS. Cela ne me       d\u00e9range pas, au contraire. Pour les banques, je leur ai vers\u00e9 le jour m\u00eame       un million de dinars couvrant largement (plus que le double) les traites       pass\u00e9es et \u00e0 venir. Concernant le fisc et la s\u00e9curit\u00e9 sociale, cela       m\u2019arrange que \u00e7a se sache. Que l\u2019on sache que Larbi Nasra n\u2019est pas       au-dessus de la loi et paie ce qu\u2019il doit payer \u00e0 l\u2019Etat. \u00bb              Quand on \u00e9voque la question de l\u2019insolvabilit\u00e9, il sort de ses gonds et se       f\u00e2che vraiment. \u00ab Moi insolvable ? Et pourquoi donc ? J\u2019ai de l\u2019argent et       je n\u2019ai nullement besoin de rouler X et Y pour en avoir. Je n\u2019ai pas \u00e0 me       salir pour quelques dinars. \u00bb              Il suspend l\u2019entretien et appelle son \u00ab daffeur \u00bb imm\u00e9diatement.              Un jeune gars qui semble consciencieux et \u00e0 qui il demande de t\u00e9moigner en       toute franchise. Le jeune t\u00e9moigne : \u00ab Nous r\u00e9glons la CNSS et les imp\u00f4ts       g\u00e9n\u00e9ralement dix jours avant l\u2019\u00e9ch\u00e9ance. Nous r\u00e9glons les salaires \u00e0       temps, sans retard. M. Larbi Nasra a donn\u00e9 des consignes fermes pour que       toutes les factures soient r\u00e9gl\u00e9es au maximum 48 heures apr\u00e8s leur       arriv\u00e9e. \u00bb              Que reste-t-il \u00e0 savoir ? Nous revenons sur les \u00ab pressions \u00bb et les       raisons. \u00ab Je ne comprends pas vraiment. Je suis le fils du r\u00e9gime. J\u2019aime       le Pr\u00e9sident Ben Ali,non pas en tant que pr\u00e9sident uniquement, mais en       tant que personne. J\u2019estime avoir une ligne \u00e9ditoriale conforme aux       souhaits du r\u00e9gime et du gouvernement et r\u00e9pondant aux int\u00e9r\u00eats du pays.       Cela dit, tout le monde peut se tromper et il est possible que l\u2019on ait       fait des erreurs. Mais elles ne sont nullement pr\u00e9m\u00e9dit\u00e9es. \u00bb              Pour l\u2019avenir, il d\u00e9clare que l\u2019objectif est de retenir les 35% de       Tunisiens qui regardent sa cha\u00eene. \u00ab Qu\u2019est-ce qui est mieux ? Qu\u2019on nous       regarde ou qu\u2019on aille voir Al Jazira, ses diffamations et son tissu de       mensonges ? \u00bb              Compte-t-il vendre la cha\u00eene s\u2019il trouve un bon parti ? \u00ab Pour tout l\u2019or       du monde, je ne la vendrai pas, nous r\u00e9pond-il. Je n\u2019ai pas cr\u00e9\u00e9 cette       cha\u00eene pour l\u2019argent. J\u2019ai d\u00e9j\u00e0 inject\u00e9 8 \u00e010 millions de dinars. Tant que       mon plaisir est l\u00e0, tant je continuerai. Si la pression devient forte, l\u00e0\u2026       \u00bb              Larbi Nasra ne nous d\u00e9voilera pas tout. Entre ses d\u00e9clarations, entre ses       \u201coff\u201d, entre ce qu\u2019il a gard\u00e9 pour lui, on comprendra plusieurs choses. On       comprendra que le bonhomme n\u2019est pas du style \u00e0 se laisser faire ou \u00e0 se       laisser pi\u00e9tiner. Quand on a comme lui la cinquantaine et que l\u2019on n\u2019a       plus grand-chose \u00e0 prouver, que l\u2019on se moque du \u00abqu\u2019en dira-t-on\u00bb, il       n\u2019est pas \u00e9vident de traiter avec lui.              <font><strong>(Source : \u00ab R\u00e9alit\u00e9s \u00bb (Magazine       hebdomadaire \u2013 Tunis), N\u00b0 1130 du 23 ao\u00fbt \u200f2007\u200f\u200f)<\/strong><\/font><\/div>\n<div align=\"justify\">\n<hr\/><\/div>\n<div align=\"center\">\n<h3 style=\"color: blue;\"><font size=\"3\"><strong>Grande pol\u00e9mique autour d\u2019un       concours :        <font>La paix pourra attendre \u2026<\/font><\/strong><\/font><\/h3>\n<\/div>\n<div align=\"justify\">      \u00a0<\/div>\n<div align=\"justify\"> <font>Nizar Bahloul       <\/font>       Cela ne devait \u00eatre qu\u2019un concours. Un simple concours de dessins inspir\u00e9       du tableau de Pablo Picasso \u00abLa Colombe de la Paix \u00bb pour lequel on invite       les jeunes de 15 \u00e0 18 ans d\u2019une dizaine de pays m\u00e9diterran\u00e9ens \u00e0 donner       leur vision de la paix.              Il se trouve que les noms des co-organisateurs ne plaisent pas \u00e0 tout le       monde puisqu\u2019on retrouve deux isra\u00e9liens parmi eux. Dans un mois d\u2019ao\u00fbt       synonyme de farniente et d\u2019absence d\u2019information significative, le       concours a \u00e9t\u00e9 consid\u00e9r\u00e9 par certains comme l\u2019 \u00ab affaire \u00bb de l\u2019ann\u00e9e. On       crie au scandale, on lance une p\u00e9tition, on appelle au boycott (du       concours, de ses organisateurs et de ceux qui y participent) et on       s\u2019appr\u00eate \u00e0 saisir la justice.              Le \u00ab scandale \u00bb a commenc\u00e9 d\u00e9but ao\u00fbt avec la publication dans diff\u00e9rents       organes de presse arabes et occidentaux d\u2019un communiqu\u00e9 annon\u00e7ant un       concours de dessins destin\u00e9 \u00e0 permettre aux jeunes de 15 \u00e0 18 ans de       donner leur vision de la paix d&rsquo;apr\u00e8s le c\u00e9l\u00e8bre tableau de Picasso \u00ab\u00a0La       colombe de la paix\u00a0\u00bb. Ceux qui se sont associ\u00e9s \u00e0 l\u2019organisation de ce       concours ne sont pas n\u2019importe qui. On retrouve ainsi la fondation       espagnole Picasso, le quotidien palestino-londonien Al Qods, le quotidien       \u00e9gyptien Al Ahram, ainsi que certains quotidiens maghr\u00e9bins. Tous, des       supports c\u00e9l\u00e8bres et r\u00e9put\u00e9s pour leur cr\u00e9dibilit\u00e9 et leur grand lectorat       aussi bien dans leur pays que dans le monde.              Il se trouve qu\u2019il y a parmi eux la Fondation Leo Savir pour la       M\u00e9diterran\u00e9e Vision 2020, le Centre isra\u00e9lien Per\u00e8s pour la Paix, et le       c\u00e9l\u00e8bre quotidien isra\u00e9lien Yediot Ahoronot. C\u2019est par l\u00e0 que le scandale       est arriv\u00e9 vu que certains consid\u00e8rent qu\u2019avec la participation de ces       organismes-l\u00e0, il y a une volont\u00e9 manifeste de normalisation avec Isra\u00ebl.       Peu importe que ces organismes soient reconnus pour leur volont\u00e9 de paix,       connus par leur pass\u00e9 pacifique militant, que Rabin ait d\u00e9croch\u00e9 un Nobel       de la Paix ; dans les diff\u00e9rents \u00e9crits, on ne voit que normalisation avec       celui qu\u2019on consid\u00e8re comme l\u2019ennemi num\u00e9ro un des Arabes.              \u00ab Le danger de ce projet est que ces intellectuels qui se \u201c francisent \u2019\u2019       et              s\u2019 \u201cam\u00e9ricanisent \u2019\u2019 essaient de convaincre les peuples arabes et nos       enfants d\u2019accepter ce qui ne colle nullement avec notre pass\u00e9 militant \u00bb,       \u00e9crit ce membre du bureau de l\u2019AJT.              Depuis, les articles et les communiqu\u00e9s se suivent et se ressemblent pour       d\u00e9noncer ce que l\u2019on qualifie de haute trahison \u00e0 la \u201c Cause \u2019\u2019 ! Une       p\u00e9tition est lanc\u00e9e depuis une dizaine de jours dans laquelle les       signataires protestent vigoureusement contre la participation de \u201c nos       enfants \u2019\u2019 au concours. \u00ab Des centaines de personnes l&rsquo;ont sign\u00e9e pour       manifester leur refus de cet acte de normalisation\u00bb avec Isra\u00ebl, a affirm\u00e9       \u00e0 l&rsquo;AFP Ahmed Kahlaoui, chef d&rsquo;un Comit\u00e9 national (non reconnu \u2013 NDLR) de       lutte contre la normalisation avec Isra\u00ebl.              Parmi ces signataires figurent le b\u00e2tonnier tunisien B\u00e9chir Essid, des       journalistes, des syndicalistes, des enseignants et des \u00e9crivains, qui       multiplient les d\u00e9clarations houleuses dans la presse arabe et les agences       de presse internationales.              Les r\u00e9actions, qui frisent parfois l\u2019extr\u00e9misme, sont des plus \u00e9tonnantes       dans la mesure o\u00f9 certains semblent occulter l\u2019actualit\u00e9 et la r\u00e9alit\u00e9 du       terrain.              Le sujet de la normalisation avec Isra\u00ebl est incontestablement objet de       pol\u00e9mique, mais il se trouve que la r\u00e9solution du probl\u00e8me palestinien ne       peut passer que par l\u00e0, la logique guerri\u00e8re n\u2019ayant men\u00e9 nulle part et il       est temps de trouver des solutions de paix. Or on ne peut faire la paix       qu\u2019avec ses ennemis et les Palestiniens eux-m\u00eames, \u00e0 leur t\u00eate le       Pr\u00e9sident Mahmoud Abbas, le savent.              Sur le terrain, au quotidien, les Palestiniens traitent avec les entit\u00e9s       isra\u00e9liennes et ne rejettent pas une normalisation des relations dont ils       seront les premiers b\u00e9n\u00e9ficiaires.              Les derni\u00e8res rencontres entre le Pr\u00e9sident palestinien et le Premier       ministre isra\u00e9lien, le processus d\u2019Oslo, la poign\u00e9e de mains historique       entre le leader palestinien d\u00e9funt Yasser Arafat et Ishak Rabin (et leur       Nobel commun), d\u00e9montrent parfaitement que les Palestiniens ne nient pas       l\u2019existence de l\u2019Etat d\u2019Isra\u00ebl. Ils ont accept\u00e9 une normalisation avec       l\u2019Etat h\u00e9breu, d\u00e8s lors qu\u2019il y a une paix et une possibilit\u00e9 que les deux       peuples vivent c\u00f4te \u00e0 c\u00f4te en toute qui\u00e9tude. Et cette m\u00eame r\u00e9solution a       \u00e9t\u00e9 accept\u00e9e par les pays arabes lors d\u2019un sommet de la Ligue. Le       concours, co-organis\u00e9 par l\u2019ONG isra\u00e9lienne, la fondation espagnole et les       m\u00e9dias arabes va exactement dans le sens voulu par les dirigeants       palestiniens vivants et d\u00e9funts et tous les amoureux de la paix.              Le fait m\u00eame de la participation au concours de Palestiniens reconnus       fortement pour leur patriotisme et leur loyaut\u00e9 envers leur propre              \u201c Cause \u2019\u2019, on pense notamment \u00e0 Abdelb\u00e9ri Atouane, patron d\u2019Al Qods, est       un gage que ce concours ne trompe aucunement la \u201c Cause \u2019\u2019 et que       l\u2019initiateur du projet (l\u2019ONG isra\u00e9lienne en l\u2019occurrence) ne peut \u00eatre       consid\u00e9r\u00e9 comme un ennemi.              A propos de cette ONG, il est bon peut-\u00eatre de rappeler les r\u00e9centes       initiatives qu\u2019elle a entreprises au profit des Palestiniens.              Selon des journaux cairotes, on apprend qu\u2019elle figure parmi les entit\u00e9s       les plus actives dans l\u2019organisation de manifestations \u00e9conomiques,       culturelles, sportives et sociales en direction des peuples arabes.       L\u2019objectif \u00e9tant de casser le blocage psychologique n\u00e9 avec le conflit       historique.              Le Centre Peres pour la Paix dirige ainsi un programme destin\u00e9 \u00e0 des       agriculteurs jordaniens. Gr\u00e2ce \u00e0 ce programme, ces Jordaniens b\u00e9n\u00e9ficient       des derni\u00e8res technologies en mati\u00e8re agricole, participent \u00e0 des sessions       de formation en Isra\u00ebl et \u00e9changent des informations importantes sur la       culture de leurs terres avec des agriculteurs isra\u00e9liens voisins.              Le m\u00eame centre a organis\u00e9, en ao\u00fbt dernier, une conf\u00e9rence \u00e9conomique pour       \u00e9tudier les raisons de blocage dans les \u00e9changes commerciaux entre Isra\u00ebl       et les voisins arabes et d\u00e9passer les conflits politiques. Durant cette       conf\u00e9rence, on a \u00e9tudi\u00e9 comment assurer aux Palestiniens       l\u2019approvisionnement en eau n\u00e9cessaire \u00e0 leurs cultures et comment leur       faciliter la t\u00e2che dans leur business avec Isra\u00ebl.              Ce m\u00eame centre a organis\u00e9 en novembre dernier une rencontre de football       entre une \u00e9quipe compos\u00e9e de Palestiniens et d\u2019Isra\u00e9liens d\u2019un c\u00f4t\u00e9 et la       c\u00e9l\u00e8bre \u00e9quipe de Barcelone avec toutes ses vedettes de l\u2019autre.              Autant d\u2019\u00e9l\u00e9ments qui ne sont pas du tout ignor\u00e9s par les Palestiniens et       les diff\u00e9rents participants au concours. Pour eux, il s\u2019agit tout       simplement d\u2019oeuvrer \u00e0 ce qu\u2019ils croient \u00eatre b\u00e9n\u00e9fique \u00e0 la Cause       palestinienne, dans la lign\u00e9e m\u00eame de ce qu\u2019a fait Arafat et fait       actuellement Abbas.              Peut-on donc \u00eatre plus royaliste que le roi en refusant aveugl\u00e9ment ce que       les Palestiniens mod\u00e9r\u00e9s eux-m\u00eames cherchent obstin\u00e9ment ?              Rejeter ce concours, rejeter l\u2019initiative et rejeter la volont\u00e9 de       dialoguer avec l\u2019 \u00ab ennemi \u00bb revient tout simplement \u00e0 rejeter la paix.              Il est regrettable que ce message de paix ne soit pas du tout entendu.              Apr\u00e8s les communiqu\u00e9s et la p\u00e9tition, on apprend aux derni\u00e8res nouvelles \u00e0       Tunis, que l\u2019on s\u2019appr\u00eate \u00e0 saisir la justice pour d\u00e9noncer ce concours et       ses participants. On se demande, l\u00e0, sur quelle base l\u00e9gale on va d\u00e9poser       cette plainte ! Ceux qui s\u2019appr\u00eatent \u00e0 le faire sont pourtant les m\u00eames       qui appellent \u00e0 la libert\u00e9 d\u2019expression et \u00e0 la n\u00e9cessit\u00e9 de laisser tout       un chacun s\u2019exprimer comme il l\u2019entend!              La volont\u00e9 de faire taire tout avis contraire semble h\u00e9las gagner du       terrain. La paix peut attendre, pour le moment certains ne croient qu\u2019\u00e0 la       guerre !              <font><strong>(Source : \u00ab R\u00e9alit\u00e9s \u00bb (Magazine       hebdomadaire \u2013 Tunis), N\u00b0 1130 du 23 ao\u00fbt \u200f2007\u200f\u200f)<\/strong><\/font><\/div>\n<\/p><\/div>\n<p> \u00a0<\/p>\n<\/div>\n<p><\/span><\/font><\/p>\n<hr\/>\n<p align=\"center\">\u00a0<\/p>\n<p><!-- |**|end egp html banner|**| --><\/p>\n<p align=\"center\"><b><a href=\"http:\/\/www.tunisnews.net\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><span dir=\"rtl\" lang=\"AR-SA\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/span><\/a><\/b><\/p>\n<p align=\"center\"><b><span dir=\"rtl\" lang=\"AR-SA\">\u00a0<\/span><\/b><\/p>\n<p><\/body><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Accueil &#8211; \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629 TUNISNEWS 8\u00a0\u00e8me\u00a0ann\u00e9e, N\u00b0\u00a02649 du 24.08.2007 \u00a0archives : www.tunisnews.net \u00a0 C.R.L.D.H. Tunisie: Refoulement de Ma\u00eetre Mohamed ABBOU de l\u2019a\u00e9roport de Tunis- Carthage Reporters sans fronti\u00e8res: Tunisie:Un journaliste d&rsquo;une cha\u00eene de t\u00e9l\u00e9vision priv\u00e9e agress\u00e9 par des policiers en civil Communiqu\u00e9 de la FTCR aux sans-papiers \u00e0 Lille AP: Le pr\u00e9sident tunisien pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[60,38,29],"class_list":["post-17502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-60","tag-38","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=17502"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=17502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=17502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=17502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}