{"id":17473,"date":"2011-01-07T00:00:00","date_gmt":"2011-01-07T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/7-janvier-2011\/"},"modified":"2011-01-07T00:00:00","modified_gmt":"2011-01-07T00:00:00","slug":"7-janvier-2011","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/7-janvier-2011\/","title":{"rendered":"7 janvier 2011"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\"Des sources locales affirment que des \n\t\t\t\t\t\t\t\taffrontements violents ont eu lieu aujourd'hui \u00e0 \n\t\t\t\t\t\t\t\tRegueb (Sidibouzid). La police a tir\u00e9 \u00e0 balles \n\t\t\t\t\t\t\t\tr\u00e9elles. Trois bless\u00e9s graves ont \u00e9t\u00e9 transf\u00e9r\u00e9s \n\t\t\t\t\t\t\t\t\u00e0 d'autre h\u00f4pitaux, probablement \u00e0 Sfax.\" http-equiv=\"Content-Type\"\/><\/head><body><body><\/p>\n<p align=\"center\" dir=\"ltr\"><font face=\"Arial\" size=\"2\"><b><a href=\"http:\/\/www.tunisnews.net\/\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accuei<\/span><\/a><span lang=\"FR-CH\">l<\/span><\/b><\/font><\/p>\n<div>\n<div><font face=\"Arial\" size=\"2\"><\/p>\n<div align=\"justify\">\n<div>\n<div align=\"justify\">\n<div>\n<div align=\"center\" dir=\"ltr\"><font face=\"Bookman Old Style\" size=\"7\"><strong>TUNISNEWS <\/strong><\/font><strong><font> <font face=\"Arial\">10 \u00e8me ann\u00e9e, <\/font><span lang=\"FR\"><font face=\"Arial\">N\u00b0 3881 du 07.01.2011 <\/font><\/span><\/font><\/strong><span><font face=\"Arial\"><strong>archives : <\/strong><\/font><a target=\"_blank\" rel=\"noopener\"><font face=\"Arial\"><strong>www.tunisnews.net<\/strong><\/font><\/a><\/span><span lang=\"FR\"><\/span><\/div>\n<p><font face=\"Arial\" size=\"2\"><\/p>\n<div>\n<hr\/>\n<\/div>\n<p><\/font><\/p>\n<div>\n<p><font face=\"Arial\" size=\"2\"><strong>C.R.L.D.H. Tunisie: Tirs \u00e0 balles r\u00e9elles \u00e0 Regueb &#8211; Les protestations continuent en Tunisie  <font>Libert\u00e9 et Equit\u00e9: Poursuite du mouvement de protestation et de solidarit\u00e9 &#8211; Encore des affrontements entre les lyc\u00e9ens et les forces de police <\/font>CNSPBM: Sit-in et affrontements \u00e0 Oum Larayess <font>AFP:<\/font><\/strong><\/font><\/p>\n<p><strong><\/p>\n<p><font><font><font face=\"Arial\">Tunisie: cinq manifestants bless\u00e9s dans un affrontement pr\u00e8s de Sidi Bouzid <\/font> <\/font>AFP: Tunisie: les USA, \u00ab\u00a0pr\u00e9occup\u00e9s\u00a0\u00bb par les troubles, convoquent l&rsquo;ambassadeur  <font>AFP: La France dans l&#8217;embarras face aux troubles en Tunisie et Alg\u00e9rie <\/font>Le Devoir: Pression sur la Tunisie &#8211; \u00abM. Harper, o\u00f9 \u00eates-vous?\u00bb <\/font><\/p>\n<p><font>Le D\u00e9put\u00e9 Patrick BRAOUEZEC Communiqu\u00e9 de presse &#8211; Situation en Tunisie<\/font><\/strong><\/div>\n<div><strong><\/p>\n<h2 style=\"color: red;\"><font>Reporters Without Borders : Tunisia &#8211; Wave of arrests of bloggers and activists<\/font><\/h2>\n<p><font>Mediapart: Tunisie: une journ\u00e9e de solidarit\u00e9 face \u00e0 une r\u00e9pression accrue<\/font><\/strong><\/div>\n<div>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"2\"><strong>Sit-in de solidarit\u00e9 le lundi 10 Janvier \u00e0 17h devant l\u2019Ambassade de Tunisie. \u00e0 Rabat<\/strong><\/font><\/h2>\n<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong><\/p>\n<p><font><font>Declaration\u00a0 etoile nord africaine anticapitaliste , rassemblement 6 janvier 2011 \u00e0 la Fontaine aux Innocents <\/font>Solidarit\u00e9 avec les Luttes des Habitants de Sidi Bouzid &#8211; Message \u00e0 Monsieur le Consul de Tunisie en r\u00e9sidence \u00e0 TOULOUSE  <font>ATS: Manifestation place du Molard en faveur des droits en Tunisie  <\/font>Le progres: Manifestation de soutien devant le consulat g\u00e9n\u00e9ral de Tunisie \u00e0 Lyon  <font>Nord Eclair: \u00c0 Lille, \u00ab c&rsquo;est une fiert\u00e9 de voir ce mouvement \u00bb <\/font>AFP: Troubles en Tunisie: manifestations \u00e0 Montr\u00e9al <font>AFP: Protests in Canada amid spiraling Tunisian unrest <\/font>Reuters: Un rappeur et un blogueur arr\u00eat\u00e9s en Tunisie <font>Nouvelobs: Des blogueurs tunisiens arr\u00eat\u00e9s apr\u00e8s les troubles de Sidi Bouzid <\/font>Lepost: Des Blogueurs et un rappeur arr\u00eat\u00e9s en Tunisie <font>France24: Tunis esp\u00e8re briser le mouvement de r\u00e9volte en muselant la Toile et les blogueurs <\/font>France2: Tunisie: internet au coeur de la contestation <font>Radio Canada: La r\u00e9volte s&rsquo;\u00e9tend en Tunisie <\/font>Lib\u00e9artion: Gr\u00e8ve massive des avocats en Tunisie <font>Rue89: La Tunisie gronde toujours, mais qui pour remplacer Ben Ali ? <\/font>Lemonde.fr: Manifestation de soutien aux Tunisiens \u00e0 Paris : \u00ab\u00a0Il fallait que la rage sorte\u00a0\u00bb <font>Lemonde.fr: Le ch\u00f4mage des dipl\u00f4m\u00e9s, moteur de la r\u00e9volte tunisienne <\/font>Lemonde.fr: La Tunisie, un pays qui cherche sa d\u00e9finition <font>Lib\u00e9ration: Tunisie, la col\u00e8re est dans la rue <\/font>Ei Pais: Les troubles s\u2019\u00e9tendent au Maghreb suite aux affrontements en Tunisie <font>Nord Eclair: Maghreb : un profond malaise social <\/font>Le Temps suisse: Les r\u00e9voltes tunisiennes s\u2019\u00e9tendent \u00e0 l\u2019Alg\u00e9rie <font>Le Post: Crise sociale en Tunisie : quelques cl\u00e9s pour mieux comprendre <\/font>20Minutes: R\u00e9volte en Tunisie: L&rsquo;immolation par le feu \u00abest devenu un symbole\u00bb pour les manifestants <font>Marianne: Tunisie : \u00ab Le peuple terrorise le gouvernement \u00bb  <\/font>Le Soir: Kh\u00e9ma\u00efs Chammari \u00ab Plus rien ne sera comme avant \u00bb <font>Afric.com: Entretien de Souhayr Belhassen &#8211;\u00a0 La Tunisie vers l\u2019inconnu  <\/font>Slate: Entretien de Taoufik Ben Brik \u00ab\u00a0La g\u00e9n\u00e9ration Facebook plus forte que Ben Ali\u00a0\u00bb <font>l\u2019express: Entretien de\u00a0 Bochra Belhaj Hmida &#8211; Seule la d\u00e9mocratie peut \u00ab\u00a0\u00e9pargner une d\u00e9rive islamiste\u00a0\u00bb en Tunisie <\/font>Driss Abbassi: La Tunisie, un pays qui cherche sa d\u00e9finition <font>Le Progr\u00e8s: Tunisie : \u00ab S\u2019il sait se montrer intelligent, le pouvoir peut faire baisser la pression \u00bb  <\/font>Yasmine Ryan: Tunisia&rsquo;s bitter cyberwar  <font>Soumaya Ghannoushi: Exposing the real Tunisia <\/font>Asharq Alawsat: Tunisia&rsquo;s Crisis: Searching for Islamists <font>The economist: Sour young men &#8211; Why protests, once rare, are persisting <\/font>Pedro Canales: Revuelta juvenil en T\u00fanez  <font>Pedro Canales: Ola de solidaridad con la protesta popular en T\u00fanez  <\/font>Amnesty International: Ramzi Romdhani, urgent action <\/font><\/p>\n<p><font>Luiza Toscane: Disparu depuis le 25 novembre ! Qu\u2019est-il arriv\u00e9 \u00e0 Ramzi Romdhani ?<\/font><\/strong><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\">\u0627\u0644\u0644\u062c\u0646\u0629 \u0645\u0646 \u0623\u062c\u0644 \u0627\u062d\u062a\u0631\u0627\u0645 \u0627\u0644\u062d\u0631\u064a\u0627\u062a \u0648\u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0641\u064a \u062a\u0648\u0646\u0633 <strong><font>Comit\u00e9 pour le Respect des Libert\u00e9s et des Droits de l\u2019Homme en Tunisie <\/font><\/strong>Membre du R\u00e9seau Euro-m\u00e9diterran\u00e9en des Droits de l\u2019Homme 21ter rue Voltaire \u2013 FR-75011 PARIS\u00a0 &#8211; Tel\/Fax : 00.33.(0)1.43.72.97.34 crldht@gmail.com \/ www.crldht.org   Vendredi 07 Janvier \u00a0<\/p>\n<hr\/>\n<p> \u00a0<\/font><\/div>\n<div align=\"justify\"><strong><\/p>\n<h2 style=\"color: red;\"><font>Tirs \u00e0 balles r\u00e9elles \u00e0 Regueb<\/font><\/h2>\n<p><\/strong> Des sources locales affirment que des affrontements violents ont eu lieu aujourd&rsquo;hui \u00e0 Regueb (Sidibouzid). La police a tir\u00e9 \u00e0 balles r\u00e9elles. Trois bless\u00e9s graves ont \u00e9t\u00e9 transf\u00e9r\u00e9s \u00e0 d&rsquo;autre h\u00f4pitaux, probablement \u00e0 Sfax.  Arrestation (Kidnapping) de Wissem Seghayer  Le dirigeant de l&rsquo;organisation des jeunes du PDP (parti d\u00e9mocrate progressiste) Wissem Sghayer a \u00e9t\u00e9 kidnapp\u00e9 cet apr\u00e8s-midi, par des policiers en civil devant l&rsquo;institut superieur de la musique \u00e0 Tunis &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;  <strong><\/p>\n<h2 style=\"color: red;\"><font>Les protestations continuent en Tunisie<\/font><\/h2>\n<p><\/strong> <strong><font>&#8211; Manifestation \u00e0 kasserine &#8211; Manifestation \u00e0 Jelma &#8211; Gr\u00e8ve dans les lyc\u00e9e de sidi bouzid, regueb et jelma &#8211; Gr\u00e8ve au Lycee ennfidha &#8211; Gr\u00e8ve et pr\u00e9sence polici\u00e8re important a Tela (v\u00e9hicules blind\u00e9s post\u00e9s devant les lyc\u00e9es et les principaux carrefours de la ville) &#8211; Gr\u00e8ve des lyc\u00e9es de Sfax &#8211; Manifestations \u00e0 haffouz &#8211; Gr\u00e8ve au lyc\u00e9e de jebeniana &#8211; Gr\u00e8ve de lyc\u00e9e \u00e0 Kelibia &#8211; importante pr\u00e9sence polici\u00e8re devant tout les lyc\u00e9e et toutes les universit\u00e9s en Tunisie. <\/font><\/strong> <strong>Jeudi 06 Janvier :  <\/strong> <strong><font>&#8211; Manifestations \u00e0 sidi bouzid &#8211; Manifestations \u00e0 Jelma &#8211; Manifestations \u00e0 Regueb &#8211; Manifestations \u00e0 Siliana et affrontements avec la police (Le local du RCD a \u00e9t\u00e9 brul\u00e9) &#8211; Manifestations et affrontements \u00e0 Makther (r\u00e9gion Siliana) &#8211; Confrontations entre police et habitants \u00e0 T\u00e9la (Region kasserine) &#8211; Un jeune tente de s&rsquo;immoler en plein centre ville de Tunis &#8211; Un autre jeune tente de s&rsquo;immoler \u00e0 Kasserine &#8211; Gr\u00e8ves dans les lyc\u00e9es de diff\u00e9rentes r\u00e9gions &#8211; affrontements entre police et \u00e9tudiants \u00e0 Sousse &#8211; arrestation d&rsquo;el Gen\u00e9ral (rappeur), Hamadi Kahloutcha, Azyz Ammami et slim Amamou (blogueurs)<\/font><\/strong><\/div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\">\u00a0<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div align=\"center\">Libert\u00e9 pour tous les prisonniers politiques <strong><font>Libert\u00e9 et Equit\u00e9 <\/font><\/strong>Organisation Ind\u00e9pendante de Droits de l\u2019Homme 33 rue Mokhtar Atya, 1001, Tunis Tel\/fax : 71 340 860 Liberte.equite@gmail.com Tunis, le 6 janvier 2011 <strong><\/p>\n<p><font size=\"3\">Poursuite du mouvement de protestation et de solidarit\u00e9 Encore des affrontements entre les lyc\u00e9ens et les forces de police<\/font><\/p>\n<p><\/strong><\/div>\n<div>\n<hr\/>\n<p> Le mouvement de protestation [\u2026] s\u2019\u00e9tend \u00e0 un nombre croissant de villes en d\u00e9pit du d\u00e9ploiement s\u00e9curitaire impressionnant destin\u00e9 \u00e0 r\u00e9primer tout mouvement [\u2026] La ville de Sfax a \u00e9t\u00e9 le th\u00e9\u00e2tre aujourd\u2019hui d\u2019affrontements entre les lyc\u00e9ens et les forces de police \u00e0 la cit\u00e9 Habib, quant \u00e0 la cit\u00e9 Ryadh \u00e0 Sousse, elle a vu des affrontements entre les \u00e9tudiants et la police qui a bloqu\u00e9 la facult\u00e9 et arr\u00eat\u00e9 de nombreux \u00e9tudiants. La ville de Siliana a \u00e9t\u00e9 le th\u00e9\u00e2tre dans l\u2019apr\u00e8s midi d\u2019aujourd\u2019hui d\u2019affrontements entre les citoyens et la police qui a fait usage de bombes lacrymog\u00e8nes pour disperser les manifestants. A Kasserine, une manifestation a \u00e9t\u00e9 organis\u00e9e et \u00e0 Tajerouine, il y a eu des confrontations entre les lyc\u00e9ens et les forces de police tandis que les cours n\u2019ont pas eu lieu aujourd\u2019hui \u00e0 Rgueb dans le gouvernorat de Sidi Bouzid. [\u2026] Pour le bureau ex\u00e9cutif de l\u2019Organisation Le pr\u00e9sident <font><strong>Ma\u00eetre Mohammed Nouri <\/strong><\/font><font>(traduction d\u2019extraits ni revue ni corrig\u00e9e par les auteurs de la version en arabe, LT)<\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\"> <strong><font>Comit\u00e9 National de Soutien aux Populations du Bassin Minier <\/font><\/strong><font>6 janvier 2011 <\/font><strong><font size=\"3\">Informations<\/font><\/strong><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\"><font>Nous avons su \u00e0 travers des citoyens d\u2019Oum Larayess que la ville avait \u00e9t\u00e9 le th\u00e9\u00e2tre d\u2019un mouvement de protestation qui avait pris la forme de sit-in et de tentes \u00e9rig\u00e9es sur la voie de chemin de fer et la route menant\u00a0 aux sources de production du phosphates de Gafsa, et ce, pour protester contre le ch\u00f4mage exponentiel et l\u2019absence de d\u00e9veloppement. Des affrontements ont eu lieu entre les personnes qui faisaient le sit-in (dipl\u00f4m\u00e9s, ch\u00f4meurs, militants) et les forces de l\u2019ordre. Nous avons appris \u00e9galement que des renforts s\u00e9curitaires \u00e9taient en route depuis des villes voisines aujourd\u2019hui. Le sit-in des syndicalistes lib\u00e9r\u00e9s se poursuit pour le quatri\u00e8me jour d\u2019affil\u00e9e \u00e0 l\u2019Union locale de Redeyef, pour leur droit \u00e0 r\u00e9int\u00e9grer leur emploi et la lib\u00e9ration des prisonniers du mouvement de protestation et le droit au d\u00e9veloppement r\u00e9gional.[\u2026] <\/font><strong><font>Comit\u00e9 National de Soutien aux Populations du Bassin Minier <\/font><\/strong>(traduction d\u2019extraits ni revue ni corrig\u00e9e par les auteurs de la version en arabe, LT)<\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong>Reporters Without Borders <\/strong><\/font><\/div>\n<div align=\"center\"><strong><font size=\"3\">TUNISIA \u00a0<\/font><\/strong><\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"3\">\u00a0<\/font>Wave of arrests of bloggers and activists \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> Reporters Without Borders condemned the arrests and disappearances yesterday of bloggers and online activists across a number of Tunisian cities. The worldwide press freedom organization has monitored at least five such cases but the list could well be longer. Police arrested the bloggers to question them about hacking into government websites by the militant group Anonymous, several sources told the organisation. Reporters Without Borders urged the authorities to release them as soon as possible. \u201cThese arrests, intended to intimidate Tunisian Internet-users and their international backers, are likely to prove counter-productive, by stoking up tension. Arresting several bloggers is not the way to get images of demonstrations deleted from the web or for cyber-attacks to be halted\u201d, Reporters Without Borders said. \u201cStepping up the repression is absolutely not a solution to the crisis engulfing Tunisia today\u201d. Four or five police plainclothes officers arrested the blogger and activist Hamadi Kaloutcha (http:\/\/www.facebook.com\/Kaloutcha.Hamadi) at his home at around 6am, seizing a computer and a central processing unit. They told his wife they were taking him to the nearest police station and \u201cjust have a few questions for him\u201d, and \u201cthat will only take a few hours\u201d. There has been no news of him since. Cyberdissident Sleh Edine Kchouk, a student activist, was arrested by police in Bizerte (north of Tunis) and his computer seized. Tunisian rapper El G\u00e9n\u00e9ral \u2013 real name Hamada Ben Aoun \u2013 was also reportedly arrested in Sfax, about 270kms southeast of Tunis. In his song, \u201cPresident, your people are dead\u201d, he challenged President Ben Ali over corruption and unemployment. His video is hugely popular among young Tunisians and widely circulated online. (See the video on: http:\/\/www.facebook.com\/video\/video.php?v=129701343760262&amp;oid=153793954645919&amp;comments). Further, there has been no news of Slim Amamou and Azyz Amamy, two netizens based in Tunis. Slim Amamou (http:\/\/twitter.com\/#!\/slim404) was briefly detained on 21 May 2010 just ahead of a demonstration against web censorship which he planned to hold outside the information ministry in the capital. Several human rights activists, who asked for anonymity, said he is being held at the interior ministry. Azyz Amamy apparently covered clashes a few weeks ago in Sidi Bouzid. His blog is currently inaccessible (http:\/\/azyz404.blogspot.com\/), and his Facebook page has been deactivated. These arrests come as the authorities attempt to shore up censorship of the web to try to stifle political and social protest movements which are raging in the country at the moment and to end cyber-attacks against government websites. Social networking sites have given unprecedented coverage to these events, while the traditional media, most of which are under the control of the regime, have stayed silent. See the previous release. The regime is tightening censorship of online articles on international media about the current unrest. Meanwhile, Isabelle Mandraud, a journalist with the international service of the daily Le Monde, a specialist on the Maghreb, was today refused entry to Tunisia. The daily has been banned in Tunisia since its special correspondent Florence Beaug\u00e9 was expelled in October 2009. Read the article:<a href=\"http:\/\/en.rsf.org\/tunisia-wave-of-arrests-of-bloggers-and-07-01-2011,39238.html\" target=\"_blank\" rel=\"noopener\">http:\/\/en.rsf.org\/tunisia-wave-of-arrests-of-bloggers-and-07-01-2011,39238.html<\/a> <\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\"><strong>Tunisie: cinq manifestants bless\u00e9s dans un affrontement pr\u00e8s de Sidi Bouzid<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">(\u00a9AFP \/ 07 janvier 2011 20h41)  TUNIS &#8211; Cinq manifestants et un agent de s\u00e9curit\u00e9 ont \u00e9t\u00e9 bless\u00e9s au cours d&rsquo;un affrontement violent vendredi dans une localit\u00e9 proche de Sidi Bouzid, dans le centre-ouest de la Tunisie, ont indiqu\u00e9 des proches et des t\u00e9moins. Aucune indication n&rsquo;a cependant pu \u00eatre obtenue en fin de journ\u00e9e de source gouvernementale ou s\u00e9curitaire sur ces accrochages, qui ont eu lieu \u00e0 Sa\u00efda, \u00e0 25 km de Regueb, dans la r\u00e9gion de Sidi Bouzid, principal foyer de l&rsquo;agitation que conna\u00eet la Tunisie depuis le 19 d\u00e9cembre. Des habitants et un syndicaliste t\u00e9moins ont racont\u00e9 \u00e0 l&rsquo;AFP que les forces de l&rsquo;ordre avaient ouvert le feu contre les manifestants quand ces derniers ont lanc\u00e9 une pluie de pierres sur un poste de s\u00e9curit\u00e9 et mis le feu \u00e0 un pneumatique. Ce qui devait \u00eatre une marche pacifique de lyc\u00e9ens, rejoints en cours de route par des habitants du village, a d\u00e9g\u00e9n\u00e9r\u00e9 en affrontements avec les forces de s\u00e9curit\u00e9, qui ont fait usage de lacrymog\u00e8nes, puis de leurs armes \u00e0 feu, ont-ils ajout\u00e9. Parmi les protestataires, 200 \u00e0 300 personnes, Ziyad Guesmi a \u00e9t\u00e9 atteint \u00e0 la poitrine, a indiqu\u00e9 \u00e0 l&rsquo;AFP son cousin Anis, qui l&rsquo;a transport\u00e9 \u00e0 l&rsquo;h\u00f4pital. Walid Missaoui, 25 ans, a \u00e9galement \u00e9t\u00e9 bless\u00e9 par balles, selon son fr\u00e8re Nabil, ces deux jeunes ayant \u00e9t\u00e9 ensuite transf\u00e9r\u00e9s dans un h\u00f4pital r\u00e9gional en raison de la gravit\u00e9 de leurs blessures, selon leurs proches. Un lyc\u00e9en, Mohamed Lamine Hammami, a \u00e9t\u00e9 atteint \u00e0 la jambe et \u00e0 l&rsquo;\u00e9paule, a indiqu\u00e9 un t\u00e9moin parlant \u00e0 l&rsquo;AFP sous couvert d&rsquo;anonymat depuis l&rsquo;h\u00f4pital de Regueb. En plus de ces trois bless\u00e9s identifi\u00e9s, deux autres auraient \u00e9t\u00e9 bless\u00e9s et un agent de l&rsquo;ordre hospitalis\u00e9 pour fracture, selon ce t\u00e9moin, enseignant. Des sources syndicales ont \u00e9galement fait \u00e9tat de nombreuses arrestations \u00e0 Tala dans la r\u00e9gion de kasserine, mais cette information n&rsquo;a pu \u00eatre confirm\u00e9e. Dans les lyc\u00e9es et coll\u00e8ges du pays les professeurs ont observ\u00e9 vendredi un arr\u00eat de travail de vingt minutes pour d\u00e9noncer la r\u00e9pression des manifestants et \u00ab\u00a0le traitement s\u00e9curitaire des \u00e9v\u00e8nements\u00a0\u00bb de Sidi Bouzid, a-t-on appris aupr\u00e8s du syndicat de l&rsquo;enseignement secondaire. Une source gouvernementale a admis la fermeture provisoire d&rsquo;\u00e9tablissements scolaires \u00e0 Tala, pr\u00e8s de Kasserine, dans le centre-ouest, o\u00f9 le suicide d&rsquo;un vendeur ambulant qui s&rsquo;\u00e9tait fait confisqu\u00e9 sa marchandise a d\u00e9clench\u00e9 un mouvement de protestation d&rsquo;une rare ampleur. Le pouvoir a pris des mesures pour apaiser les esprits et cr\u00e9er des emplois \u00e0 Sidi Bouzid, tout en accusant l&rsquo;opposition d&rsquo;instrumentaliser l&rsquo;agitation et les m\u00e9dias \u00e9trangers de l&rsquo;amplifier. \u00a0<\/div>\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\"><strong>Tunisie: les USA, \u00ab\u00a0pr\u00e9occup\u00e9s\u00a0\u00bb par les troubles, convoquent l&rsquo;ambassadeur<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\">AFP \/ 07 janvier 2011 19h53<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">WASHINGTON &#8211; Les Etats-Unis sont \u00ab\u00a0pr\u00e9occup\u00e9s\u00a0\u00bb par les troubles sociaux en Tunisie et ont convoqu\u00e9 l&rsquo;ambassadeur de ce pays, Mohamed Salah Tekaya, pour demander le respect des libert\u00e9s individuelles, notamment en mati\u00e8re d&rsquo;acc\u00e8s \u00e0 l&rsquo;internet, a d\u00e9clar\u00e9 vendredi un haut responsable am\u00e9ricain. \u00ab\u00a0Nous avons fait venir l&rsquo;ambassadeur de Tunisie hier et avons exprim\u00e9 notre pr\u00e9occupation \u00e0 l&rsquo;\u00e9gard de ce qui se passe avec les manifestations et avons encourag\u00e9 le gouvernement tunisien \u00e0 faire en sorte que les libert\u00e9s civiles soient garanties, notamment la libert\u00e9 de rassemblement\u00a0\u00bb, a d\u00e9clar\u00e9 ce responsable sous couvert d&rsquo;anonymat.  \u00ab\u00a0Nous avons aussi soulev\u00e9 la question de ce qui ressemble \u00e0 une ing\u00e9rence du gouvernement tunisien dans l&rsquo;internet, particuli\u00e8rement dans les comptes Facebook\u00a0\u00bb, a-t-il ajout\u00e9 devant la presse. Entre manifestations de rue, gr\u00e8ve des avocats, tentatives de suicide et arrestations d&rsquo;internautes, l&rsquo;agitation sociale partie de Sidi Bouzid (centre-ouest) il y a trois semaines s&rsquo;est poursuivie ces derniers jours en Tunisie. Deux blogueurs tr\u00e8s actifs contre la censure, Slim Amamou et El Aziz Amami, ont \u00e9t\u00e9 arr\u00eat\u00e9s jeudi, selon le journaliste d&rsquo;opposition Sofiene Chourabi, au lendemain de cyber-attaques de groupes d&rsquo;internautes solidaires du mouvement de protestation sociale. Celle d&rsquo;un troisi\u00e8me n&rsquo;a pu \u00eatre confirm\u00e9e. Ces attaques r\u00e9pondaient \u00e0 un mot d&rsquo;ordre lanc\u00e9 par les \u00ab\u00a0Anonymes\u00a0\u00bb (Anonymous) qui se pr\u00e9sentent comme un groupe d&rsquo;internautes attach\u00e9s \u00e0 la libert\u00e9 d&rsquo;expression. Le responsable am\u00e9ricain s&rsquo;est montr\u00e9 beaucoup plus prudent \u00e0 l&rsquo;\u00e9gard du voisin alg\u00e9rien, en proie aussi \u00e0 une vague d&rsquo;agitation sociale depuis le d\u00e9but de la semaine \u00e0 la suite d&rsquo;une hausse des prix alimentaires et de ce qu&rsquo;il a qualifi\u00e9 de \u00ab\u00a0p\u00e9nurie aigu\u00eb de logements, qui n&rsquo;a pas \u00e9t\u00e9 bien g\u00e9r\u00e9e par le gouvernement\u00a0\u00bb. \u00ab\u00a0Il est trop t\u00f4t pour comprendre exactement ce qui se passe\u00a0\u00bb en Alg\u00e9rie, a remarqu\u00e9 le haut responsable am\u00e9ricain. \u00ab\u00a0Nous essayons aussi de d\u00e9terminer quelles sont les choses les plus efficaces et les plus urgentes \u00e0 dire et \u00e0 faire\u00a0\u00bb. \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>La France dans l&#8217;embarras face aux troubles en Tunisie et Alg\u00e9rie<\/strong><\/font><\/h2>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div>\u00a0AFP\u00a0 07\/01\/11\u00a0|\u00a016:34<\/div>\n<div>\u00a0<\/div>\n<div>Pas d&rsquo;appel \u00e0 la lib\u00e9ration de blogueurs en Tunisie, pas ou peu de r\u00e9action face aux \u00e9meutes qui secouent l&rsquo;Alg\u00e9rie&#8230; La France, souvent prompte \u00e0 appeler \u00e0 la libert\u00e9 d&rsquo;expression dans le monde et \u00e0 la retenue lors de manifestations, est dans l&#8217;embarras avec ses voisins du sud. \u00a0<\/div>\n<div>\u00ab\u00a0Le silence des alli\u00e9s de Tunis n&rsquo;est pas sain. On laisse \u00e0 Zine El Abidine Ben Ali (pr\u00e9sident de la Tunisie) le temps de se retourner (&#8230;) On le soutient, on fera comme d&rsquo;habitude\u00a0\u00bb, d\u00e9plore Souhayr Belhassen, de nationalit\u00e9 tunisienne, pr\u00e9sidente de la F\u00e9d\u00e9ration internationale des ligues des droits de l&rsquo;Homme (FIDH) bas\u00e9e \u00e0 Paris. \u00a0<\/div>\n<div>Vendredi, le minist\u00e8re fran\u00e7ais des Affaires \u00e9trang\u00e8res s&rsquo;est retranch\u00e9 lors de son point-presse quotidien, \u00e0 propos de l&rsquo;Alg\u00e9rie, derri\u00e8re un banal: \u00ab\u00a0Nous suivons la situation avec attention\u00a0\u00bb. Rien sur la Tunisie et les blogueurs et cyber-dissidents arr\u00eat\u00e9s la veille, selon des ONG. \u00a0<\/div>\n<div>Lors d&rsquo;un colloque au minist\u00e8re fran\u00e7ais de l&rsquo;Economie, portant sur les relations entre les deux rives de la M\u00e9diterran\u00e9e, un seul intervenant, tunisien, s&rsquo;est saisi vendredi des mouvements sociaux qui touchent le Maghreb pour r\u00e9clamer \u00e0 l&rsquo;Europe une ouverture et non un repli face au Sud. \u00a0<\/div>\n<div>\u00ab\u00a0Imaginez un ou deux Mahmoud Ahmadinejad (pr\u00e9sident d&rsquo;Iran) arrivant au pouvoir en Alg\u00e9rie, en Tunisie ou au Maroc (&#8230;) C&rsquo;est entre cinq et dix millions de personnes qui quitteraient l&rsquo;Afrique du Nord, en bateaux, \u00e0 la nage, sur des radeaux, pour venir en Corse, en Sardaigne, en Sicile, sur la C\u00f4te d&rsquo;Azur\u00a0\u00bb, a mis en garde Tarak Ben Ammar, hommes d&rsquo;affaires et producteur. \u00a0<\/div>\n<div>Sans citer de pays, la ministre fran\u00e7aise des Affaires \u00e9trang\u00e8res, Mich\u00e8le Alliot-Marie, \u00e9galement pr\u00e9sente, s&rsquo;est born\u00e9e \u00e0 \u00e9voquer \u00ab\u00a0la probl\u00e9matique de l&#8217;emploi\u00a0\u00bb \u00e0 laquelle il faut trouver une solution. Selon les experts, le ch\u00f4mage qui frappe en particulier les jeunes dipl\u00f4m\u00e9s est l&rsquo;une des causes de la crise qui frappe la Tunisie et l&rsquo;Alg\u00e9rie. \u00a0<\/div>\n<div>Lors d&rsquo;un voyage en octobre \u00e0 Alger, alors qu&rsquo;elle \u00e9tait ministre de la Justice, Mme Alliot-Marie avait parl\u00e9 des relations franco-alg\u00e9riennes comme \u00e9tant \u00ab\u00a0tr\u00e8s \u00e9troites, un peu comme dans un couple\u00a0\u00bb.\u00a0 \u00a0<\/div>\n<div>La r\u00e9serve, voire le silence, affich\u00e9e par la diplomatie fran\u00e7aise tant \u00e0 l&rsquo;\u00e9gard de la Tunisie que de l&rsquo;Alg\u00e9rie, tient sans doute aux int\u00e9r\u00eats \u00e9conomiques importants entretenus dans ces pays par la France et \u00e0 la pr\u00e9sence sur le territoire fran\u00e7ais d&rsquo;importantes communaut\u00e9s maghr\u00e9bines. \u00a0<\/div>\n<div>\u00ab\u00a0Si jamais la situation empirait, la France craint un d\u00e9bordement de l&rsquo;immigration en France avec les tensions que cela comporte\u00a0\u00bb, estime \u00e0 propos de l&rsquo;Alg\u00e9rie Karim Pakzdad, de l&rsquo;Institut des relations internationales et strat\u00e9giques (Iris). \u00a0<\/div>\n<div>De son c\u00f4t\u00e9, la Tunisie a longtemps \u00e9t\u00e9 per\u00e7ue par Paris comme un \u00ab\u00a0mod\u00e8le\u00a0\u00bb dans la r\u00e9gion du Maghreb \u00ab\u00a0pour ses progr\u00e8s \u00e9conomique et social, sa ma\u00eetrise des courants migratoires, sa lutte contre le terrorisme\u00a0\u00bb, ajoute ce chercheur. \u00a0<\/div>\n<div>La retenue fran\u00e7aise vient aussi probablement des acc\u00e8s de tension survenus au cours des deux derni\u00e8res ann\u00e9es avec Tunis et Alger qui, bien qu&rsquo;aujourd&rsquo;hui r\u00e9sorb\u00e9s, ont marqu\u00e9 les esprits au Quai d&rsquo;Orsay. \u00a0<\/div>\n<div>En f\u00e9vrier 2010, l&rsquo;ex-chef de la diplomatie fran\u00e7aise Bernard Kouchner avait affirm\u00e9 que la relation bilat\u00e9rale, passionnelle depuis pr\u00e8s d&rsquo;un demi-si\u00e8cle, serait \u00ab\u00a0peut-\u00eatre plus simple\u00a0\u00bb lorsque la g\u00e9n\u00e9ration de l&rsquo;ind\u00e9pendance alg\u00e9rienne ne serait plus au pouvoir. Alger avait vivement r\u00e9agi et refus\u00e9 toute visite du ministre. \u00a0<\/div>\n<div>Avec la Tunisie, la relation s&rsquo;\u00e9tait aussi s\u00e9v\u00e8rement refroidie apr\u00e8s des critiques en novembre 2009 du m\u00eame Bernard Kouchner apr\u00e8s des arrestations de journalistes tunisiens. Il s&rsquo;\u00e9tait dit \u00ab\u00a0d\u00e9\u00e7u\u00a0\u00bb et avait qualifi\u00e9 ces d\u00e9tentions d'\u00a0\u00bbinutiles\u00a0\u00bb. Tunis avait alors d\u00e9nonc\u00e9 une \u00ab\u00a0ing\u00e9rence \u00e9trang\u00e8re inacceptable\u00a0\u00bb. \u00a0<\/p>\n<div align=\"center\">\u00a0<\/div>\n<p><strong><\/p>\n<p><font size=\"3\"><\/p>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"center\">Pression sur la Tunisie &#8211; \u00abM. Harper, o\u00f9 \u00eates-vous?\u00bb Selon la diaspora tunisienne au Qu\u00e9bec, la cl\u00e9 du changement en Tunisie passe en bonne partie par des pressions internationales<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div> M\u00e9lissa Guillemette\u00a0\u00a0 7 janvier 2011\u00a0 Actualit\u00e9s internationales  \u00a0 Une centaine de Montr\u00e9alais d\u2019origine tunisienne ont manifest\u00e9 hier contre le gouvernement de Ben Ali.  La diaspora tunisienne d&rsquo;Europe et du Qu\u00e9bec a exprim\u00e9 hier son appui aux manifestants de la Tunisie, o\u00f9 la col\u00e8re des ch\u00f4meurs et des plus d\u00e9munis agite le pays depuis trois semaines. \u00c0 Montr\u00e9al, une centaine de personnes ont demand\u00e9 au gouvernement canadien d&rsquo;effectuer des pressions sur le pr\u00e9sident Ben Ali.   La crise qui \u00e9branle le plus petit pays du Maghreb a \u00e9clat\u00e9 le 17 d\u00e9cembre \u00e0 Sidi Bouzid, une ville au centre du pays situ\u00e9e dans la province portant le m\u00eame nom. Un jeune dipl\u00f4m\u00e9 de 26 ans, Mohamed Bouazizi, a tent\u00e9 de s&rsquo;immoler par le feu pour crier son d\u00e9sarroi apr\u00e8s que la police lui eut confisqu\u00e9 son kiosque de fruits et l\u00e9gumes, faute de permis pour commercer; il est d&rsquo;ailleurs mort de ses blessures mardi. Son geste a d\u00e9clench\u00e9 tout un mouvement de protestations sociales et politiques unissant \u00e9tudiants, militants des droits de la personne, syndicalistes et ch\u00f4meurs. On parle d&rsquo;ailleurs des derni\u00e8res semaines comme de la plus grande vague de manifestations depuis que le pr\u00e9sident actuel, Zine el-Abidine ben Ali, a pris le pouvoir il y a 23 ans. Cinq personnes y ont laiss\u00e9 leur vie: deux lors de manifestations et trois suicides.  \u00c0 Montr\u00e9al, o\u00f9 plus de 5000 Tunisiens sont \u00e9tablis, la communaut\u00e9 en \u00e9tait hier \u00e0 son cinqui\u00e8me rassemblement en deux semaines. Les manifestants pr\u00e9sents estiment que la cl\u00e9 du changement en Tunisie passe en bonne partie par des pressions internationales. \u00abSi vos gouvernements parlent de nous, il peut y avoir du changement\u00bb, assure Lotfi, un homme rencontr\u00e9 devant le consulat tunisien, o\u00f9 se tenait la manifestation.  Prenant tour \u00e0 tour la parole au m\u00e9gaphone, ces Montr\u00e9alais ont questionn\u00e9 le gouvernement canadien. \u00abM. Harper, o\u00f9 \u00eates-vous?\u00bb a demand\u00e9 le porte-parole du Collectif de solidarit\u00e9 au Canada avec les luttes sociales en Tunisie, Haroun Bouazzi. \u00abApr\u00e8s combien de morts allez-vous vous prononcer sur la situation en Tunisie?\u00bb Pendant ce temps, \u00e0 Qu\u00e9bec, quelques dizaines de personnes se sont r\u00e9unies dans la rue Saint-Jean, devant les bureaux de Radio-Canada.  Hier toujours, mais de l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;oc\u00e9an, des rassemblements ont \u00e9galement \u00e9t\u00e9 organis\u00e9s en France, en Belgique, en Suisse, en Allemagne, en Grande-Bretagne, en Italie et en Alg\u00e9rie dans le cadre d&rsquo;une Journ\u00e9e de solidarit\u00e9 internationale avec Sidi Bouzid et le peuple tunisien. En France aussi on demandait au pr\u00e9sident d&rsquo;intervenir. Sur des pancartes \u00e0 Paris, on pouvait lire \u00abSarkozy, votre ami est d\u00e9savou\u00e9, Ben Ali est bien un dictateur\u00bb.   Selon des militants actifs \u00e0 Montr\u00e9al, il s&rsquo;agit d&rsquo;une mobilisation rare. \u00abJ&rsquo;organise des \u00e9v\u00e9nements \u00e0 Montr\u00e9al depuis 2000 et je n&rsquo;ai jamais vu \u00e7a\u00bb, dit le porte-parole de l&rsquo;Association des droits de la personne au Maghreb au Canada, Jamel Jani. Croit-il \u00e0 une r\u00e9volte passag\u00e8re en Tunisie ou \u00e0 une r\u00e9volution plus profonde? \u00ab\u00c7a fait trois semaines que les gens manifestent partout en Tunisie de fa\u00e7on pacifique pour demander au gouvernement de penser aux r\u00e9gions et d&rsquo;\u00e9tablir un \u00c9tat de droit.\u00bb M. Jani estime que \u00e7a ne peut que continuer.   En Tunisie, ce sont les avocats qui se sont mobilis\u00e9s hier. Pr\u00e8s de 95 % des 8000 membres de l&rsquo;Ordre national des avocats de Tunisie ont fait la gr\u00e8ve pour protester contre la r\u00e9pression polici\u00e8re des derni\u00e8res semaines, selon le b\u00e2tonnier de l&rsquo;ordre, Me Abderrazek Kilani.  Selon lui, des avocats ont \u00e9t\u00e9 violent\u00e9s par des policiers lors d&rsquo;occupations organis\u00e9es dans plusieurs villes, vendredi dernier, en soutien aux manifestations de Sidi Bouzid. \u00abLa gr\u00e8ve porte le message clair que nous n&rsquo;acceptons pas les attaques injustifi\u00e9es contre les avocats. Nous voulons protester fermement contre le passage \u00e0 tabac d&rsquo;avocats au cours des derniers jours\u00bb, a-t-il dit \u00e0 l&rsquo;agence Reuters.  \u00c0 Sidi Bouzid, la plupart des \u00e9coles et coll\u00e8ges \u00e9taient en gr\u00e8ve \u00e9galement hier. Les manifestations dans les rues se sont poursuivies \u00e9galement dans plusieurs villes du pays. La police a quant \u00e0 elle arr\u00eat\u00e9 trois blogueurs et un rappeur critiques du gouvernement actuel.  La Tunisie est connue comme un pays g\u00e9n\u00e9ralement stable. Elle a jou\u00e9 un r\u00f4le important pour l&rsquo;\u00e9mancipation des femmes et l&rsquo;\u00e9ducation au Maghreb, mais son d\u00e9veloppement \u00e9conomique des derni\u00e8res d\u00e9cennies semble se limiter aux r\u00e9gions c\u00f4ti\u00e8res, o\u00f9 le tourisme est notamment florissant. M\u00eame si le pr\u00e9sident Ben Ali a annonc\u00e9 la semaine derni\u00e8re des investissements de 124,4 millions d&rsquo;euros pour favoriser la cr\u00e9ation d&#8217;emplois et de projets, son r\u00e9gime est toujours vivement critiqu\u00e9.  \u00ab[Les Tunisiens] manifestent parce qu&rsquo;ils \u00e9touffent, ce n&rsquo;est pas une violence seulement sociale, mais une protestation contre le fonctionnement du r\u00e9gime. Le r\u00e9gime et la famille Ben Ali ont \u00e9cart\u00e9 toutes les rel\u00e8ves potentielles. Il n&rsquo;y a plus de relais du pouvoir, il y a la peur qui r\u00e8gne\u00bb, analyse le politicologue Antoine Basbous, de l&rsquo;Observatoire des pays arabes, en France.  ***  Avec Reuters et l&rsquo;AFP   <strong><\/p>\n<h3 style=\"color: blue;\"><font>(Source: \u00ab\u00a0Le Devoir\u00a0\u00bb (Quotidien &#8211; Canada) le 7 janvier 2011)<\/font><\/h3>\n<p><\/strong><\/div>\n<div><strong><font>Lien:<\/font><\/strong><a href=\"http:\/\/www.ledevoir.com\/international\/actualites-internationales\/314221\/pression-sur-la-tunisie-m-harper-ou-etes-vous\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.ledevoir.com\/international\/actualites-internationales\/314221\/pression-sur-la-tunisie-m-harper-ou-etes-vous<\/font><\/strong><\/a><\/div>\n<hr\/>\n<p> \u00a0<\/p>\n<p><\/font><\/p>\n<p><\/strong><\/div>\n<\/div>\n<div align=\"center\">L\u00b4ASSEMBL\u00c9E NATIONALE <strong><font>Patrick BRAOUEZEC <\/font><\/strong>D\u00e9put\u00e9 de la 2\u00e8&rsquo;. circonscription de la Seine-Saint-Denis Pr\u00e9sident de la Communaut\u00e9 d&rsquo;agglom\u00e9rations de Plaine Commune R\u00cbPUBLIQUI RAN\u00c7AI5[ <\/p>\n<h3 style=\"color: blue;\"><font size=\"3\"><font size=\"2\"><strong>\u00a0<\/strong><\/font><strong>Communiqu\u00e9 de presse &#8211; Situation en Tunisie<\/strong><\/font><\/h3>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> 6 ianvier 2011 Depuis plusieuts semaines des manifestations de la jeunesse tunisienne secouent la Tunisie. Mohamed Bo:uazizi, jeune ch\u00f4meut, vient de mourir apt\u00e8s s&rsquo;\u00eatte immol\u00e9 par Ie feu par d\u00e9sespoir de ne pouvoir vivte dignement dans son pays dont les performances \u00e9conomiques sont loin du &lt; miracle ) complaisamment pr\u00e9sent\u00e9 pat les m\u00e9dias. Tous les laiss\u00e9s pour compte, les exclus, les jeunes dipl\u00f4m\u00e9s mais aussi les travailleurs sont descendus dans la rue car ils ne cessent, depuis de longs mois, de protester contre des choix politiques et \u00e9conomiques qui ne tiennent nul compte des conditions dramatiques dans lesquelles vit une large part de la population tunisienne. Suite \u00e0 ces manifestations, le pouvoir tunisien rong\u00e9 par la corruption et le n\u00e9potisme n&rsquo;a trouv\u00e9 d&rsquo;autre r\u00e9ponse que la t\u00e9pression et des artestations faites la plupart du temps avec violence. Un jeune de 18 ans a ainsi \u00e9t\u00e9 tu\u00e9 par balle. Les associations et les organisations et les m\u00e9dias oeuvrant pour les dtoits de I&rsquo;homme se voient menac\u00e9es de fermeture et de privations de libert\u00e9. La France entretient des relations privil\u00e9gi\u00e9es avec le gouvernement tunisien; en 2008, de nombteux accords touchant diff\u00e9rents secteurs -financier. toutistique. ffansDorr er rourlsme- ont \u00e9t\u00e9 sign\u00e9s. Selon les normes en vigueur, un accord ne peut se concr\u00e9tiser que si les droits de l&rsquo;homme sont appliqu\u00e9s et effectifs. Or, ce n&rsquo;est plus le cas depuis un cettain temps. De nombreuses otganisations des droits de I&rsquo;Homme ont d\u00e9nonc\u00e9 cette situation o\u00f9 pr\u00e9valent des violations graves des droits humains. Des \u00e9v\u00e9nements de m\u00eame nature secouent I&rsquo;Alg\u00e9de o\u00f9 le pouvoir fait tiret sur la foule des jeunes qui s&rsquo;\u00e9puisent \u00e0 demander du travail et qui s&rsquo;insurgent contre le doublement des produits alimentaires de base. L&rsquo;image de la Ftance est tr\u00e8s atteinte pat le soutien apport\u00e9 par des dictatues qui n&rsquo;ont d&rsquo;autte atgument que la menace &lt; int\u00e9gdste ) pour justifiet les atteintes permanentes aux droits humains. Il est temps que le gouvernement fran\u00e7ais, tout comme l&rsquo;Union europ\u00e9enne, prenne ses responsabilit\u00e9s que lui dictent cettaines conventions internationales et suspende ses relations avec le gouvernement tunisien tant que les droits de i&rsquo;Homme se\u00efont ouvertement ni\u00e9s et pi\u00e9tin\u00e9s.<\/p><\/div>\n<div align=\"justify\"> <font size=\"1\">Cabinetparlementaire(H\u00f4teldevilledeSaint-Denis) :01 49336366\/Assembl\u00e9eNatronale:01 40636968\/ blog: *,rvrv.Lrarrickbraouezcc.ncr<\/font><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div>\n<div align=\"center\"><font><strong><font size=\"3\">REMDH-Tunisie<\/font><\/strong><\/font><\/div>\n<\/div>\n<div>Paris, le 7 janvier 2011   invitation presse<strong>Monsieur Thierry WICKERS <\/strong>Pr\u00e9sident du Conseil National des Barreaux  <strong>Madame Souhayr BELHASSEN  <\/strong>Pr\u00e9sidente de la FIDH  <strong>Monsieur Eric SOTTAS <\/strong>Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;OMCT  <strong>Monsieur Kamel JENDOUBI <\/strong>Pr\u00e9sident du REMDH  <strong><font>vous convient \u00e0 un point presse sur  <\/font><\/p>\n<h3 style=\"color: blue;\"><font size=\"3\">\u00ab la situation des avocats et de la soci\u00e9t\u00e9 civile en Tunisie \u00bb<\/font><\/h3>\n<p><\/strong> avec la pr\u00e9sentation de t\u00e9moignages des charg\u00e9s de mission de retour de Tunisie et l&rsquo;analyse de repr\u00e9sentants des organisations mandataires  <strong><font>le lundi 10 janvier 2011 \u00e0 11h30 au Conseil National des Barreaux 22 rue de Londres \u2013 75009 Paris  \u00a0(M\u00e9tro : St Lazare)  <\/font><\/strong>Contacts presse REMDH Paris :  Email : mse@euromedrights.net  T\u00e9l : 01 48 18 06 86<\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><font face=\"Arial\"><strong>\u00a0<font>Le Collectif de Solidarit\u00e9 <\/font><\/strong><\/font><font face=\"Arial\"><strong>avec les Luttes des Habitants de Sidi Bouzid &#8211; Tunisie<\/strong><\/font><\/div>\n<div align=\"center\"><font face=\"Arial\"><strong>Vous invite au Meeting de Solidarit\u00e9<\/strong><\/font><\/div>\n<div>\u00a0<\/div>\n<div align=\"center\">\n<h3 style=\"color: blue;\"><font face=\"Arial\"><strong>Jeudi 13 janvier 2011 \u00e0 18 heures.<\/strong><\/font><\/h3>\n<\/div>\n<div align=\"center\"><font face=\"Arial\"><strong>A la Bourse de travail, salle Croizat 3 rue du Ch\u00e2teau d&rsquo;Eau Paris 10\u00e8me<\/strong><\/font><\/div>\n<div align=\"center\"><font face=\"Arial\"><strong>M\u00e9tro R\u00e9publique <\/strong><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><font><strong>Nantes\u2026 <\/strong><\/font> <strong>HALTE A LA REPRESSION EN TUNISIE ! \u00a0  <\/strong><\/p>\n<h3 style=\"color: blue;\"><font><strong>Manifestation de solidarit\u00e9 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Samedi 8 janvier\u00a0\u00a0\u00a0\u00a0\u00a0 \u00e0\u00a0 15 heures \u00a0Place Royale \u00e0 Nantes<\/strong><\/font><\/h3>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<p><strong><i><u><span lang=\"SV\">Maroc\u2026<\/span><\/u><\/i><\/strong><\/p>\n<p>\u00a0<\/p>\n<p align=\"center\"><strong><\/p>\n<h3 style=\"color: blue;\"><font>Sit-in de solidarit\u00e9 le lundi 10 Janvier \u00e0 17h devant l\u2019Ambassade de Tunisie.<\/font><\/h3>\n<p><\/strong><\/p>\n<p align=\"center\"><strong><font>\u00e0 Rabat<\/font><\/strong><\/p>\n<p align=\"center\"><strong>APPEL DE SOLIDARITE<\/strong><\/p>\n<p align=\"center\"><strong><span lang=\"SV\">avec le peuple tunisien dans ses luttes pour la justice sociale et la d\u00e9mocratie<\/span><\/strong><\/p>\n<p align=\"center\"><strong><span lang=\"SV\"><\/span><\/strong><\/p>\n<hr\/>\n<p>\u00a0<\/p>\n<p><span lang=\"SV\">La r\u00e9volte en Tunisie s\u2019\u00e9largit sur le plan social, g\u00e9ographique et politique t\u00e9moignant d\u2019un fait irr\u00e9futable, c\u2019est qu\u2019on ne peut pas tenir un peuple sous l\u2019oppression et la marginalisation ind\u00e9finiment. Depuis le 17 d\u00e9cembre 2010, de jeunes ch\u00f4meurs, des ouvriers, des syndicats des avocats, des \u00e9tudiants\u2026, manifestent contre la chert\u00e9 de la vie, la corruption, l\u2019injustice des politiques sociales et \u00e9conomiques et remettent en cause directement la l\u00e9gitimit\u00e9 du pouvoir \u00a0qui n\u2019 a pas l\u00e9sin\u00e9 sur l\u2019emploi de la force et de la r\u00e9pression pour faire taire un peuple qui aspire \u00e0 ses droits.\u00a0<\/span><\/p>\n<p><span>Nous, organisations signataires\u00a0:<\/span><\/p>\n<p><span>\u00a7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span>Affirmons notre enti\u00e8re solidarit\u00e9 avec le mouvement de revendications et de contestation que connait la Tunisie;<\/span><\/span><\/p>\n<p><span>\u00a7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span>D\u00e9non\u00e7ons l&rsquo;usage de la violence et les recours \u00e0 la r\u00e9pression et \u00e0 l\u2019intimidation \u00a0par le pouvoir tunisien contre des populations qui manifestent de mani\u00e8re pacifique contre l\u2019injustice sociale\u00a0 et pour l\u2019emploi.<\/span><\/span><\/p>\n<p><span>\u00a7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span>Appelons \u00e0 la lib\u00e9ration imm\u00e9diate de toutes les personnes arr\u00eat\u00e9es, ainsi que toutes et tous ceux qui ont \u00e9t\u00e9 arr\u00eat\u00e9es et condamn\u00e9es lors des \u00e9v\u00e8nements du bassin minier de Gafsa.<\/span><\/span><\/p>\n<p><span>\u00a7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span>R\u00e9clamons que les responsables de la r\u00e9pression, des violences \u00e0 l&rsquo;encontre de la population qui ont caus\u00e9 la mort et des blessures graves parmi les manifestants soient traduits en justice.<\/span><\/span><\/p>\n<p><span>\u00a7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span>D\u00e9non\u00e7ons les agressions qui visent\u00a0les syndicalistes, les avocats, les m\u00e9dia ind\u00e9pendants, les associations et partis solidaires de la r\u00e9volte tunisienne.<\/span><\/span><\/p>\n<p><span>Nous appelons tous les d\u00e9mocrates et les \u00e9pris de justice\u00a0\u00e0 manifester leur solidarit\u00e9 avec le peuple tunisien dans ses luttes pour la justice sociale et la d\u00e9mocratie en <\/span><\/p>\n<p align=\"center\"><strong>participant au sit-in de solidarit\u00e9 le lundi 10 Janvier \u00e0 17h devant l\u2019Ambassade de Tunisie.<\/strong><\/p>\n<p align=\"center\"><strong>A Rabat<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>SIGNATAIRES\u00a0:<\/strong><\/p>\n<p><strong>Action Jeunesse(AJ)<\/strong><\/p>\n<p><strong>Association Beniznassen pour la Culture, le D\u00e9veloppement et la Solidarit\u00e9<\/strong><\/p>\n<p><strong>Association Chouala pour l\u2019Education et la Culture<\/strong><\/p>\n<p><strong>Association Eau et Energie pour Tous(ASEET)<\/strong><\/p>\n<p><strong>Association Femmes pour l\u2019Egalit\u00e9 et la D\u00e9mocratie (AFED)<\/strong><\/p>\n<p><strong>Association Marocaine des Droits Humains(AMDH)<\/strong><\/p>\n<p><strong>Association pour le Contrat Mondial de l\u2019Eau\/ Maroc (ACME\/Maroc)<\/strong><\/p>\n<p><strong>Association Troisi\u00e8me Mill\u00e9naire pour le D\u00e9veloppement et l\u2019Action Associatif<\/strong><\/p>\n<p><strong>Attac\/Cadtm Maroc<\/strong><\/p>\n<p><strong>Espace des Jeunes Animateurs Marrakech<\/strong><\/p>\n<p><strong>F\u00e9d\u00e9ration de la Ligue D\u00e9mocratique des Droits de la Femme(FLDDF)<\/strong><\/p>\n<p><strong>F\u00e9d\u00e9ration D\u00e9mocratique Du Travail(FDT)<\/strong><\/p>\n<p><strong>Forum Beni Zouli pour le D\u00e9veloppement et la Communication<\/strong><\/p>\n<p><strong>Forum des Alternatives Maroc(FMAS)<\/strong><\/p>\n<p><strong>Forum pour le Droit \u00e0 l\u2019eau dans la r\u00e9gion Arabe<\/strong><\/p>\n<p><strong>Groupe Antiraciste de d\u00e9fense et d\u2019accompagnement des \u00e9trangers et migrants(GADEM)<\/strong><\/p>\n<p><strong>Instance National de Protection des Biens Publics<\/strong><\/p>\n<p><strong>Instance National de Protection des Biens Publics au Maroc(INPBPM)<\/strong><\/p>\n<p><strong>Association La vall\u00e9e verte<\/strong><\/p>\n<p><strong>Mouvement Alternatives Citoyenne(ALCI)<\/strong><\/p>\n<p><strong>Observatoire Marocain des Libert\u00e9s Publiques(OMLP)<\/strong><\/p>\n<p><strong>Observatoire Marocain des Prisons (OMP)<\/strong><\/p>\n<p><strong>Organisation D\u00e9mocratique Du Travail(ODT)<\/strong><\/p>\n<p><strong>Organisation pour les libert\u00e9s d\u2019information et d\u2019expression(OLE)<\/strong><\/p>\n<p><strong>R\u00e9seau Amazigh pour la Citoyennet\u00e9(Azetta)<\/strong><\/p>\n<p><strong>R\u00e9seau des Associations de D\u00e9veloppement des Oasis du Sud Est du Maroc<\/strong><\/p>\n<p><strong>R\u00e9seau des Associations de Quartier du Grand Casablanca(RESAQ)<\/strong><\/p>\n<p><strong>R\u00e9seau Marocain Euromed des ONG<\/strong><\/p>\n<p><strong>Union des Initiatives de D\u00e9veloppement<\/strong><\/p>\n<p><strong>Union G\u00e9n\u00e9ral des Travailleurs du Maroc(UGTM)<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>FMAS<\/strong>, \u00a0<\/p>\n<p><strong>53 rue Melouiya, Appt.16, 4<sup>e<\/sup> \u00e9tage, Agdal, Rabat<\/strong><\/p>\n<p><strong>\u00a0T\u00e9l.\u00a0: 0537 68 39 26\/62,\u00a0 Fax\u00a0: 0537 77 07 22, Mobile 06 64 38 81 31<\/strong><\/p>\n<p><strong>\u00a0 <\/strong><a href=\"mailto:fmas@menara.ma\"><span><strong>fmas@menara.ma<\/strong><\/span><\/a><strong>\u00a0<\/strong><a href=\"http:\/\/www.forumalternatives.org\/\" target=\"_blank\" rel=\"noopener\"><span><strong>http:\/\/www.forumalternatives.org<\/strong><\/span><\/a><strong><\/strong><\/p>\n<\/div>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><b><span lang=\"FR\"><font size=\"2\">\u00a0<\/font>Tunisie: une journ\u00e9e de solidarit\u00e9 face \u00e0 une r\u00e9pression accrue<\/span><\/b><span lang=\"FR\"><\/span><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<p><span lang=\"FR\">Paris, Marseille, Nantes, Alger, Naples, Montr\u00e9al&#8230; Partie des jeunes dipl\u00f4m\u00e9s de Sidi Bouzid \u2013 une ville du centre-ouest tunisien, situ\u00e9e \u00e0 265 km de Tunis et en proie \u00e0 des manifestations depuis le 19 d\u00e9cembre\u2013, la r\u00e9volte s&rsquo;\u00e9tend peu \u00e0 peu aux communaut\u00e9s implant\u00e9es dans les villes europ\u00e9ennes et nord-am\u00e9ricaines. Pour les Tunisiens de l&rsquo;\u00e9tranger, ce 6 janvier est une journ\u00e9e internationale qui doit aider le mouvement et lui donner une ampleur suffisante pour lui permettre de s&rsquo;enraciner en dehors des bassins traditionnels de luttes du sud du pays, et notamment dans la capitale Tunis. \u00c0 Paris, rendez-vous est donn\u00e9 \u00e0 18h, Fontaine des Innocents, place du Ch\u00e2telet.<\/span><\/p>\n<p><span lang=\"FR\">En France, le fait nouveau est la participation au collectif parisien de militants du parti islamiste Nahda (Renaissance), dont le bureau politique demeure exil\u00e9 \u00e0 Paris depuis le d\u00e9but des ann\u00e9es 1990. Cette union inhabituelle vient \u00e0 point car, sur place, le mouvement marque un peu le pas en ce milieu de semaine, sous le double coup de la r\u00e9pression et des promesses du gouvernement.<\/span><\/p>\n<p><span lang=\"FR\">Mercredi 5 janvier, 5 000 personnes ont tout de m\u00eame march\u00e9 jusqu&rsquo;au cimeti\u00e8re de Garaat Bennour, situ\u00e9 \u00e0 16 km de Sidi Bouzid, pour comm\u00e9morer la mort du jeune Mohammed Bouazizi, qui s&rsquo;\u00e9tait immol\u00e9 par le feu mi-d\u00e9cembre devant la municipalit\u00e9 pour attirer l&rsquo;attention sur la d\u00e9tresse des dipl\u00f4m\u00e9s-ch\u00f4meurs tunisiens. Rappelons-le\u00a0: la Tunisie, c&rsquo;est aujourd&rsquo;hui ce pays vant\u00e9 comme<span>\u00a0<\/span><i><span>\u00abun mod\u00e8le de d\u00e9veloppement\u00bb<\/span><\/i><span>\u00a0<\/span>par le patron du FMI, Dominique Strauss-Kahn, mais o\u00f9 les ch\u00f4meurs repr\u00e9sentaient quelque 55% des dipl\u00f4m\u00e9s de l&rsquo;universit\u00e9 en 2008, selon l&rsquo;\u00e9conomiste Lahcen Achy. Ce chercheur au centre Carnegie pour le Moyen-Orient a publi\u00e9 en novembre 2010 une<span>\u00a0<\/span><a href=\"http:\/\/carnegie-mec.org\/publications\/?fa=show&amp;id=42103\" target=\"_blank\" rel=\"noopener\"><b><span>\u00e9tude<\/span><\/b><\/a><span>\u00a0<\/span>sur<span>\u00a0<\/span><i><span>\u00ables d\u00e9fis de l&#8217;emploi au Maghreb\u00bb.\u00a0<\/span><\/i><\/span><\/p>\n<p><span lang=\"FR\">Mercredi, selon un syndicaliste de Sidi Bouzid joint par l&rsquo;AFP, la foule a aussi cri\u00e9 sa col\u00e8re contre le co\u00fbt de la vie<span>\u00a0<\/span><i><span>\u00abqui a conduit Mohamed au suicide\u00bb<\/span><\/i>, r\u00e9p\u00e9tant<span>\u00a0<\/span><i><span>\u00abHonte au gouvernement!\u00bb<\/span><\/i>. Selon l&rsquo;oncle de la victime, Mehdi Horaire, la police massivement pr\u00e9sente a emp\u00each\u00e9 le cort\u00e8ge de s&rsquo;approcher du si\u00e8ge de la pr\u00e9fecture, l\u00e0 o\u00f9 Mohamed s&rsquo;\u00e9tait asperg\u00e9 d&rsquo;essence. Cinq jours plus tard, le jeune Houcine Neji se jetait d&rsquo;un pyl\u00f4ne \u00e9lectrique sur une ligne haute tension en criant<span>\u00a0<\/span><i><span>\u00abplus de mis\u00e8re, plus de ch\u00f4mage.\u00bb<\/span><\/i><span>\u00a0<\/span>D&rsquo;autres habitants ont tent\u00e9 de suivre cet \u00abexemple\u00bb&#8230; Mercredi encore, une femme et ses trois enfants ont grimp\u00e9 sur un pyl\u00f4ne \u00e9lectrique, en mena\u00e7ant de se donner la mort pour obtenir un emploi et un logement, avant que les autorit\u00e9s ne d\u00e9cident de couper le courant.<\/span><\/p>\n<p><span lang=\"FR\">\u00c0 Tunis et dans plusieurs villes du pays, la mobilisation \u00e9tait moindre ce mercredi.<span>\u00a0<\/span><i><span>\u00abLe r\u00e9gime joue le m\u00eame jeu que d&rsquo;habitude, la carotte et le b\u00e2ton\u00bb<\/span><\/i>,<span><i><span>\u00a0<\/span><\/i><\/span>dit Adel Ghezala, militant<span>\u00a0<\/span><i><span>\u00abde gauche mais non-encart\u00e9\u00bb<\/span><\/i>, qui vit depuis quatre ans entre Paris et Tunis. En 2008 et 2009, il s&rsquo;est impliqu\u00e9 en Tunisie dans les mouvements de solidarit\u00e9 aux gr\u00e9vistes du bassin minier de Gafsa, puis pour la lib\u00e9ration du journaliste Taoufik Ben Brik. Il d\u00e9crit la situation actuelle comme<span>\u00a0<\/span><i><span>\u00abun entre-deux: c&rsquo;est parti tr\u00e8s fort en d\u00e9cembre, et la presse internationale a mis du temps \u00e0 prendre la mesure de l&rsquo;\u00e9v\u00e9nement. Les amis sur place nous d\u00e9crivent maintenant une situation tr\u00e8s tendue, beaucoup h\u00e9sitent \u00e0 sortir, c&rsquo;est devenu compliqu\u00e9 de manifester, notamment \u00e0 Tunis\u00bb.<\/span><\/i><\/span><\/p>\n<p><span lang=\"FR\">La \u00ab<i><span>carotte<\/span><\/i>\u00bb pr\u00e9sent\u00e9e aux r\u00e9volt\u00e9s de Sidi Bouzid, outre le remplacement de deux ministres&#8230; par des proches du pr\u00e9sident Ben Ali, est faite de nombreuses promesses de relance de l&rsquo;industrie cens\u00e9e embaucher \u00e0 tour de bras dans l&rsquo;ann\u00e9e 2011, de versements d&rsquo;allocations et de la cr\u00e9ation d&rsquo;un<i><span>\u00abp\u00f4le emploi\u00bb<\/span><\/i><span>\u00a0<\/span>digne de ce nom. Est aussi annonc\u00e9e la construction de stades pour redynamiser une r\u00e9gion laiss\u00e9e \u00e0 l&rsquo;abandon.<\/span><\/p>\n<p><span lang=\"FR\">Le b\u00e2ton, Ben Ali avait pr\u00e9venu qu&rsquo;il le manierait sans m\u00e9nagement. Lors de son discours t\u00e9l\u00e9vis\u00e9 du 28 d\u00e9cembre, le pr\u00e9sident tunisien avait promis de<i><span>\u00abfrapper fort\u00bb<\/span><\/i><span>\u00a0<\/span>contre les<span>\u00a0<\/span><i><span>\u00abextr\u00e9mistes\u00bb<span>\u00a0<\/span><\/span><\/i>qui animaient le mouvement. Depuis la gr\u00e8ve g\u00e9n\u00e9rale de Gafsa en 2008-2009 et la mort d&rsquo;un jeune manifestant tu\u00e9 par l&rsquo;arm\u00e9e dans la ville de Redeyef, on sait en Tunisie ce que \u00abfrapper fort\u00bb veut dire. Le 24 d\u00e9cembre, la police a de nouveau fait feu sur la foule, tuant Mohammed Ammari, 18 ans, et blessant gri\u00e8vement Chawki Hidri, qui d\u00e9c\u00e9dera deux jours plus tard.<\/span><\/p>\n<p><span lang=\"FR\">En Tunisie, la r\u00e9pression continue donc d&rsquo;\u00eatre aussi f\u00e9roce qu&rsquo;efficace, les effectifs des policiers \u00e9tant \u00e9valu\u00e9s \u00e0 80.000 personnes, pour 10,2 millions d&rsquo;habitants.<span>\u00a0<\/span><i><span>\u00abIl est clair qu&rsquo;\u00e0 l&rsquo;heure actuelle comme depuis environ quinze ans, on r\u00e9prime davantage au quotidien en Tunisie qu&rsquo;en Syrie, pour prendre l&rsquo;exemple d&rsquo;un pays au ban de la communaut\u00e9 internationale\u00bb<\/span><\/i>, explique un doctorant de Sciences-po sp\u00e9cialis\u00e9 dans l&rsquo;\u00e9tude comparative des syst\u00e8mes politiques des deux pays et contraint de conserver l&rsquo;anonymat<\/span><\/p>\n<p><span lang=\"FR\"><strong><font>(Source: \u00ab\u00a0Mediapart\u00a0\u00bb le 6 janvier 2011)<\/font><\/strong><\/span><\/p>\n<p><font size=\"2\"><strong><font>Lien: <\/font><\/strong><a href=\"http:\/\/www.mediapart.fr\/journal\/international\/060111\/tunisie-une-journee-de-solidarite-face-une-repression-accrue\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.mediapart.fr\/journal\/international\/060111\/tunisie-une-journee-de-solidarite-face-une-repression-accrue<\/font><\/strong><\/a><\/font><\/p>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<p><font size=\"3\">DECLARATION\u00a0 ETOILE NORD AFRICAINE ANTICAPITALISTE\u00a0 RASSEMBLEMENT 6 JANVIER 2011 \u00e0 la Fontaine aux Innocents<\/font><\/p>\n<p><\/strong><\/div>\n<div align=\"justify\">\n<hr\/>\n<p>  Il existe une v\u00e9ritable lame de fond d&rsquo;un raz le bol g\u00e9n\u00e9ralis\u00e9 \u00e0 l&rsquo;ensemble de la rive sud de la M\u00e9diterran\u00e9e. Apr\u00e8s une ann\u00e9e marqu\u00e9e par des mobilisations sur la rive Nord de cette m\u00eame mer, en Gr\u00e8ce, en France, en Espagne et au Portugal, voici la rel\u00e8ve du Sud.  L\u2019Afrique du Nord est en train de vivre une synchronisation des luttes qui n\u2019a qu\u2019un seul pr\u00e9c\u00e9dant : la lutte anticoloniale. Ce qui se passe actuellement en Tunisie et commence \u00e0 se manifester dans l\u2019Alg\u00e9rie voisine apr\u00e8s un d\u00e9tour par l\u2019Egypte n\u2019est qu\u2019une m\u00eame et profonde lame de fond d\u2019une contestation sociale et politique dont le facteur d\u00e9clenchant est la crise \u00e9conomique qui frappe le syst\u00e8me capitaliste mondial. Le r\u00eave des nouvelles classes dominantes nord africaines de \u00ab tondre \u00bb les classes populaires (travailleurs, paysans, artisans, mais aussi jeunes pr\u00e9caires avec ou sans dipl\u00f4mes) dans une \u00ab transe \u00bb d\u2019un\u00a0 pur capitalisme sans foi, sans lois et sans aucunes r\u00e8gles autre que celle d\u2019engloutir pour leur seul profit toutes les richesses produites par ces m\u00eames classes populaires tourne au cauchemar.  Pressuris\u00e9es, exploit\u00e9es, renvoy\u00e9es \u00e0 un statut dont l\u2019inhumanit\u00e9 fait que l\u2019on pr\u00e9f\u00e8re aujourd\u2019hui en finir \u00ab en s\u2019immolant par le feu \u00bb, comme ce fut le cas du jeune Bouazizi en Tunisie, que de continuer \u00e0 subir ce que plus personne ne veut endurer. Le capitalisme est dans la tourmente \u00e0 l\u2019\u00e9chelle de la plan\u00e8te enti\u00e8re, sa crise s\u2019approfondissant parce que li\u00e9e au fondement m\u00eame de son fonctionnement. Comment peut-on continuer \u00e0 consid\u00e9rer les producteurs de richesses comme de simples \u00ab variables d\u2019ajustement \u00bb ? Comment peut-on continuer \u00e0 parler de \u00ab co\u00fbt \u00bb du travail ? Comment peut-on continuer \u00e0 vouloir \u00ab produire \u00bb toujours plus et au moindre \u00ab co\u00fbt \u00bb du monde du travail et en m\u00eame temps chercher \u00e0 \u00ab vendre \u00bb \u00e0 ces m\u00eames \u00ab consommateurs \u00bb de ce m\u00eame monde du travail, d\u00e9sargent\u00e9s, pr\u00e9caris\u00e9s, paup\u00e9ris\u00e9s, les marchandises produites ? Il y a l\u00e0 une contradiction que le syst\u00e8me capitaliste ne sait r\u00e9soudre qu\u2019en cherchant \u00e0 faire payer, toujours plus, aux seules classes populaires, la facture de son disfonctionnement. C\u2019est que les classes dirigeantes nord africaines ont laiss\u00e9 beaucoup de plumes dans le grand cirque de la finance mondialis\u00e9e. Les \u00ab 7 familles \u00bb tunisiennes qui avaient pens\u00e9 mettre \u00ab leur magot \u00bb, vol\u00e9, \u00e0 l\u2019abri dans les places boursi\u00e8res du Golfe, Duba\u00ef en t\u00eate, attiraient qu\u2019elles \u00e9taient par le mirage des sables de la p\u00e9ninsule arabique, se sont r\u00e9veill\u00e9es \u00e9tourdis par les pertes abyssales subies \u00e0 la suite du tsunami financier qui a touch\u00e9 le centre des Etats Unis avant de se propager \u00e0 l\u2019ensemble de la plan\u00e8te. La bourse de Duba\u00ef a perdu pr\u00e9s de 70% de sa valeur, et le \u00ab petit dragon\u00a0 arabe \u00bb a pris l\u2019allure d\u2019un parc de Disney, qui ne conna\u00eetra jamais le jour de l\u2019ouverture tant de fois repouss\u00e9e. On peut en dire autant des \u00ab nouvelles classes de riches \u00bb alg\u00e9rienne, marocaine, \u00e9gyptienne qui ont mordu la poussi\u00e8re durant les deux ann\u00e9es qui viennent de s\u2019\u00e9couler.  Les m\u00eames \u00ab familles \u00bb, sur la foi du mim\u00e9tisme propres \u00ab aux nouveaux riches \u00bb dont la premi\u00e8re g\u00e9n\u00e9ration essuie les pl\u00e2tres, a remis une partie de leur pactole entre les mains de ce \u00ab magicien \u00bb de Madoff qui a fait beaucoup de \u00ab miracles \u00bb avec sa pyramide de Ponzy. (Grande martingale invent\u00e9e par un italien, Ponzy, aux Etats Unis, qui consistait \u00e0 bien r\u00e9mun\u00e9rer les actionnaires avec leurs propres deniers, jusqu\u2019\u00e0 ce que la pyramide s\u2019effondre par manque de gogos). Ce sont les pertes colossales dans le casino financier qui expliquent, en partie, que les \u00ab m\u00eames familles \u00bb ont \u00e9t\u00e9 oblig\u00e9s de rapatrier leurs capitaux, ou ce qu\u2019il en reste pour les faire fructifier dans leur pays \u00e0 l\u2019abri du corset policier que les dictatures ont impos\u00e9 aux soci\u00e9t\u00e9s nord africaines. C\u2019est l\u00e0 o\u00f9 le cauchemar de ces familles se transforme en hallucination. Le \u00ab peuple \u00bb est m\u00e9connaissable. Non seulement, le corset policier ne l\u2019emp\u00eache plus de crier haut et fort sa r\u00e9volte contre sa condition d\u2019esclave mais de surcroit il pointe du doigt les responsables de son \u00e9tat : \u00ab Les familles r\u00e9gnantes \u00bb et r\u00e9clame leur t\u00eate.  Pour nous contacter : etoilenordafricaineantikap@gmail.fr\u00a0\u00a0\u00a0\u00a0 <\/p>\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\"><strong><\/p>\n<h3 style=\"color: blue;\"><font size=\"3\">Manifestation place du Molard en faveur des droits en Tunisie<\/font><\/h3>\n<p><\/strong><\/div>\n<div align=\"center\"><strong><font size=\"3\"><\/p>\n<hr\/>\n<p> \u00a0<\/font><\/strong><\/div>\n<div align=\"justify\">ATS | 06.01.2011 | 18:50  La situation en Tunisie a des r\u00e9percussions en Suisse. Une manifestation contre le gouvermenent tunisien a eu lieu jeudi en fin de journ\u00e9e \u00e0 Gen\u00e8ve sur la place du Molard, a indiqu\u00e9 la police sans autres d\u00e9tails. A Lausanne, une dizaine de militants de Solidarit\u00e9s ont occup\u00e9 pacifiquement jeudi les locaux abritant le consulat honoraire de Tunisie pour protester contre la r\u00e9pression exerc\u00e9e par le r\u00e9gime du pr\u00e9sident Ben Ali. Ils ont demand\u00e9 au consul de d\u00e9missionner pour marquer son d\u00e9saccord avec ce r\u00e9gime, demande d\u00e9clin\u00e9e par l\u2019int\u00e9ress\u00e9. Troubles sociaux Des gr\u00e8ves, des manifestations de rue et des tentatives de suicide ont \u00e9t\u00e9 observ\u00e9es jeudi dans des localit\u00e9s du centre, du sud et de l\u2019ouest de la Tunisie, a-t-on appris de sources syndicales locales. Le pays est le th\u00e9\u00e2tre de troubles sociaux sur fond de ch\u00f4mage depuis le 19 d\u00e9cembre.  A Sidi Bouzid (265 km au sud de Tunis), la plupart des lyc\u00e9es et coll\u00e8ges \u00e9taient en gr\u00e8ve mais aucun incident violent n\u2019a \u00e9t\u00e9 enregistr\u00e9 dans cette ville endeuill\u00e9e au lendemain de l\u2019enterrement de Mohamed Bouaziz, a indiqu\u00e9 Ali Zari, responsable syndical local. Mohamed Bouazizi, 26 ans, s\u2019\u00e9tait immol\u00e9 devant les locaux du gouvernerat (pr\u00e9fecture) le 18 d\u00e9cembre pour protester contre la saisie de son \u00e9tal de primeurs par des agents municipaux. Il est devenu depuis le symbole de la contestation contre le ch\u00f4mage et la pr\u00e9carit\u00e9 sociale. Avant de passer \u00e0 l\u2019acte, il avait cherch\u00e9 en vain \u00e0 plaider sa cause devant le gouverneur de la r\u00e9gion, limog\u00e9 par la suite. Une femme et ses trois enfants, qui avaient menac\u00e9 mercredi soir de se suicider collectivement pour exiger du travail et un logement, ont \u00e9t\u00e9 re\u00e7us par le nouveau gouverneur, a ajout\u00e9 M. Zari. Manifestation dispers\u00e9e  Plus au sud, \u00e0 Jbeniana, une localit\u00e9 rurale de Sfax (300 km de Tunis), la police a dispers\u00e9 une manifestation de lyc\u00e9ens, alors qu\u2019un suicide et des tentatives de suicide \u00e9taient rapport\u00e9s par de sources syndicales. A Regueb, pr\u00e8s de Sfax, Hamed Slimi, 26 ans, un ch\u00f4meur a menac\u00e9 de se suicider par \u00e9lectrocution du haut d\u2019un pyl\u00f4ne \u00e9lectrique pour d\u00e9noncer la corruption et l\u2019in\u00e9galit\u00e9 face \u00e0 l\u2019emploi, avant de se faire promettre du travail par les autorit\u00e9s locales, a rapport\u00e9 Kamel laabidi. Un ch\u00f4meur s\u2019immole, un ouvrier se pend  A Metlaoui, zone mini\u00e8re th\u00e9\u00e2tre de troubles sociaux en 2008, un jeune ch\u00f4meur, Mosbah Al Jawhari, s\u2019est immol\u00e9 et a \u00e9t\u00e9 transf\u00e9r\u00e9 dans l\u2019h\u00f4pital de Tunis, a indiqu\u00e9 un habitant sous couvert d\u2019anonymat. Enfin, \u00e0 Chebba, une localit\u00e9 du centre-est, Mohamed Slimane, 52 ans, un ouvrier du b\u00e2timent, p\u00e8re de quatre enfants dont deux dipl\u00f4m\u00e9s de l\u2019universit\u00e9 sans emploi, a \u00e9t\u00e9 retrouv\u00e9 pendu mardi dernier, a indiqu\u00e9 un t\u00e9moin. Selon Nizar Belhassine, l\u2019homme atteint d\u2019insuffisance r\u00e9nale avait d\u00e9sesp\u00e9r\u00e9 de recevoir une aide pour se soigner et nourrir sa famille.<\/div>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<p align=\"center\"><b><span lang=\"FR\"><font size=\"3\">Message \u00e0 Monsieur le Consul de Tunisie en r\u00e9sidence \u00e0 TOULOUSE\u00a0:<\/font><\/span><\/b><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Le jeudi 6 janvier 2011, les Toulousains venus \u00e0 titre personnel ou r\u00e9pondant \u00e0 l\u2019invitation des organismes signataires de l\u2019appel ci-dessous veulent exprimer leur \u00e9motion \u00e0 l\u2019annonce de la mort de Mohamed Bouazizi et devant la situation qui a conduit ce jeune universitaire sans emploi \u00e0 ce geste de d\u00e9sespoir.<\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Ils expriment leur solidarit\u00e9 pour tous les Tunisiens que le manque de ressources, le manque de travail, le manque de perspective d\u2019un avenir meilleur a jet\u00e9s dans les rues des villes tunisiennes malgr\u00e9 la r\u00e9pression pr\u00e9visible des forces de police.<\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Ils expriment, en venant se rassembler de mani\u00e8re pacifique devant le Consulat de Tunisie de Toulouse, leur espoir que tous les Tunisiens puissent trouver chez eux l\u2019emploi correspondant \u00e0 leur comp\u00e9tence universitaire ou professionnelle de mani\u00e8re \u00e0 vivre librement dans leur pays dans la paix, la s\u00e9r\u00e9nit\u00e9 et la dignit\u00e9.<\/span><\/p>\n<p align=\"center\">\u00a0<\/p>\n<p align=\"center\">\u00a0<\/p>\n<p align=\"center\"><b><span lang=\"FR\">JOURN\u00c9E INTERNATIONALE de SOLIDARIT\u00c9<\/span><\/b><\/p>\n<p align=\"center\"><b><span lang=\"FR\">avec SIDI BOUZID et le PEUPLE TUNISIEN<\/span><\/b><\/p>\n<p align=\"center\"><b><span lang=\"FR\">6 JANVIER 2011<\/span><\/b><\/p>\n<p align=\"center\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Comme Paris, Nantes, Lyon, Marseille, Montpellier, Strasbourg, Lille, \u2026en France et Alger, Rabat, Nouakchott, Beyrouth, Bruxelles, Gen\u00e8ve, Berlin, Naples, Londres, Montr\u00e9al,\u00a0&#8230; dans le monde,\u00a0 TOULOUSE s\u2019associe, ce 6 janvier 2011,\u00a0 \u00e0 la journ\u00e9e internationale de solidarit\u00e9 avec le peuple tunisien qui lutte pour obtenir le respect des droits fondamentaux\u00a0: le travail, la dignit\u00e9,\u00a0 la libert\u00e9,\u00a0 la d\u00e9mocratie.<\/span><\/p>\n<p align=\"center\"><b><span lang=\"FR\">Les Toulousains sont appel\u00e9s \u00e0 se r\u00e9unir <\/span><\/b><\/p>\n<p align=\"center\"><b><span lang=\"FR\">ce jeudi 6 janvier \u00e0 18h<\/span><\/b><\/p>\n<p align=\"center\"><b><span lang=\"FR\">devant le Consulat de Tunisie, 19 all\u00e9es Jean Jaur\u00e8s .<\/span><\/b><\/p>\n<p align=\"center\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Un hommage sera rendu au jeune ch\u00f4meur, Mohamed Bouazizi, d\u00e9c\u00e9d\u00e9 le 4 janvier \u00e0 l\u2019h\u00f4pital des grands br\u00fbl\u00e9s de Ben Arous apr\u00e8s son immolation par le feu \u00e0 Sidi Bouzid le 17 d\u00e9cembre. Cet \u00e9v\u00e9nement a d\u00e9clench\u00e9 la r\u00e9volte qui a gagn\u00e9 tout le pays.<\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Premiers signataires de l\u2019appel \u00e0 ce rassemblement\u00a0:<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Mouvement de la Paix 31, FSU 31, NPA, SOLIDAIRES 31, Europe \u00c9cologie Les Verts- Midi Pyr\u00e9n\u00e9es &#8211; , PCF 31, \u00c9lus de Toulouse de EELV, Le Parti de Gauche 31, La Maison de Quartier de Bagatelle,\u00a0 \u00ab\u00a0Partenia 31\u00a0\u00bb, l\u2019Appel des Appels Midi Pyr\u00e9n\u00e9es, MRAP 31, LDH 31, C.G.T\u2026.<\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"FR\">Information\u00a0:<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">helene.dupont@free.fr<\/a><\/span><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<p align=\"center\"><span lang=\"FR\"><strong><\/p>\n<h3 style=\"color: blue;\"><font>Manifestation de soutien devant le consulat g\u00e9n\u00e9ral de Tunisie \u00e0 Lyon<\/font><\/h3>\n<p><\/strong><\/span><\/p>\n<div align=\"justify\"> R\u00e9unis \u00e0 l\u2019appel de plusieurs organisations et partis politiques, comme la F\u00e9d\u00e9ration des Tunisiens pour la citoyennet\u00e9 des deux rives (FTCR), le Syndicat des avocats de France (SAF), le Syndicat de la magistrature, le PS, le PC et la Ligue des Droits de l\u2019Homme, notamment, plusieurs dizaines de manifestants se sont rassembl\u00e9es, hier, devant le consulat g\u00e9n\u00e9ral de Tunisie \u00e0 Lyon, avenue Mar\u00e9chal Foch. Il s\u2019agissait pour les manifestants d\u2019apporter leur soutien au peuple tunisien au moment o\u00f9 des troubles importants secouent le pays. \u00ab Le pouvoir, enferm\u00e9 dans son autisme, a refus\u00e9 d\u2019entendre ces cris de d\u00e9sespoir. Sa premi\u00e8re r\u00e9ponse \u00e0 ce mouvement pacifique a \u00e9t\u00e9 l\u2019utilisation des forces de r\u00e9pression \u00bb, ont constat\u00e9 les orateurs avant de d\u00e9noncer les brutalit\u00e9s, les menaces et tentatives d\u2019intimidation dont ont \u00e9t\u00e9 victimes, depuis le d\u00e9but des \u00e9v\u00e9nements, des avocats, des journalistes, des militants syndicaux et associatifs. La manifestation qui a d\u00e9but\u00e9 \u00e0 12 h 30 s\u2019est achev\u00e9e dans le calme en tout d\u00e9but d\u2019apr\u00e8s-midi.  <font><strong>(Source: leprogres.fr le 07.01.2011 02h01) Lien: <\/strong><a href=\"http:\/\/www.leprogres.fr\/fr\/region\/la-loire\/loire\/article\/4421606,182\/Manifestation-de-soutien-devant-le-consulat-general-de-Tunisie-a-Lyon.html\" target=\"_blank\" rel=\"noopener\"><strong>http:\/\/www.leprogres.fr\/fr\/region\/la-loire\/loire\/article\/4421606,182\/Manifestation-de-soutien-devant-le-consulat-general-de-Tunisie-a-Lyon.html<\/strong><\/a><\/font><\/div>\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><font><\/p>\n<div align=\"center\">\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>\u00c0 Lille, \u00ab c&rsquo;est une fiert\u00e9 de voir ce mouvement \u00bb<\/strong><\/font><\/h3>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> Publi\u00e9 le vendredi 07 janvier 2011 \u00e0 06h00 Dans la capitale des Flandres, \u00e0 des milliers de kilom\u00e8tres des heurts qui bousculent leur pays d&rsquo;origine, les membres de l&rsquo;association des Tunisiens du Nord de la France ont scand\u00e9 hier que leurs compatriotes \u00ab ne sont pas seuls \u00bb.  Ils \u00e9taient entre 70 et 80, au pied du Th\u00e9\u00e2tre du Nord sur la Grand-Place de Lille hier soir, tandis qu&rsquo;au m\u00eame moment, 200 personnes manifestaient pour la m\u00eame cause \u00e0 Paris, 60 \u00e0 Lyon&#8230; Pour crier leur soutien aux Tunisiens avides de d\u00e9mocratie. D\u00e9noncer le r\u00e9gime de Ben Ali \u00ab corrompu, antid\u00e9mocratique \u00bb, o\u00f9 la censure est reine depuis des ann\u00e9es. \u00ab Des d\u00e9cennies de r\u00e9pression \u00bb, glissait, plong\u00e9e dans la manifestation lilloise, l&rsquo;eurod\u00e9put\u00e9e des Verts H\u00e9l\u00e8ne Flautre. Elle tenait \u00e0 participer \u00e0 cette manifestation, convaincue que \u00ab ce qui se passe aujourd&rsquo;hui en Tunisie se prolongera par un changement en profondeur. Plus rien ne sera plus comme avant \u00bb, dit-elle. L&rsquo;eurod\u00e9put\u00e9e c\u00f4toyait quelques syndicalistes (Sud, FO), le Mrap et bien s\u00fbr l&rsquo;association des Tunisiens du Nord ainsi que des personnes venues, seules, soutenir le rassemblement. Adjem fait partie de ceux-l\u00e0 : \u00ab C&rsquo;est une vraie fiert\u00e9 pour nous de voir ce mouvement d\u00e9mocratique, non int\u00e9griste, qui sort dans les rues tunisiennes et rappelle les fondamentaux : le droit \u00e0 la dignit\u00e9, le d\u00e9part n\u00e9cessaire de Ben Ali. \u00bb Il est convaincu que \u00ab lutter pour la d\u00e9mocratie en Tunisie c&rsquo;est se battre contre l&rsquo;int\u00e9grisme \u00bb et en appelle aux gouvernements europ\u00e9ens.   Car tous se disent choqu\u00e9s du \u00ab comportement \u00bb des politiques occidentaux. \u00ab La France doit cesser de soutenir aveugl\u00e9ment le gouvernement tunisien. Elle doit demander la d\u00e9mocratie, la valorisation des organisations politiques et syndicales avant de poursuivre ses relations avec la Tunisie \u00bb, clamait ainsi Hafedh, l&rsquo;un des organisateurs de la manifestation lilloise.w B\u00c9RANG\u00c8RE BARRET <strong><font>(Source: Nord Eclair le 7 janvier 2011) Lien:<\/font><\/strong><a href=\"http:\/\/www.nordeclair.fr\/France-Monde\/Monde\/2011\/01\/07\/a-lille-c-est-une-fierte-de-voir-ce-mouv.shtml\" target=\"_blank\" rel=\"noopener\">http:\/\/www.nordeclair.fr\/France-Monde\/Monde\/2011\/01\/07\/a-lille-c-est-une-fierte-de-voir-ce-mouv.shtml<\/a><\/div>\n<p><\/font><\/p>\n<p>\u00a0<\/p>\n<hr\/>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<p align=\"justify\">\u00a0<\/p>\n<div align=\"center\"><strong><\/p>\n<h4 style=\"color: blue;\"><font>Sidi Bouzid <font size=\"3\">Troubles en Tunisie: manifestations \u00e0 Montr\u00e9al<\/font><\/font><\/h4>\n<p><\/strong><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">AFP 07\/01\/2011 12h55   Une soixantaine de Tunisiens du Canada, dont de nombreux \u00e9tudiants, se sont rassembl\u00e9s jeudi soir devant le consulat de leur pays \u00e0 Montr\u00e9al pour exprimer leur solidarit\u00e9 avec la r\u00e9volte sociale de leurs compatriotes et r\u00e9clamer le d\u00e9part du pr\u00e9sident Zine El Abidine Ben Ali.  Bravant le froid et la neige, ils ont d\u00e9ploy\u00e9 des banderoles et des drapeaux tunisiens et scand\u00e9 des slogans tels que \u00abBen Ali, c&rsquo;est fini, Tunisiens tous unis\u00bb ou \u00abArr\u00eatez le pillage, d\u00e9gagez de Carthage\u00bb, dans une allusion au palais pr\u00e9sidentiel, mais aussi \u00abDu travail et du pain pour tous les Tunisiens\u00bb et \u00abLibert\u00e9 d&rsquo;expression, arr\u00eatez la r\u00e9pression\u00bb.  La manifestation a \u00e9t\u00e9 organis\u00e9e par un Collectif de solidarit\u00e9 pour la justice sociale en Tunisie, r\u00e9unissant des militants d&rsquo;horizons politiques divers, a indiqu\u00e9 \u00e0 l&rsquo;AFP sa coordonatrice Sonia Djelidi.  Un rassemblement analogue d&rsquo;une quarantaine de personnes s&rsquo;est d\u00e9roul\u00e9 jeudi soir \u00e0 Qu\u00e9bec, devant le b\u00e2timent de Radio-Canada. <\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\"><strong><\/p>\n<h4 style=\"color: blue;\"><font size=\"3\">Protests in Canada amid spiraling Tunisian unrest<\/font><\/h4>\n<p><\/strong><\/div>\n<hr\/>\n<p> AFP le 6 janvier 2011 \u00a0 MONTREAL \u2014 Dozens of Tunisians, many of them students, gathered late Thursday before their country&rsquo;s consulate in Montreal to call for President Zine El Abidine Ben Ali&rsquo;s ouster amid growing unrest at home. Braving snow and frigid temperatures, the demonstrators unfurled banners and Tunisian flags. \u00ab\u00a0Ben Ali, it&rsquo;s over, Tunisians all together,\u00a0\u00bb they chanted. \u00ab\u00a0Stop the carnage, get out of Carthage,\u00a0\u00bb others yelled in reference to the presidential palace. \u00ab\u00a0Freedom of expression, stop the repression.\u00a0\u00bb The protest was organized by a Tunisian social justice group formed by activist citizens from various political beliefs, coordinator Sonia Djelidi told AFP. Another 40-some people held another protest meanwhile in Quebec in front of the Radio-Canada building. Earlier in Tunisia, thousands of lawyers in Tunisia went on strike Thursday, a week after a police crackdown on protests they staged in support of protesters against unemployment in the tightly controlled country. Trade unionists said strikes, protests, even attempted suicides also took place in other parts of the country. The strikes came amid growing unrest following the death of a jobless 26-year-old university graduate who set himself alight last month in the central town of Sidi Bouzid to protest his lack of opportunities. In a related development, police arrested a rapper and two bloggers, their families and friends announced, but could not say why or where they were being detained.<\/p><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><span lang=\"FR\"><font face=\"Arial\" size=\"3\"><span lang=\"SV\"><strong>Des Blogueurs et un rappeur arr\u00eat\u00e9s en Tunisie<\/strong><\/span><\/font><\/span><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<p><span>07\/01\/2011 \u00e0 10h34 &#8211; mis \u00e0 jour le 07\/01\/2011 \u00e0 11h34 <\/span><\/p>\n<p><span><b><span>La Tunisie connait actuellement une r\u00e9volte sociale in\u00e9dite. Les Blogueurs Slim Amamou,\u00a0<\/span><span>El Aziz Amami et\u00a0<\/span><span>Hamadi Kaloutcha<\/span><span>, tr\u00e8s actifs contre la censure dans leur pays ont \u00e9t\u00e9 arr\u00eat\u00e9s ainsi que le rappeur\u00a0<\/span><span>Hamada Ben Amor<\/span><span>.<\/span><\/b><\/span><\/p>\n<p><span>Le blogueur<\/span><span> et activiste tunisien Slim Amamou a \u00e9t\u00e9 arr\u00eat\u00e9 le 6 janvier au alentour de 13h, heure \u00e0 laquelle ses amis et coll\u00e8gues n\u2019avaient plus de ses nouvelles. On ne connait toujours pas les circonstances exactes de son arrestation.<\/span><\/p>\n<p><span>Slim Amamou est l\u2019un des blogueurs tunisien les plus connu. Il a d\u00e9nonc\u00e9 l\u2019ann\u00e9e derni\u00e8re une op\u00e9ration de phishing des comptes mails des internautes tunisiens. Il a \u00e9galement \u00e9tait parmi les initiateurs de l\u2019op\u00e9ration \u201c<\/span><span>Nhar 3la 3ammar<\/span><span>\u201d et l\u2019un des organisateur de\u00a0<\/span><span>la manifestation contre la censure le 22 mai 2010<\/span><span> \u00e0 Tunis.<\/span><\/p>\n<p><span>La veille de cette manifestation,\u00a0<\/span><span>il a \u00e9t\u00e9 arr\u00eat\u00e9<\/span><span> avec son cosignataire\u00a0<\/span><span>Yassine Ayari<\/span><span> et d\u00e9tenu pendant plus de 12h \u00e0 la fin desquelles il a \u00e9t\u00e9 oblig\u00e9 de faire d\u2019enregistrer une vid\u00e9o appelant \u00e0 l\u2019annulation de la manifestation.<\/span><\/p>\n<p><b><span>Il est important de se tenir au courant de la situation de ces personnes qui ont \u00e9t\u00e9 interpell\u00e9s visiblement par qu&rsquo;ils disent simplement ce qu&rsquo;ils pensent en Tunisie, et d&rsquo;en parler un maximum afin de ne pas les oublier.<\/span><\/b><\/p>\n<p><b><span>Arnaud MOUILLARD<\/span><\/b><\/p>\n<p><b><span>source : <\/span><span><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">http:\/\/fr.readwriteweb.com<\/a><\/span><span><\/span><\/b><\/p>\n<p>\u00a0<\/p>\n<p><font size=\"2\"><strong>(Source: Lepost.fr le 7 janvier 2011)<\/strong><\/font><\/p>\n<p><font size=\"2\"><strong>Lien:<\/strong><\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\"><strong>http:\/\/www.lepost.fr\/article\/2011\/01\/07\/2362641_trois-blogueurs-et-un-rappeur-arretes-en-tunisie.html<\/strong><\/font><\/a><\/p>\n<p><font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"><font size=\"3\">\u00a0<strong>Un rappeur et un blogueur arr\u00eat\u00e9s en Tunisie<\/strong><\/font><\/div>\n<p><font face=\"Arial\"><\/p>\n<div align=\"justify\">\n<hr\/>\n<p> Reuters: 07\/01\/11 13:08   TUNIS (Reuters) &#8211; La police tunisienne a arr\u00eat\u00e9 un rappeur et un blogueur critiques du pouvoir sans donner de raisons, a-t-on appris vendredi. La Tunisie conna\u00eet depuis le mois dernier une rare agitation sociale, les jeunes d\u00e9non\u00e7ant la p\u00e9nurie d&#8217;emplois dans le pays du pr\u00e9sident Zine el Abidine ben Ali. Quatre civils sont morts depuis le d\u00e9but de la vague de manifestations: deux ont \u00e9t\u00e9 tu\u00e9s par des policiers lors d&rsquo;une \u00e9meute et deux se sont suicid\u00e9s. La police a arr\u00eat\u00e9 jeudi \u00e0 Sfax le rappeur Hamada Ben-Amor, connu sous le pseudo d'\u00a0\u00bbEl General\u00a0\u00bb, a dit son fr\u00e8re. Le rappeur de 22 ans a mis en ligne fin d\u00e9cembre une chanson intitul\u00e9e \u00ab\u00a0Pr\u00e9sident, ton peuple est mort\u00a0\u00bb. \u00ab\u00a0Une trentaine de policiers en civil sont venus chez nous pour arr\u00eater Hamada et l&rsquo;ont pris sans nous dire o\u00f9 ils l&#8217;emmenaient\u00a0\u00bb, a dit Hamdi Ben-Amor \u00e0 Reuters. \u00ab\u00a0Quand nous avons demand\u00e9 pourquoi ils l&rsquo;arr\u00eataient, ils ont r\u00e9pondu: &lsquo;Il sait pourquoi'\u00a0\u00bb, a-t-il ajout\u00e9. Par ailleurs, le blogueur Aziz Amami, qui faisait ces derni\u00e8res semaines la publicit\u00e9 des \u00e9meutes, a \u00e9galement \u00e9t\u00e9 arr\u00eat\u00e9, a dit Sofiane Chourabi, un militant d&rsquo;opposition \u00e0 Ben Ali. Son blog et sa page sur le r\u00e9seau Facebook \u00e9taient inaccessibles vendredi. Les autorit\u00e9s tunisiennes n&rsquo;ont pas comment\u00e9 ces arrestations dans l&rsquo;imm\u00e9diat. Tarek Amara, Cl\u00e9ment Guillou pour le service fran\u00e7ais, \u00e9dit\u00e9 par Gilles Trequesser<\/p><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h4 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Des blogueurs tunisiens arr\u00eat\u00e9s apr\u00e8s les troubles de Sidi Bouzid<\/strong><\/font><\/h4>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"left\"><font face=\"Arial\" size=\"2\"><span>07\/01\/11<\/span><span>12:50<\/span><\/font><\/div>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Cinq cyber-dissidents ont d\u00e9j\u00e0 \u00e9t\u00e9 arr\u00eat\u00e9s et leurs ordinateurs ont \u00e9t\u00e9 confisqu\u00e9s. Le Parti Pirate se dit \u00e9galement \u00ab\u00a0sans nouvelles\u00a0\u00bb d&rsquo;un de ses membres franco-tunisien.<\/font><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">\u00a0<span>Un tract des Anonymous adress\u00e9 \u00e0 Ammar, surnom donn\u00e9 au censeur de l&rsquo;Internet tunisien (DR)<\/span><\/font><\/div>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Face \u00e0 l&rsquo;agitation sociale \u00e0 <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Sidi Bouzid<\/font><\/a><font face=\"Arial\" size=\"2\"> et son <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">onde de choc en ligne<\/font><\/a><font face=\"Arial\" size=\"2\">, le gouvernement tunisien a choisi de<strong> durcir la r\u00e9pression<\/strong>.\u00a0Au moins cinq blogueurs et cyber-dissidents ont \u00e9t\u00e9 arr\u00eat\u00e9s et leur ordinateur ont \u00e9t\u00e9 saisi, jeudi 6 janvier, dans diff\u00e9rentes villes de Tunisie.<\/font><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Reporters Sans Fronti\u00e8res dresse ainsi <strong>une liste<\/strong> &#8211;\u00ab\u00a0qui pourrait \u00eatre plus longue\u00a0\u00bb&#8211; de cyberdissidents arr\u00eat\u00e9s : Hamadi Kaloutcha, Hamada Ben Aoun,\u00a0Slim Amamou, Azyz Amamy et Slah Eddin Kchouk.<\/font><\/div>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Ces arrestations seraient li\u00e9es au mouvement des <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Anonymous<\/font><\/a><font face=\"Arial\" size=\"2\"> [qui lancent des attaques informatiques contre les sites web officiels tunisiens, <em>NDLR<\/em>]\u00a0\u00bb, explique \u00e0 Nouvelobs.com Lucie Morillon, responsable du dossier chez RSF. \u00ab\u00a0Le gouvernement tenterait d<strong>&lsquo;identifier les responsables des cyberattaques<\/strong> et de remonter aux responsables, tout en \u00e9touffant l&rsquo;\u00e9lan des journalistes-citoyens qui s&rsquo;est manifest\u00e9 sur les r\u00e9seaux sociaux\u00a0\u00bb apr\u00e8s les \u00e9v\u00e9nements de Sidi Bouzid.<\/font><\/p>\n<p align=\"justify\"><strong><font face=\"Arial\" size=\"2\">Sans nouvelles d&rsquo;un franco-tunisien<\/font><\/strong><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Le blogueur et militant<strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Hamadi Kaloutcha<\/a><\/strong> a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 son domicile de Tunis jeudi \u00ab\u00a0aux alentours de 6 heures du matin par quatre ou cinq policiers en civil\u00a0\u00bb, rapporte RSF. Les policiers ont affirm\u00e9 \u00e0 son \u00e9pouse qu&rsquo;ils n&rsquo;avaient que \u00ab\u00a0quelques questions \u00e0 lui poser\u00a0\u00bb et que \u00ab\u00a0cela ne prendrait que quelques heures\u00a0\u00bb, raconte Lucie Morillon. Son ordinateur et son unit\u00e9 centrale ont \u00e9t\u00e9 saisis.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Le rappeur tunisien Hamada Ben Aoun, dit \u00ab\u00a0<strong>El G\u00e9n\u00e9ral<\/strong>\u00ab\u00a0, a lui \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 Sfax (270 km au sud-est de Tunis). Dans son morceau \u00ab\u00a0<\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Pr\u00e9sident, ton peuple est mort<\/font><\/a><font face=\"Arial\" size=\"2\">\u00ab\u00a0, le chanteur interpelle le pr\u00e9sident Ben Ali sur la corruption et le ch\u00f4mage.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Les cybermilitants et membres du Parti Pirate tunisien <strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Slim Amamou<\/a><\/strong>,<strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Azyz Amamy<\/a><\/strong> et <strong>Slah Eddine Kchouk<\/strong> ont \u00e9galement \u00e9t\u00e9 arr\u00eat\u00e9s, \u00e0 Tunis pour les deux premiers et \u00e0 Bizerte (60 km au nord-ouest de Tunis) pour le troisi\u00e8me. Leurs ordinateurs ont \u00e9galement confisqu\u00e9. Slim Amamou seraient actuellement interrog\u00e9 au minist\u00e8re de l&rsquo;Int\u00e9rieur, selon ses proches qui ont pu le g\u00e9olocaliser via son t\u00e9l\u00e9phone.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Contact\u00e9 par Nouvelobs.com, le pr\u00e9sident du Parti Pirate fran\u00e7ais, Paul Da Silva, affirme \u00eatre \u00ab\u00a0sans nouvelles de Slim [Amadou] depuis hier [jeudi] vers 13h30\u00a0\u00bb. Inquiet, il \u00e9voque \u00e9galement <strong>\u00ab\u00a0la disparition\u00a0\u00bb d&rsquo;un franco-tunisien<\/strong>, membre du Parti Pirate fran\u00e7ais, sur place pour aider les militants tunisiens.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Dans <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">un message<\/font><\/a><font face=\"Arial\" size=\"2\"> post\u00e9 sur Facebook, le Parti Pirate tunisien appelle \u00ab\u00a0la communaut\u00e9 internationale \u00e0 faire pression sur le gouvernement tunisien \u00e0 lib\u00e9rer nos membres\u00a0\u00bb.<\/font><\/p>\n<p align=\"justify\"><strong><font face=\"Arial\" size=\"2\">Le Quai d&rsquo;Orsay \u00ab\u00a0suit de tr\u00e8s pr\u00e8s la situation en Tunisie\u00a0\u00bb<\/font><\/strong><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">\u00ab\u00a0Ces arrestations se d\u00e9roulent alors que les autorit\u00e9s tentent, en renfor\u00e7ant la censure sur le web, d&rsquo;\u00e9<strong>touffer les mouvements de contestation<\/strong> sociale et politique qui agitent le pays et de ma\u00eetriser les cyberattaques dirig\u00e9es contre des sites gouvernementaux\u00a0\u00bb, r\u00e9sume RSF.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">De son c\u00f4t\u00e9, la France dit suivre de pr\u00e8s la situation en Tunisie, a d\u00e9clar\u00e9 la porte-parole adjointe du minist\u00e8re fran\u00e7ais des Affaires \u00e9trang\u00e8res, Christine Fages. \u00a0\u00ab\u00a0Nous continuons de suivre de tr\u00e8s pr\u00e8s<strong> la situation en Tunisie<\/strong> et souhaitons que les tensions, qui ne sont dans l&rsquo;int\u00e9r\u00eat de personne, s&rsquo;apaisent. Il n&rsquo;appartient pas \u00e0 la France, pas plus qu&rsquo;\u00e0 un autre \u00c9tat, de conseiller les autorit\u00e9s tunisiennes dans le domaine \u00e9conomique et social\u00a0\u00bb, a-t-elle ajout\u00e9.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">La ministre des Affaires \u00e9trang\u00e8res, Mich\u00e8le Alliot-Marie, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">doit rencontrer<\/font><\/a><font face=\"Arial\" size=\"2\"> ce vendredi \u00e0 18h son homologue tunisien, Kamel Morjane.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">(Boris Manenti &#8211; Nouvelobs.com)<\/font><\/p>\n<p align=\"justify\"><strong><font face=\"Arial\" size=\"2\">(Source: Nouvelobs.com le 7 janvier 2011) Lien: <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">http:\/\/tempsreel.nouvelobs.com\/actualite\/monde\/20110107.OBS5863\/des-blogueurs-tunisiens-arretes-apres-les-troubles-de-sidi-bouzid.html<\/a><\/font><\/strong><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><\/font><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h4 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Tunis esp\u00e8re briser le mouvement de r\u00e9volte en muselant la Toile et les blogueurs<\/strong><\/font><\/h4>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\">Par FRANCE 24 le 07\/01\/2011 &#8211; 12:02<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<div align=\"justify\">Les internautes tunisiens ont une part active dans la propagation du mouvement de protestations qui agite leur pays. Inacceptable, pour le r\u00e9gime de Ben Ali qui exerce une censure cibl\u00e9e et a proc\u00e9d\u00e9 \u00e0 l\u2019arrestation de plusieurs blogueurs.<\/div>\n<div align=\"justify\">\n<div>\n<div>\n<div>\n<div>En marge<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>du mouvement de protestations sociales<\/font><\/a> qui va crescendo en<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>Tunisie<\/font><\/a> depuis<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>l&rsquo;immolation par le feu de Mohamed Bouazizi<\/font><\/a>, le 17 d\u00e9cembre dernier \u00e0 Sidi Bouzid, une cyber-guerre oppose les internautes et le pouvoir. C\u2019est dans ce contexte qu\u2019un rappeur et deux blogueurs renomm\u00e9s du pays, Slim Amamou et El Aziz Amami, ont \u00e9t\u00e9 arr\u00eat\u00e9s ce jeudi.<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>L&rsquo;organisation Reporters sans fronti\u00e8res<\/font><\/a>\u00a0 (RSF) fait \u00e9tat de son c\u00f4t\u00e9 d\u2019une quatri\u00e8me arrestation, celle du blogueur et militant Hamadi Kaloutcha. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 <strong>\u00ab\u00a0Les flics me cherchent, apparemment\u00a0\u00bb<\/strong> Quelques heures avant son arrestation, Slim Amamou, avait signal\u00e9 sur<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>son compte Twitter<\/font><\/a> qu&rsquo;il \u00e9tait d\u00e9sormais sous surveillance. Extraits : \u00ab\u00a0Flics autour de la maison hier et chez un ami ce matin, coup de fil au bureau ce matin\u00a0\u00bb. Ou encore : \u00ab\u00a0J&rsquo;\u00e9l\u00e8ve mon niveau de menace \u00e0 orange. Les flics me cherchent apparemment\u00a0\u00bb, a-t-il \u00e9crit dans un autre tweet.\u00a0 Selon le site Readwriteweb.com, un blog collectif ind\u00e9pendant, dont Slim est l\u2019un des contributeurs, ce dernier aurait indiqu\u00e9 sa position g\u00e9ographique sur Internet via son t\u00e9l\u00e9phone, peu apr\u00e8s son arrestation. Une capture d\u2019\u00e9cran,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>publi\u00e9e en ligne<\/font><\/a>, indique qu\u2019il se trouvait alors dans les locaux du minist\u00e8re de l\u2019Int\u00e9rieur \u00e0 Tunis. Une information que FRANCE 24 n\u2019a pas pu confirmer.  \u00ab\u00a0Slim ne se cache pas derri\u00e8re un pseudonyme, il assume ses id\u00e9es et par cons\u00e9quent il s\u2019expose \u00e0 une arrestation, comme ce f\u00fbt le cas l\u2019ann\u00e9e derni\u00e8re\u00a0\u00bb, explique \u00e0 France24.com, Sami Ben Gharbia, un blogueur tunisien r\u00e9fugi\u00e9 aux Pays-Bas. En effet, Slim a d\u00e9j\u00e0 eu des ennuis avec les autorit\u00e9s. En mai 2010, il avait \u00e9t\u00e9 interpell\u00e9 \u00e0 la veille d\u2019une manifestation contre la censure, dont il \u00e9tait l\u2019un des initiateurs. Il n\u2019avait \u00e9t\u00e9 rel\u00e2ch\u00e9 qu\u2019apr\u00e8s avoir appel\u00e9 \u00e0 l\u2019annulation de la marche. <strong> Objectif du r\u00e9gime : b\u00e2illonner le Web<\/strong> Ces interpellations men\u00e9es par le pouvoir visent d\u2019une part \u00e0 b\u00e2illonner le Web, utilis\u00e9 par les internautes comme un instrument de mobilisation, et d\u2019autre part \u00e0 mettre un terme au piratage des sites gouvernementaux, men\u00e9 par le groupe de hackers militants Anonymous. \u00ab\u00a0Cette cyber-guerre n\u2019est pas nouvelle en Tunisie, le pouvoir a toujours cherch\u00e9 \u00e0 museler la Toile\u00a0\u00bb, affirme Sami Ben Gharbia, fondateur du site d\u2019h\u00e9bergement de blogs<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>nawaat.org<\/font><\/a>. \u00ab\u00a0L\u2019arrestation des blogueurs peut soit avoir un impact dissuasif sur les internautes, soit d\u00e9clencher un \u00e9lan de solidarit\u00e9 en ligne et sur le terrain\u00a0\u00bb, poursuit-il. Outre les blogueurs, les r\u00e9seaux sociaux sont dans le collimateur de la censure \u00e9tatique. C&rsquo;est bien \u00e9videmment le cas de<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>Facebook<\/font><\/a>, qui compte pr\u00e8s de deux millions d&rsquo;utilisateurs en Tunisie, et du site de micro-blogging Twitter, o\u00f9 le \u00ab\u00a0hashtag\u00a0\u00bb (mot-cl\u00e9, NDLR)<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>#sidibouzid<\/font><\/a>, du nom de la ville \u00e0 l\u2019origine du mouvement, est largement utilis\u00e9. Depuis le d\u00e9but du mouvement de protestation,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>ces sites ont contribu\u00e9 \u00e0 diffuser les informations<\/font><\/a> sur les \u00e9v\u00e8nements qui secouent le pays, inaccessibles dans les m\u00e9dias traditionnels qui sont contr\u00f4l\u00e9s par l\u2019Etat. M\u00eames les m\u00e9dias \u00e9trangers sont surveill\u00e9s de pr\u00e8s. Selon RSF,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>certains articles de France 24<\/font><\/a> \u00e9taient inaccessibles ces derniers jours en Tunisie.\u00a0  <strong>Les internautes doivent contourner la censure<\/strong> Ces derni\u00e8res semaines, Tunis a r\u00e9agi non pas en bloquant l\u2019acc\u00e8s \u00e0 Facebook, mais en piratant des pages et des comptes du r\u00e9seau social pour les d\u00e9sactiver en s\u2019emparant des mots de passe des utilisateurs. D&rsquo;apr\u00e8s le site Assabilonline, une centaine de pages individuelles et des groupes hostiles au r\u00e9gime de<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>Ben Ali<\/font><\/a> ont ainsi \u00e9t\u00e9 d\u00e9sactiv\u00e9es. \u00ab\u00a0\u00c0 tous les utilisateurs de Facebook et, a fortiori, s\u2019ils se connectent \u00e0 partir de la Tunisie : ne vous connectez jamais \u00e0 partir d\u2019une page non s\u00e9curis\u00e9e\u00a0\u00bb, recommande ainsi aux internautes tunisiens le site nawaat.org,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>qui explique par ailleurs comment proc\u00e9der pour contourner la censure<\/font><\/a>. Par ailleurs, selon l&rsquo;organisation de d\u00e9fense de la libert\u00e9 de la presse RSF, qui a class\u00e9 le pays parmi les \u00ab\u00a0ennemis d&rsquo;Internet\u00a0\u00bb, il est impossible \u00ab\u00a0depuis quelques jours, de t\u00e9l\u00e9charger des photos et des vid\u00e9os sur Facebook depuis la Tunisie\u00a0\u00bb. <strong>(Source: france24.fr le 7 janvier 2011)<\/strong> \u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><strong>Lien: <\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.france24.com\/fr\/20110107-tunisie-censure-arrestations-blogueurs-slim-Amamou-web-internet-facebook-twitter-ben-ali-sidi-bouzid<\/font><\/strong><\/a> <\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><span lang=\"FR\"><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\"><strong>Tunisie: internet au coeur de la contestation<\/strong><\/font><\/h4>\n<p><\/span><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<p align=\"justify\"><span lang=\"FR\">\u00ab\u00a0Anonymous\u00a0\u00bb (\u00ab\u00a0Anonymes\u00a0\u00bb) qui ont r\u00e9cemment d\u00e9fendu WikiLeaks.  Dans le m\u00eame temps, les r\u00e9seaux sociaux comme Facebook sont tr\u00e8s largement utilis\u00e9s. Sur une population de 10 millions d&rsquo;habitants, la Tunisie compterait 3,6 millions d&rsquo;internautes, selon\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Reporters sans Fronti\u00e8res<\/font><\/a>\u00a0(RSF).  <strong>A l&rsquo;int\u00e9rieur du pays <\/strong>La presse tunisienne a mis quatre ou cinq jours avant de parler de l&rsquo;actuel\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">mouvement de manifestations<\/font><\/a>. \u00ab\u00a0Mais parall\u00e8lement, le net s&rsquo;est mis \u00e0 cr\u00e9piter: de message en message, de page Facebook en blog de jeunes, l&rsquo;info s&rsquo;est rapidement r\u00e9pandue, avec des appels \u00e0 la manifestation et des images, photos ou vid\u00e9o de la r\u00e9pression polici\u00e8re\u00a0\u00bb, rapporte le\u00a0site de\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Radio France Internationale<\/font><\/a>\u00a0(RFI). Selon un blogueur tunisien rest\u00e9 anonyme et cit\u00e9 par RFI, \u00ab\u00a0Facebook a fonctionn\u00e9 comme une train\u00e9e de poudre, en quelques heures, plusieurs villes du pays se sont mises dans le mouvement\u00a0\u00bb.\u00a0  Dans un pays o\u00f9 s\u00e9vit la censure, Facebook est ressenti comme un refuge et un espace de libert\u00e9, notamment parmi les jeunes dipl\u00f4m\u00e9s, tr\u00e8s souvent au ch\u00f4mage. \u00ab\u00a0C&rsquo;est l\u00e0 que nous trouvons l&rsquo;info libre. Facebook nous redonne l&rsquo;espoir dans un contexte de grande frustration\u00a0\u00bb, explique un jeune blogueur cit\u00e9 par le site de RFI. Selon le site\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Tunisie num\u00e9rique<\/font><\/a>, les internautes tunisiens sont \u00ab\u00a0la communaut\u00e9 la plus connect\u00e9e au Facebook dans l\u2019Afrique du Nord\u00a0\u00bb. Pour cette raison, le gouvernement \u00ab\u00a0n&rsquo;a pas os\u00e9 bloquer\u00a0\u00bb ce r\u00e9seau social comme il l&rsquo;a fait par le pass\u00e9, estime un blogueur tunisien cit\u00e9 par\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Rue88<\/font><\/a>.  D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, notent les observateurs, la Toile est devenue l&rsquo;instrument d&rsquo;une contestation qui para\u00eet peu structur\u00e9e et, pour l&rsquo;instant, d\u00e9pourvue de leadership. Gr\u00e2ce \u00e0 internet, \u00ab\u00a0on d\u00e9couvre une soci\u00e9t\u00e9\u00a0civile vivante, en marge des partis politiques\u00a0\u00bb, note-t-on \u00e0 la F\u00e9d\u00e9ration internationale des ligues des droits de l&rsquo;homme (FIDH), ONG bas\u00e9e \u00e0 Paris. La Toile \u00ab\u00a0a servi d&rsquo;instrument de mobilisation de la soci\u00e9t\u00e9 civile. C&rsquo;est un moyen de communication qui d\u00e9passe celle des autorit\u00e9s\u00a0\u00bb, ajoute-t-on \u00e0 la FIDH.\u00a0\u00a0  Pour l&rsquo;instant, le pouvoir n&rsquo;a donc pas r\u00e9ussi \u00e0 faire un blackout total sur l&rsquo;information comme\u00a0au printemps\u00a02008, lors des \u00e9v\u00e8nements du bassin minier de Gafsa (sud-ouest de la Tunisie), rapporte rue89.\u00a0Il avait\u00a0alors pu\u00a0circonscrire \u00e0\u00a0la r\u00e9gion\u00a0la r\u00e9volte de la population en bloquant toute information sur les manifestations pour l&#8217;emploi et de meilleures conditions de vie.\u00a0\u00a0  <strong>A l&rsquo;ext\u00e9rieur du pays <\/strong>De nombreux sites officiels tunisiens, ou ceux de la banque Zitouna,\u00a0\u00e9taient toujours inaccessibles jeudi 6 janvier. Ils sont en fait bloqu\u00e9s par des cyber-attaques r\u00e9pondant \u00e0 un mot d&rsquo;ordre r\u00e9pandu sur internet par les \u00ab\u00a0Anonymous\u00a0\u00bb\u00a0(\u00ab\u00a0Anonymes\u00a0\u00bb). Lesquels se pr\u00e9sentent comme un groupe d&rsquo;internautes attach\u00e9s \u00e0 la libert\u00e9 d&rsquo;expression. Ces \u00ab\u00a0anonymes\u00a0\u00bb reprochent aux grands m\u00e9dias internationaux de ne pas \u00e9voquer suffisamment la situation en Tunisie. Ils avaient \u00e9t\u00e9 associ\u00e9s \u00e0 un \u00e9lan de soutien au site\u00a0WikiLeaks en partie priv\u00e9 de financement apr\u00e8s qu&rsquo;il r\u00e9v\u00e9l\u00e9 des milliers de t\u00e9l\u00e9grammes diplomatiques secrets du\u00a0D\u00e9partement d&rsquo;Etat am\u00e9ricain.  <strong>Sur\u00a0<\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\"><strong>anonnews.org<\/strong><\/font><\/a><strong>, forum en ligne pour les \u00ab\u00a0hacktivists\u00a0\u00bb <\/strong>(contraction de hacker et activiste), les \u00ab\u00a0Anonymous\u00a0\u00bb ont publi\u00e9 une d\u00e9claration dans laquelle ils expliquent: \u00ab\u00a0Le gouvernement tunisien veut contr\u00f4ler le pr\u00e9sent avec des mensonges et de la d\u00e9sinformation, pour contr\u00f4ler le futur en dissimulant la v\u00e9rit\u00e9 \u00e0 ses citoyens. (&#8230;). Anonymous a entendu la demande de libert\u00e9 des Tunisiens. (&#8230;) Toute organisation impliqu\u00e9e dans la censure sera vis\u00e9e, et ne sera pas en paix tant que le gouvernement tunisien n&rsquo;entendra pas la demande de libert\u00e9 de son peuple\u00a0\u00bb.  Plusieurs sites internet tunisiens non-officiels se sont faits l&rsquo;\u00e9cho de cette offensive, qui consiste \u00e0 submerger de trafic les serveurs des sites vis\u00e9s. \u00ab\u00a0Les attaques cybern\u00e9tiques s&rsquo;amplifient en ce d\u00e9but 2011 en Tunisie! Cinq sites gouvernementaux tunisiens, un site informationnel officiel et un site d\u2019une banque islamique priv\u00e9e ont \u00e9t\u00e9 pirat\u00e9s\u00a0(&#8230;) par un groupe d&rsquo;activistes plus ou moins organis\u00e9s qui s&rsquo;est d\u00e9j\u00e0 attaqu\u00e9 \u00e0 Paypal et Mastercard\u00a0\u00bb, rapportait ainsi le site\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Tunisie num\u00e9rique<\/font><\/a>. Les organismes financiers Paypal et Mastercard avaient \u00e9t\u00e9 attaqu\u00e9s par des internautes qui voulaient les \u00ab\u00a0punir\u00a0\u00bb d&rsquo;avoir\u00a0interrompu les financements de WikiLeaks.  <strong>Le contr\u00f4le du pouvoir <\/strong>Si Facebook reste un espace de libert\u00e9, les autorit\u00e9s tunisiennes tentent de contr\u00f4ler de pr\u00e8s la Toile et ses acc\u00e8s. Selon RFI,\u00a0elles ont\u00a0ainsi r\u00e9ussi \u00e0 \u00ab\u00a0totalement\u00a0\u00bb censurer Youtube, Twitter ou Dailymotion.\u00a0A tel point que\u00a0RSF classe la Tunisie parmi les \u00ab\u00a0ennemis d&rsquo;internet\u00a0\u00bb. \u00ab\u00a0Internet, consid\u00e9r\u00e9 comme une menace potentielle pour la stabilit\u00e9 et l&rsquo;image du pays, est soumis \u00e0 une censure pernicieuse. Un filtrage tr\u00e8s strict, un harc\u00e8lement des opposants et une surveillance \u00e0 la Big Brother, permettent de contr\u00f4ler \u00e9troitement l&rsquo;information\u00a0\u00bb, note le site de l&rsquo;ONG.  \u00ab\u00a0La bande passante appartient \u00e0 l&rsquo;Agence tunisienne d&rsquo;internet (ATI), contr\u00f4l\u00e9e par le gouvernement, qui impose un filtrage s\u00e9v\u00e8re. Des adresses URLs ainsi que des mots cl\u00e9s sont bloqu\u00e9s. Les 12 fournisseurs d&rsquo;acc\u00e8s \u00e0 internet, priv\u00e9s ou publics, sont tous contr\u00f4l\u00e9s indirectement ou non par le r\u00e9gime\u00a0\u00bb du pr\u00e9sident Ben Ali, poursuit le site de RSF. Dans le m\u00eame temps, les bo\u00eetes e-mails et les sites, notamment ceux des opposants,\u00a0sont contr\u00f4l\u00e9s. Pourtant, officiellement, la censure ne concerne que le terrorisme et la pornographie.  Malgr\u00e9 cela, \u00ab\u00a0la blogosph\u00e8re tunisienne se r\u00e9v\u00e8le dynamique et capable de se mobiliser pour certaines causes\u00a0\u00bb, selon RSF.\u00a0Les internautes savent ainsi se d\u00e9brouiller en utilisant des \u00ab\u00a0d\u00e9viations\u00a0\u00bb, notamment des \u00ab\u00a0proxies\u00a0\u00bb (outils permettant de\u00a0cacher l&rsquo;origine d&rsquo;une connexion, et notamment utilis\u00e9s pour contourner la censure) temporaires. R\u00e9sultat: \u00ab\u00a0les autorit\u00e9s s&rsquo;int\u00e9ressent de pr\u00e8s aux proxies\u00a0\u00bb, note RSF&#8230; \u00ab\u00a0Sans attendre de nouvelles mesures, les activistes tunisiens ont commenc\u00e9 le d\u00e9veloppement de nouveaux moyens pour contourner la censure\u00a0\u00bb, pr\u00e9cise\u00a0le site du\u00a0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">Monde<\/font><\/a>. Un jeu du chat et de la souris \u00e0 l&rsquo;\u00e8re num\u00e9rique, en quelque sorte&#8230;<\/span><\/p>\n<p align=\"justify\"><b><span lang=\"FR\">(Source\u00a0: \u00ab\u00a0France2.fr\u00a0\u00bb Le 06-01-2010)<\/span><\/b><\/p>\n<p align=\"justify\"><b><span lang=\"FR\">Lien\u00a0: <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">http:\/\/info.france2.fr\/monde\/tunisie-internet-au-coeur-de-la-contestation-66675379.html<\/font><\/a><\/span><\/b><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h4 style=\"color: blue;\"><font face=\"Arial\" size=\"3\">La r\u00e9volte s&rsquo;\u00e9tend en Tunisie<\/font><\/h4>\n<p><\/strong><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<p align=\"justify\">Mise \u00e0 jour le jeudi 6 janvier 2011 \u00e0 23 h 02<\/p>\n<div align=\"justify\">Le mouvement de contestation contre le ch\u00f4mage et le co\u00fbt de la vie parti de la r\u00e9gion de Sidi Bouzid continue de s&rsquo;\u00e9taler en Tunisie, alors que les arrestations s&rsquo;accroissent.<\/div>\n<div align=\"justify\">L&rsquo;agitation a notamment gagn\u00e9 dans la journ\u00e9e des localit\u00e9s du littoral est, pourtant plus nanti que la r\u00e9gion du centre-ouest o\u00f9 tout a commenc\u00e9. \u00c0 Jbeniana et \u00e0 Tala, les policiers ont proc\u00e9d\u00e9 \u00e0 des arrestations muscl\u00e9es de manifestants d\u00e8s mercredi soir. Par ailleurs, un troisi\u00e8me suicide a \u00e9t\u00e9 signal\u00e9 depuis le d\u00e9but des troubles. C&rsquo;est un homme de 52 ans, Mohamed Slimane, qui a \u00e9t\u00e9 retrouv\u00e9 pendu \u00e0 Chebba, sur le littoral est. Il \u00e9tait un ouvrier du b\u00e2timent dont les enfants, dipl\u00f4m\u00e9s de l&rsquo;universit\u00e9, n&rsquo;avaient pas d&#8217;emploi. Il \u00e9tait malade et aurait \u00e9t\u00e9 d\u00e9sesp\u00e9r\u00e9 de recevoir une aide pour se soigner et nourrir sa famille. \u00c0 Regueb, pr\u00e8s de Sfax, un jeune homme a menac\u00e9 de s&rsquo;\u00e9lectrocuter pour d\u00e9noncer la corruption et l&rsquo;in\u00e9galit\u00e9 face \u00e0 l&#8217;emploi. Un autre s&rsquo;est immol\u00e9 dans la r\u00e9gion mini\u00e8re de Metlaoui. La journ\u00e9e a aussi \u00e9t\u00e9 marqu\u00e9e par l&rsquo;arrestation de Hamada Ben Amor, un rappeur critique du r\u00e9gime, et deux blogueurs, au lendemain de cyberattaques de groupes d&rsquo;internautes s&rsquo;opposant \u00e0 la censure et solidaires du mouvement de protestation sociale. La majorit\u00e9 des coll\u00e8ges et des lyc\u00e9es de Sidi Bouzid \u00e9taient en gr\u00e8ve jeudi, au lendemain des<a href=\"http:\/\/www.radio-canada.ca\/nouvelles\/International\/2011\/01\/05\/009-tunisie-bouazizi-funerailles.shtml\" target=\"_blank\" rel=\"noopener\"><strong>fun\u00e9railles de Mohamed Bouazizi<\/strong><\/a>, le jeune homme qui s&rsquo;est immol\u00e9 par le feu \u00e0 la mi-d\u00e9cembre, et dont le geste d\u00e9sesp\u00e9r\u00e9 est \u00e0 l&rsquo;origine du mouvement de protestation populaire. Bouazizi est devenu l&#8217;embl\u00e8me du mouvement de r\u00e9volte des jeunes ch\u00f4meurs dipl\u00f4m\u00e9s, des militants syndicalistes et des activistes des droits de l&rsquo;homme \u00e0 travers le pays. La semaine derni\u00e8re, le gouvernement a d\u00e9bloqu\u00e9 plus de 116 millions d&rsquo;euros pour l&#8217;emploi, et 7,8 millions d&rsquo;euros pour la cr\u00e9ation de projets \u00e0 Sidi Bouzid. Or, les mesures ne semblent pas avoir r\u00e9ussi \u00e0 appaiser l&rsquo;opinion publique. Le mouvement de contestation des trois derni\u00e8res semaines est consid\u00e9r\u00e9 comme le plus important en Tunisie depuis que le pr\u00e9sident Ben Ali a d\u00e9pos\u00e9 23 ans plus t\u00f4t Habib Bourguiba, le p\u00e8re de l&rsquo;ind\u00e9pendance tunisienne. <b>Les avocats en gr\u00e8ve<\/b> \u00a0<\/div>\n<div align=\"justify\">\n<table cellspacing=\"0\">\n<tr>\n<td>\u00a0<\/td>\n<\/tr>\n<tr>\n<td>\n<p><font face=\"Arial\" size=\"2\">Un avocat et activiste des droits humains, M. Trifi (\u00e0 gauche), et des coll\u00e8gues avocats, en gr\u00e8ve par solidarit\u00e9 avec mouvement de contestation \u00e0 Sidi Bouzid.<\/font><\/p>\n<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<div align=\"justify\">Des milliers d&rsquo;avocats ont observ\u00e9 une gr\u00e8ve, jeudi, pour s&rsquo;opposer \u00e0 la r\u00e9pression. Le barreau d\u00e9nonce \u00ab\u00a0un usage sans pr\u00e9c\u00e9dent\u00a0\u00bb de la force et affirme \u00ab\u00a0le droit des habitants de Sidi Bouzid et d&rsquo;autres r\u00e9gions d\u00e9munies \u00e0 l&#8217;emploi [et] \u00e0 la dignit\u00e9\u00a0\u00bb. Les avocats d\u00e9noncent \u00e9galement l&rsquo;usage de la force contre leurs coll\u00e8gues. Selon le b\u00e2tonnier de l&rsquo;ordre des avocats tunisiens, Me Abderrazek Kilani, des avocats ont \u00e9t\u00e9 battus par des policiers lors de manifestations organis\u00e9es la semaine derni\u00e8re \u00e0 Tunis et dans les villes de Monastir et Grombalia. \u00a0<\/div>\n<div align=\"justify\">\n<div>La gr\u00e8ve porte le message clair que nous n&rsquo;acceptons pas les attaques injustifi\u00e9es contre les avocats. Nous voulons protester fermement contre le passage \u00e0 tabac d&rsquo;avocats au cours des derniers jours. \u00a0<\/div>\n<p>\u2014\u00a0Me Abderrazek Kilani, b\u00e2tonnier de l&rsquo;ordre des avocats tunisiens<\/p>\n<\/div>\n<div align=\"justify\">Le parti au pouvoir, le Rassemblement constitutionnel d\u00e9mocratique, a qualifi\u00e9 la gr\u00e8ve de geste \u00ab\u00a0politique\u00a0\u00bb contre le r\u00e9gime. \u00a0<\/div>\n<div align=\"justify\">\n<div>\n<h4 style=\"color: blue;\">Manifestations \u00e0 Montr\u00e9al et \u00e0 Qu\u00e9bec<\/h4>\n<p>Une soixantaine de manifestants tunisiens se sont rassembl\u00e9s jeudi soir devant le consulat de Tunisie \u00e0 Montr\u00e9al, rue University, tandis qu&rsquo;une quarantaine d&rsquo;autres faisaient de m\u00eame devant le b\u00e2timent de Radio-Canada \u00e0 Qu\u00e9bec, pour exprimer leur solidarit\u00e9 \u00e0 l&rsquo;\u00e9gard de leurs compatriotes.  Sous la banni\u00e8re du Collectif de solidarit\u00e9 pour la justice sociale en Tunisie, les manifestants, dont plusieurs \u00e9tudiants, r\u00e9clamaient \u00e9galement le d\u00e9part du pr\u00e9sident Zine El Abidine Ben Ali. Ils ont brandi des banderoles, des drapeaux, tout en scandant des slogans comme \u00ab\u00a0Du travail et du pain pour tous les Tunisiens\u00a0\u00bb et \u00ab\u00a0Libert\u00e9 d&rsquo;expression, arr\u00eatez la r\u00e9pression\u00a0\u00bb. <font face=\"Arial\" size=\"2\"><strong>(Source: \u00ab\u00a0Radio Canada\u00a0\u00bb le 6 janvier 2011)<\/strong><\/font> <font face=\"Arial\" size=\"2\"><strong>Lien: <\/strong><\/font><a href=\"http:\/\/www.radio-canada.ca\/nouvelles\/International\/2011\/01\/06\/009-tunisie-revolte-greve.shtml\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\"><strong>www.radio-canada.ca\/nouvelles\/International\/2011\/01\/06\/009-tunisie-revolte-greve.shtml<\/strong><\/font><\/a> \u00a0<\/div>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h4 style=\"color: blue;\"><font size=\"3\"><strong>Gr\u00e8ve massive des avocats en Tunisie<\/strong><\/font><\/h4>\n<\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<p align=\"justify\">Ils d\u00e9noncent la r\u00e9pression le 31 d\u00e9cembre d\u2019une manifestation de solidarit\u00e9 avec les habitants de Sidi Bouzid, principal foyer de protestations contre le ch\u00f4mage et la pr\u00e9carit\u00e9 dans le pays.<\/p>\n<div align=\"justify\">\u00a0<\/div>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\">Des milliers d\u2019avocats ont observ\u00e9 jeudi une gr\u00e8ve tr\u00e8s suivie dans tous les tribunaux tunisiens pour d\u00e9noncer la r\u00e9pression le 31 d\u00e9cembre d\u2019une manifestation<a href=\"http:\/\/\/\" rel=\"nofollow noopener\" target=\"_blank\">de solidarit\u00e9 avec les habitants de Sidi Bouzid<\/a>, principal foyer de protestations contre le ch\u00f4mage et la pr\u00e9carit\u00e9 dans le pays.<\/p>\n<p align=\"justify\"><em>\u00abLa gr\u00e8ve a \u00e9t\u00e9 suivie par 95% des avocats dans l\u2019ensemble des tribunaux\u00bb,<\/em> \u00e0 l\u2019appel du Conseil national de l\u2019Ordre des avocats (CNOA), a indiqu\u00e9 \u00e0 l\u2019AFP le b\u00e2tonnier Abderrazak Kilani.<\/p>\n<p align=\"justify\"><em>\u00abCela s\u2019est d\u00e9roul\u00e9 dans le calme et aucun incident n\u2019a \u00e9t\u00e9 enregistr\u00e9 dans les r\u00e9gions ni dans Tunis, les avocats d\u00e9montrant qu\u2019ils peuvent riposter avec sagesse et responsabilit\u00e9\u00bb,<\/em> a-t-il affirm\u00e9.<\/p>\n<p align=\"justify\">Des permanences ont \u00e9t\u00e9 assur\u00e9es aupr\u00e8s de tribunaux pour les affaires pr\u00e9sentant un risque de rejet mais l\u2019\u00e9carasante majorit\u00e9 des 8000 avocats que compte la Tunisie a suivi le mouvement, a ajout\u00e9 le b\u00e2tonnier. A Tunis, les avocats en robe se sont regroup\u00e9s dans la salle des pas perdus du Palais de justice, sur l\u2019avenue Bab Bnet, o\u00f9 les forces de s\u00e9curit\u00e9 tr\u00e8s pr\u00e9sentes observaient sans intervenir, a constat\u00e9 l\u2019AFP.<\/p>\n<h4 align=\"justify\" class=\"ecxarticleContent\" style=\"color: blue;\"><font size=\"2\">\u00abFrapp\u00e9s, pourchass\u00e9s et insult\u00e9s\u00bb<\/font><\/h4>\n<p align=\"justify\">Le CNOA avait appel\u00e9 \u00e0 cette gr\u00e8ve apr\u00e8s la r\u00e9pression le 31 d\u00e9cembre d\u2019une manifestation du barreau en soutien \u00e0 la population de Sidi Bouzid (centre-ouest), point de d\u00e9part de troubles et manifestations sociales sur fond de ch\u00f4mage depuis le 19 d\u00e9cembre.<\/p>\n<p align=\"justify\">Le 31 d\u00e9cembre, le CNOA avait d\u00e9nonc\u00e9 <em>\u00abun usage sans pr\u00e9c\u00e9dent\u00bb <\/em>de la force pour <em>\u00abfaire taire les avocats\u00bb<\/em> et affirm\u00e9 que ceux-ci \u00e9taient <em>\u00abd\u00e9termin\u00e9s \u00e0 d\u00e9fendre la libert\u00e9 d\u2019expression\u00bb <\/em>et <em>\u00able droit des habitants de Sidi Bouzid et d\u2019autres r\u00e9gions d\u00e9munies \u00e0 l\u2019emploi, \u00e0 la dignit\u00e9\u00bb.<\/em><\/p>\n<p align=\"justify\">Des avocats avaient \u00e9t\u00e9<em> \u00abfrapp\u00e9s, pourchass\u00e9s et insult\u00e9s\u00bb<\/em> \u00e0 Tunis, Grombalia, Sousse, Monastir, Mahdia, Gafsa et Jendouba. L\u2019un d\u2019eux avait eu le nez fractur\u00e9 et un autre avait \u00e9t\u00e9 <em>\u00abgravement bless\u00e9 \u00e0 l\u2019oeil\u00bb,<\/em> selon le CNOA. Le b\u00e2tonnier s\u2019est bri\u00e8vement adress\u00e9 \u00e0 ses confr\u00e8res jeudi les invitant \u00e0 <em>\u00abtourner la page maintenant que la profession s\u2019est exprim\u00e9e pour dire qu\u2019il n\u2019est pas permis de taper sur les avocats\u00bb.<\/em><\/p>\n<p align=\"justify\">Des membres du Rassemblement constitutionnel d\u00e9mocratique (RCD, parti au pouvoir du pr\u00e9sident Zine El Abidine Ben Ali) se sont oppos\u00e9s \u00e0 la gr\u00e8ve.<em> \u00abCela n\u2019a rien d\u2019une action de d\u00e9fense du barreau, c\u2019est un acte d\u2019intrumentalisation politique\u00bb<\/em> dans le conteste de l\u2019agitation sociale, a affirm\u00e9 Me Mohsen Harbi.<\/p>\n<p align=\"justify\"><font><strong>(Source: \u00ab\u00a0Lib\u00e9artion.fr le 6 janvier 2011) <\/strong><\/font><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><font><\/p>\n<h4 style=\"color: blue;\"><font size=\"3\"><strong>La Tunisie gronde toujours, mais qui pour remplacer Ben Ali ?<\/strong><\/font><\/h4>\n<p><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\"><font size=\"2\">By <em>Marie Kostrz<\/em><\/font><\/div>\n<div align=\"justify\"><font size=\"2\">Created <em>01\/06\/2011 &#8211; 17:12<\/em><\/font><\/div>\n<p align=\"justify\">\u00a0<\/p>\n<div align=\"justify\">\n<div><font size=\"2\">Ent\u00eate large:\u00a0<\/font><\/div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<p align=\"justify\"><font size=\"2\">Faute de relais suffisant dans la population, l&rsquo;opposition ne devrait pas profiter du mouvement de protestation parti de Sidi Bouzid.<\/font><\/p>\n<p><\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><font size=\"2\">Plus de trois semaines apr\u00e8s le d\u00e9but des \u00e9meutes et malgr\u00e9 le durcissement de la r\u00e9pression, les Tunisiens continuent <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">\u00e0 descendre dans la rue<\/font><\/a><font size=\"2\"><span>[1]<\/span> pour demander le d\u00e9part de Ben Ali. Pourtant, les alternatives au r\u00e9gime actuel sont minces et ont du mal \u00e0 se structurer.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">En France depuis trois mois, Adel Ghazala suit les manifestations tunisiennes avec beaucoup d&rsquo;attention. Cet activiste qui a demand\u00e9 l&rsquo;asile politique est pessimiste quand il s&rsquo;agit d&rsquo;\u00e9voquer l&rsquo;apr\u00e8s Ben Ali\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il n&rsquo;y a pas d&rsquo;alternative possible pour le moment. Cela va prendre des ann\u00e9es pour mettre sur pied un projet politique porteur.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<h5 align=\"justify\" class=\"ecxprint-content\" style=\"color: blue;\"><font size=\"2\">\u00ab\u00a0Les Tunisiens n&rsquo;ont pas de culture politique du d\u00e9bat\u00a0\u00bb<\/font><\/h5>\n<p align=\"justify\"><font size=\"2\">Pour expliquer cette impasse, Yanis -le pr\u00e9nom a \u00e9t\u00e9 modifi\u00e9-, universitaire tunisien, d\u00e9nonce le verrouillage politique op\u00e9r\u00e9 par Ben Ali\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Le r\u00e9gime a d\u00e9truit tout espace de d\u00e9bat. Les Tunisiens n&rsquo;ont pas de culture politique du d\u00e9bat, il est impossible de susciter un dialogue intellectuel d&rsquo;o\u00f9 une personnalit\u00e9 et des id\u00e9es nouvelles pourraient \u00e9merger.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Selon Vincent Geisser<\/font><\/a><font size=\"2\"><span>[2]<\/span>, chercheur \u00e0 l&rsquo;Institut de recherche et d&rsquo;\u00e9tudes sur le monde arabe et musulman <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">(Iremam)<\/font><\/a><font size=\"2\"><span>[3]<\/span> et sp\u00e9cialiste du Maghreb, le pr\u00e9sident tunisien a op\u00e9r\u00e9 un virage s\u00e9curitaire depuis le d\u00e9but des ann\u00e9es 90 . Contrairement \u00e0 ce qu&rsquo;il avait promis, le syst\u00e8me de parti unique (le Rassemblement constitutionnel d\u00e9mocratique (<\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">RCD<\/font><\/a><font size=\"2\"><span>[4]<\/span>), h\u00e9ritier du <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Parti socialiste destourien<\/font><\/a><font size=\"2\"><span>[5]<\/span> d&rsquo;Habib Bourguiba) n&rsquo;a pas \u00e9t\u00e9 remis en cause.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">L&rsquo;\u00e9tau s&rsquo;est progressivement resserr\u00e9 autour des organisations susceptibles de tenir t\u00eate au pouvoir en place. Le principal syndicat, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">l&rsquo;Union g\u00e9n\u00e9rale du travail de Tunisie<\/font><\/a><font size=\"2\"><span>[6]<\/span> (l&rsquo;UGTT), a ainsi \u00e9t\u00e9 infiltr\u00e9 par le gouvernement. Selon Yanis, quelques sections r\u00e9gionales refusent encore de rallier le mouvement de protestation\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Certains responsables de l&rsquo;UGTT occupent des fonctions dans le parti unique, ils ne veulent pas se mouiller.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Des partis d&rsquo;oppositions officiels existent bien, mais n&#8217;emportent pas l&rsquo;adh\u00e9sion des Tunisiens. Un professeur tunisien pr\u00e9cise\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Ils ont \u00e9t\u00e9 cr\u00e9\u00e9s par le gouvernement afin de l\u00e9gitimer son action. C&rsquo;est un simulacre de d\u00e9mocratie.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Depuis le d\u00e9but des \u00e9meutes, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">cinq partis ont ainsi rejoint la position officielle<\/font><\/a><font size=\"2\"><span>[7]<\/span> dict\u00e9e lors du <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">discours de Ben Ali<\/font><\/a><font size=\"2\"><span>[8]<\/span> et selon laquelle les m\u00e9dias \u00e9trangers ont instrumentalis\u00e9 la r\u00e9volte partie de Sidi Bouzid.<\/font><\/p>\n<h5 align=\"justify\" class=\"ecxprint-content\" style=\"color: blue;\"><font size=\"2\">Une opposition d\u00e9connect\u00e9e de la r\u00e9alit\u00e9<\/font><\/h5>\n<p align=\"justify\"><font size=\"2\">Malgr\u00e9 ce blocage politique, des personnalit\u00e9s se d\u00e9marquent. Parmi elles, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Hamma Hammami<\/font><\/a><font size=\"2\"><span>[9]<\/span>, leader du parti communiste des ouvriers de Tunisie (PCOT). D\u00e9j\u00e0 opposant sous Bourguiba, il a acquis une r\u00e9putation d&rsquo;homme honn\u00eate et constant dans sa lutte pour la d\u00e9mocratie. <\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Les membres de cette organisation, non autoris\u00e9e par le pouvoir, sont oblig\u00e9s de vivre clandestinement. Un probl\u00e8me selon Yanis\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Hamma Hammami est longtemps rest\u00e9 dans la clandestinit\u00e9. M\u00eame si ses id\u00e9es sont int\u00e9ressantes, il peine \u00e0 \u00eatre en lien direct avec la population tunisienne.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Moncef Marzouki<\/font><\/a><font size=\"2\"><span>[10]<\/span>, ancien candidat \u00e0 la pr\u00e9sidentielle contre ben Ali, exil\u00e9 politique en France depuis le d\u00e9but des ann\u00e9es 2000, est aussi une des figures de l&rsquo;opposition tunisienne. Fondateur du Congr\u00e8s pour la R\u00e9publique, il milite pour l&rsquo;instauration d&rsquo;une seconde r\u00e9publique, le r\u00e9gime actuel se rapprochant selon lui davantage d&rsquo;une monarchie.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">S&rsquo;il n&rsquo;exclut pas d&rsquo;\u00eatre candidat \u00e0 la pr\u00e9sidentielle de 2014, il reconnaissait lors d&rsquo;une conf\u00e9rence \u00e0 Sciences-Po que le mouvement qu&rsquo;il incarne ne repr\u00e9sente pas une r\u00e9elle menace pour le r\u00e9gime de Ben Ali\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0C&rsquo;est \u00e0 la jeunesse maintenant de sortir, c&rsquo;est \u00e0 elle d&rsquo;organiser ce front de rupture [avec la dictature].\u00a0\u00bb <em>(Voir la vid\u00e9o)<\/em><\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p><span><\/p>\n<p align=\"justify\"> \u00a0<\/p>\n<p align=\"justify\">\n<p><\/span><\/p>\n<p align=\"justify\"><font size=\"2\">Le professeur tunisien, que j&rsquo;ai interrog\u00e9, nuance cependant son influence\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il est tr\u00e8s populaire parmi la diaspora qui l&rsquo;appr\u00e9cie pour sa combativit\u00e9 et la pertinence de son analyse, mais il n&rsquo;est pas connu en Tunisie.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Pour Vincent Geisser, une caract\u00e9ristique commune emp\u00eache les deux hommes de percer\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Ils font partie d&rsquo;un cercle \u00e9litiste d&rsquo;intellectuels en rupture avec le petit peuple tunisien, dont il n&rsquo;a pas vu venir la col\u00e8re. Le moteur des revendications actuelles provient vraiment de la base de la population.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Le chercheur souligne que les \u00e9meutes, qui ne sont pas du tout organis\u00e9es, reposent davantage sur une solidarit\u00e9 familiale et locale que sur un soutien politique de ces partis d&rsquo;opposition, aussi ind\u00e9pendants soient-ils.<\/font><\/p>\n<p align=\"justify\"><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Ettajdid<\/font><\/a><font size=\"2\"><span>[11]<\/span>, le seul d&rsquo;entre eux qui soit ind\u00e9pendant et tol\u00e9r\u00e9 par le r\u00e9gime, partage ce m\u00eame d\u00e9faut. Marguerite Rollinde, chercheurse au Centre de recherche en science sociale et politique de Paris-\u00e9quipe Genre, travail et mobilit\u00e9s, ajoute\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Comme d&rsquo;autres partis d&rsquo;opposition, il ne pourra pas prendre le relais car ses dirigeants ont trop longtemps oscill\u00e9 entre une position en claire opposition \u00e0 Ben Ali et un soutien au pr\u00e9sident, pour faire front commun contre les islamistes.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<h5 align=\"justify\" class=\"ecxprint-content\" style=\"color: blue;\"><font size=\"2\">Les islamistes, une crainte r\u00e9elle\u00a0?<\/font><\/h5>\n<p align=\"justify\"><font size=\"2\">Ces derniers inqui\u00e8tent Yanis\u00a0:<\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il existe \u00e0 pr\u00e9sent un terreau fertile pour les islamistes en Tunisie. Les habitants sont frustr\u00e9s par la pauvret\u00e9 et sont d\u00e9sormais nombreux \u00e0 se tourner vers la religion.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Les attaques contre les personnalit\u00e9s critiques envers la pression de l&rsquo;islam se sont multipli\u00e9es. Sawsen M\u00e2alej, com\u00e9dienne progressiste, a ainsi \u00e9t\u00e9 victime d&rsquo;une <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">campagne de d\u00e9nigrement<\/font><\/a><font size=\"2\"><span>[12]<\/span> men\u00e9e par le chanteur tunisien Psycho-M et tr\u00e8s relay\u00e9e sur Facebook, pour quelques blagues os\u00e9es \u00e0 la t\u00e9l\u00e9vision.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">La s\u00e9natrice Riadh Zghal, qui a \u00e9mis l&rsquo;id\u00e9e que l&rsquo;appel \u00e0 la pri\u00e8re pouvait g\u00eaner les \u00e9l\u00e8ves des \u00e9coles situ\u00e9es \u00e0 proximit\u00e9 des mosqu\u00e9es,<\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">a elle aussi \u00e9t\u00e9 vivement critiqu\u00e9e<\/font><\/a><font size=\"2\"><span>[13]<\/span>. Certains d\u00e9tracteurs ont m\u00eame demand\u00e9 <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">la d\u00e9ch\u00e9ance de son statut de musulmane<\/font><\/a><font size=\"2\"><span>[14]<\/span>.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Pourtant, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\">Rached Ghannouchi<\/font><\/a><font size=\"2\"><span>[15]<\/span>, leader historique des islamistes tunisiens, ne fait plus l&rsquo;unanimit\u00e9. Exil\u00e9 \u00e0 Londres, il a laiss\u00e9 derri\u00e8re lui les partisans de son parti, Ennahada. S\u00e9v\u00e8rement opprim\u00e9s par Ben Ali et lib\u00e9r\u00e9s depuis peu, ils restent discrets et ne cherchent pas \u00e0 prendre le contr\u00f4le du mouvement de revendication. <\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Vincent Geisser pr\u00e9cise\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Ghannouchi n&rsquo;a aucune prise sur la population, les jeunes ne le connaissent pas. Au m\u00eame titre que les autres partis d&rsquo;opposition, il est d\u00e9pass\u00e9 par la r\u00e9alit\u00e9 du terrain.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Selon Yanis, l&rsquo;alternative islamiste, possible sans \u00eatre imm\u00e9diate, sera plus radicale\u00a0:<\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il s&rsquo;agira d&rsquo;un mouvement situ\u00e9 \u00e0 la droite de Ghanouchi, qui n&rsquo;acceptera pas de faire un compromis politique comme Ennahda a tent\u00e9 pour int\u00e9grer le r\u00e9gime.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<h5 align=\"justify\" class=\"ecxprint-content\" style=\"color: blue;\"><font size=\"2\">Un rempla\u00e7ant issu du parti unique, mais \u00e0 la r\u00e9putation intacte\u00a0?<\/font><\/h5>\n<p align=\"justify\"><font size=\"2\">Le vide politique qu&rsquo;a cr\u00e9\u00e9 Ben Ali ne donne pas beaucoup d&rsquo;illusions aux Tunisiens\u00a0: personne n&rsquo;affirme que son r\u00e9gime s&rsquo;effondrera dans une semaine ou dans un mois. Vincent Geisser appelle \u00e0 encore plus de patience. Pour lui, le changement ne sera pas radical, et viendra davantage de l&rsquo;int\u00e9rieur\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Des \u00e9lites du parti de Ben Ali contestent de plus en plus la dictature. Une partie des cadres du parti est saine, il s&rsquo;agit de haut fonctionnaires qui administrent le pays en d\u00e9pit du r\u00e9gime autoritaire.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Selon lui, il est possible que l&rsquo;un d&rsquo;entre eux succ\u00e8de au pr\u00e9sident actuel\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il faudrait un rempla\u00e7ant issu du s\u00e9rail, mais dont la r\u00e9putation n&rsquo;a pas \u00e9t\u00e9 salie par des affaires de corruption. Un technicien qui engagerait des r\u00e9formes \u00e9conomiques et politiques, pour ouvrir progressivement le paysage politique.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">Il s&rsquo;agira forc\u00e9ment de quelqu&rsquo;un de soutenu par la communaut\u00e9 internationale\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Wikileaks a d\u00e9montr\u00e9 l&rsquo;implication des Etats-Unis, qui semblent chercher un successeur \u00e0 Ben Ali,<\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font size=\"2\"> dont ils d\u00e9plorent la corruption<\/font><\/a><font size=\"2\"><span>[16]<\/span>.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">En attendant, les \u00e9meutes continuent. En France, Adel Ghazal esp\u00e8re un changement, sans r\u00e9ellement y croire\u00a0: <\/font><\/p>\n<blockquote>\n<p align=\"justify\"><font size=\"2\">\u00ab\u00a0Il ne suffit pas d&rsquo;\u00eatre opposant pour \u00eatre un leader cr\u00e9dible et porter une alternative.\u00a0\u00bb<\/font><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<\/blockquote>\n<p align=\"justify\"><font size=\"2\">\u25ba <strong>Mis \u00e0 jour le 7\/01\/2011 \u00e0 12h15\u00a0: <\/strong>Ce n&rsquo;est pas Marguerite Rollinde, chercheurse au Centre de recherche en science sociale et politique de Paris-\u00e9quipe Genre, travail et mobilit\u00e9s, qui s&rsquo;est exprim\u00e9e sur Hamma Hammami mais bien Yanis.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\"><strong>(Source: Rue89.com le 6 janvvier 2011)<\/strong><\/font><\/p>\n<p align=\"justify\"><font size=\"2\"><strong>Lien: <\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong>http:\/\/www.rue89.com\/2011\/01\/06\/la-tunisie-gronde-toujours-mais-qui-pour-remplacer-ben-ali-184012<\/strong><\/a><\/font><\/p>\n<p align=\"justify\">\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"center\"><font><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\"><strong>Manifestation de soutien aux Tunisiens \u00e0 Paris : \u00ab\u00a0Il fallait que la rage sorte\u00a0\u00bb<\/strong><\/font><\/h5>\n<p><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div align=\"justify\">pour Le Monde.fr | 07.01.11 | 06h31\u00a0\u00a0\u2022\u00a0\u00a0Mis \u00e0 jour le 07.01.11 | 09h37 <\/div>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span>P<\/span>lace de la fontaine des Innocents, \u00e0 Paris, la pluie irr\u00e9guli\u00e8re qui tombe en cette fin de journ\u00e9e, jeudi 6 janvier, n&rsquo;a pas emp\u00each\u00e9 environ 250 manifestants de participer \u00e0 un rassemblement de soutien au peuple tunisien. <em>\u00ab\u00a0Nous sommes ici pour affirmer notre solidarit\u00e9 \u00e0 l&rsquo;\u00e9gard de nos confr\u00e8res en Tunisie\u00a0\u00bb<\/em>, assure un \u00e9tudiant venu ici avec son fr\u00e8re et un ami. <em>\u00ab\u00a0Ce qui se passe est un mal pour un bien,<\/em> poursuit-il,<em> il fallait que la rage sorte un jour.\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\">Une m\u00e8re de famille raconte que ses proches sur place ne sont pas touch\u00e9s par la r\u00e9pression, mais elle se dit tr\u00e8s inqui\u00e8te \u00e0 propos de ce qu&rsquo;elle entend. Elle ne comprend pas le tragique destin de Mohamed Bouazizi, le jeune homme dont le suicide par le feu, le 17 d\u00e9cembre, est \u00e0 l&rsquo;origine des troubles actuels. Il est d\u00e9c\u00e9d\u00e9 mardi soir. <em>\u00ab\u00a0Il \u00e9tait dipl\u00f4m\u00e9 et pourtant, il n&rsquo;a pas pu trouver de travail, comme tant d&rsquo;autres jeunes en Tunisie.\u00a0\u00bb<\/em> \u00a0<\/p>\n<p align=\"justify\"><strong>\u00ab\u00a0\u00c9LU AVEC 99 % DES VOIX\u00a0\u00bb<\/strong><\/p>\n<p align=\"justify\">Les revendications sont plus larges, elles d\u00e9passent le seul aspect social. Trois jeunes femmes affirment qu&rsquo;elles sont ici contre la dictature. <em>\u00ab\u00a0Ce n&rsquo;est pas normal que Ben Ali soit r\u00e9\u00e9lu tous les cinq ans avec 99,9 % des voix\u00a0\u00bb<\/em>. Une de ses amies la reprend et ironise : <em>\u00ab\u00a0Il y a du progr\u00e8s maintenant, le dernier scrutin lui donnait 96 %&#8230;\u00a0\u00bb<\/em> Les trois sont fi\u00e8res du mouvement de protestation. <em>\u00ab\u00a0Notre soutien ici en Europe va beaucoup les aider. En g\u00e9n\u00e9ral, les mouvements sociaux sont trop vite r\u00e9prim\u00e9s.\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\">L&rsquo;un des jeunes pr\u00e9sents au rassemblement est n\u00e9 et a pass\u00e9 son bac \u00e0 Sidi Bouzid, l\u00e0 o\u00f9 les \u00e9meutes ont commenc\u00e9. Il y \u00e9tait le 18 d\u00e9cembre, un jour apr\u00e8s le d\u00e9but des troubles. Il se demandait ce qu&rsquo;il se passait. <em>\u00ab\u00a0J&rsquo;\u00e9tais choqu\u00e9, je me croyais \u00e0 Bagdad. Il y avait des pneus et des poubelles qui br\u00fblaient sur les routes. J&rsquo;ai mis une heure et demie pour arriver chez moi depuis la gare, d&rsquo;habitude je mets une demi-heure&#8230;\u00a0\u00bb<\/em> \u00a0<\/p>\n<p align=\"justify\"><strong>\u00ab\u00a0C&rsquo;EST COMME LA R\u00c9VOLUTION FRAN\u00c7AISE\u00a0\u00bb<\/strong><\/p>\n<p align=\"justify\">Une fois mis au courant de la situation par sa m\u00e8re et ses copains, il a lui-m\u00eame particip\u00e9 aux manifestations, qu&rsquo;il qualifie de gu\u00e9rilla entre les jeunes et la police. <em>\u00ab\u00a0C&rsquo;est triste, mais les grands changements se passent comme \u00e7a. C&rsquo;est comme la R\u00e9volution fran\u00e7aise\u00a0\u00bb<\/em>, pense l&rsquo;\u00e9tudiant.<\/p>\n<p align=\"justify\">La nouvelle g\u00e9n\u00e9ration est le moteur du mouvement. Elle cherche \u00e0 s&rsquo;\u00e9manciper d&rsquo;un pouvoir qui ne lui laisse pas assez de place \u00e0 ses yeux. <em>\u00ab\u00a0Les jeunes doivent participer \u00e0 la vie sociale et politique. Ils doivent prendre leur part\u00a0\u00bb<\/em>, d\u00e9clare un manifestant dont le sentiment est partag\u00e9 par tous ici.<\/p>\n<p align=\"justify\">Un avocat consid\u00e8re que le premier objectif des manifestations est de briser le mur de la peur. <em>\u00ab\u00a0L&rsquo;opposition est fragment\u00e9e, affaiblie mais on assiste peut-\u00eatre \u00e0 une fin de r\u00e8gne. Le r\u00e9sultat sera sans doute une scission au sein du parti au pouvoir. Un clan s&rsquo;est accapar\u00e9 toutes les richesses du pays, \u00e7a ne peut plus durer.\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\">Comme tous les interlocuteurs franco-tunisiens rencontr\u00e9s, cet avocat ne donnera pas son nom. Trop risqu\u00e9 pour eux, s&rsquo;ils esp\u00e8rent se rendre encore en Tunisie, et aussi pour leurs familles rest\u00e9es sur place. Ils craignent trop les pressions.<\/p>\n<p align=\"justify\">Les autorit\u00e9s tunisiennes ont d\u00e9cid\u00e9 d&rsquo;interdire l&rsquo;acc\u00e8s au site Le Monde.fr.<\/p>\n<div align=\"justify\"><strong><font><span>Guillaume Clerc<\/span><\/font><\/strong><\/div>\n<div align=\"justify\"><strong><font>(Source: Lemonde.fr le 7 janvier 2011)<\/font><\/strong><\/div>\n<div align=\"justify\"><strong><font>Lien: <\/font><\/strong><a href=\"http:\/\/www.lemonde.fr\/societe\/article\/2011\/01\/07\/manifestation-de-soutien-aux-tunisiens-a-paris_1462109_3224.html\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.lemonde.fr\/societe\/article\/2011\/01\/07\/manifestation-de-soutien-aux-tunisiens-a-paris_1462109_3224.html<\/font><\/strong><\/a><\/div>\n<p align=\"justify\">\u00a0<\/p>\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"justify\"><font><\/p>\n<div align=\"center\"><strong><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">Le ch\u00f4mage des dipl\u00f4m\u00e9s, moteur de la r\u00e9volte tunisienne<\/font><\/h5>\n<p><\/strong><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">LEMONDE.FR | 07.01.11 | 17h30\u00a0\u00a0\u2022\u00a0\u00a0Mis \u00e0 jour le 07.01.11 | 19h13 <\/div>\n<p align=\"justify\">\u00a0<\/p>\n<div align=\"justify\"><span>E<\/span>n Tunisie, l&rsquo;expression est longtemps rest\u00e9e taboue. Dans un pays qui avait tant investi dans l&rsquo;\u00e9ducation, parler de \u00ab\u00a0ch\u00f4mage des dipl\u00f4m\u00e9s\u00a0\u00bb sonnait comme un aveu d&rsquo;\u00e9chec. Mais la r\u00e9alit\u00e9 est venue rattraper les autorit\u00e9s : le suicide d&rsquo;un jeune vendeur ambulant a d\u00e9clench\u00e9 un mouvement de r\u00e9volte in\u00e9dit, et depuis la mi-d\u00e9cembre, les Tunisiens sont dans la rue. Au premier rang desquels les jeunes, pouss\u00e9s \u00e0 bout par le ch\u00f4mage et l&rsquo;injustice sociale. Mohamed Bouazizi, bachelier de 26 ans, s&rsquo;\u00e9tait immol\u00e9 par le feu apr\u00e8s que les autorit\u00e9s eurent confisqu\u00e9 les fruits et l\u00e9gumes qu&rsquo;il vendait pour subsister. <\/div>\n<p align=\"justify\">Les 5 % de croissance annuelle moyenne de l&rsquo;\u00e9conomie tunisienne ces derni\u00e8res ann\u00e9es cachent une situation \u00e9conomique tr\u00e8s dure pour les jeunes du pays : selon une<a href=\"http:\/\/www-wds.worldbank.org\/external\/default\/WDSContentServer\/WDSP\/IB\/2009\/11\/12\/000020953_20091112162329\/Rendered\/PDF\/515650ESW0P1111CH0Rapport0Dynamique.pdf\" target=\"_blank\" rel=\"noopener\"><font>\u00e9tude officielle<\/font><\/a> r\u00e9alis\u00e9e par le minist\u00e8re de l&#8217;emploi tunisien en collaboration avec la Banque mondiale, si le taux de ch\u00f4mage global s&rsquo;\u00e9tablissait en 2008 \u00e0 14 %, celui des jeunes de 18 \u00e0 29 ans \u00e9tait pr\u00e8s de trois fois sup\u00e9rieur \u00e0 celui des adultes.<\/p>\n<p align=\"justify\"><strong>UNE JEUNESSE DIPL\u00d4M\u00c9E MAIS AU CH\u00d4MAGE \u00a0<\/strong><\/p>\n<p align=\"justify\">Ironie d&rsquo;un syst\u00e8me \u00e0 bout de souffle, les dipl\u00f4m\u00e9s de l&rsquo;enseignement sup\u00e9rieur sont particuli\u00e8rement touch\u00e9s : si les chiffres pr\u00e9cis sont difficiles \u00e0 obtenir, le<a href=\"http:\/\/web.worldbank.org\/WBSITE\/EXTERNAL\/ACCUEILEXTN\/PAYSEXTN\/MENAINFRENCHEXT\/TUNISIAINFRENCHEXTN\/0,,contentMDK:22342094~pagePK:1497618~piPK:217854~theSitePK:468201,00.html\" target=\"_blank\" rel=\"noopener\"><font>suivi<\/font><\/a> d&rsquo;une cohorte de dipl\u00f4m\u00e9s de 2004 montrait que 37 % d&rsquo;entre eux \u00e9taient sans emploi trois ans et demi apr\u00e8s l&rsquo;obtention de leur dipl\u00f4me.<em> <\/em><\/p>\n<p align=\"justify\"><em>\u00ab\u00a0La Tunisie a produit \u00e9norm\u00e9ment de dipl\u00f4m\u00e9s gr\u00e2ce \u00e0 une priorit\u00e9 donn\u00e9e \u00e0 l&rsquo;\u00e9ducation, et ce d\u00e8s l&rsquo;ind\u00e9pendance<\/em>, explique Vincent Guessier, sociologue \u00e0 l&rsquo;Institut de recherche sur le monde arabe et musulman, et auteur de plusieurs travaux sur la Tunisie. <em>En trente ans, le pays a connu un d\u00e9veloppement universitaire incomparable \u00e0 ce que pouvaient conna\u00eetre d&rsquo;autres pays au m\u00eame stade de d\u00e9veloppement. Il s&rsquo;est retrouv\u00e9 dans une situation de &lsquo;surproduction&rsquo; de dipl\u00f4m\u00e9s \u2013 m\u00eame si je n&rsquo;aime pas ce terme&#8230;\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\">Dans une \u00e9conomie fortement soutenue par l&rsquo;Etat, un dipl\u00f4me de l&rsquo;enseignement sup\u00e9rieur \u00e9tait autrefois la garantie d&rsquo;un emploi stable, souvent dans le secteur public ou para-public (anciennes entreprises d&rsquo;Etat notamment). Mais la donne a chang\u00e9 avec les grandes r\u00e9formes structurelles de l&rsquo;\u00e8re post-Bourguiba.<\/p>\n<p align=\"justify\">D\u00e8s la fin des ann\u00e9es 1990, le march\u00e9 de l&#8217;emploi s&rsquo;est av\u00e9r\u00e9 incapable d&rsquo;absorber cet afflux de jeunes dipl\u00f4m\u00e9s, et la situation s&rsquo;est aggrav\u00e9e ces derni\u00e8res ann\u00e9es.<em> \u00ab\u00a0La v\u00e9rit\u00e9 dans notre pays est que si tu n&rsquo;as pas de piston tu ne peux rien faire<\/em>, explique un jeune ing\u00e9nieur tunisien \u00e9migr\u00e9 au Canada. <em>M\u00eame en ayant des dipl\u00f4mes, tu n&rsquo;es pas assur\u00e9 d&rsquo;avoir un travail si tu ne donnes pas de pots-de-vin ou si tu ne connais personne de haut plac\u00e9.\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\"><strong>D\u00c9CLASSEMENT ET MIS\u00c8RE SOCIALE<\/strong><\/p>\n<p align=\"justify\">Beaucoup de dipl\u00f4m\u00e9s issus de cursus universitaires, dans le secteur tertiaire en particulier, se sont retrouv\u00e9s d\u00e9class\u00e9s une fois sur le march\u00e9 de l&#8217;emploi.<em> \u00ab\u00a0Ici, il n&rsquo;est pas rare d&rsquo;\u00eatre servi \u00e0 la pompe \u00e0 essence par un jeune titulaire d&rsquo;un master en sociologie<\/em>, raconte un commer\u00e7ant fran\u00e7ais install\u00e9 \u00e0 Sousse<em><\/em>depuis 2009. <em>La femme de m\u00e9nage est licenci\u00e9e d&rsquo;anglais, le vendeur de fruits et l\u00e9gumes est docteur en math\u00e9matiques et ainsi de suite&#8230;\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\">Un d\u00e9classement g\u00e9n\u00e9ralis\u00e9 particuli\u00e8rement mal v\u00e9cu par des populations o\u00f9 la nouvelle g\u00e9n\u00e9ration \u00e9tait la premi\u00e8re \u00e0 acc\u00e9der \u00e0 l&rsquo;enseignement sup\u00e9rieur : c&rsquo;est le cas en particulier des r\u00e9gions du Centre, o\u00f9 se trouve Sidi Bouzid. <em>\u00ab\u00a0Souvent, les familles<\/em>[de cette r\u00e9gion] <em>s&rsquo;endettent pour que les jeunes fassent des \u00e9tudes et puissent, en retour, aider la famille\u00a0\u00bb<\/em>, explique Vincent Geisser. <em>\u00ab\u00a0Mais aujourd&rsquo;hui, les jeunes reviennent au contraire comme charge suppl\u00e9mentaire. Ils sont oblig\u00e9s de faire des petits boulots non qualifi\u00e9s pour survivre<\/em>. (&#8230;) <em>Le retour vers la famille est alors v\u00e9cu comme une humiliation, un \u00e9chec personnel. C&rsquo;est presque une mort sociale\u00a0\u00bb<\/em>, constate le sociologue.<\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><strong>UN MOUVEMENT SOCIAL ET POLITIQUE \u00a0<\/strong><\/p>\n<p align=\"justify\">Une situation d\u00e9sesp\u00e9r\u00e9e qui a fini par d\u00e9clencher la r\u00e9volte : trois semaines apr\u00e8s le geste de Mohamed Bouazizi, le mouvement se poursuit et a gagn\u00e9 les grandes villes du pays. Les revendications politiques ont commenc\u00e9 \u00e0 fleurir sur la Toile et dans la rue, l\u00e0 o\u00f9 parler des affaires de \u00ab\u00a0la famille\u00a0\u00bb \u2013 celle de la premi\u00e8re dame, Leila Ben Ali, accus\u00e9e d&rsquo;orchestrer une corruption g\u00e9n\u00e9ralis\u00e9e \u2013 \u00e9tait autrefois tabou. Pouss\u00e9s \u00e0 bout par la situation, les manifestants d\u00e9noncent haut et fort la mainmise du pouvoir sur l&rsquo;\u00e9conomie du pays.<\/p>\n<p align=\"justify\"><em>\u00ab\u00a0Il ne faut pas se tromper sur le sujet,<\/em> explique une jeune Tunisienne \u00e9tudiante \u00e0 Paris<em>, les manifestants ne demandent pas \u00e0 l&rsquo;Etat de leur trouver du travail mais d\u00e9noncent le fait que, sur le march\u00e9 de l&#8217;emploi, les choses ne se font jamais dans la transparence et avec justice.\u00a0\u00bb<\/em><\/p>\n<p align=\"justify\"><em>\u00ab\u00a0Si nous sommes dans les revendications sociales aujourd&rsquo;hui<\/em>, ajoute la jeune femme, <em>c&rsquo;est parce que la corruption, la pr\u00e9carit\u00e9 et un Etat non d\u00e9mocratique ont conduit notre pays dans une m\u00e9diocrit\u00e9 soutenue<\/em>.<em>\u00ab\u00a0<\/em> Pour Vincent Geisser, la frustration politique accumul\u00e9e pendant des ann\u00e9es de dictature est l&rsquo;un des facteurs expliquant l&rsquo;\u00e9clatement soudain du mouvement. <em>\u00ab\u00a0L&rsquo;Etat disait en substance &lsquo;vous n&rsquo;avez pas de libert\u00e9, pas de d\u00e9mocratie mais on vous assure un bien-\u00eatre social &lsquo;. Cette \u00e9quation a vol\u00e9 en \u00e9clats.\u00a0\u00bb<\/em><\/p>\n<div align=\"justify\"><strong><font><span>Marion Solletty<\/span><\/font><\/strong><\/div>\n<div align=\"justify\"><strong><font>(Source: \u00ab\u00a0Lemonde.fr\u00a0\u00bb le 7 janvier 20119 Lien: <\/font><\/strong><a href=\"http:\/\/www.lemonde.fr\/afrique\/article\/2011\/01\/07\/le-chomage-des-diplomes-moteur-de-la-revolte-tunisienne_1462244_3212.html\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.lemonde.fr\/afrique\/article\/2011\/01\/07\/le-chomage-des-diplomes-moteur-de-la-revolte-tunisienne_1462244_3212.html<\/font><\/strong><\/a><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">La Tunisie, un pays qui cherche sa d\u00e9finition<\/font><\/h5>\n<p><\/strong><\/div>\n<div align=\"justify\">\n<hr\/>\n<p> Depuis quelques jours les m\u00e9dias internationaux s&rsquo;int\u00e9ressent \u00e0 la situation en Tunisie et aux troubles qui ont accompagn\u00e9 le suicide d&rsquo;un jeune tunisien de Sidi Bouzid dans le centre du pays. Vu d&rsquo;Europe, cette autre image de la Tunisie peut surprendre. Car dans l&rsquo;esprit de tous, la Tunisie v\u00e9hicule plusieurs repr\u00e9sentations, devenues classiques : une destination touristique prestigieuse, une soci\u00e9t\u00e9 qui s&rsquo;ins\u00e8re dans la modernit\u00e9 et une \u00e9conomie parmi les plus dynamiques de l&rsquo;aire sud-m\u00e9diterran\u00e9enne. N\u00e9anmoins, ce pays renvoie une autre image, plus complexe sur le plan des imaginaires politiques et des rapports entre gouvernants et gouvern\u00e9s. La Tunisie est un pays \u00e0 histoire et g\u00e9ographie variables selon la place qu&rsquo;on lui donne par rapport au Maghreb, \u00e0 l&rsquo;Occident chr\u00e9tien, \u00e0 la M\u00e9diterran\u00e9e, au monde arabo-musulman et \u00e0 l&rsquo;Afrique. Il s&rsquo;agit d&rsquo;un pays \u00e9cartel\u00e9 entre deux mondes, l&rsquo;occidental et l&rsquo;oriental, qui cherche sa d\u00e9finition depuis son acc\u00e8s \u00e0 l&rsquo;ind\u00e9pendance, il y a bient\u00f4t cinquante cinq ans. Une des \u00e9volutions r\u00e9centes, initi\u00e9e par le r\u00e9gime de Zine el-Abibine Ben Ali, consiste \u00e0 attribuer \u00e0 la M\u00e9diterran\u00e9e et \u00e0 la p\u00e9riode ant\u00e9-islamique la vraie identit\u00e9 tunisienne. La rh\u00e9torique officielle tente alors d&rsquo;imposer cette ligne comme une \u00e9vidence historique. C&rsquo;est ce que les enjeux de la promotion d&rsquo;une telle vision identitaire sont \u00e9normes. Il s&rsquo;agit d&rsquo;abord, apr\u00e8s avoir mis \u00e0 l&rsquo;\u00e9cart Bourguiba et la personnification de l&rsquo;histoire nationale (1956-1987) qu&rsquo;il incarnait, de gagner la bataille, y compris id\u00e9ologique, contre les islamistes. C&rsquo;est donc une r\u00e9ponse implicite de la part des autorit\u00e9s tunisiennes, politiques et scientifiques, \u00e0 la menace int\u00e9griste et \u00e0 la situation alg\u00e9rienne tenue \u00e0 cet \u00e9gard pour un contre mod\u00e8le. Il r\u00e9pond de ce fait \u00e0 un enjeu politique pour le r\u00e9gime tunisien : sortir du face \u00e0 face avec l&rsquo;islam sur le terrain symbolique de l&rsquo;histoire ; l&rsquo;identit\u00e9 tunisienne n&rsquo;a pas pour origine la conqu\u00eate musulmane et ne commence pas au Moyen-Age. Plus largement, le faire-valoir d&rsquo;une identit\u00e9 \u00e0 la fois plus riche et plus ancienne va se renforcer en r\u00e9action aux facteurs conjoncturels des ann\u00e9es 1990. La guerre du Golfe (1991) et la d\u00e9ception ressentie \u00e0 propos de l&rsquo;Union du Maghreb arabe, dont les diff\u00e9rends alg\u00e9ro-marocains ont refait surface et conduit au gel des institutions de cette union en 1994, ont pour cons\u00e9quence un retour sur soi et une plong\u00e9e aux sources de la m\u00e9moire. Dans un tel contexte, avec un horizon politiquement neutre, le th\u00e8me de la M\u00e9diterran\u00e9e, et la revendication d&rsquo;une identit\u00e9 plurielle qui lui est sous-jacente, va asseoir son h\u00e9g\u00e9monie id\u00e9ologique par rapport aux autres th\u00e8mes identitaires (\u00ab\u00a0identit\u00e9 maghr\u00e9bine\u00a0\u00bb, arabe, africaine, musulmane). Cette ligne politico-id\u00e9ologique rev\u00eat un autre enjeu important qui se situe sur le terrain \u00e9conomique et diplomatique. Il s&rsquo;agit pour les autorit\u00e9s tunisiennes de r\u00e9pondre \u00e0 la nouvelle configuration des rapports Nord\/Sud de la M\u00e9diterran\u00e9e, en inscrivant la Tunisie dans la nouvelle politique euro-m\u00e9diterran\u00e9enne inaugur\u00e9e par la conf\u00e9rence de Barcelone des 27 et 28 novembre 1995. Cet arrimage de la Tunisie \u00e0 l&rsquo;Europe et le discours m\u00e9diterran\u00e9en qui lui est propre a pour cons\u00e9quence d&rsquo;accentuer la rh\u00e9torique officielle portant sur le th\u00e8me de l'\u00a0\u00bbexceptionnalit\u00e9\u00a0\u00bb de la Tunisie et de son patrimoine, comme offre touristique aux \u00e9trangers, mais aussi pour relier \u00ab\u00a0la diaspora\u00a0\u00bb tunisienne et son potentiel \u00e9conomique et touristique \u00e0 la patrie d&rsquo;origine.<\/p><\/div>\n<div align=\"justify\"> <strong>UNE EXTR\u00caME TENSION SOCIALE <\/strong>Mais n\u00e9anmoins la construction politico-identitaire \u2013 a priori int\u00e9ressante ne serait-ce que par son ouverture sur l&rsquo;autre \u2013 est loin de passionner l&rsquo;immense majorit\u00e9 d&rsquo;un peuple qui, tout en \u00e9tant ancr\u00e9 dans l&rsquo;arabisme et l&rsquo;islam, comme les enqu\u00eates sociologiques le montrent, sa pr\u00e9occupation principale tourne autour du r\u00eave d&rsquo;une vie mat\u00e9rielle \u00e0 l&rsquo;europ\u00e9enne. Or, sur fond d&rsquo;une atmosph\u00e8re de fin de r\u00e8gne, l&rsquo;autoritarisme politique tel qu&rsquo;il s&rsquo;exerce au quotidien de mani\u00e8re tr\u00e8s complexe, et les pratiques client\u00e9listes, r\u00e9elles ou suppos\u00e9es, dans l&rsquo;exercice du pouvoir \u00e0 toutes les \u00e9chelles de la soci\u00e9t\u00e9, n&rsquo;ont cess\u00e9 d&rsquo;approfondir le foss\u00e9 entre gouvernants et gouvern\u00e9s. Dans ces conditions, la parole politique a non seulement rat\u00e9 sa cible mais elle a produit de la d\u00e9sesp\u00e9rance. Et la fin tragique du jeune tunisien de Sidi-Bouzid \u2013 esp\u00e9rons que son cas ne fera pas \u00e9cole chez ses coreligionnaires \u2013 traduit un profond malaise notamment chez les jeunes. Et \u00e0 ce stade d&rsquo;une situation marqu\u00e9e par une extr\u00eame tension sociale, on est tent\u00e9 d&rsquo;affirmer que dans le monde arabe et en particulier en Tunisie, la tradition de l&rsquo;Etat fort et son appareil r\u00e9pressif ont toujours pu faire taire les m\u00e9contentements populaires, sauf que les r\u00e9gimes en place, on l&rsquo;a vu r\u00e9cemment en Iran, doivent faire face maintenant \u00e0 une in\u00e9dite mobilisation populaire orchestr\u00e9e principalement sur la Toile. Face \u00e0 la r\u00e9volution du Web, vecteur \u00e0 l&rsquo;efficacit\u00e9 redoutable d&rsquo;une aspiration l\u00e9gitime \u00e0 des valeurs universelles, l&rsquo;enseignement tir\u00e9 de l&rsquo;histoire atteint ici ses limites. Tous les sc\u00e9narios sont d\u00e9sormais possibles.<\/div>\n<div align=\"justify\"> (Source: \u201cLe Monde.fr\u201d Le 07-01-2011) Lien: http:\/\/www.lemonde.fr\/idees\/article\/2011\/01\/07\/la-tunisie-un-pays-qui-cherche-sa-definition_1462051_3232.html<\/div>\n<p><\/font><strong><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><font><strong><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">Tunisie, la col\u00e8re est dans la rue<\/font><\/h5>\n<p><\/strong><\/font><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<p><\/strong><\/div>\n<p align=\"justify\">Par<strong>CHRISTOPHE AYAD; <\/strong><\/p>\n<p align=\"justify\">Que se passe-t-il en Tunisie\u00a0? Pas encore une r\u00e9volution, mais plus qu\u2019une r\u00e9volte. Cela fait deux semaines et demi que le pays couve comme un volcan en phase de r\u00e9veil. Le pr\u00e9sident Ben Ali, qui r\u00e8gne d\u2019une main de fer depuis 1987, a cru y mettre fin par un discours t\u00e9l\u00e9vis\u00e9 de p\u00e8re (Fouettard) de famille, dans lequel il a expliqu\u00e9 comprendre les manifestants mais ne plus tol\u00e9rer de troubles. Deux ministres et trois gouverneurs ont \u00e9t\u00e9 d\u00e9barqu\u00e9s pour l\u2019exemple. Mais, rien n\u2019y fait. La protestation se poursuit\u00a0: avocats, enseignants, lyc\u00e9ens prennent le relais un peu partout, comme un feu de prairie qui s\u2019\u00e9teint ici pour reprendre l\u00e0. Hier, la police a violemment dispers\u00e9 des centaines de lyc\u00e9ens \u00e0 Tala, dans l\u2019ouest du pays, rassembl\u00e9s pour une marche de solidarit\u00e9.<\/p>\n<p align=\"justify\">Tout a commenc\u00e9 le vendredi 17\u00a0d\u00e9cembre. Mohamed Bouazizi, un dipl\u00f4m\u00e9 ch\u00f4meur de 26\u00a0ans, tente de mettre fin \u00e0 ses jours en s\u2019aspergeant d\u2019essence et en craquant une allumette sur la place principale de Sidi Bouzid (centre), juste devant la pr\u00e9fecture. Il entend protester contre la confiscation de sa marchandise par des agents municipaux et, plus g\u00e9n\u00e9ralement, contre une vie de mis\u00e8re\u00a0: \u00e0 quoi bon faire des \u00e9tudes, si c\u2019est pour vendre des l\u00e9gumes au march\u00e9. Le lendemain, des dizaines, puis des centaines de jeunes participent \u00e0 un sit-in devant le si\u00e8ge du gouverneur. Lequel les fait chasser par la police \u00e0 coups de gaz lacrymog\u00e8nes et de matraques. La ville s\u2019enflamme, rapidement imit\u00e9e par d\u2019autres bourgades de la r\u00e9gion. La r\u00e9pression alimente les manifestations. Le 22\u00a0d\u00e9cembre, un autre jeune, Houcine Neji, se suicide sous les yeux de la foule, \u00e0 Menzel Bouzaiane, en s\u2019accrochant \u00e0 une ligne haute tension\u00a0: <em>\u00abJe ne veux plus de la mis\u00e8re et du ch\u00f4mage\u00bb<\/em>, crie-t-il \u00e0 la foule. La bourgade entre en convulsions. Les manifestants incendient trois voitures de police, les bureaux du Rassemblement constitutionnel d\u00e9mocratique (RCD, au pouvoir), un poste de la garde nationale et un train marchandises\u2026 Le 24, la police tire \u00e0 balles r\u00e9elles et tue un manifestant, Mohamed Ammari, 18\u00a0ans, touch\u00e9 en pleine poitrine. L\u00e9gitime d\u00e9fense plaide la police. Un deuxi\u00e8me manifestant, Chawki Hidri, gri\u00e8vement bless\u00e9, d\u00e9c\u00e8de le 1er janvier.<\/p>\n<p align=\"justify\"><strong>Black-out.<\/strong><\/p>\n<p align=\"justify\">Puis, le mouvement prend une tournure nationale. Des ch\u00f4meurs dipl\u00f4m\u00e9s manifestent le samedi\u00a025 et le dimanche 26\u00a0d\u00e9cembre, au centre de Tunis, sur la place Mohamed-Ali. Des rassemblements de solidarit\u00e9 essaiment dans le pays\u00a0: Bizerte, Sfax, Kairouan, Meknessi, Regueb, Souk Jedid, Ben Gardane, Medenine, Siliana, Sousse\u00a0etc. L\u2019UGTT, la centrale syndicale dont la direction est acquise au gouvernement, se d\u00e9chire. La Tunisie \u00abde l\u2019int\u00e9rieur\u00bb, loin des c\u00f4tes, du tourisme et des investissements, n\u2019est pas la seule touch\u00e9e par cette vague de col\u00e8re. A Paris, la diaspora manifeste devant l\u2019ambassade de Tunisie. Un rassemblement est pr\u00e9vu demain \u00e0 18\u00a0heures, Fontaine des Innocents, \u00e0 Paris.<\/p>\n<p align=\"justify\">Sur place, les journalistes Zouheir Makhlouf et Moez El-Bey sont violemment emp\u00each\u00e9s de travailler, ce dernier \u00e9tant m\u00eame tabass\u00e9 en direct lors d\u2019une \u00e9mission de radio le 24\u00a0d\u00e9cembre. Un black-out quasi total de l\u2019information est organis\u00e9\u00a0; m\u00eame les agences de presse internationales pr\u00e9sentes \u00e0 Tunis n\u2019acc\u00e8dent aux informations qu\u2019avec la plus grande difficult\u00e9. L\u2019essentiel de la mobilisation &#8211; surtout celle des lyc\u00e9ens &#8211; passe par Facebook, dernier espace du Net que le pouvoir n\u2019a pas encore verrouill\u00e9. Dans la r\u00e9gion de Sidi Bouzid, plusieurs localit\u00e9s sont plac\u00e9es sous couvre-feu et l\u2019arm\u00e9e est mobilis\u00e9e. A Menzel Bouzaiane, les bless\u00e9s ne peuvent pas \u00eatre transport\u00e9s, les habitants ont du mal \u00e0 s\u2019approvisionner et les \u00e9coles servent \u00e0 loger les renforts de police.<\/p>\n<p align=\"justify\">Le 28\u00a0d\u00e9cembre, ce sont deux avocats qui sont arr\u00eat\u00e9s \u00e0 l\u2019issue d\u2019une journ\u00e9e de solidarit\u00e9 de la profession &#8211; les membres du barreau ont tous port\u00e9, ce jour-l\u00e0, un brassard rouge. Mes Abderraouf Ayadi et Choukri Bela\u00efd ont \u00e9t\u00e9 rel\u00e2ch\u00e9s apr\u00e8s une nuit au poste, le premier ayant \u00e9t\u00e9, au passage, violemment molest\u00e9. Des journalistes \u00e0 Tunis, des enseignants \u00e0 Bizerte ont aussi men\u00e9 des actions symboliques. Si aucun chiffre n\u2019est disponible sur le nombre d\u2019arrestations ces trois derni\u00e8res semaines, plusieurs cas de torture ont \u00e9t\u00e9 confirm\u00e9s, notamment un militant du PDP (opposition de gauche) \u00e0 Sidi Bouzid.<\/p>\n<p align=\"justify\"><strong>D\u00e9connexion.<\/strong><\/p>\n<p align=\"justify\">\u00a0La r\u00e9pression ne suffisant pas, Zine el-Abidine Ben Ali sort de son silence le 28\u00a0au soir. Dans une rare et solennelle allocution pour un homme qui n\u2019aime pas s\u2019exprimer ni agir sous la pression, il dit comprendre <em>\u00ables circonstances et les facteurs psychologiques\u00bb<\/em> de la r\u00e9volte des ch\u00f4meurs. C\u2019est pour mieux recourir aux vieilles recettes\u00a0: Ben Ali d\u00e9nonce <em>\u00abl\u2019instrumentalisation politique de certaines parties\u00bb<\/em> et l\u2019influence de cha\u00eenes \u00e9trang\u00e8res. <em>\u00abL\u2019usage de la violence dans les rues par une minorit\u00e9 d\u2019extr\u00e9mistes contre les int\u00e9r\u00eats de leur pays n\u2019est pas acceptable\u00bb<\/em>, met-il en garde. D\u2019autant, explique-t-il, qu\u2019elle va d\u00e9courager touristes et investisseurs.<\/p>\n<p align=\"justify\">Le remaniement gouvernemental, annonc\u00e9 dans la foul\u00e9e, donne la mesure de la d\u00e9connexion du r\u00e9gime avec les attentes de la soci\u00e9t\u00e9\u00a0: le principal changement consiste en effet \u00e0 remplacer\u2026 le ministre de la Communication, Oussama Romdhani, par son homologue de la Jeunesse et des Sports. Le titulaire des Affaires religieuses change aussi, remplac\u00e9 par un proche du gendre du Pr\u00e9sident, Sakher el-Materi, cit\u00e9 comme un dauphin potentiel. Trois gouverneurs, dont celui de Sidi Bouzid, sont limog\u00e9s. Tout \u00e7a pour \u00e7a\u00a0: comme si les \u00e9v\u00e9nements des jours pass\u00e9s relevaient d\u2019un probl\u00e8me de communication.<\/p>\n<p align=\"justify\">Lamin\u00e9e par deux d\u00e9cennies de r\u00e9pression, l\u2019opposition politique tente, elle, tant bien que mal de suivre un mouvement qu\u2019elle n\u2019a ni vu venir ni pu organiser. Regroup\u00e9es dans l\u2019Alliance pour la citoyennet\u00e9 et l\u2019\u00e9galit\u00e9, plusieurs formations de gauche ont r\u00e9clam\u00e9 des <em>\u00absolutions radicales\u00bb<\/em> pour traiter cette <em>\u00abcrise sociale grave, loin d\u2019\u00eatre conjoncturelle\u00bb<\/em>. En l\u2019absence de cadre politique et syndical, il y a peu de chance que la r\u00e9volte de Sidi Bouzid d\u00e9bouche sur un changement politique. En revanche, elle en dit long sur la fragilit\u00e9 du contr\u00f4le du parti-Etat au pouvoir, le RCD, qui revendique pr\u00e8s d\u2019un million d\u2019adh\u00e9rents, soit un Tunisien sur dix. Les services de s\u00e9curit\u00e9, qui emploient 100 000\u00a0personnes (1\u00a0pour 100\u00a0habitants\u00a0!), se sont montr\u00e9s tout aussi impuissants. Les failles du syst\u00e8me Ben Ali sont b\u00e9antes, mais il n\u2019y en a pas de rechange. Demain, une journ\u00e9e de gr\u00e8ve nationale de solidarit\u00e9 est pr\u00e9vue. Un nouveau test pour le r\u00e9gime.<\/p>\n<p align=\"justify\">C.A.<\/p>\n<p align=\"justify\"><strong><font>(Source: \u00ab\u00a0Lib\u00e9ration\u00a0\u00bb (quotidien &#8211; France9 le 5 janvier 2011) <\/font><\/strong><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<p align=\"justify\">\u00a0<\/p>\n<p><font><\/p>\n<p align=\"center\"><b><span><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">Les troubles s\u2019\u00e9tendent au Maghreb suite aux affrontements en Tunisie<\/font><\/h5>\n<p><\/span><\/b><\/p>\n<p align=\"justify\"><b><span><\/span><\/b><\/p>\n<hr\/>\n<p>\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\"><strong>Par Ignacio Cembrero<\/strong><\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">EL PAIS 7 janvier 2011<\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\"><strong>Traduit de l\u2019espagnol par Abdelatif Ben Salem<\/strong><\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">Les protestations sociales en Tunisie s\u2019\u00e9tendent \u00e0 l\u2019Alg\u00e9rie voisine, plus peupl\u00e9e et plus riche des cinq pays Maghrebins. Dans la capitale mais aussi dans une dizaine d\u2019autres villes comme Boumerdes ou Oran, deuxi\u00e8me grande ville du pays, des centaines des jeunes ont violemment affront\u00e9 les forces de l\u2019ordre tout au long de l\u2019apr\u00e8s-midi de mercredi, jusqu\u2019\u00e0 la matin\u00e9e de jeudi.<\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">L\u2019origine de ces protestations sociales, n\u2019est pas aussi claire que celle de la Tunisie. Les premiers signes de m\u00e9contentement ont surgi mardi 4 janvier en Alg\u00e9rie, mais ce fut le lendemain que les jeunes, parfois le visage masqu\u00e9, arm\u00e9s de b\u00e2tons ou de barres de fer, investirent le centre d\u2019Oran et au moins quatre quartiers \u00e0 Alger, dont le quartier central de Bab el Oued.<\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">Les jeunes sont descendus dans la rue pour protester contre la hausse des prix de denr\u00e9es alimentaires de base tels que l\u2019huile et le sucre, ils ont d\u00e9vast\u00e9 le mobilier urbains et lanc\u00e9 des cocktails <i>molotov<\/i> contre des \u00e9difices publics en commen\u00e7ant par des commissariats comme celle de Bab El Oued. L\u2019Etat continuera \u00e0 subventionner les produits de premi\u00e8re n\u00e9cessit\u00e9\u00a0\u00bb,\u00a0 s\u2019est empress\u00e9 d\u2019annoncer le ministre de Commerce, Mustapha Ben Bada, pour tenter d\u2019\u00e9teindre la r\u00e9volte.<\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">La r\u00e9volte en Alg\u00e9rie est plus jeune, moins massive, mais plus violente qu\u2019en Tunisie. Au-del\u00e0 de leurs irruptions ponctuelles, elles soulignent dans les deux cas le d\u00e9sespoir total d\u2019une jeunesse majoritairement au ch\u00f4mage, qui n\u2019a pas d\u2019avenir et qui de surcro\u00eet se consid\u00e8re comme victime de deux r\u00e9gimes autoritaires mais aux politiques \u00e9conomique pourtant diff\u00e9rentes, lib\u00e9rale en Tunisie et socialisante en Alg\u00e9rie.\u00a0 <\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">En Tunisie, la r\u00e9volte qui a commenc\u00e9 il y a trois semaines avec l\u2019auto-immolation par le feu d\u2019un jeune homme de 26 ans, universitaire dipl\u00f4m\u00e9, dont le chariot de vendeur ambulant de fruits et l\u00e9gumes fut saisie et renvers\u00e9e par la police, se poursuit jusqu\u2019\u00e0 aujourd\u2019hui jeudi avec la gr\u00e8ve g\u00e9n\u00e9rale appel\u00e9e par l\u2019ordre des avocats, et suivie par 95%\u00a0 des 8.000 avocats que compte le pays, selon les d\u00e9clarations de ma\u00eetre Aberrazak Kilani, pr\u00e9sident de l\u2019ordre des avocats. Des avocats par centaines se sont r\u00e9unis dans le hall du palais de justice de la capitale sous bonne garde des forces anti-\u00e9meute qui se sont abstenus d\u2019intervenir.<\/font><\/span><\/p>\n<p align=\"justify\"><span><font size=\"2\">Les forces de police ont en revanche proc\u00e9d\u00e9, d\u2019apr\u00e8s \u00a0le site web alternatif nawaat.org, \u00e0 l\u2019arrestation dans la matin\u00e9e, d\u2019un des plus c\u00e9l\u00e8bres bloggeurs, Hamadi Kaloutcha (pseudo), ainsi que <i>El General<\/i> un rappeur tunisien auteur d\u2019un rap intitul\u00e9 \u00ab\u00a0<i>Pr\u00e9sident, ton peuple est mort<\/i>\u00a0\u00bb. Plusieurs autres arrestations eurent lieu sans que l\u2019on en sache le nombre exact.<\/font><\/span><\/p>\n<p align=\"justify\"><b><span><font size=\"2\">Contre le r\u00e9gime<\/font><\/span><\/b><\/p>\n<p align=\"justify\"><span><font size=\"2\">Malgr\u00e9 la r\u00e9pression polici\u00e8re, certaines figures traditionnelles de l\u2019opposition au r\u00e9gime de Ben Ali, prises de court par le mouvement de protestation sociale, sont convaincues que la r\u00e9volte allait se poursuivre. Car au-del\u00e0 des \u00ab\u00a0m\u00e9thodes barbares\u00a0\u00bb des forces de l\u2019ordre\u00a0 \u00ab\u00a0le r\u00e9gime se refuse toujours \u00e0 donner la moindre r\u00e9ponse aux revendications l\u00e9gitimes de la population\u00a0\u00bb, a d\u00e9clar\u00e9 \u00e0 France 24 l\u2019avocate Radhia Nasraoui, pr\u00e9sidente de l\u2019Association (non reconnue) de Lutte contre la Torture.<\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\">Sihem Bensedrine, porte-parole du Conseil National pour les Libert\u00e9s qui vit en exil \u00e0 Barcelone, s\u2019est risqu\u00e9e m\u00eame \u00e0 proph\u00e9tiser au cours d\u2019une conversation avec le correspondant de ce journal, \u00ab\u00a0\u2026la fin du r\u00e9gime du Pr\u00e9sident Ben Ali\u00a0\u00bb Pourquoi\u00a0? \u00ab\u00a0Parce que jamais dans l\u2019histoire contemporaine de la Tunisie , un chef d\u2019Etat n\u2019a \u00e9t\u00e9 aussi maltrait\u00e9 par des citoyens qui jusqu\u2019ici respectaient, vaille qui vaille, par peur ou par respect les institutions\u00a0\u00bb, a-elle r\u00e9pondu. <\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\">\u00ab\u00a0Les slogans repris massivement dans la rue sont une preuve du m\u00e9pris qu\u2019inspire le r\u00e9gime\u00a0\u00bb, poursuit Bensedrine. Les mots d\u2019ordres qui reviennent le plus souvent sont d\u2019apr\u00e8s elle, \u00ab\u00a0Ben Ali est un l\u00e2che\u00a0!\u00a0\u00bb, \u00ab\u00a0Kleptocrates, rendez l\u2019argent du peuple\u00a0!\u00bb, \u00ab\u00a0Dehors les voleurs de Carthage\u00a0!\u00a0\u00bb du nom du palais pr\u00e9sidentiel que Ben Ali occupe depuis 23ans.<\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\">Abdelatif Bensalem, intellectuel hispanophone vivant en exil \u00e0 Paris, d\u00e9plore, quant \u00e0 lui que le r\u00e9gime au pouvoir dans son pays continue de b\u00e9n\u00e9ficier d\u2019un large soutien de la France , de l\u2019Italie, de l\u2019Espagne et des Etats-Unis, pays qu\u2019il a r\u00e9ussi \u00e0 convaincre que son r\u00e9gime constitue le meilleur rempart contre l\u2019islamisme radical. Pour l\u2019instant aucun gouvernement europ\u00e9en n\u2019a condamn\u00e9 les violences polici\u00e8res qui ont caus\u00e9 la mort par balles de deux hommes \u00e0 Menzel Bouzayane dans le gouvernorat de Sidi Bouzid. <\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\">Le secr\u00e9taire d\u2019Etat espagnol pour l\u2019Union europ\u00e9enne, Diego L\u00f3pez Garrido, a d\u00e9ploy\u00e9, au cours de la pr\u00e9sidence espagnole, des efforts soutenus pour tenter de faire b\u00e9n\u00e9ficier la Tunisie du \u00ab\u00a0statut de partenaire avanc\u00e9\u00a0\u00bb, un statut que le Maroc a d\u00e9j\u00e0 obtenu en 2008, qui devrait le hisser au rang de \u00a0partenaire privil\u00e9gi\u00e9 de l\u2019Europe, mais ses efforts ont \u00e9chou\u00e9 et les n\u00e9gociations n\u2019ont pu aboutir.<\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span><font size=\"2\">IFEX, un Ong canadienne qui voulait venir en aide \u00e0 l\u2019opposition tunisienne en tentant d\u2019organiser au mois de novembre une r\u00e9union \u00e0 Madrid des dissidents tunisiens de l\u2019int\u00e9rieur et de l\u2019ext\u00e9rieur du pays, fut contrainte, d\u2019apr\u00e8s ses organisateurs, d\u2019abandonner ce projet en raison du refus du consulat d\u2019Espagne en Tunisie d\u2019accorder des visas \u00e0 deux adversaires politiques connus du r\u00e9gime de Ben Ali.<\/font><\/span><\/p>\n<p align=\"justify\">\u00a0<\/p>\n<p align=\"justify\"><span lang=\"EN-GB\"><font size=\"2\">&#8211; I-C-\u00a0<\/font><\/span><\/p>\n<p align=\"justify\"><span lang=\"EN-GB\"><font size=\"2\">Courtesy El PAIS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/font><\/span><\/p>\n<p align=\"justify\"><span lang=\"EN-GB\"><font size=\"2\"><strong>(Source: \u00ab\u00a0El Pais\u00a0\u00bb (Quotidien &#8211; Espagne) le 7 janvier 2011)<\/strong><\/font><\/span><\/p>\n<p align=\"justify\"><strong><\/strong><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<p><font><\/p>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong><\/p>\n<h5 style=\"color: blue;\"><font size=\"3\">Les r\u00e9voltes tunisiennes s\u2019\u00e9tendent \u00e0 l\u2019Alg\u00e9rie<\/font><\/h5>\n<p><\/strong><\/font><\/div>\n<div align=\"justify\">\n<hr\/>\n<p> LT avec les agences  Les manifestations se multiplient pour d\u00e9noncer le malaise social Est-ce un effet de contagion? Apr\u00e8s la Tunisie, en proie \u00e0 une vague de contestation sociale depuis la mi-d\u00e9cembre, son grand voisin du Maghreb, l\u2019Alg\u00e9rie, est \u00e0 son tour secou\u00e9 par de violentes manifestations. Jeudi, la jeunesse est descendue dans les rues de plusieurs villes du pays pour protester contre la vie ch\u00e8re, le manque de logements et le ch\u00f4mage. La veille, dans la nuit, \u00e0 Bab el Oued, un des grands quartiers populaires du vieux centre d\u2019Alger, des dizaines de manifestants avaient attaqu\u00e9 le commissariat \u00e0 coups de pierres. Ils ont \u00e9galement saccag\u00e9 et incendi\u00e9 le magasin du concessionnaire de Renault r\u00e9duisant en carcasses une dizaine de v\u00e9hicules. Le Quotidien d\u2019Oran, \u00e0 430 km \u00e0 l\u2019ouest d\u2019Alger, a rapport\u00e9 hier que les jeunes avaient forc\u00e9 un d\u00e9p\u00f4t pour en voler des sacs de farine, au moment o\u00f9 le prix du pain est en hausse et qu\u2019une p\u00e9nurie de bl\u00e9 pointe. Le gouvernement s\u2019efforce pour l\u2019heure de jouer l\u2019apaisement: mercredi, le ministre du Commerce Mustapha Benbada a ainsi affirm\u00e9 que l\u2019\u00abEtat continuera \u00e0 subventionner les produits\u00bb de premi\u00e8re n\u00e9cessit\u00e9. En r\u00e9alit\u00e9, observe l\u2019AFP, les manifestations se multiplient un peu partout dans le pays contre l\u2019absence de logements sociaux, les passe-droits et la corruption. Dans le m\u00eame temps, des bidonvilles ill\u00e9gaux sont ras\u00e9s. A l\u2019aube de son troisi\u00e8me mandat, en 2009, le pr\u00e9sident Abdelaziz Bouteflika s\u2019\u00e9tait pourtant engag\u00e9 \u00e0 construire un million d\u2019appartements manquants depuis le s\u00e9isme de 2003 et le triplement de la population (35,6 millions d\u2019habitants) depuis l\u2019ind\u00e9pendance en 1962. Seules 10\u2009000 habitations ont \u00e9t\u00e9 livr\u00e9es cette ann\u00e9e \u00e0 Alger. En Tunisie, o\u00f9 un appel \u00e0 la gr\u00e8ve nationale avait \u00e9t\u00e9 lanc\u00e9 pour jeudi, les organisations syndicales ont fait \u00e9tat de manifestations de rue et de nouvelles tentatives de suicide dans des localit\u00e9s du centre, du sud et de l\u2019ouest du pays. Un rappeur et deux activistes blogueurs ont \u00e9t\u00e9 arr\u00eat\u00e9s par la police, ont indiqu\u00e9 leurs familles. Les blogs et r\u00e9seaux sociaux sont devenus les espaces privil\u00e9gi\u00e9s d\u2019expression contestataire pour des milliers de jeunes.  \u00a0 <strong><font>\u00a0(Source: \u00ab\u00a0Le Temps\u00a0\u00bb (Quotidien &#8211; Suisse) le 7 janvier 2011) <\/font><\/strong> <a href=\"http:\/\/www.letemps.ch\/Page\/Uuid\/6cff3ca6-19e2-11e0-a565-8959e08567fa\/Les_rvoltes_tunisiennes_stendent__lAlgrie\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\">http:\/\/www.letemps.ch\/Page\/Uuid\/6cff3ca6-19e2-11e0-a565-8959e08567fa\/Les_r%e9voltes_tunisiennes_s%e9tendent_%e0_lAlg%e9rie<\/font><\/a> <\/p>\n<hr\/>\n<\/div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\"><strong><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\">Maghreb : un profond malaise social<\/font><\/h6>\n<p><\/strong><\/font><\/h6>\n<\/div>\n<p><font face=\"Arial\" size=\"2\"><\/p>\n<div align=\"justify\">\n<hr\/>\n<p> Publi\u00e9 le vendredi 07 janvier 2011 \u00e0 06h00 Les protestations sociales en Alg\u00e9rie et en Tunisie t\u00e9moignent d&rsquo;un malaise social profond, touchant en particulier les jeunes diplom\u00e9s, aggrav\u00e9 par la crise \u00e9conomique et l&rsquo;usure des \u00e9lites politiques. Analyse.  La Tunisie est en proie, depuis le 17 d\u00e9cembre, \u00e0 une r\u00e9volte sociale in\u00e9dite, partie du centre-ouest du pays, qui a fait 4 morts au total : deux lors de manifestations et deux suicides. En Alg\u00e9rie, des \u00e9meutes ont \u00e9clat\u00e9 ces derniers jours dans les villes du pays pour d\u00e9noncer le ch\u00f4mage et le co\u00fbt de la vie. Selon les analystes, il y a des points communs entre les deux pays, ainsi qu&rsquo;avec le Maroc voisin. Leurs \u00e9conomies ne parviennent pas \u00e0 offrir des perspectives aux jeunes, souvent dipl\u00f4m\u00e9s, qui arrivent sur le march\u00e9 du travail.  \u00ab Dans ces trois pays, il y a eu des efforts dans le domaine de l&rsquo;\u00e9ducation, mais on n&rsquo;a pas pens\u00e9 aux m\u00e9canismes d&rsquo;int\u00e9gration des jeunes dipl\u00f4m\u00e9s \u00e0 la collectivit\u00e9, une int\u00e9gration qui passe \u00e9videmment par l&#8217;emploi \u00bb, estime Driss Benali, \u00e9conomiste, professeur \u00e0 l&rsquo;universit\u00e9 Mohammed V de Rabat. Le Tunisien de 26 ans qui s&rsquo;\u00e9tait immol\u00e9 par le feu en d\u00e9cembre et qui est mort mardi des suites de ses blessures \u00e9tait l&rsquo;un de ces jeunes dipl\u00f4m\u00e9s. Il \u00e9tait vendeur ambulant, faute de mieux, et sa marchandise venait d&rsquo;\u00eatre confisqu\u00e9e par la police. La crise mondiale est venue s&rsquo;ajouter \u00e0 ces difficult\u00e9s, de m\u00eame que la hausse des prix alimentaires qui, dans ces pays, sont pourtant subventionn\u00e9s par l&rsquo; \u00c9tat. Apr\u00e8s les manifestations en Alg\u00e9rie, le gouvernement vient d&rsquo;assurer que l&rsquo;\u00ab \u00c9tat continuera \u00e0 subventionner les produits \u00bb de premi\u00e8re n\u00e9cessit\u00e9. \u00ab Il y a beaucoup de ch\u00f4mage, beaucoup de dipl\u00f4m\u00e9s-ch\u00f4meurs et \u00e7a fait longtemps que \u00e7a dure. La situation tient tant qu&rsquo;il y a de la croissance \u00e9conomique \u00bb, observe Pierre Vermeren, ma\u00eetre de conf\u00e9rence \u00e0 l&rsquo;universit\u00e9 de Paris I.  <strong>L&rsquo;attente, sans perspective  <\/strong>\u00ab De plus, la crise \u00e9conomique a bloqu\u00e9 l&rsquo;\u00e9migration \u00bb qui \u00e9tait une soupape pour les \u00e9conomies du Maghreb, en offrant un d\u00e9bouch\u00e9 \u00e0 certains dipl\u00f4m\u00e9s, note-t-il. En outre, explique le chercheur, l&rsquo;Alg\u00e9rie et la Tunisie sont \u00ab deux pays qui ont des syst\u00e8mes politiques en crise \u00bb avec deux pr\u00e9sidents, Abdelaziz Bouteflika et Zine el Abidine Ben Ali, qui s&rsquo;approchent de la fin de leur carri\u00e8re. En l&rsquo;absence de rel\u00e8ve, \u00ab C ela cr\u00e9e une situation politique d&rsquo;attente, sans perspective \u00bb, note-t-il. Les r\u00e9gimes politiques des pays du Maghreb sont pourtant tr\u00e8s diff\u00e9rents, la Tunisie \u00e9tant tr\u00e8s critiqu\u00e9e pour l&rsquo;absence de libert\u00e9s politiques. \u00ab En Tunisie, ils manifestent parce qu&rsquo;ils \u00e9touffent, ce n&rsquo;est pas une violence seulement sociale mais une protestation contre le fonctionnement du r\u00e9gime. Le r\u00e9gime et la famille Ben Ali ont \u00e9cart\u00e9 toutes les rel\u00e8ves potentielles. Il n&rsquo;y a plus de relais du pouvoir, il y a la peur qui r\u00e8gne \u00bb, souligne Antoine Basbous, de l&rsquo;Observatoire des pays arabes. De fait, le pr\u00e9sident Ben Ali, qui tient le pays d&rsquo;une main de fer, a peu de craintes de voir son pouvoir menac\u00e9 par la r\u00e9volte sociale, selon les analystes. \u00ab Au Maroc, la situation n&rsquo;est pas aussi ferm\u00e9e, il y a une opposition constitu\u00e9e. Les jeunes au ch\u00f4mage peuvent manifester durant des mois devant l&rsquo;Assembl\u00e9e nationale \u00e0 Rabat \u00bb, ajoute Karim Pakzad, de l&rsquo;Institut des relations internationales et strat\u00e9giques (IRIS), \u00e0 Paris. En Alg\u00e9rie, \u00ab Le FLN (au pouvoir) a gard\u00e9 une l\u00e9gitimit\u00e9 du parti de lib\u00e9ration nationale \u00bb et \u00ab dans l&rsquo;espace public, les partis d&rsquo;opposition peuvent s&rsquo;exprimer \u00bb, pr\u00e9cise-t-il. Pour les trois pays, il faut aussi d\u00e9sormais prendre en compte la dimension Internet et le possible effet de contagion. \u00ab Les gens sont toute la journ\u00e9e sur internet, sur Facebook et les Alg\u00e9riens voient tr\u00e8s bien ce qui se passe en Tunisie \u00bb, rel\u00e8ve Pierre Vermeren, qui souligne aussi le r\u00f4le de la cha\u00eene Al-Jazirah dans la diffusion de l&rsquo;information au Maghreb.  <strong><font>(Source: Nord Eclair le 7 janvier 2011) Lien: http:\/\/www.nordeclair.fr\/France-Monde\/2011\/01\/07\/maghreb-un-profond-malaise-social.shtml<\/font><\/strong><\/div>\n<p><\/font><\/font><\/font><\/p>\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"center\"><font><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Crise sociale en Tunisie : quelques cl\u00e9s pour mieux comprendre<\/strong><\/font><\/h6>\n<p><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<p align=\"justify\">07\/01\/2011 \u00e0 16h10 | <\/p>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\n<p><strong>A vouloir d\u00e9cortiquer les \u00e9v\u00e9nements en Tunisie \u00e0 travers un prisme occidental, les m\u00e9dias fran\u00e7ais se mettent le doigt dans l\u2019oeil. Aveugl\u00e9s, nos journalistes ont r\u00e9ussi \u00e0 se convaincre qu\u2019un mensonge r\u00e9p\u00e9t\u00e9 mille fois devient une v\u00e9rit\u00e9.<\/strong><\/p>\n<p><span><\/span> \u00a0<\/p>\n<p>Servile, le peuple tunisien ? C\u2019est ce que l\u2019on pourrait d\u00e9duire \u00e0 la lecture des r\u00e9cents articles sur la situation en Tunisie, tant les m\u00e9dias feignent de d\u00e9couvrir que la population y est capable de soul\u00e8vements de grande ampleur.<em>\u2018<\/em><span><em><font>Le r\u00e9gime vieillissant de Ben Ali va-t-il s\u2019effondrer\u2019<\/font><\/em><\/span> s\u2019interrogent Les Inrocks. \u2018<span><em><font>Les richesses du pays sont monopolis\u00e9es par la famille du Pr\u00e9sident<\/font><\/em><\/span>\u2018 affirme sur Rue89 le pr\u00e9sident de Byrsa, un mouvement anecdotique lui-m\u00eame tenu par les nantis qui profitent du syst\u00e8me. Aucun r\u00e8glement de compte : ce sont pour la plupart des amis d\u2019enfance, des gens avec qui j\u2019ai \u00e9tudi\u00e9 \u00e0 Tunis, que je connais depuis le primaire. Autant dire que je suis bien plac\u00e9e pour conna\u00eetre leurs motivations d\u2019aujourd\u2019hui.<\/p>\n<p>\u00c9meutes en Tunisie : le spectre d\u2019une r\u00e9volution ? C\u2019est bien mal conna\u00eetre la culture du pays. Si en France le peuple a pour habitude de d\u00e9capiter ses \u00e9lites, la Tunisie a une tradition contestataire moins radicale. Et cela ne date pas de l\u2019\u00e8re <strong>Ben Ali<\/strong>.<\/p>\n<p><span><strong>Une longue tradition de contestation<\/strong>\u2026<\/span> <\/p>\n<p>En 1968 d\u00e9j\u00e0, alors que la France traverse une crise politique et sociale historique, la pr\u00e9sidence d\u2019<strong>Habib Bourguiba<\/strong> conna\u00eet elle aussi des manifestations \u00e9tudiantes. A l\u2019universit\u00e9 de Tunis, berceau des contestations sociales depuis cette \u00e9poque, on d\u00e9bat des orientations d\u00e9cid\u00e9es par le pr\u00e9sident et l\u2019on conteste la mainmise du Parti socialiste destourien sur les institutions du pays. Le soul\u00e8vement dure quelques mois, il est violemment r\u00e9prim\u00e9 par les forces de l\u2019ordre.<\/p>\n<p>Une d\u00e9cennie plus tard, une gr\u00e8ve g\u00e9n\u00e9rale est d\u00e9cr\u00e9t\u00e9e le 26 janvier 1978. Il faut savoir qu\u2019une <strong>tradition syndicaliste <\/strong>tente alors de s\u2019installer en Tunisie. Le mot d\u2019ordre provoque des heurts entre manifestants et forces de l\u2019ordre. Le pr\u00e9sident ordonne l\u2019intervention de l\u2019arm\u00e9e. Bilan : plusieurs dizaines de morts, des centaines de bless\u00e9s.<\/p>\n<p>Ce n\u2019est rien compar\u00e9 \u00e0 la <strong>r\u00e9bellion dans la r\u00e9gion de Gafsa<\/strong> en 1980. Une commando d\u2019opposants tunisiens expatri\u00e9s tente le coup d\u2019Etat, soutenu par le r\u00e9gime libyen. Le putsch \u00e9choue l\u00e0 encore.<\/p>\n<p>Trois ans plus tard, ce sont les fameuses \u2018<strong><em>\u00e9meutes du pain<\/em><\/strong>\u2018. Alors que le gouvernement annonce une augmentation des prix du pain et des produits c\u00e9r\u00e9aliers, \u00e0 la base de l\u2019alimentation tunisienne, des \u00e9meutes \u00e9clatent dans plusieurs villes du sud tunisiens, avant d\u2019atteindre la capitale Tunis. Un peu comme<span><font>en Bolivie il y a quelques semaines<\/font><\/span> \u00e0 l\u2019annonce de l\u2019augmentation des prix du carburants. Etat d\u2019urgence, couvre-feu, rien n\u2019y fait. Habib Bourguiba finit par reculer et annuler toutes les augmentations. La vague de contestation aura dur\u00e9 une dizaine de jours. Officiellement, il y a eu 70 morts.<\/p>\n<p>Ce qui est int\u00e9ressant dans cette chronologie, c\u2019est que la Tunisie s\u2019emballe d\u00e8s lors que s\u2019engage une logique de transition. Un peu comme si le peuple tunisien devenait f\u00e9brile quand son avenir politique est incertain. Habib Bourguiba conna\u00eet son premier malaise cardiaque en 1975. A partir de cette ann\u00e9e, naissent de nouveaux partis d\u2019opposition, qui tous reprennent \u00e0 leur compte l\u2019accusation de n\u00e9potisme. Le pays serait tenu par quelques nantis, des proches du pr\u00e9sident, de son \u00e9pouse, de ses ministres. Tous promettent de mettre fin \u00e0 ce syst\u00e8me. Et c\u2019est bien entendu le mot d\u2019ordre que l\u2019on retrouve dans les manifestations.<\/p>\n<p><span><strong>\u2026 qui n\u2019\u00e9pargne pas la pr\u00e9sidence Ben Ali<\/strong><\/span> <\/p>\n<p><strong>Ben Ali arrive au pouvoir en 1987<\/strong>. Parmi ses priorit\u00e9s : le d\u00e9veloppement \u00e9conomique du pays et la lutte contre l\u2019islamisme qui gagne peu \u00e0 peu la soci\u00e9t\u00e9 tunisienne. Il me semble qu\u2019\u00e0 la lumi\u00e8re de son bilan, il est permis de dire que les deux objectifs ont \u00e9t\u00e9 atteint. S\u2019il para\u00eet peu politiquement correct en France de trouver des qualit\u00e9s \u00e0 Ben Ali,\u00a0 il faut tout de m\u00eame reconna\u00eetre que le syst\u00e8me de sant\u00e9 est plus performant aujourd\u2019hui qu\u2019\u00e0 son arriv\u00e9e au pouvoir. Le taux d\u2019analphab\u00e9tisme a recul\u00e9 sous sa pr\u00e9sidence. De nouvelles infrastructures ont vu le jour. L\u2019islamisme a \u00e9t\u00e9 davantage contenu que dans les pays voisins. Et les investisseurs \u00e9trangers sont attir\u00e9s par ce pays politiquement stable.<\/p>\n<p>Alors on me parle de n\u00e9potisme, d\u2019un \u2018<span><em><font>pays tenu par quelques familles<\/font><\/em><\/span>\u2018. Dois-je vous rappeler les amis l\u2019affaire de l\u2019<strong>Epad<\/strong> ? Dois-je vous parler de la vente de l\u2019<strong>hippodrome de Compi\u00e8gne<\/strong> ? De la <strong><span><font>consanguinit\u00e9 des conseils d\u2019administration<\/font><\/span> du CAC40<\/strong> ? Pourquoi ce qui est consid\u00e9r\u00e9 comme un mythe en France \u2013 \u2018<strong><em><span><font>les 200 familles<\/font><\/span><\/em><\/strong>\u2018 \u2013 n\u2019en serait-il pas un en Tunisie ? Sommes-nous en train de condamner en Tunisie ce que nous n\u2019osons remettre en cause dans nos syst\u00e8mes occidentaux ? Ce ne sont pas l\u00e0 des affirmations, mais des interrogations qui nous am\u00e8nent \u00e0 r\u00e9fl\u00e9chir davantage \u00e0 notre approche quelque fois \u00e9motive et souvent subjective face \u00e0 des \u00e9v\u00e9nements qui demandent un peu de recul.<\/p>\n<p>Alors parlons des \u00e9meutes parties de <strong>Sidi Bouzid<\/strong>. Il faut savoir que ce ne sont pas les premi\u00e8res de la pr\u00e9sidence Ben Ali. En 2000 d\u00e9j\u00e0, le Sud-Est tunisien s\u2019enflammait face \u00e0 la crainte d\u2019une hausse du prix du pain. Article de Taoufik Ben Brik \u00e0 relire <span><strong><font>ici<\/font><\/strong><\/span>. Les \u00e9tudiants et lyc\u00e9ens avaient embo\u00eet\u00e9 le pas \u00e0 leurs a\u00een\u00e9s. Je me souviens encore de cette foule et des slogans scand\u00e9s au <strong>Campus d\u2019El-Manar<\/strong>, pr\u00e8s duquel j\u2019habitais alors. Beaucoup criaient leur col\u00e8re face \u00e0 un avenir professionnel peu r\u00e9jouissant. Un enseignant professait : <em>\u2018Une jeune g\u00e9n\u00e9ration d\u2019\u00e9meutiers est apparue<\/em>\u2018.<\/p>\n<p>En janvier 2008, des mouvements sociaux \u00e9clataient dans la r\u00e9gion de <strong>Redeyef<\/strong> pr\u00e8s du bassin minier de Gafsa \u2013 l\u00e0 encore. Les manifestants d\u00e9noncent le ch\u00f4mage, le co\u00fbt de la vie, la corruption et le client\u00e9lisme. L\u2019un d\u2019eux est tu\u00e9 en juin d\u2019une balle en plein poumon. L\u2019ann\u00e9e suivante, la r\u00e9gion s\u2019embrase apr\u00e8s des<span><font>inondations meurtri\u00e8res<\/font><\/span>, la population accusant le pouvoir de ne pas \u00eatre \u00e0 la hauteur. Et en 2010, Sidi Bouzid et tutti quanti.<\/p>\n<p><span><strong>La Tunisie en phase de transition<\/strong><\/span> <\/p>\n<p>Ces \u00e9meutes peuvent-elles signer la fin de la pr\u00e9sidence Ben Ali ? R\u00e9ponse cat\u00e9gorique : non. Encore une fois, le peuple tunisien a horreur de l\u2019instabilit\u00e9 politique. S\u2019il est loin d\u2019\u00eatre servile et s\u2019il sait se soulever quand il l\u2019estime n\u00e9cessaire, il n\u2019a pas cette tradition de la R\u00e9volution que peut avoir le peuple fran\u00e7ais.<\/p>\n<p>Tout comme la transition s\u2019est faite en douceur en 1987, Habib Bourguiba c\u00e9dant plus ou moins volontairement la place \u00e0 Ben Ali \u2013 les historiens se d\u00e9chirent sur ce point \u2013 le sch\u00e9ma sera le m\u00eame cette fois-ci. Les \u00e9v\u00e9nements actuels en Tunisie en attestent : le pays est bel et bien entr\u00e9 en phase de transition, de transmission du pouvoir. Cela peut durer 5, 10 ou 15 ans, mais c\u2019est un fait. Une certaine \u00e9lite intellectuelle, politique et \u00e9conomique s\u2019agite actuellement pour jouer un r\u00f4le dans cette Tunisie de demain.<span><font>Quitte \u00e0 parler vite, trop vite, avant de regretter<\/font><\/span>. Quitte \u00e0 manipuler un mouvement initialement populaire. Il s\u2019agit pour cette <em>nomenklatura<\/em> d\u2019acc\u00e9l\u00e9rer le calendrier. De se rendre indispensable. De forcer la main du pr\u00e9sident. Qui lui semble d\u00e9termin\u00e9 \u00e0 faire les choses \u00e0 son rythme. D\u2019ailleurs, contrairement \u00e0 ce qu\u2019ont racont\u00e9 un certain nombre de confr\u00e8res, le remaniement partiel n\u2019est pas la cons\u00e9quence des \u00e9meutes de Sidi Bouzid. Il \u00e9tait pr\u00e9vu depuis l\u2019\u00e9t\u00e9 au moins.<\/p>\n<p>Quelle peut-\u00eatre la suite en Tunisie ? A court terme, il y a fort \u00e0 parier que l\u2019agitation m\u00e9diatique occidentale se d\u00e9gonfle. Des \u00e9meutiers seront interpell\u00e9s. Certains d\u2019entre eux jet\u00e9s en prison. A moyen terme, un nouveau remaniement aura lieu dans quelques mois, pour tester de nouveaux leaders, de nouveaux acteurs. A long terme, Zine el-Abidine Ben Ali s\u2019en ira. En laissant un pays moderne et \u00e9conomiquement solide au successeur qu\u2019il aura choisi. Et pour lequel les citoyens tunisiens auront sans doute vot\u00e9. Car si le tunisien sait se montrer contestataire, il sait aussi faire preuve de gratitude. Et il gardera en m\u00e9moire, tout comme il l\u2019a fait avec Habib Bourguiba, l\u2019image d\u2019un pr\u00e9sident qui a su inscrire la Tunisie dans l\u2019histoire contemporaine.<\/p>\n<p><strong><font>(Source: \u00ab\u00a0Lepost.fr\u00a0\u00bb le 7 janvier 2011)<\/font><\/strong><\/p>\n<p><strong><font>Lien: <\/font><\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.lepost.fr\/article\/2011\/01\/07\/2363089_crise-sociale-en-tunisie-quelques-cles-pour-mieux-comprendre.html<\/font><\/strong><\/a><\/p>\n<\/div>\n<p align=\"justify\">\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"center\"><font><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Tunisie : \u00ab Le peuple terrorise le gouvernement \u00bb<\/strong><\/font><\/h6>\n<p><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<p align=\"justify\"><font size=\"2\">La r\u00e9bellion tunisienne entre dans sa quatri\u00e8me semaine. Le peuple enrage contre l&rsquo;\u00c9tat, ce r\u00e9gime policier si cadenass\u00e9. La raison de cette ire populaire ? Un ch\u00f4mage qui grimpe&#8230;<\/font><\/p>\n<div align=\"justify\">La rue tunisienne entre dans sa quatri\u00e8me semaine de r\u00e9bellion. Deux, trois jours de turbulence pl\u00e9b\u00e9ienne n\u2019ont jamais fait de mal \u00e0 aucune dictature. Quand on entre dans la dur\u00e9e, la pouss\u00e9e de fi\u00e8vre se change en pathologie lourde. Ce n\u2019est plus une r\u00e9volte, c\u2019est autre chose. Quoi ? \u00a0 Les touristes ne per\u00e7oivent pas toujours que la Tunisie, sous un dehors convivial et bon enfant, est gouvern\u00e9e par un des r\u00e9gimes policiers les plus cadenass\u00e9s de ce monde. Exemple : Vous \u00eates coinc\u00e9 dans un embouteillage d\u00fb au passage du cort\u00e8ge pr\u00e9sidentiel. Vous t\u00e9l\u00e9phonez \u00e0 votre petite amie pour vous excuser du retard : <em>\u00ab Je suis bloqu\u00e9 par ce con de pr\u00e9sident. <\/em>\u00bb Dix minutes plus tard, les flics interceptent votre voiture \u00e0 un barrage, vous conduisent au poste o\u00f9 l\u2019on vous rosse comme pl\u00e2tre \u00e0 titre d\u2019avertissement. Bien heureux si vous ne finissez pas dans un cul de basse-fosse. Voil\u00e0 le sort des bourgeois voitur\u00e9s. \u00a0 Quant au bas-peuple, rouable et tabassable \u00e0 merci, il ne se risque ni \u00e0 un mot, ni \u00e0 un geste de travers, il sait trop ce qui l\u2019attend. Pour les dix millions de Tunisiens, on compte plus de fonctionnaires de s\u00e9curit\u00e9 que pour les 65 millions de Fran\u00e7ais. Contr\u00f4l\u00e9 par la terreur et les guetteurs, le pays est p\u00e9trifi\u00e9 devant un pr\u00e9sident, lui-m\u00eame poulet de haute vol\u00e9e, qui conna\u00eet la musique. Pas une fissure de libert\u00e9 autre que le simulacre de multipartisme propre \u00e0 faire taire des ambassadeurs occidentaux au d\u00e9mocratisme chatouilleux. Appuy\u00e9 sur sa r\u00e9putation d\u2019Eden touristique et de champion des succ\u00e8s \u00e9conomiques, le r\u00e9gime baigne depuis une vingtaine d\u2019ann\u00e9es dans une b\u00e9atitude de tous les instants. La famille pr\u00e9sidentielle se remplit les poches, la poign\u00e9e de d\u00e9mocrates casse-cous en prend plein la gueule, les ch\u00f4meurs et salari\u00e9s mis\u00e9reux cr\u00e8vent la dalle ou sombrent en immigr\u00e9s clandestins et les vacanciers bronzent. L\u2019ordre r\u00e8gne, que demande le peuple ? \u00a0 L\u2019ordre r\u00e9gnait. Le 14 d\u00e9cembre, le peuple a ouvert sa grande gueule et ne l\u2019a pas boucl\u00e9 \u00e0 ce jour. Une Intifada \u00e0 la mode de chez nous d\u00e9ferle sur un r\u00e9gime qui ne sait plus ou mettre de la t\u00eate. Sousse, Sfax, Gab\u00e8s, toutes villes r\u00e9put\u00e9es pour leur docilit\u00e9 exemplaire, entre en r\u00e9bellion. Les premiers jours, la police, pensant bien faire, a tir\u00e9 \u00e0 balles r\u00e9elles, histoire de tuer l\u2019Intifada dans l\u2019\u0153uf. Les deux morts attis\u00e8rent au contraire la rage. Manifestations, gr\u00e8ves de lyc\u00e9ens, avocats en mutinerie, intellectuels d\u00e9cha\u00een\u00e9s, syndicats mobilis\u00e9s, vol\u00e9es de lacrymos, diplomates \u00e9chevel\u00e9s, ministres affol\u00e9s, l\u2019impeccable tyrannie prend le visage du bateau ivre. Et tout \u00e7a pourquoi ? Parce qu\u2019un jeune homme s\u2019est immol\u00e9 par le feu.  Mohamed Bouazizi, 25 ans \u00e0 Sidi bou Zid, ce maudit mardi, avait comme \u00e0 l\u2019accoutum\u00e9e, expos\u00e9 son \u00e9talage de l\u00e9gumes sur le trottoir. Eduqu\u00e9 \u00e0 l\u2019Universit\u00e9, Mohamed, seul soutien de sa m\u00e8re et de la marmaille, n\u2019a pas d\u00e9nich\u00e9 d\u2019autre job. La moiti\u00e9 des jeunes sont au ch\u00f4mage dans cette ville cern\u00e9e de montagne, coup\u00e9e du monde au fin fond d\u2019une cuvette ; lui tirera quelques dinars de ses tomates. Mais la police s\u2019en m\u00eame. Papiers ! Marchandises saisies. Mohamed au d\u00e9sespoir. Comment acheter le pain, l\u2019huile et la semoule ? Comment se venger des flics ? Il n\u2019a qu\u2019une balle \u00e0 tirer\u00a0 : sa vie. Il s\u2019asperge d\u2019essence et flambe. On se pr\u00e9cipite \u00e0 son secours. Trop tard. La ville a tout compris. Elle aussi bout de col\u00e8re. Depuis vingt ans elle serre les poings, elle grince des dents et patiente en silence. Cette fois c\u2019en est trop, la rage \u00e9clate. A Sidi bou Zid, dans les villes voisines, plus loin, jusqu\u2019\u00e0 s\u2019\u00e9tendre \u00e0 tout le pays. En s\u2019enflammant, Mohamed a mis le feu au pays. Les balles, les morts n\u2019y font rien. Par un prodige suffocant, la peur s\u2019\u00e9vanouit. Le gouvernement terrorisait le peuple et voil\u00e0 que le peuple terrorise le gouvernement. Par une inconcevable op\u00e9ration des dieux, la peur change de camp. La police tremble, la rue met les menottes au pouvoir. \u00a0 Rien n\u2019est plus \u00e9tranger \u00e0 la Tunisie et au Maghreb que l\u2019immolation par le feu. Par quelle voie myst\u00e9rieuse l\u2019id\u00e9e a-t-elle pu s\u2019infiltrer jusqu\u2019\u00e0 Sidi bou Zid, jusqu\u2019au bon Mohamed Bouazizi (que D. ait son \u00e2me), nul ne le saura jamais. Trois jours plus tard, un autre jeune homme se suicide en s\u2019accrochant \u00e0 un fil de haute tension. Une jeune maman cherche \u00e0 en faire autant serr\u00e9e contre ses deux enfants (on coupe \u00e0 temps l\u2019\u00e9lectricit\u00e9 de la ville). Et si un jour cent enfants, main dans la main, s\u2019\u00e9lectrocutaient pour protester contre la mis\u00e8re de ce temps ? \u00a0 La Tunisie est cit\u00e9e partout en exemple d\u2019une r\u00e9ussite \u00e9clatante de la mondialisation. A bon entendeur. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\"><strong><font>Guy Sitbon<\/font> &#8211; Marianne<\/strong><\/div>\n<div align=\"justify\">\n<address><strong><font>(Source:<\/font><\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.marianne2.fr<\/font><\/strong><\/a><strong><font>\u00a0le 7 Janvier 2011)<\/font><\/strong><\/address>\n<address><strong><font>Lien: <\/font><\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.marianne2.fr\/Tunisie-Le-peuple-terrorise-le-gouvernement_a201383.html<\/font><\/strong><\/a><\/address>\n<\/div>\n<p align=\"justify\"><strong><\/strong><\/p>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><font><span lang=\"FR\"><strong><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\">R\u00e9volte en Tunisie: L&rsquo;immolation par le feu \u00abest devenu un symbole\u00bb pour les manifestants<\/font><\/h6>\n<p><\/strong><\/span><\/font><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<p align=\"justify\"><span lang=\"FR\">DECRYPTAGE &#8211; Apr\u00e8s trois semaines de manifestations de jeunes tunisiens&#8230;<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Vendredi, cela fera trois semaines que la<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Tunisie<\/a> est secou\u00e9e par des <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">manifestations<\/a>. 20minutes.fr fait le point sur ce mouvement qui a d\u00e9j\u00e0 fait quatre morts.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Que s\u2019est-il pass\u00e9 le 17 d\u00e9cembre \u00e0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Sidi Bouzid<\/a>?<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Ce jour-l\u00e0, Mohamed Bouazizi, un vendeur ambulant de 26 ans, s\u2019est asperg\u00e9 d&rsquo;essence et a tent\u00e9 de s&rsquo;immoler par le feu devant la pr\u00e9fecture. La police municipale venait de lui confisquer sa charrette de fruits et l\u00e9gumes parce qu&rsquo;il n&rsquo;avait pas les autorisations n\u00e9cessaires.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Pourquoi cet incident d\u00e9clenche autant de protestations?<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">La charrette confisqu\u00e9e \u00e9tait le seul gagne-pain du jeune homme, dipl\u00f4m\u00e9 mais ch\u00f4meur. Cet incident est devenu un symbole pour les jeunes ch\u00f4meurs dipl\u00f4m\u00e9s, qui ont manifest\u00e9 dans la r\u00e9gion de Sidi Bouzid d\u00e8s le 19 d\u00e9cembre contre le ch\u00f4mage et la vie ch\u00e8re. Une <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">vague de manifestations<\/a> sans pr\u00e9c\u00e9dent &#8211; mais dont on ignore le nombre exact de participants &#8211; a alors d\u00e9ferl\u00e9 dans tout le pays. Des d\u00e9fil\u00e9s et des rassemblements ont eu lieu \u00e0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Thala<\/a>, \u00e0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Kairouan<\/a>, \u00e0<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Sousse<\/a> ou m\u00eame dans la capitale,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Tunis<\/a>. La r\u00e9pression a \u00e9t\u00e9 tr\u00e8s dure, les heurts entre les manifestants et la police ont ainsi fait quatre morts en trois semaines.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Pour quelle raison ces<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">manifestations<\/a> sont-elles aussi f\u00e9d\u00e9ratrices?<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">\u00abL\u2019immolation a \u00e9t\u00e9 l\u2019\u00e9l\u00e9ment d\u00e9clencheur, dans un contexte \u00e9conomique et social particuli\u00e8rement dur\u00bb, analyse <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Olfa Lamloum<\/a>, chercheur politologue franco-tunisienne \u00e0 l&rsquo;<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Institut frran\u00e7ais du Proche-Orient (Ifpo)<\/a>. Le taux de ch\u00f4mage en <a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Tunisie<\/a> est de 14%, selon les chiffres officiels &#8211; \u00abdes chiffres de propagande\u00bb selon Olfa Lamloum. Et les jeunes, m\u00eame qualifi\u00e9s, sont particuli\u00e8rement touch\u00e9s. Ainsi, parmi les manifestants tu\u00e9s, il y avait \u00abun ing\u00e9nieur en informatique et un professeur de maths\u00bb, souligne Olfa Lamloum.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">\u00abCela en dit long sur le ras-le-bol de la population dans son ensemble: ce ne sont pas des jeunes socialement marginaux, mais qui ont fait des \u00e9tudes. Jusque-l\u00e0, le pr\u00e9sident Ben Ali avait toujours r\u00e9ussi \u00e0 r\u00e9primer les mouvements sociaux, mais aujourd\u2019hui il y a un effet cumulatif. La mobilisation prend de telles proportions car les gens n\u2019ont plus rien \u00e0 perdre: apr\u00e8s des ann\u00e9es de privation et de r\u00e9pression, ils ont perdu leur dignit\u00e9, leur droit \u00e0 s\u2019exprimer, \u00e0 voter, et se sont m\u00eame tus sur la corruption \u00e0 grande \u00e9chelle qui gangr\u00e8ne le pays.\u00bb<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Pourquoi le pouvoir tunisien parle d&rsquo;instrumentalisation?<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">D\u00e9j\u00e0 parce que les<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">manifestations<\/a> sont rares dans le pays, dirig\u00e9 depuis 23 ans d\u2019une main de fer par le pr\u00e9sident Zine el Abidine ben Ali. \u00abLe malaise des dirigeants est palpable parce qu\u2019ils savent que pour la premi\u00e8re fois depuis longtemps, ils sont face \u00e0 un mouvement populaire de masse\u00bb, indique Olfa Lamloum.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">De plus, les manifestants sont soutenus par le syndicat de l&rsquo;union g\u00e9n\u00e9rale des travailleurs et par des militants des droits de l&rsquo;homme. Des soutiens qui ont incit\u00e9, le 28 d\u00e9cembre, le pr\u00e9sident Ben Ali \u00e0 d\u00e9noncer \u00abl&rsquo;ampleur exag\u00e9r\u00e9e qu&rsquo;ont pris ces \u00e9v\u00e9nements \u00e0 cause de leur instrumentalisation politique par certaines parties qui ne veulent pas le bien de leur patrie\u00bb.<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\">Ce soul\u00e8vement risque-t-il de durer encore longtemps?<\/span><\/p>\n<p align=\"justify\"><span lang=\"FR\"><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Mohamed Bouazizi est mort de ses blessures mardi soir <\/a>et doit \u00eatre enterr\u00e9 \u00e0 Sidi Bouzid ce mercredi. Un d\u00e9c\u00e8s qui peut \u00abpeut-\u00eatre assurer la continuit\u00e9 du mouvement\u00bb sur le sol tunisien, selon Olfa Lamloum. Des<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">manifestations<\/a> de soutien sont par ailleurs pr\u00e9vues en Europe, au Canada, et en Alg\u00e9rie jeudi. A Paris, un rassemblement doit \u00eatre organis\u00e9 place de la Fontaine des Innocents.<\/span><\/p>\n<div align=\"justify\"><strong>(Source : \u00ab 20Minutes.fr \u00bb Le 06-01-2011) Lien : http:\/\/www.20minutes.fr\/article\/647834\/monde-revolte-tunisie-immolation-feu-est-devenu-symbole-manifestants <\/p>\n<hr\/>\n<p><\/strong><\/p>\n<p align=\"center\"><span lang=\"FR\"><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\">Tunisie Le dipl\u00f4m\u00e9 ch\u00f4meur qui s\u2019\u00e9tait immol\u00e9 par le feu est d\u00e9c\u00e9d\u00e9 mercredi<\/font><\/h6>\n<p><\/span><\/p>\n<p align=\"center\"><font><span lang=\"FR\">\u00a0\u00ab Plus rien ne sera comme avant \u00bb<\/span><\/font><\/p>\n<p>\u00a0<\/p>\n<hr\/>\n<p>\u00a0<\/p>\n<p><b>LOOS,BAUDOUIN; RENETTE,ERIC<\/b><\/p>\n<p>\u00a0Jeudi 6 janvier 2011<\/p>\n<p>Son geste d\u00e9sesp\u00e9r\u00e9 avait lanc\u00e9 quinze jours de convulsions sociales sporadiques \u00e0 travers toute la Tunisie. Mohamed Bouazizi, 26 ans, est mort dans la nuit de mardi \u00e0 mercredi au centre des grands br\u00fbl\u00e9s et de traumatologie de Ben Arous, pr\u00e8s de Tunis, o\u00f9 il avait \u00e9t\u00e9 hospitalis\u00e9 apr\u00e8s sa tentative de suicide par le feu le 17 d\u00e9cembre \u00e0 Sidi Bouzid. Le jeune homme, dipl\u00f4m\u00e9 au ch\u00f4mage, avait ainsi r\u00e9pondu au harc\u00e8lement policier dont il faisait l\u2019objet comme vendeur ambulant \u00e0 la sauvette.<\/p>\n<p><i>\u00ab On peut supposer que le r\u00e9gime reprendra les choses en main,<\/i> nous explique par t\u00e9l\u00e9phone depuis Tunis Kh\u00e9ma\u00efs Chammari, v\u00e9t\u00e9ran de l\u2019opposition et des droits de l\u2019homme, <i>mais il y aura clairement un \u201cavant\u201d et un \u201capr\u00e8s\u201d Sidi Bouzid. Au niveau de la population, quelque chose a chang\u00e9. \u00bb<\/i> Les manifestations spontan\u00e9es de col\u00e8re et d\u2019indignation qui suivirent l\u2019immolation de Mohamed Bouazizi ont en effet largement d\u00e9pass\u00e9 le cadre de l\u2019\u00e9v\u00e9nement, les foules s\u2019en prenant notamment aux symboles du pouvoir comme des permanences du RCD, le parti quasi unique. Au moins quatre morts, dont deux par balles, sont \u00e0 d\u00e9plorer.<\/p>\n<p><i>\u00ab J\u2019en tire deux conclusions, <\/i>pr\u00e9cise notre interlocuteur :<i> l\u2019image de stabilit\u00e9 socio-\u00e9conomique ch\u00e8re au r\u00e9gime a \u00e9t\u00e9 s\u00e9rieusement \u00e9corn\u00e9e et la d\u00e9nonciation de la corruption, obs\u00e9dante pour les Tunisiens, a \u00e9t\u00e9 le mot d\u2019ordre le plus r\u00e9pandu des protestataires qui ne supportent plus la mainmise du r\u00e9gime sur l\u2019\u00e9conomie et l\u2019enrichissement de certains. \u00bb<\/i><\/p>\n<p>La corruption ! Le r\u00e9gime du pr\u00e9sident Zine el-Abidine Ben Ali s\u2019assimile depuis longtemps \u00e0 cette d\u00e9rive, qui est g\u00e9n\u00e9ralis\u00e9e mais aussi et surtout le fait d\u2019une minorit\u00e9 affairiste gravitant dans et autour de la \u00ab famille \u00bb. Ce ne sont pas des observateurs ou journalistes \u00e9trangers mal intentionn\u00e9s, comme le d\u00e9nonce le gouvernement tunisien, qui le disent : les r\u00e9v\u00e9lations du site WikiLeaks montrent que les diplomates am\u00e9ricains \u00e0 Tunis ont largement \u00e9voqu\u00e9 ce ph\u00e9nom\u00e8ne dans leurs t\u00e9l\u00e9grammes vers Washington ces derni\u00e8res ann\u00e9es, exemples concrets \u00e0 l\u2019appui.<\/p>\n<p><i>\u00ab Ben Ali et son r\u00e9gime ont perdu le contact avec le peuple tunisien,<\/i> \u00e9crivait ainsi l\u2019ambassadeur US en 2008. <i>Ils ne tol\u00e8rent pas de conseils ou de critiques, fussent-elles nationales ou internationales. Ils s\u2019appuient de plus en plus sur le contr\u00f4le par la police et se concentrent sur la pr\u00e9servation du pouvoir. La corruption dans les premiers cercles s\u2019accentue. M\u00eame les Tunisiens moyens sont \u00e0 pr\u00e9sent tr\u00e8s conscients de cela, et les voix de leurs plaintes s\u2019amplifient [\u2026]. Les Tunisiens n\u2019aiment vraiment pas, voire \u00e9prouvent de la haine envers la premi\u00e8re dame Leila Trabelsi et sa famille. En priv\u00e9, les opposants au r\u00e9gime se moquent d\u2019elle. M\u00eame dans les cercles proches du pouvoir, on exprime la consternation face \u00e0 ses frasques. Entre-temps, la col\u00e8re s\u2019intensifie face au taux de ch\u00f4mage qui grimpe et aux in\u00e9galit\u00e9s r\u00e9gionales. En cons\u00e9quence, les risques pour la stabilit\u00e9 \u00e0 long terme du r\u00e9gime sont en augmentation \u00bb <\/i>(traduction du site nawaat.org). Voil\u00e0 de la pr\u00e9monition.<\/p>\n<p>Il reste malais\u00e9 de jauger la capacit\u00e9 d\u2019amendement du r\u00e9gime. <i>\u00ab A moins de fortes pressions de la rue ou des alli\u00e9s \u00e9trangers<\/i> (Paris, Rome et Madrid, surtout, NDLR), <i>on voit mal le pouvoir d\u00e9cider une vraie ouverture, <\/i>estime Kh\u00e9ma\u00efs Chammari. <i>Malgr\u00e9 l\u2019\u00e9pisode tragique et inqui\u00e9tant que le pays vient de vivre, il n\u2019y a pas de volont\u00e9 politique en ce sens. \u00bb<\/i><\/p>\n<p>Alors, la r\u00e9ponse du r\u00e9gime, en dehors de \u00ab mesurettes \u00bb, comme un d\u00e9bat t\u00e9l\u00e9vis\u00e9 sans langue de bois rest\u00e9 sans lendemain ou le limogeage de l\u2019un ou l\u2019autre sous-fifre f\u00fbt-il ministre, devrait rester\u2026 la force. Comme toujours. Ainsi en va-t-il d\u00e9j\u00e0 de la r\u00e9pression contre les internautes (Facebook a jou\u00e9 un r\u00f4le de catalyseurs dans les \u00e9v\u00e9nements r\u00e9cents). Une blogueuse tunisienne pourtant visiblement peu politis\u00e9e \u00e9crivait ceci ce dimanche : <i>\u00ab Autour de moi, beaucoup de personnes me f\u00e9licitent pour mon \u201ccourage\u201d, alors que moi, je meurs de trouille. J\u2019ai peur au r\u00e9veil, quand je partage des liens, quand j\u2019\u00e9cris, quand je parle, quand un inconnu m\u2019interpelle dans la rue, et la peur me poursuit jusqu\u2019\u00e0 en perdre le sommeil. (\u2026) Quand j\u2019ai demand\u00e9 \u00e0 la femme de m\u00e9nage ce que pensaient les gens de ce qui se passe actuellement \u00e0 Sidi Bouzid, elle m\u2019a r\u00e9pondu que dans le bus personne n\u2019osait en parler car tout le monde a peur qu\u2019il y ait des \u201cintrus\u201d qui \u00e9coutent. \u00bb<\/i><\/p>\n<p>Un internaute lui r\u00e9pondait, le m\u00eame jour : <i>\u00ab Ce qui est positif dans les \u00e9v\u00e9nements de ces derniers jours, c\u2019est que c\u2019est des mouvements spontan\u00e9s\u2026 Aucun parti politique ou organisation n\u2019est derri\u00e8re. Cela veut dire que la peur n\u2019est plus la m\u00eame\u2026 Tu en es le meilleur exemple : malgr\u00e9 toute la peur que tu ressens, tu continues \u00e0 t\u2019exprimer. Et c\u2019est le cas de milliers d\u2019autres comme toi \u00bb<\/i>.<\/p>\n<p><strong><font>(Source: \u00ab\u00a0Le Soir\u00a0\u00bb (Quotidien &#8211; Belgique) le 6 janvier 2011)<\/font><\/strong><\/p>\n<\/div>\n<div align=\"justify\"><span lang=\"FR\"><font><strong><\/p>\n<p>\u00a0<\/p>\n<hr\/>\n<p> \u00a0<\/strong><font><\/p>\n<div align=\"center\"><span><strong><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\">La Tunisie vers l\u2019inconnu<\/font><\/h6>\n<p><\/strong><\/span><\/div>\n<div align=\"center\"><span><strong><font size=\"3\"><\/p>\n<hr\/>\n<p><\/font><\/strong><\/span><\/div>\n<div align=\"justify\">Entretien de Souhayr Belhassen, pr\u00e9sidente de la F\u00e9d\u00e9ration internationale des droits de l\u2019homme (FIDH)<\/div>\n<div align=\"justify\"><span><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>vendredi 7 janvier 2011<\/font><\/a><span> \/ par<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>Djamel Belayachi<\/font><\/a><\/span><\/span><\/div>\n<map>\n<area coords=\"0,0,12,12\" shape=\"rect\" target=\"_blank\" title=\"Augmenter la police\"\/>\n<area coords=\"15,0,27,12\" shape=\"rect\" target=\"_blank\" title=\"Diminuer la police\"\/>\n<area coords=\"33,0,44,12\" shape=\"rect\" target=\"_blank\" title=\"Imprimer l'article\"\/>\n<area coords=\"51,0,62,12\" shape=\"rect\" target=\"_blank\" title=\"Envoyer l'article \u00e0 un ami\"\/>\n<area coords=\"69,0,80,12\" href=\"http:\/\/reaction21667.html\" shape=\"rect\" target=\"_blank\" title=\"R\u00e9agir \u00e0 l'article\"\/><\/map>\n<div align=\"justify\">\n<table>\n<tr>\n<td>\u00a0<\/td>\n<td valign=\"top\"><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><\/a>\u00a0<\/td>\n<td width=\"6\">\u00a0<\/td>\n<td valign=\"top\">\u00a0<\/td>\n<td width=\"6\">\u00a0<\/td>\n<td>\u00a0<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<div align=\"justify\">\u00a0L\u2019agitation sociale se poursuit en Tunisie. Les avocats ont observ\u00e9 jeudi, dans le calme, une gr\u00e8ve dans plusieurs villes. Le m\u00eame jour, \u00e0 la cit\u00e9 universitaire El-Ghazali de Sousse, ville portuaire de l\u2019Est, une nouvelle manifestation \u00e9tudiante a \u00e9t\u00e9 durement r\u00e9prim\u00e9e par les forces de l\u2019ordre. Trois semaines apr\u00e8s le suicide d\u2019un jeune ch\u00f4meur \u00e0 Sidi Bouzid, les jeunes Tunisiens ne d\u00e9col\u00e8rent pas. Une situation qui inqui\u00e8te Souhayr Belhassen, pr\u00e9sidente de la F\u00e9d\u00e9ration internationale des droits de l\u2019homme (FIDH) et de la Ligue tunisienne des droits de l\u2019Homme.<\/div>\n<p align=\"justify\">Le jeune Mohamed Bouazizi, dont l\u2019immolation par le feu le 17 d\u00e9cembre \u00e0 Sidi Bouzid (centre-ouest), a d\u00e9clench\u00e9 une<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>vague de manifestations<\/font><\/strong><\/a> \u00e0 travers le pays, a \u00e9t\u00e9 inhum\u00e9 mercredi, apr\u00e8s avoir succomb\u00e9 \u00e0 ses blessures la veille dans un h\u00f4pital de Tunis. \u00ab\u00a0Je ne sais pas dans quoi la Tunisie va basculer\u00a0\u00bb, s\u2019interroge Souhayr Belhassen, qui nous a accord\u00e9 un entretien.<\/p>\n<div align=\"justify\">\n<div>\n<div>\u00a0 <\/p>\n<div><a href=\"http:\/\/\/\" target=\"_blank\" title=\"JPEG - 7.1 ko\" rel=\"noopener\"><img decoding=\"async\" border=\"0\" height=\"15\" src=\"http:\/\/www.afrik.com\/images\/loupe.png\" width=\"16\"\/><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Quelles nouvelles vous sont parvenues jeudi de Tunisie\u00a0? Souhayr Belhassen\u00a0:<\/strong> Selon les informations qui nous sont parvenues, la gr\u00e8ve des avocats annonc\u00e9e en solidarit\u00e9 avec les habitants de Sidi Bouzid a connu une participation maximale. Les avocats \u00e9taient rassembl\u00e9s \u00e0 l\u2019int\u00e9rieur du tribunal d\u2019instance de Tunis, et portaient leur robe en signe de solidarit\u00e9 avec les habitants de Sidi Bouzid et pour d\u00e9noncer la r\u00e9pression d\u2019une manifestation de leurs confr\u00e8res, le 31 d\u00e9cembre, en soutien \u00e0 la population de cette r\u00e9gion. La FIDH a envoy\u00e9 une mission de solidarit\u00e9 du barreau de Paris et du R\u00e9seau euro-m\u00e9diterran\u00e9en des droits de l\u2019Homme. L\u2019entr\u00e9e \u00e9tait tr\u00e8s filtr\u00e9e mais les d\u00e9l\u00e9gu\u00e9s ont pu entrer sans probl\u00e8me. Par ailleurs, un mouvement d\u2019\u00e9tudiants a \u00e9t\u00e9 violemment dispers\u00e9 \u00e0 Sousse, qui est une station baln\u00e9aire situ\u00e9e \u00e0 pr\u00e8s de 150 km de Tunis. Un centre universitaire, El-Ghazali, a \u00e9t\u00e9 envahi par les forces de l\u2019ordre qui ont dispers\u00e9 violemment les manifestants. La police s\u2019est \u00e9galement introduite aux dortoirs des filles dont certaines ont \u00e9t\u00e9 molest\u00e9es. On ne sait pas s\u2019il y a des bless\u00e9s ou pas. Ces deux mouvements refl\u00e8tent ce qui s\u2019est pass\u00e9 le 17 d\u00e9cembre,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font> l\u2019immolation du jeune Mohamed Bouazizi<\/font><\/strong><\/a> pour protester contre le vol de son \u00e9tal de fruits.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Pourquoi les manifestations ont-elles pris de telles proportions\u00a0?  Souhayr Belhassen\u00a0:<\/strong> C\u2019est un mouvement spontan\u00e9 des jeunes qui sont touch\u00e9s dans leur quotidien, un mouvement dont la grande nouveaut\u00e9 est qu\u2019<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>il mobilise sur Internet<\/font><\/strong><\/a>. A travers les r\u00e9seaux sociaux, c\u2019est une solidarit\u00e9 agissante qui se fait. Cela permet une mobilisation, des \u00e9changes entre les internautes. Cette force de mobilisation et cette imm\u00e9diatet\u00e9 est quelque chose de compl\u00e8tement nouveau que les autorit\u00e9s ne savent pas g\u00e9rer. Ces explosions de col\u00e8re \u00e0 r\u00e9p\u00e9tition, l\u2019Etat n\u2019arrive pas \u00e0 les ma\u00eetriser. C\u2019est le ras-le-bol des jeunes. Les manifestations, et c\u2019est fondamental, d\u00e9bordent les autorit\u00e9s, et d\u00e9bordent m\u00eame les traditionnels partis de l\u2019opposition. Ce sont des mouvements spontan\u00e9s qui ne mobilisent que sur Internet, \u00e0 travers les r\u00e9seaux sociaux, comme Facebook et<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>Twitter<\/font><\/strong><\/a>.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Pensez-vous que le r\u00e9gime de Ben Ali soit en danger\u00a0? Peut-on parler d\u2019un avant et d\u2019un apr\u00e8s Sidi Bouzid\u00a0?  Souhayr Belhassen\u00a0:<\/strong> Nous sommes dans l\u2019inconnu. C\u2019est vrai qu\u2019il y a un mouvement incroyable de solidarit\u00e9 avec les jeunes Tunisiens sur Internet. C\u2019est la premi\u00e8re fois que des hackers d\u00e9truisent les sites du gouvernement. Mais je ne peux pas pour autant dire qu\u2019il y a un avant et un apr\u00e8s Sidi Bouzid. Je ne me pose pas cette question. Des lyc\u00e9ens ont incendi\u00e9 les locaux du RCD (parti au pourvoir) lors des affrontements de Thala (mardi, ndlr). On n\u2019avait jamais vu cela. Le syndicat des travailleurs tunisiens, l\u2019Union g\u00e9n\u00e9rale tunisienne du travail (UGTT), est clairement partag\u00e9e entre la base qui soutient les manifestants et les dirigeants, proches du pouvoir, qui cherchent \u00e0 juguler le mouvement. Mais je doute que ces manifestations soient le d\u00e9but de la fin du r\u00e9gime de Ben Ali. Tant que les alli\u00e9s de la Tunisie, la France en premier lieu et les pays Europ\u00e9ens, ne bougent pas, ils donnent du temps de survie au r\u00e9gime.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Est-ce qu\u2019il y a eu des arrestations lors des affrontements de Thala\u00a0?  Souhayr Belhassen\u00a0:<\/strong> La police a arr\u00eat\u00e9 des manifestants et les a rel\u00e2ch\u00e9s. Je me demande si ce n\u2019\u00e9tait pas pour les ficher et si le v\u00e9ritable coup de filet ne va pas venir une fois que la situation sera calme.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Pourquoi les pays europ\u00e9ens ne r\u00e9agissent-ils pas\u00a0?  Souhayr Belhassen\u00a0:<\/strong> Il y a des int\u00e9r\u00eats. La Tunisie est un filtre en ce qui concerne l\u2019immigration. Les dirigeants tunisiens sont plus commodes que les Alg\u00e9riens et moins impr\u00e9visibles que Kadhafi.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: Comment expliquez-vous qu\u2019on en arrive \u00e0 s\u2019immoler pour protester contre le ch\u00f4mage\u00a0?  Souhayr Belhassen\u00a0:<\/strong> Parce qu\u2019il s\u2019agit d\u2019un d\u00e9sespoir r\u00e9el. C\u2019est le v\u00e9cu des gens. Cela veut dire qu\u2019on n\u2019a r\u00e9ellement plus rien \u00e0 perdre. Hier encore (mercredi), un jeune homme expuls\u00e9 de France s\u2019est immol\u00e9 \u00e0 Kebili, dans le sud du pays. Il a \u00e9t\u00e9 transport\u00e9 \u00e0 l\u2019h\u00f4pital de Sfax. Cet acte, comme celui de Mohamed Bouazizi, illustre le d\u00e9sespoir des jeunes qui ne trouvent pas de r\u00e9ponse \u00e0 leur probl\u00e8me. La r\u00e9ponse, ce n\u2019est pas de leur trouver du travail mais d\u2019\u00eatre juste avec eux et leur dire la v\u00e9rit\u00e9. Au bac, le taux de r\u00e9ussite atteint 90%, ce qui est absolument aberrant. Les universit\u00e9s sont devenues de vraies fabriques de ch\u00f4meurs.<\/p>\n<p align=\"justify\"><strong>Afrik.com\u00a0: La Tunisie est pourtant cit\u00e9e en exemple pour ses performances \u00e9conomiques. Et selon les chiffres officiels le taux de ch\u00f4mage se situe \u00e0 14%&#8230; Souhayr Belhassen\u00a0:<\/strong> Je pense que le ch\u00f4mage se situe plut\u00f4t autour de 22 \u00e0 25%. Il s\u2019est aggrav\u00e9 ces derni\u00e8res ann\u00e9es, avec la crise mondiale et les autorit\u00e9s restent autistes. L\u2019investissement \u00e9tranger \u00e0 recul\u00e9 en Tunisie au profit de march\u00e9s asiatiques plus attractifs. La corruption d\u00e9courage elle aussi les investisseurs. La Tunisie n\u2019est plus ce pays qu\u2019on qualifiait de \u00ab\u00a0Tigre de Maghreb\u00a0\u00bb.  <strong><font>(Source: Afric.com le 7 janvier 2011)<\/font><\/strong><\/p>\n<p align=\"justify\"><strong><font>Lien: <\/font><\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.afrik.com\/article21667.html<\/font><\/strong><\/a><\/p>\n<\/p>\n<p><\/font><\/font><\/span><\/p>\n<hr\/>\n<p> \u00a0<\/p><\/div>\n<\/div>\n<div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><font>\u00a0<\/font><strong>La g\u00e9n\u00e9ration Facebook plus forte que Ben Ali<\/strong><\/font><\/h6>\n<\/div>\n<div><font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div><font face=\"Arial\">Depuis que Mohamed Bouazizi s\u2019est immol\u00e9 par le feu le 17 d\u00e9cembre, la r\u00e9gion de Sidi Bouzid conna\u00eet de graves troubles. Pour le journaliste et \u00e9crivain tunisien Taoufik Ben Brik, le r\u00e9gime de Ben Ali commence \u00e0 se fissurer. <\/font><\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\n<div><font face=\"Arial\">Depuis que Mohamed Bouazizi, un vendeur de fruits et l\u00e9gumes, s\u2019est immol\u00e9 par le feu le 17 d\u00e9cembre apr\u00e8s que la police municipale lui a confisqu\u00e9 sa marchandise, la r\u00e9gion de Sidi Bouzid conna\u00eet de graves troubles. Des manifestations de soutien ont eu lieu dans plusieurs villes de Tunisie, <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\">faisant trois morts.<\/font><\/a><font face=\"Arial\"> Un vent de contestation souffle, fait tr\u00e8s rare dans un pays o\u00f9 l\u2019opposition est b\u00e2illonn\u00e9e. Face aux troubles, le pr\u00e9sident Ben Ali, au pouvoir depuis 1987, a remani\u00e9 son gouvernement le 29 d\u00e9cembre et limog\u00e9 des gouverneurs de r\u00e9gion. Pour le journaliste et \u00e9crivain tunisien <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\">Taoufik Ben Brik<\/font><\/a><font face=\"Arial\">, le r\u00e9gime commence \u00e0 se fissurer. <\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>Mohamed Bouazizi, le jeune homme qui s&rsquo;\u00e9tait immol\u00e9 le 17 d\u00e9cembre \u00e0 Sidi Bouzid est d\u00e9c\u00e9d\u00e9 le 5 janvier. <\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Cette mort va donner un second souffle au mouvement de contestation. Ces derniers temps, cette contestation s&rsquo;exprimait surtout \u00e0 travers l&rsquo;Internet. Cette cyberguerre, on la veut aussi sur le terrain. La Tunisie avait besoin de son martyr. Maintenant, elle l&rsquo;a.<\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>De quels moyens disposent les journalistes pour rendre compte des \u00e9v\u00e9nements de Sidi Bouzid?<\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Personne n\u2019a foul\u00e9 la \u00ablune\u00bb Sidi Bouzid. C\u2019est la cit\u00e9 interdite. Interdite \u00e0 tous ceux et celles qui savent \u00e9bruiter de scandaleuses v\u00e9rit\u00e9s sur la place publique. Des \u00e9bruiteurs, observateurs, journalistes; tous sont pris en chasse. Mais les autorit\u00e9s tunisiennes peuvent-elles emp\u00eacher l\u2019information de gambader hors de leur p\u00e9rim\u00e8tre de s\u00e9curit\u00e9? A part le bouche-\u00e0-oreille, le t\u00e9l\u00e9phone arabe, il y a ces instruments du diable contre lesquels le pr\u00e9sident Ben Ali ne peut rien: les SMS, Internet, et surtout Facebook. Les Tunisiens font partie des plus grands utilisateurs de Facebook. Jamais un \u00e9v\u00e9nement local n\u2019a \u00e9t\u00e9 aussi \u00e9bruit\u00e9. La circulation de l\u2019information a \u00e9t\u00e9 tellement dense qu\u2019elle a cr\u00e9\u00e9 un bouchon sur l\u2019Internet. En fait, sans Internet, il n&rsquo; y aurait jamais eu une telle implosion. Il vous suffit de taper <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\">\u00abSidi Bouzid\u00bb sur Facebook<\/font><\/a><font face=\"Arial\">. Des dizaines de pages s&rsquo;affichent. Les Tunisiens sont de plus en plus nombreux dans le cyberespace.<\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>Quelles sont les revendications de ces manifestants?<\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Ils n\u2019appartiennent ni \u00e0 des partis, ni \u00e0 des organisations syndicales, ni \u00e0 des associations de la soci\u00e9t\u00e9 civile. Ces jeunes se sont identifi\u00e9s \u00e0 Mohamed Bouazizi. Ben Ali a cherch\u00e9 \u00e0 le maintenir artificiellement en vie, mais Mohamed Bouazizi n&rsquo;a pas voulu. Il s&rsquo;est immol\u00e9 par le feu. Il n&rsquo;a pas voulu que ses br\u00fblures restent vaines. Il faut que cette mort tragique ouvre enfin la voie \u00e0 la libert\u00e9. Celle dont la Tunisie r\u00eave depuis l&rsquo;ind\u00e9pendance. Celle qu&rsquo;elle n&rsquo;a jamais eu depuis l&rsquo;ind\u00e9pendance. L&rsquo;heure est venue d&rsquo;y acc\u00e9der enfin.<\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>Pourquoi les jeunes sont-ils aux avants-postes de la r\u00e9volte?<\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Les villes tunisiennes ne sont pas adapt\u00e9es aux jeunes ni aux jeunes adultes. Ils n&rsquo;ont pas beaucoup de loisirs, pas de possibilit\u00e9 de s&rsquo;impliquer v\u00e9ritablement dans la citoyennet\u00e9. Les nouveaux m\u00e9dias sont un v\u00e9ritable d\u00e9fouloir pour cette frange de la population en mal d&rsquo;expression. Internet est le relais d&rsquo;un hymne \u00e0 l&rsquo;action.<\/font> <font face=\"Arial\">Les grandes cha\u00eenes de t\u00e9l\u00e9vision comme Al Jazeera ou France24 se sont transform\u00e9es en \u00abradios-trottoir\u00bb. Leurs sources principales ce sont ces internautes, des journalistes amateurs. Les vid\u00e9os qu&rsquo;ils postent. Les journalistes de ces m\u00e9dias ont \u00e9t\u00e9 censur\u00e9s: ils n&rsquo;ont pas vraiment eu acc\u00e8s aux \u00e9v\u00e8nements. Sauf la cha\u00eene priv\u00e9e Nessma TV. Mais on peut se poser des questions sur le l&rsquo;ind\u00e9pendance de ce m\u00e9dia vis-\u00e0-vis du r\u00e9gime de Ben Ali.<\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>Le r\u00e9gime de Ben Ali est-il menac\u00e9\u00a0par ces troubles?<\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Il ne peut rien contre ce raz-de-mar\u00e9e qui touche bien un million de Tunisiens. Barak Obama avait qualifi\u00e9 le r\u00e9gime tunisien d&rsquo;\u00abennemi de l&rsquo;Internet\u00bb parce que tous ces sites participatifs et ces r\u00e9seaux ont \u00e9t\u00e9 bloqu\u00e9s par Ben Ali. Mais la pression est trop grande. Les \u00abintifadas\u00bb successives, tout au long de ces deux derni\u00e8res ann\u00e9es, dans le bassin minier de Gafsa, \u00e0 Ben Guerdane \u2014ville frontali\u00e8re tuniso-libyenne\u2014, \u00e0 Sidi Bouzid, sont venues \u00e0 bout du \u00abmythe Ben Ali\u00bb, le Caligula maghr\u00e9bin.<\/font> <font face=\"Arial\">A Tunis, on raconte que m\u00eame la propre fille du pr\u00e9sident, Cyrine Mabrouk, l&rsquo;a suppli\u00e9 de d\u00e9bloquer Internet. Elle dirigeait le premier fournisseur d&rsquo;acc\u00e8s Internet en Tunisie. C&rsquo;\u00e9tait vital pour elle. Cela l&rsquo;est tout autant pour le reste des Tunisiens.\u00a0 <\/font> \u00a0<\/p>\n<blockquote><p><font face=\"Arial\"><strong>Le pouvoir tunisien a-t-il encore les moyens de b\u00e2illonner cette opposition?<\/strong><\/font> \u00a0<\/p><\/blockquote>\n<p><font face=\"Arial\">Bien s\u00fbr la r\u00e9pression est l\u00e0. Mais les internautes savent bien contourner le probl\u00e8me. Pour ouvrir ces sites, tous utilisent un serveur <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\">proxy<\/font><\/a><font face=\"Arial\"> qui leur permet de masquer leur adresse IP. C&rsquo;est le cas dans tous les pays o\u00f9 la libert\u00e9 d&rsquo;expression n&rsquo;existe pas, en Chine, en Cor\u00e9e du nord. Ben Ali n&rsquo;a pas les moyens d&#8217;emp\u00eacher cette intifada de prendre de l&rsquo;ampleur.<\/font> <font face=\"Arial\"><strong>Propos recueillis par Pierre Malet et Agn\u00e8s Ratsimiala<\/strong><\/font> <font face=\"Arial\"><strong>(Source: Slate.fr le 4 janvier 2011)<\/strong><\/font> <font face=\"Arial\"><strong>Lien: <\/strong><a href=\"http:\/\/www.slate.fr\/story\/32201\/facebook-manifestations-ben-ali-sidi-bouzid-tunisie\" target=\"_blank\" rel=\"noopener\"><strong><font>http:\/\/www.slate.fr\/story\/32201\/facebook-manifestations-ben-ali-sidi-bouzid-tunisie<\/font><\/strong><\/a> \u00a0<\/font><\/div>\n<\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font size=\"3\"><font size=\"2\"><strong>\u00a0<\/strong><\/font><strong>Seule la d\u00e9mocratie peut \u00ab\u00a0\u00e9pargner une d\u00e9rive islamiste\u00a0\u00bb en Tunisie<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> Alors que la Tunisie est secou\u00e9e par une vague de protestation, Bochra Belhaj Hmida, Avocate, explique l&rsquo;engagement du barreau tunisien. Elle appelle au dialogue. \u00a0  L&rsquo;appel \u00e0 la gr\u00e8ve lanc\u00e9 par le Conseil de l&rsquo;ordre des avocats a \u00e9t\u00e9 largement suivi en Tunisie le 6 janvier. Avocate, ex-pr\u00e9sidente de l&rsquo;Association des femmes d\u00e9mocrates, Bochra Belhaj Hmida explique l&rsquo;engagement du barreau tunisien.\u00a0\u00a0 <\/p><\/div>\n<div align=\"justify\"> <strong>Pourquoi les avocats tunisiens \u00e9taient-il en gr\u00e8ve hier? <\/strong>Cette gr\u00e8ve, largement suivie, avait \u00e9t\u00e9 organis\u00e9e en solidarit\u00e9 avec les avocats agress\u00e9s par les forces de l&rsquo;ordre lors d&rsquo;une pr\u00e9c\u00e9dente manifestation.\u00a0 <\/div>\n<div align=\"justify\"> <strong>En quoi le barreau se sent-il particuli\u00e8rement concern\u00e9 par le mouvement de protestation de la jeunesse? <\/strong>Femmes et hommes de loi, les avocats sont naturellement sensibles \u00e0 la probl\u00e9matique des libert\u00e9s et des droits individuels.\u00a0 <\/div>\n<div align=\"justify\"> <strong>Comment interpr\u00e9ter cette vague protestataire? Ses motivations sont-elles principalement d&rsquo;ordre \u00e9conomique et social? Ou politique? <\/strong>A la base, ses motivations sont d&rsquo;ordre \u00e9conomique et social. Tout n&rsquo;est pas n\u00e9gatif en Tunisie. Il y a des projets de d\u00e9veloppement, des mesures qui visent \u00e0 cr\u00e9er des emplois. Mais cette politique n&rsquo;est pas adapt\u00e9e aux besoins de la soci\u00e9t\u00e9. Or l&rsquo;Etat tunisien, qui se veut un Etat providence, a tendance \u00e0 occulter les situations de crise. Ce sont l&rsquo;absence de transparence, le d\u00e9ficit d\u00e9mocratique qui expliquent que la crise d\u00e9bouche aussi sur un malaise politique.\u00a0<\/div>\n<div align=\"justify\"> <strong>Personne, semble-t-il, ne l&rsquo;avait vu venir, ni du cot\u00e9 des autorit\u00e9s, ni du cot\u00e9 des militants d\u00e9mocrates. Pourquoi? <\/strong>Je ne suis pas d&rsquo;accord. Depuis une dizaine d&rsquo;ann\u00e9es d\u00e9j\u00e0 des syndicalistes, certains m\u00e9dias priv\u00e9s, des d\u00e9fenseurs des droits de l&rsquo;homme, certaines ONG, des journaux d&rsquo;opposition avaient mis en garde les autorit\u00e9s. L&rsquo;UGET, le syndicat des \u00e9tudiants, n&rsquo;a pas cess\u00e9, ces deux derni\u00e8res ann\u00e9es d&rsquo;attirer l&rsquo;attention de l&rsquo;Etat sur la d\u00e9t\u00e9rioration de conditions de vie des \u00e9tudiants, en particulier la question du logement. De nouvelles associations, qui n&rsquo;ont malheureusement pas \u00e9t\u00e9 autoris\u00e9es, ont vu le jour, qu&rsquo;il s&rsquo;agisse du mouvement altermondialiste ou de la Ligue des ch\u00f4meurs dipl\u00f4m\u00e9s. Sans parler des \u00e9v\u00e8nements de Redeyef (Gafsa), il y a trois ans. Mais l&rsquo;Etat a choisi de faire la sourde oreille, refusant d&rsquo;engager le dialogue, continuant \u00e0 privil\u00e9gier les associations et les partis d&rsquo;all\u00e9geance et consid\u00e9rant tous les autres comme des \u00ab\u00a0ennemis\u00a0\u00bb.\u00a0 <\/div>\n<div align=\"justify\"> <strong>Le pouvoir parle d&rsquo;instrumentalisation, certains, dont r\u00e9cemment encore l&rsquo;ambassadeur de Tunisie en France, agitent l&rsquo;\u00e9pouvantail islamiste. Qu&rsquo;en est-il? <\/strong>L&rsquo;instrumentalisation est le fait de tout le monde, \u00e0 commencer par l&rsquo;Etat. Mais c&rsquo;est un ph\u00e9nom\u00e8ne secondaire, et m\u00eame d&rsquo;une certaine fa\u00e7on, normal. Ce n&rsquo;est ni la cause du probl\u00e8me, ni sa solution. Je fais partie des Tunisiens qu&rsquo;inqui\u00e8tent la mont\u00e9e des islamistes et la menace de nos acquis qu&rsquo;elle repr\u00e9sente. Mais \u00e0 mes yeux, seul l&rsquo;engagement de notre pays sur la voie d\u00e9mocratique peut nous \u00e9pargner une d\u00e9rive, islamiste ou autre, et pas l&rsquo;inverse.\u00a0\u00a0 <\/div>\n<div align=\"justify\"> <strong>C&rsquo;est un mouvement sans leader&#8230; O\u00f9 cela peut-il conduire? <\/strong>Nous n&rsquo;avons pas besoin d&rsquo;un leader, cette id\u00e9e de leader est l&rsquo;une des causes de nos maux. Nous avons en revanche besoin de r\u00e9fl\u00e9chir ensemble, Tunisiens de tous les bords, \u00e0 l&rsquo;avenir de notre pays. Le pouvoir doit prendre l&rsquo;initiative de rompre avec la langue de bois, et cesser de monopoliser la parole politique. M\u00eame si ce mouvement s&rsquo;essouffle, ce qui est possible, rien se sera plus comme avant.\u00a0 <\/div>\n<div align=\"justify\"> <strong><font>(Source : \u00ab l\u2019express.fr \u00bb Le 07-01-2011) Lien : http:\/\/www.lexpress.fr\/actualite\/monde\/seule-la-democratie-peut-epargner-une-derive-islamiste-en-tunisie_950638.html<\/font><\/strong><\/div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>La Tunisie, un pays qui cherche sa d\u00e9finition<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> LEMONDE.FR | 07.01.11 | 09h27\u00a0 \u2022\u00a0 Mis \u00e0 jour le 07.01.11 | 10h36  Depuis quelques jours les m\u00e9dias internationaux s&rsquo;int\u00e9ressent \u00e0 la situation en Tunisie et aux troubles qui ont accompagn\u00e9 le suicide d&rsquo;un jeune tunisien de Sidi Bouzid dans le centre du pays. Vu d&rsquo;Europe, cette autre image de la Tunisie peut surprendre. Car dans l&rsquo;esprit de tous, la Tunisie v\u00e9hicule plusieurs repr\u00e9sentations, devenues classiques : une destination touristique prestigieuse, une soci\u00e9t\u00e9 qui s&rsquo;ins\u00e8re dans la modernit\u00e9 et une \u00e9conomie parmi les plus dynamiques de l&rsquo;aire sud-m\u00e9diterran\u00e9enne. N\u00e9anmoins, ce pays renvoie une autre image, plus complexe sur le plan des imaginaires politiques et des rapports entre gouvernants et gouvern\u00e9s. La Tunisie est un pays \u00e0 histoire et g\u00e9ographie variables selon la place qu&rsquo;on lui donne par rapport au Maghreb, \u00e0 l&rsquo;Occident chr\u00e9tien, \u00e0 la M\u00e9diterran\u00e9e, au monde arabo-musulman et \u00e0 l&rsquo;Afrique. Il s&rsquo;agit d&rsquo;un pays \u00e9cartel\u00e9 entre deux mondes, l&rsquo;occidental et l&rsquo;oriental, qui cherche sa d\u00e9finition depuis son acc\u00e8s \u00e0 l&rsquo;ind\u00e9pendance, il y a bient\u00f4t cinquante cinq ans. Une des \u00e9volutions r\u00e9centes, initi\u00e9e par le r\u00e9gime de Zine el-Abibine Ben Ali, consiste \u00e0 attribuer \u00e0 la M\u00e9diterran\u00e9e et \u00e0 la p\u00e9riode ant\u00e9-islamique la vraie identit\u00e9 tunisienne. La rh\u00e9torique officielle tente alors d&rsquo;imposer cette ligne comme une \u00e9vidence historique. C&rsquo;est ce que les enjeux de la promotion d&rsquo;une telle vision identitaire sont \u00e9normes. Il s&rsquo;agit d&rsquo;abord, apr\u00e8s avoir mis \u00e0 l&rsquo;\u00e9cart Bourguiba et la personnification de l&rsquo;histoire nationale (1956-1987) qu&rsquo;il incarnait, de gagner la bataille, y compris id\u00e9ologique, contre les islamistes. C&rsquo;est donc une r\u00e9ponse implicite de la part des autorit\u00e9s tunisiennes, politiques et scientifiques, \u00e0 la menace int\u00e9griste et \u00e0 la situation alg\u00e9rienne tenue \u00e0 cet \u00e9gard pour un contre mod\u00e8le. Il r\u00e9pond de ce fait \u00e0 un enjeu politique pour le r\u00e9gime tunisien : sortir du face \u00e0 face avec l&rsquo;islam sur le terrain symbolique de l&rsquo;histoire ; l&rsquo;identit\u00e9 tunisienne n&rsquo;a pas pour origine la conqu\u00eate musulmane et ne commence pas au Moyen-Age. Plus largement, le faire-valoir d&rsquo;une identit\u00e9 \u00e0 la fois plus riche et plus ancienne va se renforcer en r\u00e9action aux facteurs conjoncturels des ann\u00e9es 1990. La guerre du Golfe (1991) et la d\u00e9ception ressentie \u00e0 propos de l&rsquo;Union du Maghreb arabe, dont les diff\u00e9rends alg\u00e9ro-marocains ont refait surface et conduit au gel des institutions de cette union en 1994, ont pour cons\u00e9quence un retour sur soi et une plong\u00e9e aux sources de la m\u00e9moire. Dans un tel contexte, avec un horizon politiquement neutre, le th\u00e8me de la M\u00e9diterran\u00e9e, et la revendication d&rsquo;une identit\u00e9 plurielle qui lui est sous-jacente, va asseoir son h\u00e9g\u00e9monie id\u00e9ologique par rapport aux autres th\u00e8mes identitaires (\u00ab\u00a0identit\u00e9 maghr\u00e9bine\u00a0\u00bb, arabe, africaine, musulmane). Cette ligne politico-id\u00e9ologique rev\u00eat un autre enjeu important qui se situe sur le terrain \u00e9conomique et diplomatique. Il s&rsquo;agit pour les autorit\u00e9s tunisiennes de r\u00e9pondre \u00e0 la nouvelle configuration des rapports Nord\/Sud de la M\u00e9diterran\u00e9e, en inscrivant la Tunisie dans la nouvelle politique euro-m\u00e9diterran\u00e9enne inaugur\u00e9e par la conf\u00e9rence de Barcelone des 27 et 28 novembre 1995. Cet arrimage de la Tunisie \u00e0 l&rsquo;Europe et le discours m\u00e9diterran\u00e9en qui lui est propre a pour cons\u00e9quence d&rsquo;accentuer la rh\u00e9torique officielle portant sur le th\u00e8me de l'\u00a0\u00bbexceptionnalit\u00e9\u00a0\u00bb de la Tunisie et de son patrimoine, comme offre touristique aux \u00e9trangers, mais aussi pour relier \u00ab\u00a0la diaspora\u00a0\u00bb tunisienne et son potentiel \u00e9conomique et touristique \u00e0 la patrie d&rsquo;origine. UNE EXTR\u00caME TENSION SOCIALE Mais n\u00e9anmoins la construction politico-identitaire \u2013 a priori int\u00e9ressante ne serait-ce que par son ouverture sur l&rsquo;autre \u2013 est loin de passionner l&rsquo;immense majorit\u00e9 d&rsquo;un peuple qui, tout en \u00e9tant ancr\u00e9 dans l&rsquo;arabisme et l&rsquo;islam, comme les enqu\u00eates sociologiques le montrent, sa pr\u00e9occupation principale tourne autour du r\u00eave d&rsquo;une vie mat\u00e9rielle \u00e0 l&rsquo;europ\u00e9enne. Or, sur fond d&rsquo;une atmosph\u00e8re de fin de r\u00e8gne, l&rsquo;autoritarisme politique tel qu&rsquo;il s&rsquo;exerce au quotidien de mani\u00e8re tr\u00e8s complexe, et les pratiques client\u00e9listes, r\u00e9elles ou suppos\u00e9es, dans l&rsquo;exercice du pouvoir \u00e0 toutes les \u00e9chelles de la soci\u00e9t\u00e9, n&rsquo;ont cess\u00e9 d&rsquo;approfondir le foss\u00e9 entre gouvernants et gouvern\u00e9s. Dans ces conditions, la parole politique a non seulement rat\u00e9 sa cible mais elle a produit de la d\u00e9sesp\u00e9rance. Et la fin tragique du jeune tunisien de Sidi-Bouzid \u2013 esp\u00e9rons que son cas ne fera pas \u00e9cole chez ses coreligionnaires \u2013 traduit un profond malaise notamment chez les jeunes. Et \u00e0 ce stade d&rsquo;une situation marqu\u00e9e par une extr\u00eame tension sociale, on est tent\u00e9 d&rsquo;affirmer que dans le monde arabe et en particulier en Tunisie, la tradition de l&rsquo;Etat fort et son appareil r\u00e9pressif ont toujours pu faire taire les m\u00e9contentements populaires, sauf que les r\u00e9gimes en place, on l&rsquo;a vu r\u00e9cemment en Iran, doivent faire face maintenant \u00e0 une in\u00e9dite mobilisation populaire orchestr\u00e9e principalement sur la Toile. Face \u00e0 la r\u00e9volution du Web, vecteur \u00e0 l&rsquo;efficacit\u00e9 redoutable d&rsquo;une aspiration l\u00e9gitime \u00e0 des valeurs universelles, l&rsquo;enseignement tir\u00e9 de l&rsquo;histoire atteint ici ses limites. Tous les sc\u00e9narios sont d\u00e9sormais possibles. Driss Abbassi est l&rsquo;auteur de plusieurs ouvrages sur la Tunisie contemporaine.<\/p><\/div>\n<div> <strong><font>Driss Abbassi,<\/font> historien <\/strong> <font><strong>(Source: \u00ab\u00a0Lemonde.fr\u00a0\u00bb le 7 janvier 20119 Lien: <\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong>http:\/\/www.lemonde.fr\/idees\/article\/2011\/01\/07\/la-tunisie-un-pays-qui-cherche-sa-definition_1462051_3232.html<\/strong><\/a><\/font><\/div>\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"justify\"><font><\/p>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Tunisie : \u00ab S\u2019il sait se montrer intelligent, le pouvoir peut faire baisser la pression \u00bb<\/strong><\/font><\/h6>\n<\/div>\n<div>\n<hr\/>\n<p> publi\u00e9 le 07.01.2011 02h01 \u00a0 <strong>&gt;&gt; Alors que vous \u00eates vous-m\u00eame d\u2019origine tunisienne, comment appr\u00e9hendez-vous la situation dans ce pays ? <\/strong>La Tunisie ressent les effets de la crise qui ont conduit \u00e0 une d\u00e9r\u00e9glementation de l\u2019\u00e9conomie et \u00e0 un d\u00e9sengagement de l\u2019Etat sous la pression du FMI. Or, sa jeunesse est massivement victime du ch\u00f4mage et, en particulier, les jeunes dipl\u00f4m\u00e9s souvent contraints de recourir \u00e0 l\u2019\u00e9conomie informelle pour tenter de survivre. A cet \u00e9gard, l\u2019histoire de ce jeune qui s\u2019est immol\u00e9 par le feu \u00e0 Sidi Bouzid illustre parfaitement cette situation. D\u2019autant que ce drame s\u2019est d\u00e9roul\u00e9 dans une r\u00e9gion du sud-tunisien qui est une v\u00e9ritable poche de mis\u00e8re.  <strong>&gt;&gt; En quoi ce mouvement se diff\u00e9rencie-t-il d\u2019autres troubles ? <\/strong>Ce mouvement de protestation, entam\u00e9 par la jeunesse, a \u00e9t\u00e9 relay\u00e9 par d\u2019autres forces, \u00e0 commencer par les unions locales du syndicat UGTT. Lequel a proprement \u00e9clat\u00e9 sous la pression des \u00e9v\u00e9nements puisque la direction de l\u2019UGTT, qui est rappelons-le l\u2019unique syndicat de Tunisie, ne s\u2019est pas d\u00e9solidaris\u00e9e du pouvoir, elle. Depuis, d\u2019autres forces ont rejoint le mouvement, les avocats, la Ligue des Droits de l\u2019Homme et des organisations f\u00e9minines.  <strong>&gt;&gt; Le pouvoir du pr\u00e9sident Ben Ali est-il pour autant \u00e9branl\u00e9 ? <\/strong>Pas pour l\u2019instant, mais la balle est dans son camp. S\u2019il sait se montrer intelligent, s\u2019il sait saisir cette occasion pour l\u00e2cher des concessions il pourrait d\u00e9samorcer cette crise. Si les choses restent en l\u2019\u00e9tat, si le pouvoir se contente de quelques limogeages tout en comptant sur son appareil r\u00e9pressif pour ramener le calme, alors il est \u00e0 craindre que la violence s\u2019attise et profite aux islamistes qui, pour l\u2019instant, se montrent \u00e9trangement silencieux.  <strong>&gt;&gt; Dans ces conditions que peut faire l\u2019Europe et la France ? <\/strong>Elles pourraient rappeler le pouvoir tunisien \u00e0 ses devoirs, le contrat d\u2019association liant l\u2019Europe \u00e0 la Tunisie pr\u00e9voyant dans son article 98 le respect des Droits de l\u2019Homme. C\u2019est d\u2019ailleurs tout l\u2019int\u00e9r\u00eat de l\u2019Europe.  Il n\u2019est pas besoin d\u2019\u00eatre devin pour pr\u00e9voir que de troubles prolong\u00e9s auraient des cons\u00e9quences en mati\u00e8re d\u2019immigration. <strong><font>Propos recueillis par Ren\u00e9 Raffin <\/font><\/strong><\/div>\n<div>\u00a0<\/div>\n<div><strong><font>(Source: \u00ab\u00a0Lerogres.fr\u00a0\u00bb le 7 janvier 2011)<\/font><\/strong><\/div>\n<div><strong><font>Lien:<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.leprogres.fr\/fr\/france-monde\/article\/4421465\/Tunisie-S-il-sait-se-montrer-intelligent-le-pouvoir-peut-faire-baisser-la-pression.html<\/a><\/font><\/strong><\/div>\n<p><\/font><\/p>\n<hr\/>\n<\/div>\n<\/div>\n<div>\n<div align=\"center\"><strong><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\">Exposing the real Tunisia<\/font><\/h6>\n<p>A recent wave of unrest belies the myth of a Tunisian miracle, and offers a stark warning \u00a0<\/strong><\/div>\n<div align=\"justify\">\n<hr\/>\n<p> <strong><font>Soumaya Ghannoushi<\/font><\/strong><\/div>\n<div align=\"justify\"> It seems that the waters of the stagnant Arab swamp may be stirring at last. Tunisia, that small north African country on the Arab world&rsquo;s western shores, has for the past two weeks been the scene of a social uprising rare in this tightly controlled part of the world. This outburst of popular anger was ignited by an unemployed 26-year-old university graduate setting himself ablaze outside a police station in the provincial town of Sidi Bouzid. Soon afterwards another young man electrocuted himself, shouting \u00ab\u00a0No unemployment, no misery!\u00a0\u00bb and more attempted suicides have been reported since. A wave of riots and protests has ensued, sweeping through towns and villages all over the country \u2013 even in the capital, Tunis. As in many Arab nations, political despotism and socioeconomic failure is acute in Tunisia. And this unrest points to the reality hidden behind the facade of tourist brochures and lavish resorts exhibited to the outside world. This is the world of ordinary Tunisians, of a rapidly depleted middle class crushed under the weight of rampant privatisation and a decreasing public sector, of soaring prices, debt, unemployment, social marginalisation and young men boarding \u00ab\u00a0death boats\u00a0\u00bb in the hope of escape to the other side of the Mediterranean. It is a world of the systematic impoverishment of the masses in inner cities and villages by the nouveaux riches, by a wealthy minority linked to the president and his family through a tight web of corruption and theft. This is the \u00ab\u00a0Tunisian miracle\u00a0\u00bb trumpeted by president Zine Ben Ali&rsquo;s regime and echoed by its backers in the European Union, particularly France, Italy and Spain. For its sake, Tunisians were told to keep quiet and relinquish all hope of political freedom and democracy. While acknowledging the regime&rsquo;s flagrant human rights violations, the EU is considering upgrading relations with Tunisia and granting it \u00ab\u00a0advanced-partner status\u00a0\u00bb. The myth of socioeconomic success is not the only fabrication. The official discourse is borrowed from the latest liberal dictionary, replete with such phrases as civil society, individual freedom and human rights. But these ring hollow in Ben Ali&rsquo;s police state. He seized power from his predecessor in a coup d&rsquo;\u00e9tat 23 years ago, and has not budged from his throne since, thanks to a string of falsified elections \u2013 in which his share of the votes has ranged from 97% to 99% \u2013 and a 150,000-strong police force, the same size as Britain&rsquo;s, with a population a sixth as large. The general&rsquo;s eradication campaign began with a crackdown on an-Nahda, the main opposition party of liberal democratic Islamist tendencies, in 1990, in the name of combating the \u00ab\u00a0fundamentalist threat\u00a0\u00bb. It then moved on to devour all political dissidents, including nationalists, leftists, liberals and student activists. Next came civil society&rsquo;s turn. Between annexation and dissolution, no association remained autonomous or active, including trade unions, human rights organisations, and cultural, social and even sports associations. Tunisian jails became the sole gathering point for activists. Journalists have fared no better. No other Arab country has imprisoned more journalists since 2000. The Committee for the Protection of Journalists has declared the regime to be one of the world&rsquo;s 10 worst enemies of the press. Tellingly, the only images of the current protests have been captured on mobile- phone cameras and released on the web, as no foreign reporters are allowed into the country. Only North Korea can compete with Tunisia in this regard. Ben Ali may have brought the stability desired by his foreign backers, but it was the stability of the dead, of graves and cemeteries. Amid the wreckage of political life, Tunisia&rsquo;s general grapples with two phenomena of his own making. The first is the rise of violent anarchist groups associated with al-Qaida, which have emerged in the vacuum generated by his eradication policy. The second is rage at corruption, unemployment and government repression, which has erupted in the past few weeks. Events in Tunisia are symptomatic of what lies ahead. Arab rulers have striven to kill politics in all its forms. But as they do away with organised mainstream parties and associations, they will find themselves, like Ben Ali, face to face with a younger generation mobilised by feelings of frustration and humiliation, and yearning for revenge. And when all vessels of movement and expression are shut off, explosions and eruptions become the only possibility left.<\/div>\n<div>\u00a0<\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>(Source: The Guardian, Tuesday 4 January 2011)<\/strong><\/font><\/div>\n<div><font face=\"Arial\" size=\"2\"><strong>Lien: <\/strong><\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\" size=\"2\"><strong>http:\/\/www.guardian.co.uk\/commentisfree\/2011\/jan\/04\/tunisia-riots-economic-miracle-ben-ali<\/strong><\/font><\/a> \u00a0<\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div>\n<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td valign=\"top\">\n<div align=\"center\"><span><font size=\"2\"><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Tunisia&rsquo;s bitter cyberwar<\/strong><\/font><\/h6>\n<p><strong><\/strong><\/font><\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">\u00a0<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><font size=\"2\"><strong>Anonymous has joined with Tunisian activists to call for end to the government&rsquo;s stifling of online dissent. <\/strong><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div>\u00a0<\/div>\n<div><font size=\"2\"><span><strong><font>Yasmine Ryan<\/font><\/strong><\/span><span> Last Modified:<span>06 Jan 2011 16:23 GMT<\/span> <\/span><\/font><\/div>\n<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<div>\u00a0<\/div>\n<div>Thousands of Tunisians have taken to the streets in recent weeks to call for extensive economic and social change in their country. Among the fundamental changes the protesters have been demanding is an end to the government&rsquo;s repressive online censorship regime and freedom of expression. That battle is taking place not just on the country&rsquo;s streets, but in internet forums, blogs, Facebook pages and Twitter feeds. The Tunisian authorities have allegedly carried out targeted \u00ab\u00a0phishing\u00a0\u00bb operations: stealing users passwords\u00a0to spy on them and eradicate online criticism. Websites on both sides have been hacked. Anonymous, the loosely-knit group of international web activists that<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">drew world attention<\/a> for their \u00ab\u00a0distributed denial of service\u00a0\u00bb (DDoS) attacks on the servers of companies that blocked payments and server access to the whistle-blowing website, WikiLeaks,\u00a0joined the fray, in solidarity with the Tunisian uprising. Most international news organisations have no presence in the country (and, some say,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">a lack of interest<\/a> in the protests). Media posted online by Tunisian web activists has been some of the only material that has slipped through the blackout, even if their videos and photos haven&rsquo;t\u00a0generated quite the same enthusiastic coverage by Western media\u00a0as the Iranian protest movement did\u00a0in 2009. <strong>Killing dissent<\/strong> The attacks against some of the most vocal voices in the Tunisian cyber-community were sharp and swift. Sofiene Chourabi, a journalist for <em>Al-Tariq al-Jadid\u00a0<\/em>magazine\u00a0and blogger known for his unabashed criticism of the Tunisian authorities, has been unable to recover his email and Facebook accounts after they were hijacked several days ago. The first attempted hijacking of his Facebook account happened last week. \u00ab\u00a0My personal account on the Facebook, including around 4200 friends, was exposed to failed hacking attempt last Friday, but I quickly recovered it after an unidentified person had taken control of it,\u00a0\u00bb he told Al Jazeera. Then, on Monday, Chourabi was locked out of his Facebook and Gmail accounts. Chourabi says he believes the Tunisian Internet Agency is responsible for hijacking his accounts. The agency has blocked access to his Facebook wall since October 2009, and his blogs are also unreachable from within Tunisia. Several of his friends have contacted Facebook and Google asking for his accounts to be returned, to no avail.\u00a0 \u00ab\u00a0I think it is high time for Facebook and Google to take serious steps to protect Tunisian activists and journalists,\u00a0\u00bb he said in an interview via email, using a new account. Facebook is working to ensure it can respond to all its users, Stefano Hesse, Facebook&rsquo;s head of communications for Europe, the Middle East and Africa, told Al Jazeera. \u00ab\u00a0One thing needs to be clear: we, as Facebook, are not censoring any content, and we had not been approached by the local government in order to do anything regarding anyone,\u00a0\u00bb Hesse said via email. Google did not respond to requests for comment from Al Jazeera. Lina Ben Mhenni also had her Facebook page and Yahoo email account pirated, although she managed to retain control of<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">her blog<\/a>. She told Al Jazeera that, as of Wednesday, web users in Tunisia were unable to change their passwords for Facebook. Another activist who was caught in the phishing campaign is a Tunis-based man, who goes by the name of Azyz Amamy in the online world. \u00a0 Amamy told Al Jazeera in a phone interview that his Facebook and email accounts had been hijacked on Monday. Amamy was able to recover both accounts within two hours, after Facebook and Gmail responded to his request. The difference is that he had retained control of a separate email account with which he had registered both accounts. Two hours was enough time for the authorities to get the login information for his four blogs from his email accounts, deleting all the content. \u00ab\u00a0When they took Lina [Ben Mhenni]&rsquo;s account, and Sofiene Chourabi&rsquo;s, within an hour all the Facebook pages they administrated had disappeared. And then their accounts were deleted,\u00a0\u00bb Amamy explained. The speed of the phishing operation, hitting several high-profile targets in a single day, demonstrated that it was exceptionally sophisticated, he said. As well as<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Chourabi<\/a>, Amamyma and Ben Mhenni, those known to have been targeted include<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Med Salah M&rsquo;Barek<\/a>\u00a0and<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Haythem El Mekki<\/a>.\u00a0 Amamy suspects the phishing operation was far-reaching and that many more were hit, but are too scared to go public. Several sources Al Jazeera spoke with said that web activists had been receiving anonymous phone calls, warning them to delete critical posts on their Facebook pages or face the consequences. <strong>&lsquo;Phishing&rsquo; for dissent<\/strong> The phishing was carried out by a malware code, several sources told Al Jazeera. Sami Ben Gharbia, who monitors Tunisia&rsquo;s web censorship for Global Voices, said that Google and Facebook were in no way\u00a0complicit in\u00a0the\u00a0sophisticated phishing technique. \u00a0<\/p>\n<table align=\"right\" border=\"0\" bordercolor=\"#ffffff\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td>\u00a0<\/td>\n<\/tr>\n<tr>\n<td align=\"middle\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>The initial signs that something was underway came on Saturday, he said, when the secure https protocol became unavailable in Tunisia. This forced web users to use the non-secure http protocol. The government&rsquo;s internet team then appears to have gone phishing for individuals&rsquo; usernames and passwords on services including Gmail, Facebook, Yahoo and Hotmail. Web activists and journalists alerted others of the alleged hacking by the government via Twitter, which is not susceptible to the same types of operations. \u00a0 \u00ab\u00a0The goal, amongst others, is to delete the Facebook pages which these people administer,\u00a0\u00bb a Tunisian internet professional, who has also been in contact with Anonymous, told Al Jazeera in an emailed interview. The same source, who asked to remain unidentified due to the potential consequences for speaking out, said that in communication with the international group, he had come up with a<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">Greasemonkey script<\/a> for fireFox internet browsers that deactivated the government&rsquo;s malicious code. The script had been installed\u00a01,669 times at the time of writing. \u00ab\u00a0It isn&rsquo;t like China and Gmail several months ago, where China attacked Gmail,\u00a0\u00bb\u00a0the web professional\u00a0said in an email, referring to<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">last year&rsquo;s incident<\/a><span><\/span>when Chinese hackers allegedly broke in the accounts of Chinese dissidents. \u00ab\u00a0This is much more intelligent (and I\u2019m proud of this intelligence!). It&rsquo;s the communication with Gmail [and the other sites] that is intercepted,\u00a0\u00bb he said. The\u00a0Committee to Protect Journalists says there is<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">clear proof<\/a><span><\/span>that the phishing campaign is organised and co-ordinated by the Tunisian government, as did other sources that Al Jazeera spoke with. <strong>Unexpected allies<\/strong> Tunisian web activists found an ally in Anonymous, whose international activists have turned their attention to overthrowing the Tunisian regime of web censorship. The group&rsquo;s DDoS attacks, which began on Sunday night, local time,<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">succeeded in taking at least eight websites<\/a>, including those for the president, prime minister, the ministry of industry, the ministry of foreign affairs, and the stock exchange. The web site of the government internet agency &#8211; known by Tunisian web dissidents ironically as \u00ab\u00a0Ammar 404\u00a0\u00bb, or \u00ab\u00a0Page not found\u00a0\u00bb for its\u00a0oversight of censorship operations\u00a0&#8211;\u00a0was also targeted. In email correspondence with Al Jazeera, one Anonymous activist described the group as a \u00ab\u00a0hive mind,\u00a0\u00bb centred on collective, rather than individual, identity.\u00a0 The activists, who prefer to go unnamed, co-ordinate their operations through discussions held in Internet Relay Chat (IRC) networks, a type of online discussion forum. Al Jazeera discussed \u00ab\u00a0OpTunisia\u00a0\u00bb with a group of the online activists on Tuesday. The operation began when one Anon spent last weekend \u00ab\u00a0spamming\u00a0\u00bb the forum, drawing support from activists around the world. The Tunisian government first drew the Anons&rsquo; ire, they say, when it extended its pervasive filtering to WikiLeaks. \u00ab\u00a0The thing that did it for us, was initially their censoring of WikiLeaks, when WikiLeaks reports on .tn came out,\u00a0\u00bb one participant in the forum wrote in response to questions from Al Jazeera, referring the Tunisia-based website that had been set up to host the WikiLeaks memos. With their collective gaze turned to Tunisia, the Anons came into contact with Tunisian web activists. \u00ab\u00a0We did initially take an interest in Tunisia because of WikiLeaks, but as more Tunisians have joined they care more about the general internet censorship there, so that&rsquo;s what it has become,\u00a0\u00bb another Anon said. It is hard to generalise the Anons&rsquo; diverse range of motivations and ever-changing targets, but most appear to share an outrage over the Tunisian government&rsquo;s censorship and phishing activities, and a sense of solidarity with Tunisian web users. Attacking government-linked websites is much more dangerous for those living within Tunisia, they noted, who risk arrest if they are\u00a0identitied by the authorities. \u00ab\u00a0Although many Tunisians understandably do not feel comfortable participating in this operation out of precaution, I estimate there [were] about 50 Tunisians participating, to whom we provide the means and knowledge to properly secure their online behaviour from exposure to their government,\u00a0\u00bb one Anon activist wrote\u00a0via email. Ben Gharbia says he accessed IRC to observe the discussions, and that there were some people chatting in Tunisian dialect. By Tuesday, the government appeared to have taken steps to protect its websites from attack by making them inaccessible from overseas. The same sites were available within Tunisia. On Wednesday, Anonfymous informed Al Jazeera that its<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">own site<\/a><span><\/span>was under DDoS attack. Anonymous was continuing its DDoS attacks on Thursday, and is likely to move on to another target now that momentum has gathered. \u00ab\u00a0We, as Anonymous, feel we have accomplished our mission with the major media now involved in Tunisia.\u00a0 We will keep DDoS&rsquo;ing that DNS server probably until after the [Thursday&rsquo;s] strike,\u00a0\u00bb wrote the source by email. <strong>Government hacking, en masse<\/strong> This is hardly the first time Tunisian censors have phished for dissidents&rsquo; private information, nor is its censorship anything new. Most popular video-sharing websites have been blocked for years now. Facebook was<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">completely blocked<\/a> in 2008. Tunisia no longer blocks the entire Facebook platform, and is one of the main ways people are able to share video. Individual Facebook pages are quickly censored, however, often within an hour of going online, Ben Gharbia said. \u00ab\u00a0Once they identify a link that needs to be blocked, they block it instantly,\u00a0\u00bb he said. In the siege against cyber dissidence, Twitter has been a bastion for activists. Because people can access Twitter via clients rather than going through the website itself, many Tunisians can still communicate online. The web-savvy\u00a0use proxies to browse the other censored sites. Yet even if bloggers manage to maintain their blogging, the censorship deprives them of those readers who do not use proxies. The result is what Ben Gharbia described as the \u00ab\u00a0killing\u00a0\u00bb of the Tunisian blogosphere.\u00a0 Ben Mhenni said that the government&rsquo;s biggest censorship of webpages en masse happened in April 2010, when more than 100 blogs were blocked, in addition to other websites. She said the hijackings that had taken place in the past week, however, marked the biggest government-organised hacking operation. Most of the pages that had been deleted in recent days were already censored. Amamy said the government&rsquo;s approach to the\u00a0internet policy is\u00a0invasive and\u00a0all-controlling. \u00ab\u00a0Here we don&rsquo;t really have internet, we have a national intranet,\u00a0\u00bb he said. <strong><em>You can follow Yasmine on Twitter<a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\">@yasmineryan<\/a><\/em><\/strong> <strong>Updates:\u00a0 Azyz Amamy was arrested on Thursday, sources in Tunisia told Al Jazeera. Another web activist, Slim Amamou was also taken by the authorities.<\/strong> <strong>Amamy&rsquo;s last Tweet prior to his arrest was published on Thursday morning, as was Amamou&rsquo;s. (6 Jan 2011 21:03 GMT)<\/strong> <strong><font>(Source: aljazeera.net le 6 janvier 2011)<\/font><\/strong> <strong><font>Lien: <\/font><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><font>http:\/\/english.aljazeera.net\/indepth\/features\/2011\/01\/20111614145839362.html<\/font><\/a><\/strong> \u00a0<\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Tunisia&rsquo;s Crisis: Searching for Islamists<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> The West is fearful of the Nahda Movement\u2019s influence in Tunisia, and this has caused America and its European allies to turn a blind eye to the mistakes committed by the Tunisian government. However, of course, the government has been responsible for some development achievements witnessed in the country.  The US, and influential western countries, are committing a grave error when dealing with some of the more repressive countries in the Islamic world. The US and its European allies support and endorse these countries, or at least turn a blind eye to their practices, in accordance with Western interests. When we say that Western states have committed a fundamental mistake, it is not because they have prevented Islamic movements from coming to power \u2013 in doing so they are simply acting in accordance with their interests and strategies. Islamic trends are viewed by the West as nothing more than an opposition which must be prevented from gaining control, at all costs. This may mean a total disregard for democratic outcomes, and the results of fair polls \u2013 as happened in the Algerian and Palestinian elections \u2013 regardless of the catastrophic consequences this may have for Arab or Islamic nations.  The fundamental mistake of the Western strategy is that it fails to put pressure on these countries to improve moral relations with their populace, by undertaking genuine economic, political and developmental reforms, fighting corruption, and loosening their iron fist. Failing to do so only generates a sense of injustice and oppression, which results in public uprisings and riots. Sometimes these have catastrophic consequences, as was evident in the Algerian case, which we fear may now be repeated in Tunisia.  The US and its European allies could have designed their strategies in a manner that prevented Islamic trends from reaching power, but via the consolidation of pubic liberties, fighting corruption and promoting development. A clean and a fair government with a strong economy, and a transparent supervisory and accountability system, even if it rejected the Islamic agenda completely, would be fully resistant to change, and the Malaysian experience is testament to this.  The historic, charismatic, political figure of [former Malaysian Prime Minister] Mahathir Mohamed is not the product of Islamic trends, although he shares some characteristics with them. Indeed he is in some sense an authoritarian, although he did not reach the level of dictator. He competed with the strong Malaysian Islamic movement, and took part in a fierce struggle with its one of its key figures, Anwar Ibrahim. In the end, Mathathir was successful in ousting Ibrahim from government, dismissing him in a somewhat ugly fashion.  Nevertheless, this confrontation did not disrupt Mahathir\u2019s government, because the Malaysian nation appreciated his patriotism, and his contribution to the country&rsquo;s developmental plans, which would enable Malaysia to later become one of the Asian Tigers. The man was religious by nature, and had no quarrel with Islam in general. There is a clear difference between antagonizing the political Islamic movement, and antagonizing the religion of Islam. Therefore, the nation raised no objection, nor did they care much about the defeat of a key symbol of the Malaysian Islamic movement, whilst Mahathir strengthened his firm grip on power. Had Arab states \u2013 suffering from disorders and divisions between them and their people &#8211; been governed by the Mahathir model, we would not find problems as serious as those ongoing in Tunisia, even when faced with an Islamist opposition.  <font><strong>(Source: \u201cAsharq Alawsat\u201d Le 06-01-2011) Lien: <\/strong><a href=\"http:\/\/\/\" target=\"_blank\" rel=\"noopener\"><strong>http:\/\/aawsat.com\/english\/news.asp?section=2&amp;id=23682<\/strong><\/a> \u00a0<\/font><\/div>\n<div align=\"justify\"><strong><\/p>\n<hr\/>\n<p><\/strong><\/div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Sour young men<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Why protests, once rare, are persisting<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> <font>UNABLE to find a job after university, Muhammad Bouazizi moved to a big city and tried to get by, selling vegetables from a barrow. But police confiscated his unlicensed cart, slapping and insulting him. The 26-year-old returned to his home town in despair. Last month he stood in its main square, doused himself in petrol and struck a match. On January 4th he died of his injuries.  A tragedy like Mr Bouazizi\u2019s might pass unnoticed in many countries. But his struck a rare chord of dissonance with\u00a0 Tunisia\u2019s carefully nurtured image as a tranquil, orderly, mildly prosperous playground for tourists and foreign investors. The dramatic act sparked not just sympathy but a wave of protest that has carried on for three weeks, with no sign of stopping. Trade unionists have joined students, lawyers, political campaigners and unemployed youths to demonstrate repeatedly in more than a dozen cities. Police have struck back with clubs, tear gas and even bullets, killing two protesters in the southern town of Bouziane. President Zine el-Abidine Ben Ali has also sounded a conciliatory note, firing a handful of ministers and promising to inject as much as $4.5 billion into job-creation schemes.  The ostensible focus of protest is unemployment; 13% of Tunisians are officially out of work. The figure is double for young people, and even higher for recent college graduates. But the scale and persistence of the unrest point to deeper causes. Young Tunisians often find that the available jobs are menial, in keeping with a model of development that offers cheap labour to European investors. Another complaint is that Tunisia\u2019s prosperity is unevenly shared between richer coastal cities and the poor interior.  Some causes of the unrest are political. Since Mr Ben Ali overthrew Tunisia\u2019s last president, Habib Bourguiba, then 84, in a peaceful coup 23 years ago, his people have submitted to an unspoken bargain. In exchange for slowly rising prosperity, steady gains in health and education, and a degree of social peace that contrasts starkly with next-door Libya and Algeria, Tunisians have put up with diminished political rights, intrusive and unaccountable security services, and rising corruption at the top.  With formal politics and the press allowing little outlet for grievances, discontent has festered. At the same time, better education has turned nearly 4m of Tunisia\u2019s 10.5m people into internet users, with some 1.8m running accounts on Facebook alone. Despite efforts at censorship that put Tunisia\u2019s government among the worst offenders in global listings of enemies of free expression (measured for instance by a French-based lobby, Reporters Sans Fronti\u00e8res), most Tunisians have heard about the WikiLeaks cables alleging greed and nepotism in Mr Ben Ali\u2019s circle.  Tunisia\u2019s troubles are unlikely to unseat the 74-year-old president or even to jolt his model of autocracy. Yet they may serve warning to governments across the Maghreb that a growing number of young people in the region feel increasingly frustrated and marginalised, as ageing and undemocratic leaders seem ever more out of touch with them. <\/font> <strong>(Source:\u201d The economist\u201d Le 06-01-2010) Lien: http:\/\/www.economist.com\/node\/17862305?story_id=17862305&amp;fsrc=rss<\/strong><\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div align=\"center\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"3\"><strong>Revuelta juvenil en T\u00fanez<\/strong><\/font><\/h6>\n<\/div>\n<div align=\"justify\">\n<hr\/>\n<p> <strong>Crece el descontento social y pol\u00edtico en T\u00fanez. Miles de j\u00f3venes han salido a las calles en diversas ciudades en las dos \u00faltimas semanas en protesta contra la falta de trabajo, la carest\u00eda de la vida y la corrupci\u00f3n en las altas esferas del Estado. En su mayor\u00eda universitarios, los manifestantes han decidido romper con el fatalismo que acarrea la crisis y exigir p\u00fablicamente sus derechos, una mejor redistribucion de las riquezas y derecho a un futuro digno. <\/strong><\/div>\n<div align=\"justify\"> La ola de protestas ha sacudido varias ciudades de T\u00fanez. Toda la regi\u00f3n del centro del pa\u00eds conoce desde hace diez d\u00edas graves acontecimientos, que se han saldado con la muerte de dos j\u00f3venes manifestantes, Mohamed Amari y Chawki Haydari, abatidos con balas por la polic\u00eda antidisturbios en una peque\u00f1a localidad del sur de T\u00fanez, as\u00ed como numerosos heridos y detenidos.  \u00abLa elevada tasa de paro de los diplomados universitarios, el alza de precios de los productos b\u00e1sicos y el recurso como \u00fanica salida al sector agr\u00edcola, son las causas de los disturbios\u00bb, afirma Rauf Nasiri, presidente de la secci\u00f3n regional de Sidi Buzid de la Liga de derechos del Hombre. Seg\u00fan cifras oficiales, la tasa de desocupaci\u00f3n en el pais es del 14 por ciento, y de los titulados de diplomas superiores de un 30 por ciento.  Las manifestaciones comenzaron en Sidi Buzid, una peque\u00f1a localidad a 265 kil\u00f3metros al sur de T\u00fanez, el 19 de diciembre pasado, y se extendieron a otras ciudades del pais. El gobierno denunci\u00f3 su \u00abmanipulaci\u00f3n con oscuros fines pol\u00edticos\u00bb, hasta que reconoci\u00f3 la gravedad del problema. En el origen, un joven diplomado universitario, obligado a vender frutas y verduras por la calle, al que la polic\u00eda confisc\u00f3 sus mercanc\u00edas. Desesperado, el joven se roci\u00f3 con gasolina e intent\u00f3 inmolarse. Fue salvado a tiempo, pero su vida sigue en estado cr\u00edtico. Cinco d\u00edas despu\u00e9s otro joven se suicid\u00f3 al abalanzarse sobre el tendido de alta tensi\u00f3n. \u00abEl paro es la consecuencia inmediata con todo lo que conlleva\u00bb, explica Tuhami Heni, responsable regional de la central sindical UGTT.  Para la oposici\u00f3n se trata del fracaso del modelo de desarrollo econ\u00f3mico en T\u00fanez. \u00abHay desigualdad entre las regiones\u00bb, afirma Rachid Jechana. \u00abEl 90 por ciento de los proyectos se hacen en las regiones costeras, mientras que el interior del pais s\u00f3lo recoge el 10 por ciento\u00bb. Los universitarios provenientes de las regiones alejadas del mar, no tienen ning\u00fan futuro.  Ayer, lunes 27 de diciembre, la polic\u00eda intervino sin miramientos contra un millar de j\u00f3venes que se manifestaban en el centro de la capital, T\u00fanez, al llamado de los sindicatos independientes, en solidaridad con los j\u00f3venes en el resto del pa\u00eds, reclamando empleo y atajar la corrupci\u00f3n en las cumbres del poder. Los choques entre polic\u00edas y manifestantes se han saldado con al menos 12 heridos. Los enfrentamientos se han extendido a otras ciudades como Sousse, Sfax, Meknassi, Kairuan y Bizerta.  En nombre del Consejo Nacional por las Libertades y el Trabajo (CNLT), una organizaci\u00f3n de la oposici\u00f3n, Sihem Bensedrine ha condenado la represi\u00f3n de las manifestaciones, exigido responsabilidades y manifestado su solidaridad con los j\u00f3venes. Segun el CNLT la regi\u00f3n de Sidi Buzid, donde se originaron los disturbios, tiene una tasa de mas del 32 por ciento de diplomados en paro, la mayor de todo el pais. \u00abEstos j\u00f3venes son tratados con desprecio por las autoridades y no encuentran ning\u00fan marco de expresi\u00f3n, en contra de toda la campa\u00f1a mentirosa de las Autoridades en favor de los j\u00f3venes\u00bb. Para el CNLT, el clima que ha generado las protestas es producto de \u00ablas frustraciones frente al agravamiento de las desigualdades y el enriquecimiento il\u00edcito de personajes cercanos al poder pol\u00edtico\u00bb.  En Europa se han registrado manifestaciones de apoyo a los j\u00f3venes tunecinos. El grupo parlamentario Ecologia y Verdes, del Parlamento europeo, ha afirmado su solidaridad con los manifestantes \u00abque desde hace dias se movilizan por sus derechos en T\u00fanez\u00bb, y exige la liberaci\u00f3n de las personas detenidas y el fin de la pr\u00e1ctica de la tortura. Ecologia-Verdes denuncia as\u00ed mismo el silencio c\u00f3mplice de las autoridades francesas y condena expl\u00edcitamente la pol\u00edtica represiva del r\u00e9gimen del general Ben Ali.  En Argelia, el sindicato independiente de funcionarios p\u00fablicos SNAPAP se ha manifestado en solidaridad con las reivindicaciones leg\u00edtimas de los ciudadanos tunecinos por sus derechos sociales, y denuncia \u00abel asesinato de los dos j\u00f3venes\u00bb que reclamaban su derecho al trabajo y a la dignidad humana.  El portal de oposici\u00f3n tunecino Tunis-News informa adem\u00e1s de que el presidente Ben Ali junto con toda su familia han viajado fuera del pa\u00eds. De ello no hay ning\u00fan comunicado oficial; pero en las filas de la oposici\u00f3n pol\u00edtica se interrogan c\u00f3mo es posible que el Jefe del Estado abandone el pa\u00eds en los momentos en que las protestas se hacen mas virulentas y cuando se ha conocido por medio del portal Wikileaks las exhaustivas informaciones de la corrupci\u00f3n que los diplomaticos estadounidenses han hecho ante las Autoridades de Washington, y que afectan a la familia directa del Presidente. <strong><font>Pedro Canales. <\/font><\/strong> <strong><font>(Source: \u00ab\u00a0El Imparcial\u00a0\u00bb (Quotidien Espagne) le 28 decembre 2010) lien: http:\/\/www.elimparcial.es\/mundo\/revuelta-juvenil-en-tunez-76316.html<\/font><\/strong><\/div>\n<\/div>\n<div>\u00a0<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div align=\"center\"><font size=\"3\"><b>Los colegiales salen a las calles <\/b><\/font><\/div>\n<div align=\"center\">\u00a0<\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong><\/p>\n<h6 style=\"color: blue;\"><font><font size=\"3\">Ola de solidaridad con la protesta popular en T\u00fanez<\/font><\/font><\/h6>\n<p><\/strong><\/font><\/div>\n<div align=\"center\">\n<hr\/>\n<\/div>\n<div><b>Cincuenta organizaciones pol\u00edticas, sindicales y de derechos humanos, han convocado en Par\u00eds una gran manifestaci\u00f3n de solidaridad con la revuelta popular en T\u00fanez. Asociaciones tunecinas, argelinas, marroqu\u00edes, africanas y francesas, se congregar\u00e1n en la plaza de la Fuente de los Inocentes, en el centro de la capital francesa no lejos del museo del Louvre, en apoyo a la revuelta iniciada en la localidad tunecina de Sidi Buzid y que se ha extendido durante el mes de diciembre a media docena de ciudades inclu\u00edda la capital T\u00fanez. <\/b><\/div>\n<div><font>Los convocantes denuncian la represi\u00f3n ejercida por el <b>Poder tunecino<\/b> que ha costado ya la vida a tres manifestantes, y exigen la liberaci\u00f3n de todos los detenidos, estudiantes, empleados, abogados y periodistas. Reclaman adem\u00e1s que \u00ab\u00a0los responsables de la represi\u00f3n contra la poblaci\u00f3n sean llevados ante los tribunales\u00a0\u00bb.  Desde hace ya tres semanas se producen importantes manifestaciones populares en <b>T\u00fanez<\/b>. La \u00faltima ha sido protagonizada por los colegiales de secundaria en la ciudad de Thala, a 250 km al suroeste de la capital. Los alumnos de Institutos y colegios se hab\u00edan trasmitido las consignas para manifestar a trav\u00e9s faceebok, por los tel\u00e9fonos m\u00f3viles y de boca a boca. En el centro de la urbe se congregaron 250 colegiales al t\u00e9rmino de las clases de la tarde. La marcha pac\u00edfica de protesta degener\u00f3 cuando la polic\u00eda carg\u00f3 con bombas lacrim\u00f3genas contra los j\u00f3venes, que respondieron incendiando neum\u00e1ticos y atacando un local del partido en el poder, la Reagrupaci\u00f3n Constitucional Democr\u00e1tica, del presidente Ben Ali.  Las manifestaciones de los colegiales han tenido lugar este lunes 3 de enero, primer d\u00eda de vuelta a las clases tras las vacaciones de A\u00f1o Nuevo. En <b>Sidi Buzid<\/b>, la ciudad en la que empez\u00f3 el movimiento popular de protesta, los j\u00f3venes estudiantes pudieron manifestarse sin incidentes. En la base de todas las acciones de protesta est\u00e1n las tres reivindicaciones que han dado origen a la revuelta : \u00ab\u00a0derecho al trabajo y a ganarse la vida dignamente ; un reparto equitativo de las riquezas ; y contra la corrupci\u00f3n y el nepotismo\u00a0\u00bb. Los tunecinos han conocido por medio de los cables de wikileaks publicados en la red, el nivel de la corrupci\u00f3n que gangrena el aparato del poder, hasta los estamentos familiares del entorno del Jefe del Estado, <b>Zine el Abidine Ben Ali<\/b>. En este \u00faltimo fin de semana se ha denunciado que la familia del Presidente ha sacado del pa\u00eds una verdadera fortuna en joyas, oro y divisas, que las ha llevado a Dubai, donde la esposa de Ben Ali, Leila posee varias residencias de lujo.  La gravedad de la crisis social en el pa\u00eds ha sido admitida por el propio Presidente en su mensaje a la naci\u00f3n el 28 de diciembre pasado. Sindicatos y organizaciones de derechos humanos dentro de T\u00fanez se han declarado solidarios con el movimiento de protesta. La <b>Alianza por la Ciudadan\u00eda y la Igualdad (ACI)<\/b>, estima por su parte que \u00ab\u00a0la amplitud de la crisis pol\u00edtica que vive el pa\u00eds\u00a0\u00bb, est\u00e1 mostrando que \u00ab\u00a0las estructuras y las instituciones legales se encuentran totalmente sometidas a la hegemon\u00eda absoluta del partido en el poder\u00a0\u00bb, y por consiguiente \u00ab\u00a0est\u00e1n desconectadas completamente de las preocupaciones de los ciudadanos\u00a0\u00bb.  La <b>ACI<\/b> constata que \u00ab\u00a0el pensamiento \u00fanico, la monopolizaci\u00f3n del poder de decisi\u00f3n y el tratamiento unilateral de las cuestiones nacionales ha conducido el pa\u00eds a un callej\u00f3n sin salida\u00a0\u00bb. \u00ab\u00a0La \u00fanica manera de salir del mismo es instaurar una verdadera democracia fundada en el pluralismo, la participaci\u00f3n y la transparencia\u00a0\u00bb.  Desde la <b>sociedad civil<\/b> tunecina se han lanzado una serie de cyberataques contra las p\u00e1ginas web gubernamentales. En la noche del 2 de enero, varios portales del gobierno han sido bloqueados por hackers que responden al nombre de \u00ab\u00a0Anonymous\u00a0\u00bb. En un comunicado, este grupo amenaza con retomar el ataque cybern\u00e9tico a gran escala si el gobierno no revisa su pol\u00edtica. Entre sus peticiones est\u00e1 \u00ab\u00a0la apertura del campo medi\u00e1tico y la libertad de la informaci\u00f3n\u00a0\u00bb.<font face=\"Arial\" size=\"2\"><strong>Pedro Canales. Rabat<\/strong><\/font> <font face=\"Arial\" size=\"2\"><strong>(Source: \u00ab\u00a0El Imparcial\u00a0\u00bb (Quotidien Espagne) le\u00a04\u00a0janvier\u00a02011) lien:http:\/\/www.elimparcial.es\/contenido\/76613.html#<\/strong> \u00a0<\/font><\/font><\/div>\n<p><strong><\/p>\n<div>\n<hr\/>\n<\/div>\n<div align=\"center\"><font><font face=\"Arial\"><strong>Amnesty International:\u00a0<\/strong><\/font><font face=\"Arial\" size=\"2\"><strong><font>\u00a0<\/font><\/strong><\/font><\/font><\/div>\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><strong><\/p>\n<h6 style=\"color: blue;\"><font>URGENT ACTION  INCREASED TORTURE RISK FOR TUNISIAN PRISONER<\/font><\/h6>\n<p><\/strong><\/font><\/div>\n<div>\n<hr\/>\n<\/div>\n<div align=\"justify\">Ramzi Romdhani, who is serving a 29-year prison sentence, has been denied family visits since 18 November 2010 as a disciplinary measure. He has repeatedly reported being tortured and otherwise ill-treated while in detention, and is believed to now be at heightened risk of abuse.  When Ramzi Romdhani\u2019s family last saw him in Mornaguia Prison in November, he told them that he had been tortured and severely beaten on his ear and that he had been taken to hospital for treatment. When Ramzi Romdhani\u2019s family tried to visit him the following week, on 25 November, they were told that he had been transferred to Messaidine Prison in Sousse \u2013 around 150 kilometres from Tunis, where his family live. One of Ramzi Romdhani\u2019s relatives travelled to visit him the following day, but was informed that Ramzi Romdhani was subject to disciplinary measures which prevent him from receiving family visits.   They prison authorities have continued to prevent Ramzi Romdhani\u2019s family from seeing him. Every time they visit the prison, they are told to leave as he is still being disciplined. His family last tried to visit him on 5 January. The Messaidine prison authorities have also refused to take the food and clothes that Ramzi Romdhani\u2019s family have brought for him. The continued prohibition on visiting Ramzi Romdhani is in breach of the Tunisian law on prisons, which states that such a ban may not last more than 15 days (Law No. 2001-52, Article 22). Continued denial of family visits sparks fears that he is at an increased risk of torture or other ill-treatment in prison.   Ramzi Romdhani\u2019s family have written letters to the Tunisian authorities, including the Minister of Justice, the Sousse Public Prosecutor and the Prison Director, asking them to be allowed to visit him but have had no answer.   Ramzi Romdhani was arrested in April 2007 and is now serving a sentence totalling 29 years in prison, imposed under anti-terrorism legislation in nine separate cases. He has previously alleged that he was tortured and otherwise ill-treated on at least three occasions: in April 2009, August 2009 and December 2009 (see original UA and follow-ups), but to date the Tunisian authorities have failed to conduct an independent investigation, as required under international law.   PLEASE WRITE IMMEDIATELY in Arabic, French or your own language:  n\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expressing concern that Ramzi Romdhani has been denied family visits since 18 November 2010, in violation of Tunisian law;  n\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Asking the reasons for this, and urging that he be permitted to receive regular family visits without delay;  n\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Calling on the Tunisian authorities to treat him humanely, and not torture or otherwise ill-treat him;  n\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Calling for an urgent thorough, independent and impartial investigation into allegations that Ramzi Romdhani has been tortured, and for any officials found responsible to be brought to justice;  n\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Demanding that they ensure Ramzi Romdhani has access to the medical care he needs.   PLEASE SEND APPEALS BEFORE 18 FEBRUARY 2011 TO:  Minister of Justice and Human Rights  Lazhar Bououni  Ministry of Justice and Human Rights  31 Boulevard Bab Benat\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0  1006 Tunis \u2013 La Kasbah\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0  Fax: + 216 71 568 106  Salutation: Your Excellency   Minister of Interior  Rafik Belhaj Kacem\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0  Ministry of Interior and Local Development  Avenue Habib Bourguiba\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0  1000 Tunis\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0  Fax: +216 71 340 888  Salutation: Your Excellency   And copies to:  Directeur g\u00e9n\u00e9ral des prisons et de la r\u00e9\u00e9ducation Rue 8003 \u2013 Appartement L  Espace de Tunis  Monplaisir, Tunis  Also send copies to diplomatic representatives accredited to your country. Please check with your section office if sending appeals after the above date. This is the second update of UA 130\/09 (MDE 30\/004\/2009). Further information: http:\/\/www.amnesty.org\/en\/library\/info\/MDE30\/004\/2009\/en and http:\/\/www.amnesty.org\/en\/library\/info\/MDE30\/001\/2010\/en Additional Information  On 31 December 2009, Ramzi Romdhani told his brother that he was tortured on 24 and 25 December after he had been transferred to the Department of State Security (DSS) of the Ministry of Interior in the Tunisian capital, Tunis, from Mornaguia Prison. He said he was tortured for two days and interrogated in connection with other cases. He told his brother that he was beaten, had his nails and fingers burned and that his head was plunged repeatedly in hot water for about 30 minutes. He said he was beaten on his eyes and sustained serious eye injuries. During the visit, his brother was able to observe several bruises on his body and burn marks on his fingers. In April 2009, Ramzi Romdhani is reported to have been tortured and otherwise ill-treated by officers at Mornaguia Prison, by guards who beat him with sticks, kicked him while wearing military boots, inflicted cigarette burns on his body, and plunged his head repeatedly into a bucket of water causing him to fear drowning and eventually to lose consciousness.  In August 2009, he alleges that he was beaten by prison guards and then taken to the DSS, where he was tortured, including with electric shocks, suspension and simulation of hanging.  In December 2009, the prison doctor at Mornaguia told Ramzi Romdhani that he required surgery to safeguard his sight but it is not known whether this has been provided. He is reported to have sustained serious eye injuries while detained for interrogation by officials of the Department of State Security of the Ministry of Interior in Tunis. His brother was arrested on 18 January 2010 at his home by eight DSS officers and detained incommunicado until 20 January, when he was released uncharged. His arrest is believed to have been linked to his efforts to expose and publicize the torture and other ill-treatment of Ramzi Romdhani, including his contacts with human rights lawyers and local and international human rights organizations. Amnesty International has received numerous reports of torture and other ill-treatment by the Tunisian security forces. In virtually all cases, allegations of torture are not investigated and the perpetrators are not brought to justice. Individuals are most at risk of torture when held incommunicado. The most commonly reported methods of torture are beatings on the body, especially the soles of the feet; suspension by the ankles or in contorted positions; electric shocks; and burning with cigarettes. There are also reports of mock executions, sexual abuse, including rape with bottles and sticks, and threats of sexual abuse of female relatives.  Tunisia is a state party to the Convention against Torture and Other Cruel, Inhuman or Degrading Treatment or Punishment, and the Tunisian authorities are under an obligation to prevent torture and to \u201censure that its competent authorities proceed to a prompt and impartial investigation, wherever there is reasonable ground to believe that an act of torture has been committed in any territory under its jurisdiction.\u201d  Tunisia\u2019s anti-terrorism legislation has been repeatedly criticized by UN human rights bodies and local and international human rights organizations as overly general and broad, and could be used as a repressive measure to curtail legitimate dissent. Similar concerns were reiterated by the United Nations Human Rights Committee in March 2008 in its concluding observations regarding Tunisia and by the Special Rapporteur on the promotion and protection of human rights and fundamental freedoms while countering terrorism following his visit to Tunisia in January 2010.  Further information on UA: 130\/09 Index: MDE 30\/001\/2011 Issue Date: 7 January 2011   &#8212;  Working to protect human rights worldwide  DISCLAIMER  This email has been sent by Amnesty International Limited (a company registered in England and Wales limited by guarantee, number 01606776 with registered office at 1 Easton St, London WC1X 0DW). Internet communications are not secure and therefore Amnesty International does not accept legal responsibility for the contents of this message. If you are not the intended recipient you must not disclose or rely on the information in this e-mail. Any views or opinions presented are solely those of the author and do not necessarily represent those of Amnesty International unless specifically stated. Electronic communications including email might be monitored by Amnesty International for operational or business reasons.  This message has been scanned for viruses by Postini.<a href=\"http:\/\/www.postini.com\/\" target=\"_blank\" rel=\"noopener\">www.postini.com<\/a> <\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\"><font face=\"Arial\" size=\"2\"><\/p>\n<h6 style=\"color: blue;\"><font size=\"3\"><strong>Disparu depuis le 25 novembre ! Qu\u2019est-il arriv\u00e9 \u00e0 Ramzi Romdhani ?<\/strong><\/font><\/h6>\n<p><\/font><\/div>\n<div align=\"justify\">\n<hr\/>\n<p> Sa famille n\u2019a plus de nouvelles de lui depuis le 25 novembre. Ramzi Romdhani, prisonnier politique, ant\u00e9rieurement \u00e0 la prison de Mornaguia, a \u00e9t\u00e9 transf\u00e9r\u00e9 arbitrairement \u00e0 la prison de Messaadine. C\u2019est l\u00e0 que se rend hebdomadairement sa famille, vivant \u00e0 Tunis, dans l\u2019espoir de le revoir. A chaque fois la r\u00e9ponse est la m\u00eame : pas de visite. La raison ? Il serait \u00ab sanctionn\u00e9 \u00bb. Or la loi portant organisation des prisons limite la sanction \u00e0 dix jours. Il y a maintenant un mois et demi que sa famille n\u2019a pu lui rendre visite et ni m\u00eame obtenir arracher une quelconque information.  Hier, 6 janvier, son fr\u00e8re s\u2019est rendu \u00e0 la prison de Messaadine et a demand\u00e9 \u00e0 rendre visite \u00e0 son fr\u00e8re, en vain. Il avait \u00e9galement \u00e9crit au Procureur de la R\u00e9publique de Sousse et \u00e0 l&rsquo;Administration g\u00e9n\u00e9rale des prison et n&rsquo;a pas re\u00e7u de r\u00e9ponse. Pour rappel, Ramzi Romdhani, n\u00e9 en 1977, mari\u00e9 et p\u00e8re d\u2019un enfant, a \u00e9t\u00e9 arr\u00eat\u00e9 en 2007 et condamn\u00e9 sur les fondements de la loi anti terroriste \u00e0 29 ans d\u2019emprisonnement dans des affaires distinctes mais pour les m\u00eames faits. Depuis son incarc\u00e9ration, il a subi \u00e0 plusieurs reprises de graves tortures, notamment \u00e0 l\u2019\u00e9lectricit\u00e9, et des mauvais traitements.  Signez l\u2019appel lanc\u00e9 par l\u2019Organisation Mondiale contre la Torture : http:\/\/ www.omct.org\/fr\/urgent-campaigns\/urgent-interventions\/tunisia\/2010\/12\/d20955 <strong><font>Luiza Toscane<\/font><\/strong><\/div>\n<\/div>\n<p><\/strong><\/div>\n<p> \u00a0<\/p>\n<\/div>\n<\/div>\n<p> \u00a0<\/p>\n<\/div>\n<p><\/font><\/div>\n<p dir=\"ltr\">\u00a0<\/p>\n<\/div>\n<p align=\"center\" dir=\"ltr\">\n<h6 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong><b><a href=\"http:\/\/www.tunisnews.net\/\"><font face=\"Arial\"><span><font size=\"2\">Home<\/font><\/span><font size=\"2\"><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><\/font><\/font><span dir=\"rtl\" lang=\"AR-SA\"><font size=\"2\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/font><\/span><\/a><\/b><\/strong><\/font><\/h6>\n<\/p>\n<p align=\"center\" dir=\"ltr\">\u00a0<\/p>\n<p><\/body><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Accueil TUNISNEWS 10 \u00e8me ann\u00e9e, N\u00b0 3881 du 07.01.2011 archives : www.tunisnews.net C.R.L.D.H. Tunisie: Tirs \u00e0 balles r\u00e9elles \u00e0 Regueb &#8211; Les protestations continuent en Tunisie Libert\u00e9 et Equit\u00e9: Poursuite du mouvement de protestation et de solidarit\u00e9 &#8211; Encore des affrontements entre les lyc\u00e9ens et les forces de police CNSPBM: Sit-in et affrontements [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[53,42,29],"class_list":["post-17473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-53","tag-42","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=17473"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=17473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=17473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=17473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}