{"id":17349,"date":"2009-09-09T00:00:00","date_gmt":"2009-09-09T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/9-septembre-2009\/"},"modified":"2009-09-09T00:00:00","modified_gmt":"2009-09-09T00:00:00","slug":"9-septembre-2009","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/9-septembre-2009\/","title":{"rendered":"9 septembre 2009"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\"Un policier en \t\t\t\t\t\t\t\t\t\tcivil s\u2019est pr\u00e9sent\u00e9 cet apr\u00e8s-midi \u00e0 \t\t\t\t\t\t\t\t\t\t15h30 heure locale, au domicile de Me \t\t\t\t\t\t\t\t\t\tRadhia Nasraoui, d\u00e9fenseure des droits \t\t\t\t\t\t\t\t\t\thumains et pr\u00e9sidente de l\u2019ALTT, et de \t\t\t\t\t\t\t\t\t\tHamma Hammami, porte parole du PCOT.\" http-equiv=\"Content-Type\"\/><\/head><body><body><\/p>\n<p align=\"center\" dir=\"ltr\"><font face=\"Arial\" size=\"2\"><b><a href=\"https:\/\/tunisnews.net\/ar\/\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accuei<\/span><\/a><span lang=\"FR-CH\">l<\/span><\/b><\/font><\/p>\n<div>\n<div><font face=\"Arial\" size=\"2\"><\/p>\n<div align=\"left\">\n<div>\n<div>\n<div align=\"justify\">\n<div>\u00a0<meta content=\"Microsoft SafeHTML\"\/><\/p>\n<style>.ExternalClass .ecxhmmessage P{padding:0px;}.ExternalClass body.ecxhmmessage{font-size:10pt;font-family:Verdana;}<\/style>\n<div>\n<div align=\"center\"><font face=\"Arial\" size=\"7\"><strong>TUNISNEWS<\/strong> <\/font><\/div>\n<div align=\"center\" dir=\"ltr\"><font><\/p>\n<div><strong><font face=\"Arial\">9\u00a0\u00e8me ann\u00e9e,<span lang=\"FR\">N\u00b0\u00a03426 du 09.10.2009<\/span><\/font><\/strong><\/div>\n<p><\/font><\/div>\n<div align=\"center\"><span><font><strong><font face=\"Arial\"><font>\u00a0archives<\/font> : <\/font><\/strong><\/font><a target=\"_blank\" rel=\"noopener\"><font face=\"Arial\"><strong>www.tunisnews.net<\/strong><\/font><\/a><\/span><font face=\"Arial\"><font>\u00a0<\/font>\u00a0<\/font><\/div>\n<p><font face=\"Arial\"><\/p>\n<div><font><\/p>\n<hr\/>\n<p><\/font><\/div>\n<p><\/font><\/p>\n<div>\n<div><span lang=\"FR-CH\"><strong>Al Badil Express: Radhia Nasraoui et Hamma Hammami convoqu\u00e9s cet apr\u00e8s-midi par la brigade de lutte anti- criminelle <font>Dr. Patrick CHALTIEL: Le jugement en appel du Dr Ahmed ELEUCH ajourn\u00e9 pour le 15 octobre 2009 !<\/font> Luiza Toscane: 6 octobre 2008-6 octobre 2009 : un an de r\u00e9tention, mais pourquoi ? &#8211; Les six de Lukavica sont en gr\u00e8ve de la faim <font>Omar Khayyam: Les mirages de Carthage<\/font> Le Monde: A Tunis, le quotidien d&rsquo;un couple d&rsquo;opposants <font>Le Monde: La Tunisie et ses ombres<\/font> Le Monde: Cyber-r\u00e9sistants au Maghreb <font>AFP: Pr\u00e8s du quart de la plan\u00e8te est musulmane, soit 1,57 milliard de personnes (\u00e9tude)<\/font> PurePeople: Diam&rsquo;s : la chanteuse est d\u00e9sormais mari\u00e9e&#8230; et voil\u00e9e ! <font>AFP: L&rsquo;UE accepte de signer un accord d&rsquo;association avec la Syrie (diplomates)<\/font> AFP: Accord UE-Syrie: \u00ab\u00a0nouvelle \u00e9tape dans la dynamique de rapprochement\u00a0\u00bb (Paris)<\/strong><\/span><\/div>\n<div>\n<hr\/>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div align=\"center\">\n<p><font size=\"3\"><\/p>\n<div align=\"center\"><font face=\"Arial\"><font size=\"2\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Radhia Nasraoui et Hamma Hammami convoqu\u00e9s cet apr\u00e8s-midi par la brigade de lutte anti- criminelle<\/font><\/h2>\n<p> \u00a0<\/strong><\/font><\/font><\/div>\n<p><font size=\"2\"><\/p>\n<div align=\"justify\"> <font>Un policier en civil s\u2019est pr\u00e9sent\u00e9 cet apr\u00e8s-midi \u00e0 15h30 heure locale, au domicile de Me Radhia Nasraoui, d\u00e9fenseure des droits humains et pr\u00e9sidente de l\u2019ALTT, et de Hamma Hammami, porte parole du PCOT.  Il est venu remettre \u00e0 Me Nasraoui une convocation pour 16h00, soit 30 minutes plus tard, aux locaux de la brigade de lutte anti- criminelle section d\u2019Elgorjani. Me Nasraoui a refus\u00e9 de recevoir cette convocation ill\u00e9gale, car ne mentionnant aucun motif.  A 17h15, le m\u00eame agent revient, cette fois-ci pour remettre \u00e0 Hamma Hammami une convocation pour 17h30 \u00e0 la m\u00eame section de la brigade de lutte anti-criminelle. Il a refus\u00e9 la convocation car aucun motif n\u2019y est inscrit.  Tout laisse \u00e0 penser que le but dissimul\u00e9 derri\u00e8re ces convocations, est d\u2019emp\u00eacher Hamma Hammami de se rendre \u00e0 Paris ce soir. Il devrait intervenir dans une conf\u00e9rence organis\u00e9e par l\u2019association sciences Po Monde Arabe demain 10 octobre 2009. Le th\u00e8me en est la situation politique et sociale en Tunisie \u00e0 la veille des \u00ab\u00a0\u00e9lections\u00a0\u00bb du 25 de ce mois.<\/font> <font><strong>(Source: \u00ab\u00a0Al Badil Express\u00a0\u00bb le 9 octobre 2009)<\/strong><\/font><\/div>\n<p><\/font><\/font><\/p>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\"><\/p>\n<hr\/>\n<p>Le jugement en appel du Dr Ahmed ELEUCH ajourn\u00e9 pour le 15 octobre 2009 !<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\"> Nous portons \u00e0 la connaissance de l&rsquo;opinion publique que la cour d&rsquo;appel de Tunis a d\u00e9cid\u00e9 le 5 octobre 2009 de reporter la prononciation de son jugement en appel pour le 15 octobre 2009. Dr Ahmed Eleuch a \u00e9t\u00e9 emprisonn\u00e9 pour des raisons politiques pendant 49 jours avant d&rsquo;\u00eatre lib\u00e9r\u00e9 par une gr\u00e2ce pr\u00e9sidentielle. Cette lib\u00e9ration a \u00e9t\u00e9 unanimement appr\u00e9ci\u00e9e et salu\u00e9e par de tr\u00e8s nombreux soutiens \u00e0 travers le monde entier. \u00a0 Malgr\u00e9 le fait que ce report a \u00e9t\u00e9 pr\u00e9text\u00e9 par l&rsquo;absence d&rsquo;un document judiciaire, et sans vouloir commenter la d\u00e9cision de la justice tunisienne, nous tenons \u00e0 exprimer, malgr\u00e9 tout, notre inqui\u00e9tude occasionn\u00e9e par ce report et nous exprimons notre souhait que la gr\u00e2ce pr\u00e9sidentielle obtenue puisse permettre de cl\u00f4turer cette affaire politique le plus rapidement possible.   Notre ami Ahmed Eleuch sera contraint de s&rsquo;absenter de son travail \u00e0 Paris pendant plusieurs jours pour aller, encore une fois, se pr\u00e9senter devant les juges pour un dossier vide, vieux de 17 ans.  Nous demeurons vigilants, avec un vrai espoir que le 15 octobre prochain sera l&rsquo;occasion de classer d\u00e9finitivement cette affaire qui nuit aussi bien \u00e0 l&rsquo;image de la Tunisie qu&rsquo;\u00e0 celle de la France.  <font><strong>Dr. Patrick CHALTIEL<\/strong><\/font> <strong><font>Pr\u00e9sident du Comit\u00e9 International pour la lib\u00e9ration d\u2019Ahmed Eleuch<\/font><\/strong> Site internet : www.liberez-ahmed-eleuch.net Contact : liberez.ahmed.eleuch@gmail.com<\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\n<div><span lang=\"EN\"><\/p>\n<p align=\"center\">\n<p><font face=\"Arial\"><strong>6 octobre 2008-6 octobre 2009 : un an de r\u00e9tention, mais pourquoi ?\u00a0 Les six de Lukavica sont en gr\u00e8ve de la faim<\/strong><\/font><\/p>\n<\/p>\n<p align=\"justify\">Le 6 octobre 2008, Imad El Houssine, un Bosniaque d\u2019origine syrienne, \u00e9tait plac\u00e9 au centre de r\u00e9tention pour \u00e9trangers de Lukavica, dans l\u2019attente de son renvoi en Syrie. Le 6 octobre 2009, il est toujours au centre, d\u00e9chu officiellement de sa nationalit\u00e9 bosniaque, confirm\u00e9 dans le rejet de sa demande d\u2019asile et de titre de s\u00e9jour. A la suite de sa plainte au niveau de la CEDH, diff\u00e9rentes juridictions bosniaques se sont renvoy\u00e9es la balle, dans une interminable partie de ping-pong dont on imagine mal le d\u00e9nouement. Au cours de l\u2019ann\u00e9e 2009, il a \u00e9t\u00e9 rejoint par cinq compagnons d\u2019infortune : le 10 f\u00e9vrier : Omar Frendi, un ex Bosniaque d\u2019origine alg\u00e9rienne, le 24 avril : Amar Al Hanchi, un ex Bosniaque d\u2019origine tunisienne, le 4 mai : Zeyad Algertani, un ex Bosniaque d\u2019origine irakienne, le 5 mai : A\u00efssa Benkhira, un ex-Bosniaque d\u2019origine alg\u00e9rienne et le 23 juin : Fadhil Saaied Awad Al-Hamdani, un ex-Bosniaque d\u2018origine irakienne.<\/p>\n<p align=\"justify\">Deux d\u2019entre eux sont venus en Yougoslavie, -c\u2019est le cas de Fadhil el Hamdani et Imad El Houssine-, pour y suivre leurs \u00e9tudes. Les autres sont arriv\u00e9s plus tard en Bosnie, pour des pr\u00eater main forte aux musulmans bosniaques.<\/p>\n<p align=\"justify\">Tous sont mari\u00e9s \u00e0 des ressortissantes bosniaques et ont des enfants bosniaques. En application de la nouvelle loi sur la nationalit\u00e9, cette derni\u00e8re leur a \u00e9t\u00e9 retir\u00e9e et ils n\u2019ont pas eu droit au s\u00e9jour au Bosnie, l\u2019argumentaire des autorit\u00e9s de ce pays reposant en derni\u00e8re analyse sur l\u2019invocation d\u2019une menace pour la s\u00e9curit\u00e9 du pays. Bien \u00e9videmment, la raison en question repose sur des \u00e9l\u00e9ments ou des preuves que ni les int\u00e9ress\u00e9s ni leurs avocats n\u2019ont \u00e9t\u00e9 autoris\u00e9s \u00e0 conna\u00eetre. C\u2019est en vertu d\u2019un d\u00e9cret r\u00e9galien, qui les prive de toute d\u00e9fense, qu\u2019ils sont aujourd\u2019hui retenus, retenus et non incarc\u00e9r\u00e9s, car l\u2019incarc\u00e9ration suppose passage devant la justice, acc\u00e8s au dossier, droit de se d\u00e9fendre et prononc\u00e9 d\u2019une peine limit\u00e9e dans le temps ainsi que et des droits pour le prisonnier. La r\u00e9tention au centre pour \u00e9trangers de Lukavica est une peine non prononc\u00e9e par une juridiction, ind\u00e9finie, donc illimit\u00e9e ? Guantanamo en Bosnie ? Les retenus n\u2019ont pas acc\u00e8s aux droits r\u00e9serv\u00e9s \u00e0 des prisonniers et vivent de plus dans l\u2019angoisse d\u2019un renvoi vers leurs pays d\u2019origine, pays o\u00f9 ils seraient tortur\u00e9s et emprisonn\u00e9s, dans la crainte d\u2019une s\u00e9paration d\u00e9finitive d\u2019avec leurs \u00e9pouses et enfants.<\/p>\n<p align=\"justify\">Les centaines d\u2019ex Bosniaques d\u2019origine arabe ou musulmane n\u2019ont pas tous \u00e9t\u00e9 arr\u00eat\u00e9s et plac\u00e9s au centre de r\u00e9tention. Les autorit\u00e9s bosniaques ont fait du z\u00e8le en mettant \u00e0 profit le contexte la visite en Bosnie de Jo Biden, le vice-Pr\u00e9sident des Etats-Unis pour d\u00e9ployer des forces de police devant les domiciles de ces ex Bosniaques et en arr\u00eater certains, ce qui accr\u00e9dite la th\u00e8se d\u2019arrestation pour des raisons uniquement politiques. Le ministre de la S\u00fbret\u00e9, Tarik Sadovic, aurait \u00e9t\u00e9 d\u00e9mis de ses fonctions en juillet 2009 pour avoir fait de l\u2018obstruction \u00e0 l\u2018expulsion \u00e0 des arabo musulmans, et les Am\u00e9ricains auraient exerc\u00e9 des pressions sur son parti . Mais les Am\u00e9ricains et les Europ\u00e9ens qui ont mis le pays sous leur tutelle ont peut-\u00eatre obtenu gain de cause puisque nombre de ces ex-Bosniaques se sont enfuis de Bosnie dans la crainte d\u2019\u00eatre arr\u00eat\u00e9s et renvoy\u00e9s vers leurs pays d\u2019origine.<\/p>\n<p align=\"justify\">Faute de preuves, et pour tenter de monter l\u2019opinion publique contre eux ?, cet \u00e9t\u00e9, une partie de la presse a utilis\u00e9 largement l\u2019\u00e9vasion d\u2019un criminel de droit commun, Kamel Karray, un ex Bosniaque d\u2019origine tunisienne, pour cr\u00e9er l\u2019amalgame. Le <i>Balkan Investigative Reporting Network<\/i> est all\u00e9 jusqu\u2019\u00e0 le pr\u00e9senter comme \u00ab\u3000le chef des islamistes de Bosnie\u3000\u00bb ou \u00ab\u3000une figure centrale des r\u00e9seaux islamistes\u3000\u00bb et sa photo a \u00e9t\u00e9 remplac\u00e9e par celle d\u2019Imed El Hussine dans la pr\u00e9sentation qui en a \u00e9t\u00e9 faite par \u00ab\u3000Le Courrier des Balkans\u3000\u00bb qui a traduit et publi\u00e9 l\u2018article en fran\u00e7ais .<\/p>\n<p align=\"justify\">A l\u2019heure o\u00f9 les secrets d\u2019Etat se doublent d\u2019une campagne m\u00e9diatique, les six de Lukavica et les familles qu\u2019ils ont fond\u00e9es en Bosnie devraient pouvoir compter sur le soutien des d\u00e9fenseurs des droits de l\u2019Homme. Le 4 octobre dernier, ils ont annonc\u00e9 qu\u2019ils commen\u00e7aient une gr\u00e8ve de la faim et ils se sont adress\u00e9s aux institutions europ\u00e9ennes, aux autorit\u00e9s bosniaques et aux ONG internationales de droits de l\u2019homme pour les presser d\u2019intervenir .<\/p>\n<p><font face=\"Arial\" size=\"2\"><strong>Luiza Toscane<\/strong><\/font> \u00a0<\/span><\/div>\n<\/div>\n<div>\n<hr\/>\n<\/div>\n<div>\u00a0<\/div>\n<div>\n<div align=\"center\">\n<h2 style=\"color: red;\"><font size=\"3\"><strong>Les mirages de Carthage<\/strong><\/font><\/h2>\n<\/div>\n<p> Tunis &#8211; (TNA) &#8211; L\u2019\u00e9tat de sant\u00e9 du g\u00e9n\u00e9ral Zine El-Abidine Ben Ali est le sujet de conversation num\u00e9ro un en Tunisie. Que se passera-t-il en si sa maladie prolong\u00e9e l\u2019emp\u00eache d\u2019exercer ses fonctions pr\u00e9sidentielles?\u00a0 L\u2019article 57 de la Constitution est clair \u00e0 ce sujet (1). En cas de \u00ab\u00a0d\u00e9c\u00e8s, de d\u00e9mission ou d\u2019emp\u00eachement absolu\u00a0\u00bb, le pr\u00e9sident de la Chambre des d\u00e9put\u00e9s est imm\u00e9diatement investi des fonctions de la Pr\u00e9sidence de l\u2019\u00c9tat par int\u00e9rim\u00a0\u00bb.   Le probl\u00e8me qui se pose aujourd\u2019hui: comment constater l\u2019emp\u00eachement absolu ? Le Conseil constitutionnel osera-t-il, le jour J, r\u00e9quisitionner un groupe des m\u00e9decins dont la mission serait d\u2019ausculter Ben Ali et de constater son incapacit\u00e9 \u00e0 exercer le pouvoir ?\u00a0 Si ce sc\u00e9nario de la destitution m\u00e9dicale se r\u00e9alise, la t\u00e2che de l\u2019actuel pr\u00e9sident du parlement, Foued M\u2019bazzaa, ne sera pas facile. Puisque la Constitution lui interdit de se porter candidat \u00e0 la pr\u00e9sidence, il jouera le r\u00f4le ingrat d\u2019arbitre dans la guerre des clans qui se d\u00e9clenchera d\u00e8s le d\u00e9part de Ben Ali de Carthage.   Si Le\u00efla et son clan sortent perdants de la \u00ab\u00a0guerre civile\u00a0\u00bb autour du tr\u00f4ne de Carthage, ils n\u2019auront d\u2019autre choix que de quitter la Tunisie \u00e0 la sauvette. La Tunisie paiera une forte ran\u00e7on pour leur d\u00e9part d\u00e9finitif. Des milliards de dinars tunisiens convertis en dollars prendront l\u2019avion pour aller passer des vacances dor\u00e9es en Egypte, \u00e0 Abu Dhabi, au Canada etc.  \u00c0 Redeyef, il y aura une autre explosion populaire. Mais cette fois-ci ce sera une explosion de joie. Les \u00ab\u00a0chiens de Le\u00efla\u00a0\u00bb, c.-\u00e0-d. les flics anti-\u00e9meute, ne tabasseront plus la population et ne pilleront plus les commerces. Mais cette joie sera de courte dur\u00e9e. Passer d\u2019un Omar Bongo \u00e0 un Ali Bongo est-ce vraiment un changement ? That\u2019s the question !  \u2014   <strong>(1)- Article 57 (Modifi\u00e9 par la loi constitutionnelle n\u00b0 88-88 du 25 juillet 1988 et par la loi constitutionnelle n\u00b0 2002-51 du 1er juin 2002).<\/strong> <font>\u00a0\u00bb En cas de vacance de la Pr\u00e9sidence de la R\u00e9publique pour cause de d\u00e9c\u00e8s, de d\u00e9mission ou d\u2019emp\u00eachement absolu, le Conseil constitutionnel se r\u00e9unit imm\u00e9diatement et constate la vacance d\u00e9finitive \u00e0 la majorit\u00e9 absolue de ses membres. Il adresse une d\u00e9claration \u00e0 ce sujet au pr\u00e9sident de la Chambre des conseillers et au pr\u00e9sident de la Chambre des d\u00e9put\u00e9s qui est imm\u00e9diatement investi des fonctions de la Pr\u00e9sidence de l\u2019Etat par int\u00e9rim, pour une p\u00e9riode variant entre quarante cinq jours au moins et soixante jours au plus. Si la vacance d\u00e9finitive co\u00efncide avec la dissolution de la Chambre des d\u00e9put\u00e9s, le pr\u00e9sident de la Chambre des conseillers est investi des fonctions de la Pr\u00e9sidence de l\u2019Etat par int\u00e9rim et pour la m\u00eame p\u00e9riode.  Le Pr\u00e9sident de la R\u00e9publique par int\u00e9rim pr\u00eate le serment constitutionnel devant la Chambre des d\u00e9put\u00e9s et la Chambre des conseillers r\u00e9unies en s\u00e9ance commune et, le cas \u00e9ch\u00e9ant, devant les deux bureaux des deux Chambres. Si la vacance d\u00e9finitive co\u00efncide avec la dissolution de la Chambre des d\u00e9put\u00e9s, le Pr\u00e9sident de la R\u00e9publique par int\u00e9rim pr\u00eate le serment constitutionnel devant la Chambre des conseillers et, le cas \u00e9ch\u00e9ant, devant son bureau \u00ab\u00a0.  Le Pr\u00e9sident de la R\u00e9publique par int\u00e9rim ne peut pr\u00e9senter sa candidature \u00e0 la Pr\u00e9sidence de la R\u00e9publique m\u00eame en cas de d\u00e9mission.  Le Pr\u00e9sident de la R\u00e9publique par int\u00e9rim exerce les attributions d\u00e9volues au Pr\u00e9sident de la R\u00e9publique sans, toutefois, pouvoir recourir au r\u00e9f\u00e9rendum, d\u00e9mettre le gouvernement, dissoudre la Chambre des d\u00e9put\u00e9s ou prendre les mesures exceptionnelles pr\u00e9vues par l\u2019article 46.  \u00a0\u00bb Il ne peut \u00eatre proc\u00e9d\u00e9, au cours de la p\u00e9riode de la pr\u00e9sidence par int\u00e9rim, ni \u00e0 la modification de la Constitution ni \u00e0 la pr\u00e9sentation d\u2019une motion de censure contre le Gouvernement. \u00a0\u00bb  Durant cette m\u00eame p\u00e9riode des \u00e9lections pr\u00e9sidentielles sont organis\u00e9es pour \u00e9lire un nouveau Pr\u00e9sident de la R\u00e9publique pour un mandat de cinq ans.  Le nouveau Pr\u00e9sident de la R\u00e9publique peut dissoudre la Chambre des d\u00e9put\u00e9s et organiser des \u00e9lections l\u00e9gislatives anticip\u00e9es conform\u00e9ment aux dispositions du deuxi\u00e8me alin\u00e9a de l\u2019article 63.  <\/font><font><strong>(Source : blog de Omar Khayyam (censur\u00e9 en Tunisie), le 7 octobre 2009) Lien : http:\/\/omarkhayyam.blogsome.com\/<\/strong><\/font>  \u00a0<\/p>\n<hr\/>\n<div align=\"center\"><strong>Reportage  <\/p>\n<h2 style=\"color: red;\"><font size=\"3\">A Tunis, le quotidien d&rsquo;un couple d&rsquo;opposants<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\"> Chronique de la vie quotidienne d&rsquo;une opposante politique et d&rsquo;un d\u00e9fenseur des droits de l&rsquo;homme en Tunisie. Acte I : le 29 septembre au matin, Radhia Nasraoui, une avocate connue pour sa lutte en faveur des libert\u00e9s, d\u00e9couvre en quittant son domicile de Tunis que les quatre pneus de sa voiture ont \u00e9t\u00e9 taillad\u00e9s. Tous les opposants subissent ce genre de repr\u00e9sailles. ..  L&rsquo;avocate s&rsquo;appr\u00eatait \u00e0 aller chercher son mari, Hamma Hammami, \u00e0 l&rsquo;a\u00e9roport de Tunis-Carthage. Porte-parole du Parti communiste des ouvriers de Tunisie (PCOT), une petite formation, il a d\u00e9nonc\u00e9, quatre jours plus t\u00f4t, sur Al-Jazira et France 24, la r\u00e9pression, la corruption et la fa\u00e7on, a-t-il dit, \u00ab\u00a0dont la famille du pr\u00e9sident Ben Ali s&rsquo;enrichit sur le dos des Tunisiens\u00a0\u00bb. Dans la foul\u00e9e, il a appel\u00e9 au boycottage de l&rsquo;\u00e9lection pr\u00e9sidentielle du 25 octobre.  Acte II. Alors qu&rsquo;il est encore dans l&rsquo;a\u00e9roport, du c\u00f4t\u00e9 de la douane, dans la partie inaccessible au public, Hammami est encercl\u00e9 par une vingtaine de policiers en civil. \u00ab\u00a0Ils se sont ru\u00e9s sur moi et m&rsquo;ont rou\u00e9 de coups\u00a0\u00bb, raconte-t-il. Le passage \u00e0 tabac se poursuit dans un petit bureau. Hammami est ensuite tra\u00een\u00e9 hors de l&rsquo;a\u00e9rogare, toujours sous une vol\u00e9e de coups. Sa femme tente d&rsquo;intervenir. Elle se fait malmener. \u00ab\u00a0J&rsquo;ai vu Hammami juste apr\u00e8s son agression. Il crachait du sang, souffrait d&rsquo;une blessure \u00e0 l&rsquo;oeil, d&rsquo;une autre \u00e0 l&rsquo;oreille et saignait de partout\u00a0\u00bb, t\u00e9moigne Mokhtar Trifi, le pr\u00e9sident de la Ligue tunisienne des droits de l&rsquo;homme.  Exploser \u00e0 tout moment  Acte III. Le 4 octobre, Hammami, en compagnie de sa fille Sarah, 10 ans, se rend de nouveau \u00e0 l&rsquo;a\u00e9roport de Tunis-Carthage pour accueillir sa femme de retour de Gen\u00e8ve. Comme sa voiture n&rsquo;a toujours pas \u00e9t\u00e9 r\u00e9par\u00e9e, un ami avocat, Raouf Ayadi, l&rsquo;accompagne.  Sur place, bizarrement, les choses tra\u00eenent en longueur. Le bagage de Radhia Nasraoui est introuvable. Quand ils finissent par regagner le parking, sans la valise, ils d\u00e9couvrent que la voiture de Raouf Ayadi a \u00e9t\u00e9 forc\u00e9e. Elle peine \u00e0 d\u00e9marrer. Un bruit \u00e9trange s&rsquo;\u00e9chappe du r\u00e9servoir \u00e0 essence. Les quatre passagers sortent du v\u00e9hicule. Ils appellent \u00e0 l&rsquo;aide un m\u00e9canicien. Celui-ci leur dit apr\u00e8s examen du r\u00e9servoir : \u00ab\u00a0On a m\u00e9lang\u00e9 \u00e0 l&rsquo;essence un produit inflammable. \u00a0\u00bb Quelques heures plus tard, un professeur de chimie \u00e0 l&rsquo;universit\u00e9 de Tunis confirme le diagnostic : \u00ab\u00a0Il s&rsquo;agit de la combinaison de deux acides, tr\u00e8s dangereux. \u00c7a pouvait exploser \u00e0 tout moment.\u00a0\u00bb  \u00ab\u00a0Est-ce qu&rsquo;on finira par nous liquider physiquement ?\u00a0\u00bb, s&rsquo;interroge Radhia Nasraoui.  <strong><font>Florence Beaug\u00e9<\/font><\/strong> <font><strong>(Source : \u00ab Le Monde \u00bb (Quotidien \u2013 France), le 9 octobre 2009)<\/strong><\/font> \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">La Tunisie et ses ombres<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Dans une Tunisie anesth\u00e9si\u00e9e par plus de vingt ann\u00e9es de r\u00e9gime policier, il est difficile d&rsquo;imaginer le temps o\u00f9 une vie politique fi\u00e9vreuse animait le pays. Cette p\u00e9riode, qui pr\u00e9c\u00e8de l&rsquo;ind\u00e9pendance de la Tunisie et court jusqu&rsquo;\u00e0 ce que le pr\u00e9sident Bourguiba devienne un despote, Gilbert Naccache la fait revivre avec l&rsquo;honn\u00eatet\u00e9 de l&rsquo;historien et la passion de celui qui en fut un t\u00e9moin et un acteur.  A 15 ans, \u00ab\u00a0jeune lyc\u00e9en juif avide d&rsquo;action\u00a0\u00bb, Naccache est s\u00e9duit par le Parti communiste qui lutte, au c\u00f4t\u00e9 du N\u00e9o-Destour de Bourguiba, pour l&rsquo;ind\u00e9pendance. L&rsquo;ambiance est \u00ab\u00a0formidable\u00a0\u00bb. Fr\u00e9quenter le Parti, c&rsquo;est croiser dans les rangs nationalistes des intellectuels prestigieux et vivre une semi-clandestinit\u00e9 exaltante et sans grand risque. Lorsque Naccache subit sa premi\u00e8re arrestation, en f\u00e9vrier 1954, \u00e0 la suite d&rsquo;une distribution de tracts, l&rsquo;affaire se solde par une simple admonestation.  Le livre d\u00e9crit ensuite par le menu la m\u00e9canique qui va aboutir, apr\u00e8s l&rsquo;ind\u00e9pendance, \u00e0 la mise en place d&rsquo;un r\u00e9gime autoritaire. Les \u00e9v\u00e9nements ext\u00e9rieurs p\u00e8seront sur cette \u00e9volution. Ainsi, l&rsquo;auteur attribue-t-il au souci de contr\u00f4ler les 300 000 r\u00e9fugi\u00e9s alg\u00e9riens install\u00e9s en Tunisie pendant la guerre d&rsquo;ind\u00e9pendance l&rsquo;origine de la police politique tunisienne.   De m\u00eame, Gilbert Naccache souligne combien la guerre des Six-Jours de 1967 et le cort\u00e8ge de manifestations anti-juives qui a suivi ont provoqu\u00e9 le d\u00e9part massif des juifs tunisiens et contribu\u00e9 \u00e0 la \u00ab\u00a0fermeture progressive des esprits\u00a0\u00bb dans le pays. Gilbert Naccache choisit de rester. Et de continuer \u00e0 militer. Il le fait non plus au sein du PC mais aux c\u00f4t\u00e9s des trotskistes, avant de flirter, apr\u00e8s Mai 68, avec le mao\u00efsme.  Ce qui ne varie pas, c&rsquo;est l&rsquo;opposition radicale de l&rsquo;auteur \u00e0 Bourguiba et \u00e0 son r\u00e9gime. Naccache reconna\u00eet volontiers que le \u00ab\u00a0p\u00e8re de l&rsquo;ind\u00e9pendance\u00a0\u00bb a fait passer la Tunisie \u00ab\u00a0dans un XXe si\u00e8cle rationaliste\u00a0\u00bb. Mais, s&#8217;empresse-t-il d&rsquo;ajouter, ce choix ne doit pas occulter la face sombre du \u00ab\u00a0bourguibisme\u00a0\u00bb : \u00ab\u00a0un r\u00e9gime autoritaire qui ne tol\u00e9rait pas la moindre contestation, n&rsquo;accordait aucune libert\u00e9 autre que celle de l&rsquo;applaudir\u00a0\u00bb et, sur le plan international, une \u00ab\u00a0all\u00e9geance aux Etats-Unis\u00a0\u00bb.  L&rsquo;auteur met en garde ceux qui, ayant la m\u00e9moire courte, ont \u00ab\u00a0par\u00e9 de toutes sortes de vertus\u00a0\u00bb le r\u00e8gne de Bourguiba. Il parle en connaissance de cause. Arr\u00eat\u00e9 en mars 1968, il n&rsquo;a \u00e9t\u00e9 lib\u00e9r\u00e9 qu&rsquo;en 1979.   Qu&rsquo;as-tu fait de ta jeunesse ? Itin\u00e9raire d&rsquo;un opposant au r\u00e9gime de Bourguiba, de Gilbert Naccache, \u00e9d. Cerf\/Mots passants, 284 p., 18 \u20ac.  <strong><font>\u00a0Jean-Pierre Tuquoi  (Source : \u00ab Le Monde \u00bb (Quotidien \u2013 France), le 13 mai 2009)<\/font><\/strong><\/div>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"> <strong>Chronique <\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Cyber-r\u00e9sistants au Maghreb<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">par <strong><font>Jean-PierreTuquoi<\/font><\/strong>  Blogs, r\u00e9seaux sociaux, forums de discussion&#8230; Dans les pays du Maghreb, ces outils de communication, qui ont surgi ces derni\u00e8res ann\u00e9es dans le sillage d&rsquo;Internet et du t\u00e9l\u00e9phone mobile, inqui\u00e8tent les pouvoirs.  Synonymes \u00e0 leurs yeux d&rsquo;une menace diffuse, impalpable et donc difficile \u00e0 contr\u00f4ler, ils font figure de suspects. Ne sont-ils pas porteurs \u00e0 l&rsquo;occasion d&rsquo;une contestation radicale ? Gr\u00e2ce \u00e0 la cr\u00e9ation quasi instantan\u00e9e de r\u00e9seaux informels, ne vont-ils pas prosp\u00e9rer et occuper la place des partis politiques traditionnels \u00e0 l&rsquo;agonie de Tunis \u00e0 Rabat en passant par Alger ?  La riposte est \u00e0 la mesure de la perception de la menace. Au Maroc, o\u00f9 les cybercaf\u00e9s sont l\u00e9gion et l&rsquo;usage du t\u00e9l\u00e9phone portable banal, un jeune a \u00e9t\u00e9 condamn\u00e9 par la justice \u00e0 de la prison pour avoir \u00ab\u00a0emprunt\u00e9\u00a0\u00bb sur Facebook l&rsquo;identit\u00e9 du fr\u00e8re du roi Mohammed VI &#8211; lequel devait par la suite gracier le \u00ab\u00a0premier prisonnier politique de Facebook\u00a0\u00bb.  Toujours dans le royaume, lors du dernier ramadan, une p\u00e9riode de je\u00fbne pour les musulmans, des utilisateurs de Facebook, au nom de la libert\u00e9 individuelle, projetaient de croquer des sandwichs \u00e0 l&rsquo;\u00e9cart de tout, dans une for\u00eat \u00e0 mi-chemin entre Rabat et Casablanca. Le jour pr\u00e9vu, au lieu de rendez-vous, les policiers \u00e9taient plus nombreux que les \u00ab\u00a0d\u00e9-je\u00fbneurs\u00a0\u00bb qui furent embastill\u00e9s sur-le-champ.  Les pays voisins ne sont pas mieux dispos\u00e9s. En Tunisie, o\u00f9 d\u00e8s 2001 un cyber-r\u00e9sistant se mettait \u00e0 dos la police et la justice en cr\u00e9ant un magazine en ligne (TuUNeZine), Internet est sous haute surveillance. Nombre de sites sont inaccessibles, tout comme les blogs d&rsquo;opposants en exil.  Le cas de l&rsquo;Alg\u00e9rie est un peu diff\u00e9rent. Internet et t\u00e9l\u00e9phone mobile sont moins d\u00e9velopp\u00e9s qu&rsquo;en Tunisie et au Maroc. Et les connexions \u00e0 Internet plus co\u00fbteuses qu&rsquo;ailleurs. D&rsquo;o\u00f9 sans doute l&rsquo;absence de contr\u00f4le de l&rsquo;Etat sur les contenus. L&rsquo;internaute alg\u00e9rien a acc\u00e8s \u00e0 tous les sites sans exception. S&rsquo;il est blogueur, il peut \u00e9crire ce qu&rsquo;il veut, critiquer le pr\u00e9sident Bouteflika pour avoir modifi\u00e9 la Constitution pour conserver le pouvoir ou se plaindre d&rsquo;un service militaire trop long, sans redouter les foudres du pouvoir.  Mais jusqu&rsquo;\u00e0 quand ? Une loi est en cours de discussion au Parlement qui pr\u00e9voit la cr\u00e9ation d&rsquo;une \u00ab\u00a0cyber-police\u00a0\u00bb. Il lui reviendra de surveiller les activit\u00e9s \u00ab\u00a0subversives\u00a0\u00bb et celles qui portent atteinte \u00e0 la \u00ab\u00a0s\u00e9curit\u00e9 nationale\u00a0\u00bb. Les termes en sont suffisamment vagues pour faire craindre une interpr\u00e9tation extensive.  Surtout, l&rsquo;Alg\u00e9rie risque de donner des id\u00e9es \u00e0 ses voisins \u00e0 l&rsquo;heure o\u00f9, dans le monde arabo-musulman, les lois pour contr\u00f4ler Internet commencent \u00e0 fleurir. Les Emirats en ont vot\u00e9 une en 2006. L&rsquo;Arabie saoudite a suivi. L&rsquo;Irak s&rsquo;appr\u00eate \u00e0 faire de m\u00eame. Les cyber-r\u00e9sistants vont-ils se mobiliser ?  <strong><font>(Source : \u00ab Le Monde \u00bb (Quotidien \u2013 France), le 9 octobre 2009)<\/font><\/strong> \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Pr\u00e8s du quart de la plan\u00e8te est musulmane, soit 1,57 milliard de personnes (\u00e9tude)<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">AFP, le 8 octobre 2009 \u00e0 03h06  WASHINGTON, 8 oct 2009 (AFP) &#8211; Sur le 1,57 milliard de musulmans que compte le monde, les deux-tiers vivent en Asie. Quelque 38 millions de musulmans vivent en Europe, dont 3,5 millions en France. 1,57 milliard de personnes sont musulmanes dans le monde, soit pr\u00e8s du quart de la population de la plan\u00e8te. C&rsquo;est ce que r\u00e9v\u00e8le une vaste enqu\u00eate du centre de recherche ind\u00e9pendant Pew research center publi\u00e9e, jeudi 8 octobre, aux Etats-Unis. Cette \u00e9tude, qui a rassembl\u00e9 des donn\u00e9es portant sur plus de 200 pays, est \u00ab\u00a0le plus grand projet de ce type \u00e0 ce jour\u00a0\u00bb, indique le centre de recherche am\u00e9ricain.  <strong>Asie en t\u00eate<\/strong>  Deuxi\u00e8me constat : pr\u00e8s des deux-tiers des musulmans vivent en Asie. Seulement un musulman sur cinq vit au Proche-Orient ou en Afrique du Nord, bien que plus de la moiti\u00e9 des 20 pays de la r\u00e9gion soient majoritairement musulmans. C&rsquo;est l&rsquo;Indon\u00e9sie qui compte le plus de musulmans au monde, avec pr\u00e8s de 203 millions de personnes (88% de la population), repr\u00e9sentant un peu moins de 13% des musulmans de la plan\u00e8te. Le Pakistan compte 174 millions de musulmans, soit 96% de la population. L&rsquo;Inde arrive en troisi\u00e8me place, avec pr\u00e8s de 161 millions, soit 13,4% de sa population.  <strong>38 millions de musulmans en Europe<\/strong>  La grande majorit\u00e9, soit 87 \u00e0 90%, des musulmans du monde sont des sunnites, contre 10 \u00e0 13% de chiites, r\u00e9v\u00e8le \u00e9galement l&rsquo;enqu\u00eate qui estime qu&rsquo;il y a entre 154 et 200 millions de musulmans chiites dans le monde, dont 70 millions vivent en Iran. L&rsquo;Egypte a la population musulmane la plus importante de la r\u00e9gion regroupant le Proche-Orient et l&rsquo;Afrique du Nord, tandis que le Nigeria a la plus grande population musulmane de l&rsquo;Afrique sub-saharienne. Quelque 38 millions de musulmans vivent en Europe, dont 16 millions en Russie, 4 millions en Allemagne et 3,5 millions en France, selon le centre de recherche. Sur les quelque 4,6 millions de musulmans qui vivent sur le continent am\u00e9ricain, plus de la moiti\u00e9, soit environ 2,5 millions, se trouvent aux Etats-Unis.<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">\n<div align=\"center\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Diam&rsquo;s : la chanteuse est d\u00e9sormais mari\u00e9e&#8230; et voil\u00e9e ! (r\u00e9actualis\u00e9)<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\"> A l&rsquo;aube de la sortie de son nouvel album <i>SOS<\/i>,<a href=\"http:\/\/www.purepeople.com\/people\/diam-s_p57\" target=\"_blank\" rel=\"noopener\">Diam&rsquo;s<\/a> fait parler d&rsquo;elle d&rsquo;une fa\u00e7on surprenante. Celle que l&rsquo;on conna\u00eet pour sa verve et ses mots forts fait l&rsquo;objet d&rsquo;un long article dans les pages de <i>Paris-Match<\/i> dans lequel on la voit porter le voile.<\/div>\n<p align=\"justify\">Les photos qui figurent dans <i>Paris-Match, <\/i>en kiosque aujourd&rsquo;hui, confirment son engagement. Le journaliste fait \u00e9tat des changements de comportement de la jeune femme qui accompagnent les clich\u00e9s : Diam&rsquo;s porte un voile noir associ\u00e9 \u00e0 une tenue traditionnelle noire et elle refuserait de faire la bise aux gar\u00e7ons. Toutefois, elle a choisi de prier en la mosqu\u00e9e de Gennevilliers, connue pour pratiquer un islam tol\u00e9rant. Quant \u00e0 son refus de faire la bise, ne co\u00efnciderait-il pas seulement avec le Ramadan, p\u00e9riode durant laquelle hommes et femmes se montrent distants ? Elle prie deux heures alors qu&rsquo;une pri\u00e8re dure quarante-cing minutes, lit-on dans <i>Paris-Match<\/i>, mais la d\u00e9couverte d&rsquo;une religion ne n\u00e9cessite-t-elle pas beaucoup de temps ? Le recueillement a-t-il une dur\u00e9e limit\u00e9e ?   Voir Diam&rsquo;s voil\u00e9e suscite ainsi de nombreuses interrogations et fait na\u00eetre des rumeurs et des craintes. L&rsquo;artiste refuse quant \u00e0 elle de s&rsquo;expliquer sur la question, choisissant de ne pas m\u00ealer ses convictions religieuses et la musique.<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-et-amel-bent-au-top-mais-carton-rouge-pour-veronique-sanson-paillarde-et-scato-elle-a-pete-un-plomb-regardez_a40845\/1\" target=\"_blank\" rel=\"noopener\">Lors de ses r\u00e9cents shows<\/a>, post\u00e9rieurs \u00e0 sa conversion, elle s&rsquo;est affich\u00e9e avec son look habituel, mais la t\u00eate couverte. Pour la pochette de son album, elle est simplement habill\u00e9e de blanc et les cheveux masqu\u00e9s par une casquette.  Diam&rsquo;s revient mais d&rsquo;une mani\u00e8re diff\u00e9rente de celle que l&rsquo;on attendait. Sa musique reste tout aussi forte comme on peut l&rsquo;\u00e9couter avec le single<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-a-cotoye-l-enfer-et-nous-dit-tout-ecoutez_a39863\/1\" target=\"_blank\" rel=\"noopener\"><i>Enfants du d\u00e9sert<\/i><\/a>. Si elle vit toujours \u00e0 Neuilly, les profits engendr\u00e9s par son disque seront donn\u00e9s aux associations humanitaires, telle Les Enfants du d\u00e9sert. Aujourd&rsquo;hui, elle serait mari\u00e9e avec Aziz depuis 2 mois, un homme qu&rsquo;elle a rencontr\u00e9e par l&rsquo;interm\u00e9diaire de<a href=\"http:\/\/www.purepeople.com\/article\/vitaa-un-retour-plein-de-suspense-regardez_a39142\/1\" target=\"_blank\" rel=\"noopener\">son amie<\/a><a href=\"http:\/\/www.purepeople.com\/people\/vitaa_p753\" target=\"_blank\" rel=\"noopener\">Vitaa<\/a> avec qui elle a chant\u00e9 le c\u00e9l\u00e8bre titre <i>Confessions nocturnes<\/i>. Un coup de foudre, une c\u00e9r\u00e9monie intime selon <i>Paris-Match<\/i>. N\u00e9anmoins, Diam&rsquo;s, qui semble avoir trouv\u00e9 sa voie vers la s\u00e9r\u00e9nit\u00e9, s&rsquo;appr\u00eate pourtant \u00e0 faire face \u00e0 un v\u00e9ritable tourbillon m\u00e9diatique&#8230; Retour sur son parcours :<\/p>\n<p align=\"justify\">Diam&rsquo;s, alias M\u00e9lanie Georgiades, est n\u00e9e \u00e0 Nicosie sur l&rsquo;\u00eele de Chypre il y a 29 ans. Apr\u00e8s la s\u00e9paration de ses parents, elle quitte son pays pour en adopter un autre, la France, avec sa m\u00e8re. Elle n&rsquo;a que 4 ans mais l&rsquo;absence de son p\u00e8re provoque une blessure en elle qui transpara\u00eet encore \u00e0 travers ses textes. Adolescente, elle se forge sa personnalit\u00e9 dans la banlieue du 91 et d\u00e9couvre le rap.  Son talent explose dans les m\u00e9dias avec le tube <i>DJ<\/i> qui figure sur l&rsquo;album <i>Brut de femmes<\/i> en 2003, son deuxi\u00e8me album. En 2006, <i>Dans ma bulle<\/i> fait aussi un carton et asseoit sa notori\u00e9t\u00e9. Diam&rsquo;s est une figure r\u00e9ellement incontournable du rap fran\u00e7ais mais aussi des femmes. Engag\u00e9e dans de nombreuses causes comme la violence conjugale ou pour<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-indochine-et-amadou-mariam-empechent-les-dirigeants-mondiaux-de-dormir_a41310\/1\" target=\"_blank\" rel=\"noopener\">Amnesty International<\/a>, elle n&rsquo;aime pas se taire et les paroles de ses chansons le montrent bien.   Malgr\u00e9 le succ\u00e8s incontestable de ses oeuvres, Diam&rsquo;s vit difficilement la surexposition m\u00e9diatique et le monde impitoyable du show-business. Apr\u00e8s son troisi\u00e8me album, la chanteuse se retire loin des projecteurs.<a href=\"http:\/\/www.purepeople.com\/article\/video-diam-s-une-etrange-disparition-avant-le-final-des-victoires_a5157\/1\" target=\"_blank\" rel=\"noopener\">Souvenez-vous, en mars 2008, elle fondait en larmes sur le plateau des Victoires de la musique et quittait la sc\u00e8ne<\/a>.<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-expedition-punitive-en-solo-dans-les-locaux-de-voici_a5578\/1\" target=\"_blank\" rel=\"noopener\">Elle avait d\u00e9boul\u00e9 dans un magazine people, folle de rage<\/a>, elle s&rsquo;\u00e9tait fait<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-agressee-en-sortant-de-chez-elle_a2235\/1\" target=\"_blank\" rel=\"noopener\">agresser en bas de chez elle en d\u00e9cembre 2007<\/a> (elle retirera sa plainte). Dans ce monde nouveau pour elle, rempli de faux amis, de relations compliqu\u00e9es, de mauvais conseillers, de surm\u00e9diatisation et d&rsquo;argent qui coule \u00e0 flots, son succ\u00e8s lui aurait fait perdre pied&#8230;<\/p>\n<p align=\"justify\">D&rsquo;apr\u00e8s <i>Paris-Match<\/i>, elle a effectu\u00e9 un voyage en Afrique, pour donner des concerts mais aussi pour trouver un sens \u00e0 sa vie, bouscul\u00e9e par des \u00e9v\u00e9nements qui ne sont pas faciles \u00e0 appr\u00e9hender. Si la chanteuse n&rsquo;abandonne pas la musique puisqu&rsquo;elle est directrice artistique de la<a href=\"http:\/\/www.purepeople.com\/article\/manu-larrouy-un-mec-a-la-cool-qui-previent-carla-la-roue-tourne-regardez_a38121\/1\" target=\"_blank\" rel=\"noopener\">branche fran\u00e7aise du label Motown<\/a>, elle se ressource dans la spiritualit\u00e9, plus pr\u00e9cis\u00e9ment celle de l&rsquo;Islam. SY<\/p>\n<p align=\"justify\"><strong><font>(Source: \u00ab\u00a0PurePeople\u00a0\u00bb le 8 octobre 2009)<\/font><\/strong><\/p>\n<p align=\"justify\">Lien:<a href=\"http:\/\/www.purepeople.com\/article\/diam-s-la-chanteuse-est-desormais-mariee-et-voilee-reactualise_a41539\/1\" target=\"_blank\" rel=\"noopener\">http:\/\/www.purepeople.com\/article\/diam-s-la-chanteuse-est-desormais-mariee-et-voilee-reactualise_a41539\/1<\/a><\/p>\n<\/div>\n<div align=\"justify\"> \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">L&rsquo;UE accepte de signer un accord d&rsquo;association avec la Syrie (diplomates)<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\">AFP, le 8 octobre 2009 \u00e0 19h06  BRUXELLES, 8 oct 2009 (AFP) &#8211;\u00a0 Les repr\u00e9sentants des Etats de l&rsquo;UE se sont mis d&rsquo;accord jeudi pour signer fin octobre un accord d&rsquo;association avec la Syrie apr\u00e8s plusieurs ann\u00e9es d&rsquo;h\u00e9sitation, li\u00e9es \u00e0 la situation des droits de l&rsquo;Homme dans ce pays, a annonc\u00e9 \u00e0 l&rsquo;AFP une source diplomatique. \u00ab\u00a0La signature de l&rsquo;accord est pr\u00e9vue avec la Syrie le 26 octobre \u00e0 Luxembourg\u00a0\u00bb, a pr\u00e9cis\u00e9 ce diplomate europ\u00e9en. Alors qu&rsquo;une premi\u00e8re mouture d&rsquo;un projet d&rsquo;accord attendait depuis 2004 d&rsquo;\u00eatre approuv\u00e9e par les gouvernements europ\u00e9ens, les Pays-Bas ont longtemps oppos\u00e9 leur veto \u00e0 la signature de cet accord d&rsquo;association, insistant pour qu&rsquo;une clause de suspension en cas d&rsquo;atteinte aux droits de l&rsquo;Homme soit inclue dans l&rsquo;accord. Fin septembre \u00e0 Paris, le chef de la diplomatie syrienne, Walid Mouallem, avait pr\u00e9venu que son pays n&rsquo;accepterait pas \u00ab\u00a0un accord assorti de conditions politiques\u00a0\u00bb. Au final, un compromis pr\u00e9sent\u00e9 par la pr\u00e9sidence su\u00e9doise de l&rsquo;UE pr\u00e9voit que le projet d&rsquo;accord soit accompagn\u00e9 d&rsquo;une d\u00e9claration s\u00e9par\u00e9e des Etats europ\u00e9ens, \u00ab\u00a0disant en substance que l&rsquo;UE se r\u00e9serve le droit de suspendre l&rsquo;accord d&rsquo;association\u00a0\u00bb en cas d&rsquo;atteinte aux droits de l&rsquo;Homme, a indiqu\u00e9 ce diplomate. L&rsquo;UE aimerait \u00e0 travers cet accord notamment encourager Damas \u00e0 jouer un r\u00f4le constructif au Proche-Orient et dans les relations isra\u00e9lo-palestiniennes. \u00a0<\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"center\"><strong><\/p>\n<h3 style=\"color: blue;\"><font size=\"3\">Accord UE-Syrie: \u00ab\u00a0nouvelle \u00e9tape dans la dynamique de rapprochement\u00a0\u00bb (Paris)<\/font><\/h3>\n<p><\/strong><\/div>\n<div align=\"justify\"> AFP, le 8 octobre 2009 \u00e0 14h37 PARIS, 9 oct 2009 (AFP) -Les d\u00e9put\u00e9s ont achev\u00e9 vendredi l&rsquo;examen du projet de loi sur les jeux et les paris en ligne que l&rsquo;opposition qualifie de \u00ab\u00a0loi de complaisance\u00a0\u00bb en faveur des \u00ab\u00a0amis\u00a0\u00bb du chef de l&rsquo;Etat. L&rsquo;Assembl\u00e9e se prononcera mardi prochain par un vote solennel sur l&rsquo;ensemble de ce texte d\u00e9fendu par Eric Woerth, ministre du Budget. Il comporte une soixantaine d&rsquo;articles sur lesquels ont \u00e9t\u00e9 d\u00e9pos\u00e9s 1.350 amendements. Le groupe UMP, \u00e0 l&rsquo;exception de plusieurs de ses membres, soutient ce texte de m\u00eame que le groupe du Nouveau centre (NC). Les groupes socialiste, radical et citoyen (SRC) et de la gauche d\u00e9mocrate et r\u00e9publicaine (GDR, PC et Vert) y sont hostiles. Le S\u00e9nat devrait examiner le projet de loi \u00e0 son tour en novembre. L&rsquo;objectif du gouvernement est que ce texte, qui pr\u00e9voit d&rsquo;ouvrir \u00e0 la concurrence les paris sportifs, les paris hippiques et le poker en 2010, puisse s&rsquo;appliquer pour la Coupe du monde de football qu&rsquo;organise l&rsquo;Afrique du Sud durant l&rsquo;\u00e9t\u00e9 2010. \u00ab\u00a0Nous avons choisi une voie m\u00e9diane que je crois juste et efficace\u00a0\u00bb, a assur\u00e9 le ministre du Budget. \u00ab\u00a0Celle de l&rsquo;ouverture ma\u00eetris\u00e9e (face \u00e0) l&rsquo;explosion des jeux sur internet (et) une offre ill\u00e9gale pl\u00e9thorique.\u00a0\u00bb Pour Ga\u00ebtan Gorce, d\u00e9put\u00e9 socialiste, le projet de loi ne permettra pas au gouvernement de ma\u00eetriser la concurrence. \u00ab\u00a0Loi de circonstances, sans doute, mais surtout loi de complaisance\u00a0\u00bb, a-t-il affirm\u00e9. Le texte oblige les op\u00e9rateurs \u00e0 demander une licence d&rsquo;exploitation aupr\u00e8s de l&rsquo;Autorit\u00e9 de r\u00e9gulation des jeux en ligne (Arjel) qui sera charg\u00e9e de v\u00e9rifier la conformit\u00e9 des activit\u00e9s par rapport \u00e0 la l\u00e9gislation, de faire la chasse aux d\u00e9lits \u00e9ventuels et de lutter contre l&rsquo;addiction aux jeux. MONTANT DES MISES DE 36,7 MILLIARDS Eric Woerth a estim\u00e9 \u00ab\u00a0qu&rsquo;une cinquantaine\u00a0\u00bb d&rsquo;op\u00e9rateurs devraient obtenir la licence d&rsquo;exploitation n\u00e9cessaire. L&rsquo;agr\u00e9ment sera d&rsquo;une dur\u00e9e de 5 ans renouvelables. Le texte, qui inscrit le principe d&rsquo;interdiction de participation des mineurs aux jeux d&rsquo;argent et de hasard, renforce les mesures de lutte contre les sites ill\u00e9gaux de jeux d&rsquo;argent. Il offre, par exemple, la possibilit\u00e9 pour des agents du minist\u00e8re de l&rsquo;Int\u00e9rieur, de participer sous pseudonyme \u00e0 des jeux en ligne. Enfin, parmi de nombreuses mesures, le projet de loi aligne la fiscalit\u00e9 des jeux en ligne sur celle des jeux en \u00ab\u00a0dur\u00a0\u00bb, c&rsquo;est-\u00e0-dire les casinos, La Francaise des jeux et le PMU. Le texte pr\u00e9voit que l&rsquo;Etat pr\u00e9l\u00e8vera 7,5% des mises des joueurs pour les paris sportifs et hippiques et 2% des mises pour le poker, une partie de ces recettes \u00e9tant affect\u00e9e \u00e0 la lutte contre la d\u00e9pendance aux jeux. Le secteur des jeux d&rsquo;argent et de hasard est florissant malgr\u00e9 la crise. En 2008, pr\u00e9cise un rapport de l&rsquo;Assembl\u00e9e, les Fran\u00e7ais ont mis\u00e9 36,736 milliards d&rsquo;euros par l&rsquo;interm\u00e9diaire des deux d\u00e9tenteurs du monopole, la Fran\u00e7aise des jeux et le Pari mutuel urbain (PMU). Ce chiffre ne tient pas compte du jeu clandestin qui va des 10.000 \u00e0 40.000 machines \u00e0 sous ill\u00e9gales aux tripots priv\u00e9s en passant par les sites ill\u00e9gaux de jeux et paris sur internet. <\/div>\n<\/div>\n<\/div>\n<p> \u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><\/font><\/div>\n<\/div>\n<p align=\"center\" dir=\"ltr\">\n<h3 style=\"color: blue;\"><font face=\"Arial\" size=\"2\"><strong><b><a href=\"https:\/\/tunisnews.net\/ar\/\"><font face=\"Arial\"><span><font size=\"2\">Home<\/font><\/span><font size=\"2\"><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><\/font><\/font><span dir=\"rtl\" lang=\"AR-SA\"><font size=\"2\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/font><\/span><\/a><\/b><\/strong><\/font><\/h3>\n<\/p>\n<p><\/body><\/body><\/html><\/p>","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Accueil \u00a0 TUNISNEWS 9\u00a0\u00e8me ann\u00e9e,N\u00b0\u00a03426 du 09.10.2009 \u00a0archives : www.tunisnews.net\u00a0\u00a0 Al Badil Express: Radhia Nasraoui et Hamma Hammami convoqu\u00e9s cet apr\u00e8s-midi par la brigade de lutte anti- criminelle Dr. Patrick CHALTIEL: Le jugement en appel du Dr Ahmed ELEUCH ajourn\u00e9 pour le 15 octobre 2009 ! Luiza Toscane: 6 octobre 2008-6 octobre 2009 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[61,40,29],"class_list":["post-17349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-61","tag-40","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=17349"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/17349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=17349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=17349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=17349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}