{"id":15802,"date":"2006-08-23T00:00:00","date_gmt":"2006-08-23T00:00:00","guid":{"rendered":"https:\/\/tunisnews.net\/23-aout-2006\/"},"modified":"2006-08-23T00:00:00","modified_gmt":"2006-08-23T00:00:00","slug":"23-aout-2006","status":"publish","type":"post","link":"https:\/\/tunisnews.net\/ar\/23-aout-2006\/","title":{"rendered":"23 ao\u00fbt 2006"},"content":{"rendered":"<p><html><head><meta content=\"text\/html\" description=\" qui est diab\u00e9tique \n  est priv\u00e9 des soins qui devraient lui \u00eatre prodigu\u00e9s. L\u2019attitude des autorit\u00e9s \n  qui refusent de le transporter \u00e0 l'h\u00f4pital est d\u2019autant plus inacceptable que \n  la famille Tlili n\u2019a cess\u00e9 de leur \u00e9crire pour attirer leur attention sur les \n  dangers encourus par leur fils, allant jusqu\u2019\u00e0 proposer de financer les soins \n  r\u00e9clam\u00e9s.\" http-equiv=\"Content-Type\"\/><\/head><body><body style=\"text-align: justify\"><\/p>\n<p align=\"center\"><b><a href=\"25juin06a.htm\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><span dir=\"rtl\" lang=\"AR-SA\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/span><\/a><\/b><\/p>\n<div> <font face=\"Arial\" size=\"2\"> <\/p>\n<div>\n<div>\n<table border=\"1\" width=\"100%\">\n<tr>\n<td bgcolor=\"#efefef\" width=\"100%\"> <span lang=\"AR-SA\"> <\/p>\n<div align=\"left\">  <\/div>\n<div> <span lang=\"FR\"> <\/p>\n<div align=\"center\" dir=\"ltr\"> <font size=\"2\"><font face=\"Arial\"> <span lang=\"SV\"> <strong>TUNISNEWS<\/strong><\/span> <\/font><\/font> <\/div>\n<div align=\"center\" dir=\"ltr\"> <strong><font size=\"2\"><font face=\"Arial\">              7\u00a0\u00e8me\u00a0ann\u00e9e, <span lang=\"FR\">N\u00b0\u00a02284 du 23.08.2006<\/span><\/font><\/font><\/strong><\/div>\n<div align=\"center\" dir=\"ltr\"> <strong> <\/p>\n<div align=\"center\"> <b><span><blink> <font face=\"Arial\" size=\"2\">\u00a0archives : <\/font> <a href=\"http:\/\/www.tunisnews.net\/\" target=\"_blank\" rel=\"noopener\"> <font face=\"Arial\" size=\"2\" target=\"_blank\">                www.tunisnews.net<\/font><\/a><\/blink><\/span><\/b><font face=\"Arial\" size=\"2\"> <\/font> <\/div>\n<p> <\/strong><\/div>\n<p> <\/span><\/div>\n<p> <font face=\"Arial\" size=\"2\"> <\/p>\n<div align=\"left\" dir=\"ltr\"> <font><\/p>\n<hr noshade=\"\" size=\"8\"\/><\/font> <\/div>\n<div align=\"left\" dir=\"ltr\">\n<p><font><strong> <\/p>\n<div align=\"left\" dir=\"ltr\">              L\u2019ACAT demande que les prisonniers tunisiens re\u00e7oivent dans les               h\u00f4pitaux et aupr\u00e8s de sp\u00e9cialistes les soins ad\u00e9quats auxquels ils               ont droit               <font>La Libert\u00e9 : Malika el-Aroud quitte la               Suisse<\/font>               Tribune de Gen\u00e8ve : De Tunis \u00e0 Bagdad, la femme arabe dans tous               ses \u00e9tats               <font>Jeune Afrique : Moncef bey: A l\u2019\u00e9coute de               son peuple<\/font>                Jeune Afrique : Moncef Bey, les juifs, l\u2019Axe et les Alli\u00e9s                <font>Jeune Afrique: Comment les musulmans s\u2019en               sortiront<\/font>                H\u00e8di Baccouche: \u00ab La nation tunisienne, entre hier et aujourd\u2019hui               \u00bb: Une identit\u00e9 mill\u00e9naire               <font>Soraya Messaoudi: La khobza connexion                <\/font>Amnesty International : Isra\u00ebl\/Liban. Des \u00e9l\u00e9ments montrent               que des infrastructures civiles ont \u00e9t\u00e9 d\u00e9lib\u00e9r\u00e9ment d\u00e9truites               <font>AFP: \u00ab\u00a0Isra\u00ebl arr\u00eate le vice-Premier ministre               palestinien, membre du Hamas<\/font>               Andr\u00e9 Monjardet: La bavure de la r\u00e9publique\u00a0 ou la complainte des               flics<strong><font><\/font><\/strong><\/div>\n<p> <\/strong><\/font><\/p>\n<\/div>\n<p> <\/font><\/span><\/td>\n<\/tr>\n<\/table><\/div>\n<div> <font face=\"Arial\"><\/font>\u00a0<\/div>\n<div align=\"center\"> <font face=\"Arial\">\u00a0<\/font><\/p>\n<p><font><a href=\"http:\/\/www.nawaat.org\/forums\/index.php?showtopic=11741\" target=\"_blank\" rel=\"noopener\"><font face=\"Arial\"><strong>Cliquez       ici<\/strong><\/font><\/a><font face=\"Arial\"><strong> pour acc\u00e9der au       reportage exceptionnel de l&rsquo;AISPP sur la catastrophe humanitaire       des prisonniers politiques Tunisiens<\/strong>\u00a0    <\/font><\/font><\/p>\n<\/div>\n<div align=\"center\">\n<hr\/><\/div>\n<\/p><\/div>\n<p> <\/font><\/div>\n<div>  \u00a0<\/div>\n<div align=\"center\"> <font size=\"2\"><strong><font face=\"Arial\">ACAT-France<\/font><\/strong><\/font><\/div>\n<div align=\"justify\"> <font face=\"Arial\">7 rue Georges Lardennois &#8211; 75019 Paris   Tel : 01 40 40 42 43 &#8211; Fax : 01\u00a0 40 40 42 44\u00a0    Ministre de la Justice   Minist\u00e8re de\u00a0 la Justice   31 Boulevard Bab Benat   1006 Tunis \u2013 La Kasbah   Tunisie   Fax : 00 216 71 568 106   \u00a0       Le\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2006      Monsieur le Ministre,<\/font><\/div>\n<div align=\"center\"> <strong><\/p>\n<p><font face=\"Arial\" size=\"3\">L\u2019ACAT demande que les   prisonniers tunisiens re\u00e7oivent dans les h\u00f4pitaux et aupr\u00e8s de sp\u00e9cialistes   les soins ad\u00e9quats auxquels ils ont droit.<\/font><\/p>\n<p><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong>M Abderrahmane TLILI<\/strong> qui est diab\u00e9tique   est priv\u00e9 des soins qui devraient lui \u00eatre prodigu\u00e9s. L\u2019attitude des autorit\u00e9s   qui refusent de le transporter \u00e0 l&rsquo;h\u00f4pital est d\u2019autant plus inacceptable que   la famille Tlili n\u2019a cess\u00e9 de leur \u00e9crire pour attirer leur attention sur les   dangers encourus par leur fils, allant jusqu\u2019\u00e0 proposer de financer les soins   r\u00e9clam\u00e9s.      <strong>M. Hamadi BEN ABDELMALEK<\/strong> souffre, au niveau de la poitrine,   d&rsquo;une tumeur dont on ignore l&rsquo;origine. L&rsquo;administration p\u00e9nitentiaire refuse   de le pr\u00e9senter \u00e0 des sp\u00e9cialistes afin qu&rsquo;il puisse b\u00e9n\u00e9ficier d&rsquo;un   diagnostic et de soins ad\u00e9quats.      <strong>M. Abdellatif BOUHAJILA<\/strong> souffre d\u2019asthme et de probl\u00e8mes au   c\u0153ur et aux reins, sans pouvoir b\u00e9n\u00e9ficier des soins n\u00e9cessit\u00e9s par son \u00e9tat   de sant\u00e9 d\u00e9fectueux.      L\u2019ACAT rappelle aux responsables de l&rsquo;administration p\u00e9nitentiaire qu\u2019ils ne   peuvent continuer \u00e0 ignorer les droits \u00e9l\u00e9mentaires des prisonniers malades   dont la vie est en danger.       Nous vous remercions de nous lire et nous vous prions d\u2019agr\u00e9er, Monsieur le   Ministre, l \u2018_expression de notre plus haute consid\u00e9ration      <strong><font>Pour le p\u00f4le-actions   Nicole Pignon-P\u00e9guy   <\/font><\/strong>   Copie \u00e0 l\u2019ambassade de Tunisie, 25 rue Barbet de Jouy, 75 007 Paris, Fax : 01   45 56 02 64 <\/font><\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"> <strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\"><font face=\"Arial\">Malika el-Aroud   quitte la Suisse<\/font><\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\">  \u00a0<\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong>Guin &#8211; Malika el-Aroud a subitement quitt\u00e9 la   Suisse. Dans un entretien qui sera diffus\u00e9 sur CNN, elle avoue continuer \u00e0   alimenter son site de propagande islamiste.   <\/strong> <strong><font>Sid Ahmed Hammouche, Kessava packiry   <\/font><\/strong>   Malika el-Aroud, la veuve de l&rsquo;assassin de Massoud, semble avoir fui le   territoire helv\u00e9tique. Sur son site internet (toujours actif malgr\u00e9 son   interdiction), la djihadiste \u00e9tablie \u00e0 Guin d\u00e9clare, sous le pseudonyme   d&rsquo;Oum-Obeyda: \u00abJe suis rentr\u00e9e en Belgique. Je suis hyper-heureuse d&rsquo;avoir   quitt\u00e9 la Suisse, ce pays ou l&rsquo;atmosph\u00e8re est oppressante alors que l&rsquo;on   m&rsquo;avait dit qu&rsquo;il faisait bon y respirer.\u00bb \u00abLa Libert\u00e9\u00bb a tent\u00e9 de la   contacter hier, en vain.      Cette Belge d&rsquo;origine marocaine fait l&rsquo;objet d&rsquo;une proc\u00e9dure judiciaire,   conduite par le Minist\u00e8re public de la Conf\u00e9d\u00e9ration, pour \u00abparticipation \u00e0   une organisation criminelle et provocation publique au crime ou \u00e0 la violence   via un site internet\u00bb. Malika el-Aroud et son actuel mari, le Tunisien Moez   Gharsallaoui, ont d&rsquo;ailleurs vu d\u00e9barquer la police f\u00e9d\u00e9rale \u00e0 leur domicile   de Guin, au d\u00e9but 2005. Le site a aussit\u00f4t \u00e9t\u00e9 interdit. Mais Malika el-Aroud   continue de l&rsquo;entretenir et de l&rsquo;animer.      Selon le t\u00e9moignage d&rsquo;un voisin, les volets de la maison sont aujourd&rsquo;hui   ferm\u00e9s. Mais la djihadiste l&rsquo;occupait encore il y a deux semaines, et son mari   y serait toujours domicili\u00e9.      <strong>Rencontre avec CNN<\/strong>      L&rsquo;affaire est actuellement entre les mains du juge d&rsquo;instruction de la   Conf\u00e9d\u00e9ration G\u00e9rard Sautebin, qui indique: \u00abL&rsquo;instruction est en cours. Je ne   peux pas vous en dire plus. Mais le dossier et l&rsquo;instruction doivent \u00eatre   trait\u00e9s avec diligence.\u00bb      Avec le d\u00e9part de Malika el-Aroud, les choses prennent une autre tournure, et   pourraient aller plus vite. Autre \u00e9l\u00e9ment qui plaide en faveur d&rsquo;un coup   d&rsquo;acc\u00e9l\u00e9rateur: une interview accord\u00e9e r\u00e9cemment \u00e0 la cha\u00eene CNN, dans   laquelle Malika el-Aroud dit toute l&rsquo;admiration qu&rsquo;elle voue au leader   d&rsquo;al-Qa\u00efda. Surtout, l&rsquo;activiste avoue continuer \u00e0 g\u00e9rer son site de   propagande islamiste (h\u00e9berg\u00e9 \u00e0 l&rsquo;\u00e9tranger).      L&rsquo;interview, r\u00e9alis\u00e9e dans le cadre d&rsquo;une s\u00e9rie intitul\u00e9e \u00abSur les traces de   Ben Laden\u00bb, ne sera diffus\u00e9 que le 23 ao\u00fbt sur la cha\u00eene am\u00e9ricaine. Mais un   r\u00e9sum\u00e9 de l&rsquo;entretien figure d\u00e9j\u00e0 sur le site internet de CNN. Au journaliste   venu l&rsquo;interroger \u00e0 son domicile de Guin, Malika el-Aroud dit son amour pour   Oussama Ben Laden, m\u00eame si ce dernier a envoy\u00e9 son mari \u00e0 la mort. C&rsquo;\u00e9tait le   9 septembre 2001: aid\u00e9 d&rsquo;un compatriote, le Tunisien Abdessater Dahmane   assassinait le commandant afghan Ahmed Shah Massoud lors d&rsquo;une   op\u00e9ration-suicide.      Selon Malika el-Aroud, 47 ans, l&rsquo;acte de son mari lui a valu les f\u00e9licitations   de son entourage. Dans l&rsquo;islam, affirme-t-elle aux cam\u00e9ras de CNN, c&rsquo;est   l&rsquo;apog\u00e9e d&rsquo;\u00eatre la veuve d&rsquo;un martyr. \u00abPour une femme, c&rsquo;est extraordinaire.\u00bb      <strong>Le FBI au courant<\/strong>      Vers la fin de l&rsquo;entretien, Malika el-Aroud entra\u00eene l&rsquo;\u00e9quipe de CNN dans sa   chambre pour lui montrer la mani\u00e8re dont elle g\u00e8re son forum internet. Un   forum dont elle persiste \u00e0 nier qu&rsquo;il est une plate-forme de soutien \u00e0 une   organisation terroriste.      L&rsquo;interview, r\u00e9alis\u00e9e en f\u00e9vrier, n&rsquo;\u00e9tait encore pas parvenue aux oreilles des   autorit\u00e9s suisses. Inform\u00e9 par \u00abLa Libert\u00e9\u00bb, G\u00e9rard Sautebin affirme vouloir   suivre avec beaucoup d&rsquo;attention les d\u00e9clarations de la djihadiste de Guin,   mercredi prochain sur CNN. Des \u00e9l\u00e9ments d&rsquo;informations pr\u00e9cieux, qui pourront   peser sur le dossier et relancer l&rsquo;instruction.      Selon nos sources, d&rsquo;autres personnes \u00e9taient pourtant bien au courant du   passage de l&rsquo;\u00e9quipe de CNN dans le canton: des agents du FBI, bas\u00e9s \u00e0 Berne,   qui semblent accorder une grande importance au cas el-Aroud.       <strong><font>(Source : \u00ab La Libert\u00e9 \u00bb (Suisse) du 18 ao\u00fbt   2006)<\/font><\/strong> \u00a0<\/font><\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div>\n<div align=\"center\"> <strong><\/p>\n<h2 style=\"color: red;\"><font face=\"Arial\" size=\"3\">De Tunis \u00e0 Bagdad, la     femme arabe dans tous ses \u00e9tats<\/font><\/h2>\n<p><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong><font>Gustavo Kuhn<\/font><\/strong>          Il y a cinquante ans, Tunis adoptait une l\u00e9gislation \u00e9galitaire unique dans     le monde musulman. Mais, dans l\u2019ensemble, la condition de la femme arabe     r\u00e9gresse. Et m\u00eame dramatiquement en Irak.          La Tunisie vient de c\u00e9l\u00e9brer en grande pompe les cinquante ans du Code du     statut personnel, une l\u00e9gislation lib\u00e9rale sur l\u2019\u00e9galit\u00e9 des sexes,     exceptionnelle dans le monde arabe.          Connu pour ses nombreuses atteintes aux droits de l\u2019homme, le pays du     Maghreb se targue paradoxalement d\u2019\u00eatre \u00e0 la pointe de l\u2019\u00e9mancipation des     femmes dans la r\u00e9gion.          Ainsi, 98% des filles sont scolaris\u00e9es, 34% des m\u00e9decins et 25% des juges     sont des femmes, et les bancs des universit\u00e9s et autres \u00e9coles sup\u00e9rieures     sont occup\u00e9s \u00e0 57% par des \u00e9tudiantes. \u00abLa Tunisie est un cas unique dans le     monde arabo-musulman, affirme cependant Hasni Abidi, directeur du Centre     d\u2019\u00e9tudes et de recherche sur le monde arabe et m\u00e9diterran\u00e9en (CERMAM). Car     la situation g\u00e9n\u00e9rale n\u2019est vraiment pas glorieuse et dans l\u2019ensemble, elle     r\u00e9gresse s\u00e9rieusement. \u00bb          Derni\u00e8rement, le Maroc a tout de m\u00eame essay\u00e9 d\u2019embo\u00eeter le pas de la Tunisie.     Un important progr\u00e8s l\u00e9gal a \u00e9t\u00e9 accompli en 2004, avec l\u2019entr\u00e9e en vigueur     du Code de la famille. \u00abMais il faut noter que le parlement \u00e9tait hostile \u00e0     la r\u00e9forme, rappelle Hasni Abidi. Son adoption est \u00e0 mettre au cr\u00e9dit du roi     Mohamed VI. Il a impos\u00e9 le texte en le pr\u00e9sentant peu apr\u00e8s les attentats de     Casablanca, commis par des extr\u00e9mistes islamistes. Dans ce contexte, les     partis religieux ont adopt\u00e9 un profil bas et n\u2019ont pas pu s\u2019y opposer comme     en 2000. \u00bb          <strong>Pas le droit de conduire<\/strong>          \u00abCette protection juridique est tr\u00e8s positive, mais il faudra attendre pour     voir \u00e9voluer la r\u00e9alit\u00e9, nuance Zidane Meriboute, docteur en droit et en     sciences politiques. Le regard des hommes arabes reste tr\u00e8s traditionnel et     il est vrai que les pays musulmans accusent un s\u00e9rieux retard en mati\u00e8re de     droits des femmes. Mais m\u00eame en Europe, o\u00f9 l\u2019\u00e9galit\u00e9 juridique est acquise     depuis un certain temps, de nombreuses in\u00e9galit\u00e9s subsistent. Notamment au     niveau des salaires\u00bb.          L\u2019auteur de La fracture islamique affirme cependant que les in\u00e9galit\u00e9s dans     les pays islamiques ne sont pas uniquement li\u00e9es \u00e0 certaines interpr\u00e9tations     du Coran ou de la Charia, \u00able poids des coutumes est aussi extr\u00eamement     important\u00bb. D\u2019autant que dans le monde arabo-musulman, l\u00e9gislation, religion     et tradition s\u2019entrem\u00ealent intimement.          La r\u00e9alit\u00e9 varie cependant beaucoup d\u2019un pays \u00e0 l\u2019autre. Si les femmes     proche-orientales assurent un r\u00f4le moteur dans la soci\u00e9t\u00e9, comme au Liban ou     en Palestine, leurs s\u0153urs des pays du Golfe sont confin\u00e9es chez elles. Et     presque partout, les femmes restent des citoyennes de deuxi\u00e8me zone au     regard m\u00eame de la loi. \u00abLa l\u00e9gislation de la plupart des pays arabes se     r\u00e9fugie derri\u00e8re la charia, qui donne un r\u00f4le pr\u00e9pond\u00e9rant aux hommes\u00bb,     explique Hasni Abidi. Le pire \u00e9l\u00e8ve est sans conteste l\u2019Arabie saoudite. Les     femmes n\u2019y ont pas de droit de vote et prendre le volant leur est interdit.          Enfin, si le \u00abretour du voile\u00bb dans le Maghreb n\u2019est pas forc\u00e9ment synonyme     d\u2019oppression et de recul des libert\u00e9s, son imposition en Irak est un fort     signal de ce qu\u2019Hasni Abidi appelle \u00abl\u2019islamisation par le bas\u00bb. En effet,     depuis la chute de Saddam Hussein, les droits des femmes, chiites et     sunnites, sont pi\u00e9tin\u00e9s \u00e0 Bagdad. Dans un contexte de quasi-guerre civile     interconfessionnelle, les Irakiennes re\u00e7oivent de constantes menaces dans la     rue pour les obliger \u00e0 porter le voile, cesser de travailleur ou renoncer \u00e0     conduire.          <strong>Unique<\/strong> <strong>Le 13 ao\u00fbt 1956, dans la foul\u00e9e de l\u2019ind\u00e9pendance de la Tunisie, le     pr\u00e9sident Habib Bourguiba promulgue le Code du statut personnel (CSP).          Celui-ci abolit la polygamie et la r\u00e9pudiation, institue le divorce     judiciaire et fixe l\u2019\u00e2ge minimum du mariage \u00e0 17 ans pour la femme, \u00absous     r\u00e9serve de son consentement\u00bb.          La femme tunisienne dispose depuis lors du droit de vote et d\u2019\u00e9ligibilit\u00e9.          Le cheval de bataille des associations f\u00e9ministes est d\u00e9sormais l\u2019\u00e9galit\u00e9     dans l\u2019h\u00e9ritage. Il s\u2019agit d\u2019un des seuls cas o\u00f9 le principe de la loi     islamique, qui accorde une part double aux hommes, est appliqu\u00e9 en Tunisie.          S\u2019il ne va pas aussi loin que le CSP, le Code de la famille marocain, ou     Moudawana, s\u2019en inspire largement. (gk)     <\/strong> <strong><font>(Source : \u00ab Tribune de Gen\u00e8ve \u00bb (Suisse), le     19.08.2006; page 4)<\/font><\/strong><\/font><\/div>\n<\/div>\n<div>  \u00a0<\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"> <font face=\"Arial\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Tunisiana teste le   push mail<\/font><\/h2>\n<p><\/strong>\u00a0  \u00a0<\/font><\/div>\n<div align=\"center\">  \u00a0<\/div>\n<div align=\"justify\"> <font face=\"Arial\">Apr\u00e8s Tunisie T\u00e9l\u00e9com, c\u2019est au tour de l\u2019op\u00e9rateur GSM   priv\u00e9 Tunisiana de tester les services du Push Mail. Ce service permet,   rappelons-le, de recevoir son courrier \u00e9lectronique directement sur son   t\u00e9l\u00e9phone portable et fait appel aux technologies les plus \u00e9volu\u00e9es en mati\u00e8re   de GSM de deuxi\u00e8me g\u00e9n\u00e9ration.    Tunisiana teste son r\u00e9seau \u00e0 travers une infrastructure de Nokia, la m\u00eame que   celle utilis\u00e9e par son concurrent. On ne sait rien, pour le moment, sur les   dates de commercialisation de ce service, mais on sait qu\u2019une demande a \u00e9t\u00e9   d\u00e9pos\u00e9e par l\u2019op\u00e9rateur priv\u00e9 \u00e0 l\u2019Instance de r\u00e9gulation (l\u2019INT).       D\u2019apr\u00e8s une d\u00e9claration faite par un responsable \u00e0 un confr\u00e8re de la place,   l\u2019INT r\u00e9pond \u00e0 toutes les demandes dans un d\u00e9lai de quinze jours. Ce qui   signifie que l\u2019op\u00e9rateur priv\u00e9 ne tarderait pas \u00e0 obtenir la sienne.      Par ailleurs, on apprend que Tunisiana va baisser ses prix MMS \u00e0 partir du 1er   septembre de 25%. D\u00e9sormais, l\u2019envoi d\u2019un message multim\u00e9dia co\u00fbtera 180   millimes au lieu de 240 millimes pr\u00e9c\u00e9demment.      R.B.H.      <strong><font>(Source : le portail tunisien   webmanagercenter.com, le 23 ao\u00fbt 2006 \u00e0 14h05)<\/font><\/strong><\/font><\/div>\n<div>  \u00a0<\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div>  \u00a0<\/div>\n<div>\n<div align=\"center\"> <strong><font face=\"Arial\" size=\"3\">Moncef bey<\/font><\/strong><\/div>\n<div align=\"center\">    \u00a0<\/div>\n<div align=\"center\"> <font face=\"Arial\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">A l\u2019\u00e9coute de son     peuple<\/font><\/h2>\n<p><\/strong><font> <\/font><\/font> <\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong><font>par ABDELAZIZ BARROUHI<\/font><\/strong> <\/font><font><font face=\"Arial\">Mohamed el-Moncef Pacha Bey     (4 mars 1881-1er septembre 1948) est le dernier des princes de la dynastie     husseinite \u00e0 na\u00eetre avant l\u2019\u00e9tablissement du protectorat fran\u00e7ais sur la     Tunisie (mai 1881) et le dernier des souverains \u00e0 mourir avant     l\u2019ind\u00e9pendance (1956) et l\u2019abolition de la monarchie (1957).      Il re\u00e7oit une \u00e9ducation franco-arabe au coll\u00e8ge Sadiki de Tunis, cette     p\u00e9pini\u00e8re de l\u2019\u00e9lite tunisienne dont l\u2019un des plus prestigieux \u00e9l\u00e8ves est     Habib Bourguiba.           Dans la biographie qu\u2019il lui a consacr\u00e9e, Sa\u00efd Mestiri \u00e9crit que Moncef Bey     \u00ab n\u2019\u00e9tait ni le tribun politique, ni le tribun populaire, encore moins le     marabout. Son charisme, il le devait \u00e0 sa l\u00e9gitimit\u00e9 et la profonde adh\u00e9sion     de son peuple. Sa vision des grands enjeux internationaux \u00e9tait peut-\u00eatre     limit\u00e9e au d\u00e9part, sa culture politique comportait peut-\u00eatre des lacunes.     Elles ont \u00e9t\u00e9 rapidement colmat\u00e9es par sa vive intelligence, son solide bon     sens et la catalyse que provoque l\u2019exercice du pouvoir. \u00bb Comme le note par     ailleurs Mestiri, qui a entre autres repris des t\u00e9moignages in\u00e9dits de son     beau-p\u00e8re M\u2019hamed Chenik, Premier ministre de Moncef Bey, celui-ci aimait     \u00e9couter et s\u2019informer.           Lorsque son p\u00e8re Naceur Bey acc\u00e8de au tr\u00f4ne en 1906, il devient son     conseiller personnel et confident. Au lendemain de la Premi\u00e8re Guerre     mondiale, le prince Moncef est charg\u00e9 par son p\u00e8re d\u2019entretenir des liens     avec les nationalistes. En avril 1922, Naceur Bey, m\u00e9content du traitement     que la France r\u00e9serve aux dirigeants du mouvement nationaliste naissant du     Destour, menace d\u2019abdiquer au cas o\u00f9 la France ne satisferait pas les     demandes tunisiennes d\u2019\u00e9mancipation. Les autorit\u00e9s du protectorat     s\u2019arrangent pour l\u2019amener \u00e0 renoncer \u00e0 son projet et perdre ainsi la face.     Humili\u00e9, Naceur Bey d\u00e9c\u00e8de quelques mois apr\u00e8s, en juillet 1922. L\u2019\u00e9pisode a     sans doute marqu\u00e9 Moncef Bey, qui se fait politiquement discret pendant une     vingtaine d\u2019ann\u00e9es. Conform\u00e9ment aux r\u00e8gles de succession dynastique de la     famille husseinite, il succ\u00e8de, \u00e0 l\u2019\u00e2ge de 62 ans, au falot Ahmed Bey II     (1929-1942) \u00e0 la mort de celui-ci. Il est intronis\u00e9 le 19 juin 1942.     Aussit\u00f4t, il supprime le baisemain, qu\u2019il remplace par la poign\u00e9e de main ou     l\u2019accolade, et demande aux princes husseinites, souvent habitu\u00e9s au lucre,     de se comporter plus dignement.           Bien avant son accession au tr\u00f4ne, Moncef Bey a acquis la popularit\u00e9 gr\u00e2ce \u00e0     la simplicit\u00e9 de son mode de vie. Dans cette station baln\u00e9aire de La Marsa,     o\u00f9 r\u00e9side la famille beylicale, il habite une maison modeste dans une rue     qui porte aujourd\u2019hui encore son nom. Il conna\u00eet la plupart des habitants de     la bourgade, n\u2019h\u00e9site pas \u00e0 se m\u00ealer \u00e0 eux autour d\u2019un verre de th\u00e9. Il a la     r\u00e9putation d\u2019\u00eatre pieux et croyant. Le professeur Mohktar Bey \u00e9crit \u00e0 son     propos qu\u2019il est de temp\u00e9rament gai et fougueux et que, bon vivant, le jeune     homme qu\u2019il fut succombait facilement au charme f\u00e9minin. Il a eu trois     femmes, une \u00e0 la fois, qui lui ont donn\u00e9 trois fils et une fille. Sa     derni\u00e8re \u00e9pouse, Arbia, s\u2019est montr\u00e9e sto\u00efque face aux \u00e9preuves. Elle \u00e9tait     au chevet de Moncef Bey lorsqu\u2019il est mort en exil \u00e0 Pau (France), le 1er     septembre 1948. Conform\u00e9ment \u00e0 ses v\u0153ux, il sera enterr\u00e9, le 5 septembre     1948, sur la colline de Sidi Belhassen, au cimeti\u00e8re du Jellaz, \u00e0 Tunis,     aupr\u00e8s des gens du peuple, et non point au caveau des princes husseinites     appel\u00e9 Tourbet el-Bey.           Trois cent mille personnes suivront ses fun\u00e9railles, tandis que, dans les     campagnes, le peuple le pleure. En 2004, un mausol\u00e9e a \u00e9t\u00e9 \u00e9rig\u00e9 au     cimeti\u00e8re du Jellaz \u00e0 la m\u00e9moire de celui qui a \u00e9t\u00e9 et restera le bey     bien-aim\u00e9 des Tunisiens.  \u00a0<\/font><\/font><\/div>\n<div align=\"justify\">    \u00a0<\/div>\n<div align=\"center\"> <font face=\"Arial\">    &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;     <strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Moncef Bey, les juifs, l\u2019Axe et les     Alli\u00e9s<\/font><\/h2>\n<p><\/strong> <\/font> <\/div>\n<div align=\"justify\">    \u00a0<\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong><font>par ABDELAZIZ BARROUHI<\/font><\/strong>              De son accession au tr\u00f4ne, en juin 1942, \u00e0 son abdication en juillet 1943,     le souverain de la r\u00e9gence de Tunis fit tout ce qui \u00e9tait en son pouvoir     pour prot\u00e9ger son peuple, toutes confessions confondues.           A sa mont\u00e9e sur le tr\u00f4ne, le 19 juin 1942, Moncef Bey \u00e9tait destin\u00e9 \u00e0     devenir un souverain de fa\u00e7ade, comme ce fut le plus souvent le cas pour ses     pr\u00e9d\u00e9cesseurs depuis l\u2019\u00e9tablissement du protectorat fran\u00e7ais sur la Tunisie     en 1881. Sur le papier, le bey, \u00ab souverain de la r\u00e9gence de Tunis \u00bb,     dispose d\u2019un gouvernement sous tutelle de l\u2019administration coloniale. Dans     les faits, c\u2019est le r\u00e9sident g\u00e9n\u00e9ral et son administration qui d\u00e9tiennent     les pouvoirs en mati\u00e8re l\u00e9gislative, de justice, de diplomatie, de police,     de finances et de budget. Les quelque deux cents gardes du bey ont un     officier de l\u2019arm\u00e9e fran\u00e7aise \u00e0 leur t\u00eate. Le r\u00f4le des beys est quasiment     limit\u00e9 \u00e0 l\u2019apposition du sceau beylical sur des d\u00e9crets pr\u00e9par\u00e9s par     l\u2019administration coloniale, ainsi qu\u2019\u00e0 la distribution, \u00e0 la mani\u00e8re des     r\u00e9publiques banani\u00e8res, d\u2019une d\u00e9coration appel\u00e9e Nichan al-Iftikhar \u00e0 des     personnes choisies par ces m\u00eames autorit\u00e9s. De ces deux pr\u00e9rogatives     formelles, Moncef Bey va tirer sa force pour devenir, selon ses propres     termes, un \u00ab bey pour de bon \u00bb.      En France, et sur injonction du Reich, le gouvernement collaborateur de     Vichy a promulgu\u00e9 une l\u00e9gislation antijuive. Celle-ci devait \u00eatre \u00e9tendue     aux d\u00e9pendances fran\u00e7aises, dont la Tunisie. De 1941 jusqu\u2019\u00e0 sa mort en juin     1942, le pr\u00e9d\u00e9cesseur de Moncef Bey, le falot Ahmed Pacha Bey II, r\u00e9put\u00e9     \u00eatre \u00ab le bey des Fran\u00e7ais \u00bb, a mollement r\u00e9sist\u00e9 puis a fini par apposer     son sceau sur la l\u00e9gislation vichyste relative au statut des juifs et la     limitation de leurs pouvoirs \u00e9conomiques. Lui succ\u00e9dant, Moncef Bey ne plie     pas. Non seulement il fait en sorte que cette l\u00e9gislation devienne     inop\u00e9rante, mais aussi, et malgr\u00e9 les pressions, il refuse net d\u2019apposer son     sceau sur de nouveaux d\u00e9crets raciaux qui lui sont pr\u00e9sent\u00e9s par     l\u2019administration coloniale. \u00ab Vous \u00eates mes fils, au m\u00eame titre que les     musulmans \u00bb, d\u00e9clare-t-il aux dirigeants de la communaut\u00e9 juive invit\u00e9s au     palais beylical \u00e0 la c\u00e9r\u00e9monie de son intronisation. Les juifs tunisiens     repr\u00e9sentent alors environ 7 % de la population. En 1941, sur le million     d\u2019habitants que compte la Tunisie, on d\u00e9nombre quelque 90 000 juifs, dont 68     000 de nationalit\u00e9 tunisienne, 16 500 naturalis\u00e9s fran\u00e7ais et environ 5 000     immigr\u00e9s originaires de Livourne, dont la protection rel\u00e8ve du gouvernement     italien qui fait partie de l\u2019Axe.           Le premier projet de d\u00e9cret vichyste auquel Moncef Bey refuse son sceau est     celui imposant aux juifs le port de l\u2019\u00e9toile jaune. Passant outre l\u2019accord     du bey, l\u2019amiral Jean-Pierre Esteva, r\u00e9sident g\u00e9n\u00e9ral de France en Tunisie,     impose en f\u00e9vrier 1943 le port de l\u2019\u00e9toile par un arr\u00eat\u00e9 qu\u2019il signe     lui-m\u00eame, malgr\u00e9 les r\u00e9serves du conseiller juridique fran\u00e7ais du     gouvernement. Cette ill\u00e9gitimit\u00e9 a sans doute contribu\u00e9 \u00e0 ce que la mesure     ne f\u00fbt pas appliqu\u00e9e. Les juifs en Tunisie ne porteront finalement pas     l\u2019\u00e9toile jaune, sauf \u00e0 Sousse, ville o\u00f9 le Parti populaire fran\u00e7ais (PPF,     p\u00e9tainiste), tr\u00e8s actif, l\u2019imposera pendant une br\u00e8ve p\u00e9riode.           Le second projet de d\u00e9cret instituant les camps de travail et le travail     obligatoire pour la construction d\u2019ouvrages destin\u00e9s \u00e0 la protection des     positions des forces de l\u2019Axe et de Vichy est \u00e9galement refus\u00e9 par Moncef     Bey. Les pressions sur lui et son gouvernement ayant encore \u00e9chou\u00e9, Esteva     utilise la m\u00eame proc\u00e9dure des arr\u00eat\u00e9s qu\u2019il signe lui-m\u00eame le 10 avril 1943.              Le troisi\u00e8me texte auquel le gouvernement de Moncef Bey s\u2019oppose a pour but     de chasser les commer\u00e7ants juifs des organismes \u00e9conomiques afin de faire     place nette aux Fran\u00e7ais \u00ab aryens \u00bb. L\u00e0 aussi, en l\u2019absence du sceau du bey,     c\u2019est par un arr\u00eat\u00e9 du r\u00e9sident g\u00e9n\u00e9ral que la mesure est prise. \u00c0 travers     ce texte, Rudolf Rahn, d\u00e9l\u00e9gu\u00e9 du Reich, veut cr\u00e9er des \u00ab commissions     \u00e9conomiques internationales \u00bb (franco-tuniso-germano-italiennes) qui auront     pour mission d\u2019organiser la vie \u00e9conomique et le ravitaillement. La     r\u00e9sidence g\u00e9n\u00e9rale se fait repr\u00e9senter par un membre de la chambre de     commerce fran\u00e7aise dans ces commissions qui se r\u00e9unissent au Dar Hussein, la     r\u00e9sidence de Rahn, situ\u00e9e en pleine M\u00e9dina. En revanche, M\u2019hamed Chenik, le     Premier ministre de Moncef Bey, refuse de se faire repr\u00e9senter tant que les     d\u00e9l\u00e9gu\u00e9s juifs \u00e0 la chambre tunisienne de commerce en sont exclus.           En fait, bien avant l\u2019arriv\u00e9e des forces allemandes, Moncef Bey a, durant     l\u2019\u00e9t\u00e9 1942, donn\u00e9 \u00e0 son gouvernement un mot d\u2019ordre consistant \u00e0 veiller \u00e0     la protection des juifs. Et d\u00e8s le d\u00e9but de l\u2019occupation de la Tunisie, en     novembre 1942, le bey est intervenu pour prot\u00e9ger la population, en     particulier les juifs, des exactions germano-italiennes. Lorsque, quelques     jours apr\u00e8s leur d\u00e9barquement en Tunisie, les Allemands arr\u00eatent cinq     dirigeants du Conseil de la communaut\u00e9 juive, ils les rel\u00e2chent le lendemain.     Et ce \u00e0 la demande expresse de Moncef Bey, rapporte Sa\u00efd Mestiri, qui lui     consacre une biographie (enrichie du t\u00e9moignage in\u00e9dit de son beau-p\u00e8re     M\u2019hamed Chenik, qui \u00e9tait l\u2019\u00e9minence grise et l\u2019ami de Moncef Bey)*.           Au d\u00e9but de leur occupation, les Allemands entreprennent des rafles dans les     lieux publics pour arr\u00eater les jeunes, musulmans ou juifs, en \u00e2ge de     travailler. Par la suite, ces rafles deviendront moins n\u00e9cessaires, les     dirigeants de la communaut\u00e9 juive s\u2019\u00e9tant engag\u00e9s \u00e0 choisir eux-m\u00eames la     main-d\u2019\u0153uvre r\u00e9clam\u00e9e par les Allemands, qui appellent \u00ab volontariat \u00bb ce     travail obligatoire. Les arm\u00e9es allemande et italienne entreprennent     \u00e9galement des r\u00e9quisitions et des saisies de marchandises dans les d\u00e9p\u00f4ts et     chez les commer\u00e7ants de Tunis, juifs comme musulmans.           Moncef Bey et son gouvernement ne pouvaient certes pas emp\u00eacher les     exactions allemandes \u00e0 l\u2019encontre des juifs comme des musulmans, mais les     t\u00e9moignages concordent pour dire qu\u2019ils ont contribu\u00e9 \u00e0 les att\u00e9nuer. La     Tunisie et ses juifs l\u2019ont quand m\u00eame \u00e9chapp\u00e9 belle. Un t\u00e9l\u00e9gramme de Rahn \u00e0     Berlin retrouv\u00e9 plus tard dans les archives allemandes d\u00e9voile un programme     qui aurait \u00e9t\u00e9 tragique : \u00ab L\u2019incitation au pillage des boutiques juives et     aux pogroms par voie de d\u00e9monstrations excitantes, \u00e9crit-il, [est]     inex\u00e9cutable tant que nos troupes n\u2019auront pas atteint au moins la fronti\u00e8re     alg\u00e9rienne. \u00bb Le d\u00e9barquement des Alli\u00e9s en Afrique du Nord les en emp\u00eachera.              En dehors du refus de faire appliquer en Tunisie les l\u00e9gislations inspir\u00e9es     par les nazis, quels ont \u00e9t\u00e9 les rapports de Moncef Bey avec les     repr\u00e9sentants de l\u2019Axe ? Le 8 novembre 1942, et alors que les forces     anglo-saxonnes d\u00e9barquent en Alg\u00e9rie dans le cadre de l\u2019op\u00e9ration Torche,     Hooker A. Doolittle, consul g\u00e9n\u00e9ral des \u00c9tats-Unis \u00e0 Tunis, se pr\u00e9sente \u00e0 la     r\u00e9sidence de l\u2019amiral Esteva. Celui-ci le re\u00e7oit en uniforme dans son palais     de La Marsa, dans la banlieue nord de Tunis. Doolittle lui remet deux     messages de Roosevelt : le premier destin\u00e9 \u00e0 Esteva lui-m\u00eame en tant que     repr\u00e9sentant de la France protectrice de la Tunisie. Il le prie de remettre     le second message \u00e0 Moncef Bey, en sa qualit\u00e9 de souverain du pays.           Quelques heures plus tard, Esteva remet \u00e0 son tour deux messages \u00e0 Moncef     Bey : celui de Roosevelt, et un autre du mar\u00e9chal P\u00e9tain. Dans le premier,     Roosevelt demande \u00e0 Moncef Bey le libre passage pour les forces am\u00e9ricaines     et alli\u00e9es \u00e0 travers la Tunisie. Dans le second, le mar\u00e9chal P\u00e9tain lui     signifie qu\u2019en vertu des trait\u00e9s entre la France et la Tunisie il se doit     d\u2019aligner son attitude sur celle de la France m\u00e9tropolitaine. Dilemme donc     pour Moncef Bey et ses conseillers : se plier aux ordres de P\u00e9tain ou se     ranger du c\u00f4t\u00e9 des Alli\u00e9s comme le demande Roosevelt.           La rue tunisienne et une partie de l\u2019\u00e9lite ont de la sympathie pour     l\u2019Allemagne, pour la simple raison qu\u2019elle a vaincu l\u2019oppresseur fran\u00e7ais.     Mais Habib Bourguiba, le chef du mouvement de lib\u00e9ration nationale, alors     d\u00e9tenu au fort Saint-Nicolas en France, vient, le 8 ao\u00fbt 1942, d\u2019adresser     aux dirigeants du parti N\u00e9o-Destour ses directives. L\u2019Allemagne ne pouvant,     selon lui, gagner la guerre, il leur demande d\u2019entrer en contact avec les     gaullistes et avec les repr\u00e9sentants des Anglo-Saxons, pr\u00e9cisant ceci : \u00ab     Notre soutien aux Alli\u00e9s doit \u00eatre inconditionnel. \u00bb           Apr\u00e8s consultations, la d\u00e9cision est prise de proclamer, officiellement, la     neutralit\u00e9 de la Tunisie. Moncef Bey envoie des lettres dans ce sens aux     chefs d\u2019\u00c9tat des pays bellig\u00e9rants. \u00ab Les \u00e9v\u00e9nements de ces derniers jours,     \u00e9crit-il dans sa lettre \u00e0 Roosevelt, nous imposent le devoir d\u2019\u00e9pargner \u00e0     notre peuple les souffrances de la guerre. Conscient de notre responsabilit\u00e9     et soucieux d\u2019observer vis-\u00e0-vis des bellig\u00e9rants une \u00e9gale attitude, nous     croyons devoir formuler solennellement le souhait de notre pays de rester en     dehors du conflit. \u00bb           Cette lettre officielle dat\u00e9e du 13 novembre, remise \u00e0 la r\u00e9sidence g\u00e9n\u00e9rale     pour acheminenent, ne parviendra pas \u00e0 son destinataire. Elle sera retrouv\u00e9e     plus tard dans les archives d\u2019Esteva. Mais comme si cette \u00ab censure \u00bb     coloniale \u00e9tait pressentie, deux jours auparavant, dans un message secret     dat\u00e9 du 11 novembre, des interm\u00e9diaires tunisiens ont \u00e9crit \u00e0 Roosevelt pour     l\u2019informer de l\u2019alignement formel de la Tunisie sur les Alli\u00e9s. La lettre a     \u00e9t\u00e9 remise par Abdelaziz Hussein, alias Slim Driga, membre d\u2019un r\u00e9seau     proam\u00e9ricain, \u00e0 Hooker Doolittle, le consul g\u00e9n\u00e9ral am\u00e9ricain \u00e0 Tunis, alors     assign\u00e9 \u00e0 r\u00e9sidence par la police fran\u00e7aise. Les signataires, M\u2019hamed Ali     Annabi, un familier du bey, et Driga, d\u00e9clarent que \u00ab Son Altesse le Bey,     anim\u00e9 de sentiments particuli\u00e8rement favorables \u00e0 l\u2019\u00e9gard des Anglo-Saxons,     qui l\u2019ont port\u00e9 \u00e0 adopter une attitude diplomatique [la neutralit\u00e9 et le     non-alignement sur le gouvernement de P\u00e9tain], non pr\u00e9vue dans le trait\u00e9 du     Bardo, est convaincue que le gouvernement am\u00e9ricain, en r\u00e9ponse \u00e0 son geste,     ne prendra aucun engagement et ne fera aucune d\u00e9claration susceptible de     favoriser une emprise \u00e9ventuelle sur la Tunisie par les \u00e9l\u00e9ments     imp\u00e9rialistes fran\u00e7ais \u00bb.           L\u2019accus\u00e9 de r\u00e9ception de Doolittle \u00e0 cette lettre confirme que le message     venait bien de Moncef Bey et lui apporte des assurances : \u00ab Le gouvernement     am\u00e9ricain [\u2026] donne toute assurance \u00e0 Son Altesse en ce qui concerne les     op\u00e9rations qui pourraient \u00eatre men\u00e9es \u00e9ventuellement en Tunisie. Les     Am\u00e9ricains viennent en amis et en constructeurs, et ils s\u2019efforceront de     r\u00e9duire les d\u00e9g\u00e2ts de la guerre \u00e0 ce qui est strictement n\u00e9cessit\u00e9 par les     op\u00e9rations militaires\u2026 \u00bb           Un mois apr\u00e8s le d\u00e9barquement des forces anglo-saxonnes en Alg\u00e9rie, les     troupes germano-italiennes de l\u2019Axe p\u00e9n\u00e8trent en Tunisie pour leur barrer la     route du sud de l\u2019Europe et Esteva applique un ordre de P\u00e9tain de ne pas     leur r\u00e9sister.           Moncef Bey refuse tout contact avec les repr\u00e9sentants de l\u2019Axe et demande     que les communications lui soient faites, conform\u00e9ment au protocole, \u00e0     travers son ministre des Affaires \u00e9trang\u00e8res, qui n\u2019est autre que le     r\u00e9sident g\u00e9n\u00e9ral de France, l\u2019amiral Esteva. Le jour o\u00f9 les ministres     pl\u00e9nipotentiaires allemand et italien le contactent pour demander une     audience, le bey en informe Esteva, qui lui demande de les recevoir. Moncef     Bey accueille alors Rahn, accompagn\u00e9 du g\u00e9n\u00e9ral Nehring, commandant en chef     des troupes allemandes, au palais d\u2019\u00e9t\u00e9 d\u2019Hammam Lif, le 18 novembre 1942.     Re\u00e7u en mars 1943 par Moncef Bey, Bombieri, le ministre italien, dont le     pays a des vis\u00e9es d\u00e9clar\u00e9es d\u2019annexion de la Tunisie, lui propose d\u2019annuler     le trait\u00e9 du Bardo qui le lie \u00e0 la France et d\u2019en signer un avec l\u2019Italie.     R\u00e9ponse de Moncef Bey : \u00ab Je ne peux, sans d\u00e9roger aux r\u00e8gles et sans     manquer au devoir de l\u2019amiti\u00e9 vis-\u00e0-vis du repr\u00e9sentant de la France,     prendre actuellement et par un acte unilat\u00e9ral une d\u00e9cision susceptible     d\u2019affecter le statut politique de la Tunisie. \u00bb Cette fois aussi, Moncef Bey     a inform\u00e9 Esteva.           Puis les Allemands et les Italiens vont essayer de mettre \u00e0 profit les     bombardements intensifs op\u00e9r\u00e9s par les forces alli\u00e9es contre des villes     tunisiennes d\u00e8s le d\u00e9barquement des forces de l\u2019Axe. Ils savent que Moncef     Bey et son gouvernement sont pr\u00e9occup\u00e9s par les pertes civiles occasionn\u00e9es     et qu\u2019ils cherchent \u00e0 entrer en contact avec les Alli\u00e9s pour leur demander     de tout faire pour respecter la neutralit\u00e9 de la Tunisie. Moelhausen, l\u2019un     des adjoints de Rahn en voyage, l\u2019en dissuade et tente de lui soutirer une     d\u00e9claration condamnant les bombardements alli\u00e9s. Moncef Bey refuse.     Moelhausen revient \u00e0 la charge et lui propose au nom du Reich de mettre \u00e0 sa     disposition une station de radio puissante pour qu\u2019il d\u00e9nonce lui-m\u00eame les     bombardements alli\u00e9s devant l\u2019opinion mondiale. Moncef Bey rejette l\u2019id\u00e9e.     Et, encore une fois, il informe Esteva.           S\u2019il a \u00e9vit\u00e9 le pi\u00e8ge germano-\u00aditalien, Moncef Bey va tomber dans celui que     lui tend Esteva. L\u2019amiral, qui sera condamn\u00e9 en 1945 \u00e0 la prison \u00e0     perp\u00e9tuit\u00e9 pour trahison, lui en veut \u00e0 mort pour avoir voulu jouer son r\u00f4le     de souverain patriote et permis aux Tunisiens de retrouver leur fiert\u00e9     nationale, pr\u00e9conis\u00e9 des r\u00e9formes pour l\u2019\u00e9mancipation de la Tunisie ;     r\u00e9clam\u00e9 constamment la lib\u00e9ration des dirigeants nationalistes ; nomm\u00e9 sans     le consulter un gouvernement proche des nationalistes avec comme Premier     ministre M\u2019hamed Chenik que Rahn qualifie de \u00ab demi-am\u00e9ricain \u00bb ; et refus\u00e9     d\u2019apposer son sceau sur les l\u00e9gislations antijuives. \u00c0 la suite d\u2019un     incident diplomatique qui les a oppos\u00e9s le 12 octobre 1942, Moncef Bey a     m\u00eame r\u00e9clam\u00e9 \u00e0 P\u00e9tain son rappel. Esteva, \u00e0 l\u2019approche des troupes alli\u00e9es     de Tunis et alors qu\u2019il est d\u00e9j\u00e0 question que lui-m\u00eame et les chefs de l\u2019Axe     prennent la fuite, ordonne au bey de d\u00e9cerner le Nichan al-Iftikhar \u00e0 des     officiers fran\u00e7ais de son entourage, dont le colonel fran\u00e7ais Sarton du     Jonchay, son chef de cabinet. Du Jonchay a \u00e9t\u00e9 envoy\u00e9 en Tunisie pour     organiser une \u00ab l\u00e9gion tricolore \u00bb appel\u00e9e \u00e0 se battre aux c\u00f4t\u00e9s de la     Wehrmacht. C\u2019est lui qui exerce en fait les pouvoirs de r\u00e9sident g\u00e9n\u00e9ral.     Moncef Bey plie et d\u00e9core les officiers fran\u00e7ais.           Quelques jours plus tard, Esteva pr\u00e9sente une nouvelle liste d\u2019une     quarantaine d\u2019officiers allemands et italiens qui, dit-il, trouvent anormal     qu\u2019ils ne soient pas d\u00e9cor\u00e9s comme du Jonchay. Cette fois-ci, Moncef Bey     refuse, en faisant valoir la neutralit\u00e9 de la Tunisie. Esteva insiste, pour     finir par dire \u00e0 Moncef Bey qu\u2019il le d\u00e9gage de toute responsabilit\u00e9, que ces     d\u00e9corations ne sont pas incompatibles avec la neutralit\u00e9 de la Tunisie, et     qu\u2019il l\u2019autorise \u00e0 d\u00e9corer les chefs militaires alli\u00e9s \u00ab le premier jour \u00bb     de leur arriv\u00e9e \u00e0 Tunis. Moncef Bey demande qu\u2019Esteva lui confirme cela par     \u00e9crit, ce qu\u2019il fait.           Le bey finit par c\u00e9der. Mal lui en prend, m\u00eame s\u2019il a veill\u00e9 \u00e0 ne pas     remettre lui-m\u00eame ces d\u00e9corations et qu\u2019il est \u00e9tabli qu\u2019il a agi sur     l\u2019ordre du repr\u00e9sentant du gouvernement fran\u00e7ais. Le lobby colonial autour     du g\u00e9n\u00e9ral Giraud \u00e0 Alger et dont l\u2019expert pour le dossier tunisien n\u2019est     autre que Marcel Peyrouton, ancien r\u00e9sident g\u00e9n\u00e9ral en Tunisie, a trouv\u00e9 un     pr\u00e9texte pour r\u00e9gler son compte au bey. Moncef Bey est accus\u00e9 de \u00ab     collaboration avec l\u2019Axe \u00bb. Un comble quand on sait que Peyrouton fut le     ministre de l\u2019Int\u00e9rieur du premier gouvernement collaborationniste de Vichy     !           \u00c0 l\u2019entr\u00e9e des troupes alli\u00e9es dans Tunis, le 7 mai, Moncef Bey se trouve     dans son palais d\u2019\u00e9t\u00e9 \u00e0 Hammam Lif, o\u00f9 se sont r\u00e9fugi\u00e9es plus de 100 000     personnes qui ont fui la capitale. Les Allemands ont install\u00e9 leur ligne de     front non loin du palais, qui, dans la foul\u00e9e, est touch\u00e9 par les     bombardements anglo-saxons. Deux Britanniques y font irruption, rejoints par     leur officier. Moncef Bey les re\u00e7oit et s\u2019appr\u00eate \u00e0 d\u00e9corer l\u2019officier du     Nichan al-Iftikhar. Mais c\u2019est pour l\u2019arr\u00eater qu\u2019ils sont l\u00e0. Ils l\u2019emm\u00e8nent     de force \u00e0 Tunis o\u00f9 sa voiture est gar\u00e9e devant l\u2019ambassade de France. Sans     qu\u2019on sache comment il a \u00e9t\u00e9 mobilis\u00e9, un groupe de personnes parmi lesquels     on a cru reconna\u00eetre de jeunes juifs l\u2019insultent et lui crachent dessus.           Une demi-heure apr\u00e8s, le secr\u00e9taire g\u00e9n\u00e9ral de la r\u00e9sidence g\u00e9n\u00e9rale vient     tirer Moncef Bey de ce mauvais pas avec des excuses. Sur ordre de Giraud, le     g\u00e9n\u00e9ral Alphonse Juin, fra\u00eechement arriv\u00e9 comme r\u00e9sident g\u00e9n\u00e9ral par int\u00e9rim     apr\u00e8s la fuite d\u2019Esteva avec les Allemands, vient le sommer d\u2019abdiquer.     R\u00e9ponse du bey : \u00ab J\u2019ai jur\u00e9 de d\u00e9fendre mon peuple jusqu\u2019\u00e0 mon dernier     souffle. Je ne partirai que si mon peuple me le demande. \u00bb           Le 14 mai \u00e0 l\u2019aube, il est enlev\u00e9 et plac\u00e9 \u00e0 bord d\u2019un Viking de l\u2019arm\u00e9e de     l\u2019air fran\u00e7aise qui s\u2019envole de l\u2019a\u00e9roport d\u2019El-Aouina. Pendant qu\u2019il est     dans les airs, on annonce sa d\u00e9position par une simple ordonnance sign\u00e9e par     le g\u00e9n\u00e9ral Giraud, commandant en chef civil et militaire en \u00ab Afrique     fran\u00e7aise \u00bb, bas\u00e9 \u00e0 Alger. L\u2019avion atterrit \u00e0 Laghouat, dans le Sahara     alg\u00e9rien, o\u00f9 les conditions de vie en plein \u00e9t\u00e9 forcent le prince \u00e0 abdiquer     et \u00e0 renoncer d\u00e9finitivement au tr\u00f4ne, le 8 juillet 1943. Il est alors     transf\u00e9r\u00e9 dans le nord de l\u2019Alg\u00e9rie avant d\u2019\u00eatre plac\u00e9 en r\u00e9sidence     surveill\u00e9e \u00e0 Pau, en France, o\u00f9 il mourra en 1948.           Roger Casemajor, le chef de la section musulmane des renseignements g\u00e9n\u00e9raux     fran\u00e7ais \u00e0 Tunis, peu suspect de sympathies pour les Tunisiens, commente     dans un rapport \u00e0 diffusion restreinte qui sera connu des ann\u00e9es plus tard :     \u00ab Par cette attitude de bascule entre les diplomates \u00e9trangers et les     autorit\u00e9s du protectorat, le bey de Tunis fit preuve d\u2019une grande souplesse     politique qui lui permit de servir les int\u00e9r\u00eats de ses sujets et la cause de     son pays. \u00bb           Et c\u2019est le g\u00e9n\u00e9ral Juin, promu mar\u00e9chal en 1952, qui dans ses M\u00e9moires,     Alger, Tunis, Rome (Fayard, Paris, 1959), r\u00e9tablira une grande partie de la     v\u00e9rit\u00e9. Il confirme que les directives qui lui ont \u00e9t\u00e9 donn\u00e9es exigeaient la     d\u00e9position de Moncef Bey \u00ab pour de pr\u00e9tendus faits de collaboration avec les     puissances de l\u2019Axe au cours de l\u2019occupation et aussi pour les complaisances     un peu trop marqu\u00e9es qu\u2019on lui pr\u00eatait envers les agissements du Destour,     parti nationaliste militant ouvertement hostile au protectorat\u2026 \u00bb           \u00ab Je me livrai donc, ajoute-t-il, \u00e0 une rapide enqu\u00eate afin de savoir si le     bey ou d\u2019autres personnages de la cour beylicale s\u2019\u00e9taient vraiment     compromis avec les autorit\u00e9s occupantes. Je ne d\u00e9couvris aucun grief s\u00e9rieux.     Le bey avait v\u00e9cu repli\u00e9 dans son palais, prenant pr\u00e9texte de sa situation     de souverain prot\u00e9g\u00e9 pour d\u00e9tourner vers le r\u00e9sident g\u00e9n\u00e9ral [\u2026] toutes     discussions se rapportant aux affaires de la r\u00e9gence. \u00bb \u00ab Tout au plus,     note-t-il, pouvait-on reprocher au bey Moncef d\u2019avoir, sur l\u2019insistance du     r\u00e9sident g\u00e9n\u00e9ral ou de quelqu\u2019un de son entourage, appos\u00e9 son sceau sur un     firman [un \u00e9dit] conf\u00e9rant des distinctions de son ordre, le Nichan     al-Iftikhar, \u00e0 des personnalit\u00e9s ennemies. Il avait toutefois refus\u00e9     formellement de les remettre lui-m\u00eame. Restaient les sympathies     prodestouriennes, invoqu\u00e9es comme griefs, et qui risquaient de faire prendre     au proc\u00e8s intent\u00e9 au bey un tour tendancieux. Mais les instructions avaient,     encore une fois, un caract\u00e8re imp\u00e9ratif et l\u2019on insistait d\u2019Alger pour que     l\u2019op\u00e9ration e\u00fbt lieu \u00e0 chaud afin de profiter du d\u00e9sarroi des esprits et du     choc produit par la d\u00e9faite des puissances de l\u2019Axe. Je ne pouvais qu\u2019ob\u00e9ir\u2026     \u00bb           Conclusion de Juin : \u00ab Il m\u2019est souvent arriv\u00e9 depuis ces \u00e9v\u00e9nements de     regretter, en pensant aux circonstances qui les d\u00e9termin\u00e8rent, que dans sa     pr\u00e9cipitation, et disons aussi dans son ignorance des donn\u00e9es exactes de la     situation politique en Tunisie, le pseudo-gouvernement d\u2019Alger m\u2019e\u00fbt impos\u00e9     l\u2019ex\u00e9cution d\u2019un acte impolitique, au d\u00e9triment d\u2019un souverain auquel il n\u2019y     avait rien de grave \u00e0 reprocher et qui fut toujours loyal. \u00bb           Le t\u00e9moignage de Juin aurait pu suffire, \u00e0 lui seul, pour r\u00e9parer l\u2019immense     injustice commise au nom de l\u2019\u00c9tat fran\u00e7ais \u00e0 l\u2019encontre de Moncef Bey, de     son peuple et de la Tunisie. On attend toujours.           <strong><font>(Source : Jeune Afrique, N\u00b0 2379-2380 du 13 au     26 ao\u00fbt 2006)<\/font><\/strong><\/font><\/div>\n<div align=\"center\"> <font face=\"Arial\">    &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;     <\/font><strong><font face=\"Arial\"><font>\u00ab La nation     tunisienne, entre hier et aujourd\u2019hui \u00bb     <\/font><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Une identit\u00e9 mill\u00e9naire<\/font><\/h2>\n<p><\/font><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong><font>par H\u00c9DI BACCOUCHE (*)<\/font><\/strong>          Quel devenir pour la Tunisie dans ce monde en pleine mutation ? Notre pays     est bien s\u00fbr une partie int\u00e9grante de la nation arabe et une composante de     la communaut\u00e9 musulmane. Nous avons appartenu \u00e0 des empires arabo-islamiques.     Nous avons \u00e9t\u00e9 gouvern\u00e9s tour \u00e0 tour depuis Damas, Bagdad et Marrakech. Mais     la Tunisie a toujours eu une identit\u00e9 propre et irr\u00e9ductible.     N\u2019en d\u00e9plaise aux tenants des th\u00e8ses colonialistes, qui, \u00e0 la veille et     pendant le protectorat, d\u00e9crivaient notre soci\u00e9t\u00e9 comme \u00ab une poussi\u00e8re de     tribus \u00bb sans conscience nationale, la Tunisie a, de tout temps, dispos\u00e9 des     attributs d\u2019une nation. D\u2019abord un territoire, habit\u00e9 depuis des temps     imm\u00e9moriaux par des Berb\u00e8res. Un territoire successivement conquis par les     Ph\u00e9niciens, les Romains, les Byzantins, les Vandales, puis les Arabes, mais     qui servit aussi, maintes fois, de base territoriale \u00e0 des pouvoirs     autonomes.          Fond\u00e9 en 814 avant J.-C., Carthage domina la majeure partie du littoral     africain. Son influence s\u2019\u00e9tendait \u00e0 la p\u00e9ninsule Ib\u00e9rique, \u00e0 l\u2019Italie, au     sud de la France et \u00e0 Chypre. Il \u00e9tait donc le centre d\u2019un vaste empire     puissant et prosp\u00e8re. Kairouan fut la premi\u00e8re ville de l\u2019islam au Maghreb.     Pendant le r\u00e8gne des Aghlabides (800-909), son rayonnement d\u00e9passa largement     les fronti\u00e8res de l\u2019actuelle Tunisie ; Mahdia fut, quant \u00e0 elle, la capitale     des Fatimides (909-1048), dont la mainmise s\u2019\u00e9tendit \u00e0 l\u2019ensemble de     l\u2019Afrique du Nord et \u00e0 la Syrie. Le territoire tunisien a fini par se     r\u00e9tr\u00e9cir avec la chute de la dynastie des Hafsides, \u00e0 la fin du XVIIe si\u00e8cle.     Ce sont leurs successeurs ottomans qui fixeront les limites territoriales     actuelles du pays, m\u00eame si les fronti\u00e8res avec l\u2019Alg\u00e9rie, domin\u00e9e elle aussi,     jusqu\u2019\u00e0 1830, par les Turcs, sont rest\u00e9es longtemps impr\u00e9cises et     controvers\u00e9es. Au pr\u00e9sident Houari Boumedienne, qui lui proposait, en mai     1973, une union entre les deux pays, Habib Bourguiba avait r\u00e9pondu : \u00ab Avant     de parler d\u2019union, Monsieur le Pr\u00e9sident, restituez Constantine \u00e0 la Tunisie.     Vous r\u00e9duiriez ainsi l\u2019\u00e9cart entre les superficies de nos deux pays et     rendriez l\u2019unit\u00e9 r\u00e9alisable. \u00bb          La Tunisie a aussi, de tr\u00e8s longue date, d\u2019autres caract\u00e9ristiques d\u2019une     nation digne de ce nom : l\u2019homog\u00e9n\u00e9it\u00e9 ethnique, la langue (arabe), la     religion (musulmane) &#8211; qui a toujours su cohabiter avec le juda\u00efsme,     confession d\u2019une minorit\u00e9 de la population -, ainsi que des us et coutumes     sp\u00e9cifiques. Ses habitants avaient leur propre litt\u00e9rature, leur propre     musique et leur propre art. Mais il est incontestable que nous \u00e9tions     d\u00e9pourvus, jusqu\u2019\u00e0 la d\u00e9colonisation, en 1956, d\u2019un attribut essentiel de     l\u2019\u00c9tat-nation : la souverainet\u00e9. Cette souverainet\u00e9, nous l\u2019avons perdue en     1573, au lendemain de la conqu\u00eate du pays par les Ottomans, venus     initialement pr\u00eater main-forte aux Hafsides face aux Espagnols, qui     occupaient quelques villes c\u00f4ti\u00e8res du pays. \u00c0 l\u2019instar de l\u2019Alg\u00e9rie et de     la Tripolitaine, la Tunisie fut ainsi r\u00e9duite au rang de sandjak (\u00ab province     ottomane \u00bb).          En 1881, la Tunisie change de mains. Aux termes du trait\u00e9 du Bardo, les     Fran\u00e7ais imposent leur protectorat au gouverneur turc. Un v\u00e9ritable choc     pour le pays. Insensibles aux appels au calme lanc\u00e9s par le bey et sa cour,     les Tunisiens, dans leur \u00e9crasante majorit\u00e9, rejettent le fait accompli. La     r\u00e9sistance arm\u00e9e, anim\u00e9e d\u2019abord par les grandes tribus du Nord, finit par     s\u2019\u00e9tendre \u00e0 l\u2019ensemble du territoire. Mais l\u2019issue de cette confrontation     entre un peuple quasiment d\u00e9sarm\u00e9, trahi par son propre gouvernement, et une     des arm\u00e9es r\u00e9guli\u00e8res les plus puissantes de l\u2019\u00e9poque \u00e9tait facilement     pr\u00e9visible. Malgr\u00e9 les atrocit\u00e9s des troupes coloniales, le peuple ne courbe     pas l\u2019\u00e9chine et se soul\u00e8ve contre l\u2019occupant en 1911 puis en 1912. Le combat     politique prend bient\u00f4t le relais de la r\u00e9sistance arm\u00e9e quand Abdelaziz     Thaalibi cr\u00e9e le Parti libre destourien tunisien pour porter les     revendications de la nation. Mais l\u2019\u00e9lan de la nouvelle formation est frein\u00e9     par des handicaps majeurs : l\u2019\u00e9litisme et la rigidit\u00e9 d\u2019une partie de sa     direction, ainsi que le recours \u00e0 des moyens d\u2019action d\u00e9pass\u00e9s. Cons\u00e9quence     : le blocage de l\u2019action du mouvement national.          Men\u00e9s par Habib Bourguiba, des dirigeants du Destour quittent alors le parti     pour lancer, en 1934, le N\u00e9o-Destour, qui deviendra l\u2019\u00e2me et le moteur de la     r\u00e9sistance. Avec ses programmes bien con\u00e7us et ses m\u00e9thodes efficaces, il ne     tarde pas \u00e0 g\u00eaner les autorit\u00e9s du protectorat. Quelques mois plus tard,     Bourguiba et certains de ses compagnons de lutte sont jet\u00e9s en prison.     L\u2019objectif du r\u00e9sident g\u00e9n\u00e9ral est clair : donner un coup d\u2019arr\u00eat \u00e0     l\u2019expansion du parti rapidement ralli\u00e9 par une majorit\u00e9 des destouriens.     C\u2019est la premi\u00e8re confrontation, donc, entre la formation nationaliste et     les autorit\u00e9s d\u2019occupation. Face aux r\u00e9actions populaires &#8211; manifestations     et actes de sabotage -, les Fran\u00e7ais font marche arri\u00e8re. Les leaders     nationalistes sont lib\u00e9r\u00e9s. Mieux : on est \u00e0 deux doigts d\u2019un accord portant     sur l\u2019am\u00e9lioration du syst\u00e8me du protectorat. Mais finalement, la France     n\u2019ose pas franchir le pas. Furieux, Habib Bourguiba refuse d\u00e9sormais le     moindre contact avec les autorit\u00e9s du protectorat et appelle \u00e0 la reprise de     la r\u00e9sistance. Entam\u00e9e le 9 avril 1938, cette deuxi\u00e8me \u00e9preuve se soldera     par l\u2019arrestation du leader nationaliste avec d\u2019autres dirigeants du parti.     Mais cette fois, ils sont d\u00e9port\u00e9s en France, o\u00f9 ils risquent une     condamnation \u00e0 la peine capitale.          Le mouvement national r\u00e9agit sur plusieurs registres. En Tunisie, les     manifestations se succ\u00e8dent et les attentats contre le protectorat se     multiplient. \u00c0 l\u2019\u00e9tranger, gr\u00e2ce aux efforts des militants, Paris est soumis     \u00e0 une forte pression politico-diplomatique. R\u00e9sultat : la France proclame     son intention d\u2019accorder une autonomie interne \u00e0 son protectorat avant de     renier sa propre parole, en d\u00e9cembre 1951, dans une lettre adress\u00e9e au bey.     Cette attitude irrite au plus haut point Habib Bourguiba, qui annonce alors     la troisi\u00e8me et ultime confrontation entre le N\u00e9o-Destour et la puissance     coloniale. Trente mois durant, le peuple tunisien m\u00e8ne la vie dure au     protectorat. La r\u00e9sistance ne recule devant rien : manifestations et marches     pacifiques, mais aussi actes de sabotages et assassinats dans les rangs des     forces d\u2019occupation et leurs relais locaux. Paris d\u00e9ploie 80 000 soldats     dans le pays. Mais la r\u00e9pression, pourtant f\u00e9roce et aveugle, ne vient pas \u00e0     bout du mouvement national. C\u2019est alors que le gouvernement Pierre Mend\u00e8s     France d\u00e9cide d\u2019entamer des n\u00e9gociations avec les nationalistes tunisiens et     marocains. Des facteurs ext\u00e9rieurs ont contribu\u00e9 \u00e0 cet infl\u00e9chissement de la     position fran\u00e7aise : le soutien grandissant au sein des Nations unies aux     causes tunisienne et marocaine et la crainte de Paris de voir la contagion     nationaliste toucher \u00ab l\u2019Alg\u00e9rie fran\u00e7aise \u00bb.          Toujours est-il que, le 20 mars 1956, la Tunisie acc\u00e8de \u00e0 l\u2019ind\u00e9pendance,     recueillant ainsi les fruits d\u2019une glorieuse \u00e9pop\u00e9e et de soixante-quinze     ans de sacrifices. Notre pays est depuis un \u00c9tat-nation au plein sens du     terme. Nous \u00e9tions conscients &#8211; Habib Bourguiba le premier &#8211; de l\u2019acquis que     nous venions d\u2019arracher, au prix fort, \u00e0 la puissance coloniale. Notre     pr\u00e9occupation majeure \u00e9tait d\u00e9sormais de promouvoir et d\u2019enraciner la     conscience nationale au sein de toutes les composantes de notre peuple. \u00c0     aucun moment, nous n\u2019avons \u00e9t\u00e9 sensibles aux sir\u00e8nes du panarabisme et du     panislamisme. L\u2019\u00e9volution de cette aire g\u00e9oculturelle nous a d\u2019ailleurs     donn\u00e9 raison : l\u2019\u00c9tat-nation s\u2019est impos\u00e9 partout, tandis que l\u2019unit\u00e9 arabe     ou musulmane est rest\u00e9e un v\u0153u pieux. \u00c0 cela plusieurs raisons, qui ne     r\u00e9sident pas seulement dans le manque d\u2019enthousiasme de la plupart des     dirigeants ou dans leur inf\u00e9odation \u00e0 l\u2019\u00e9tranger, comme le laisse penser     l\u2019analyse dominante dans le monde arabe, mais aussi dans l\u2019attachement des     peuples \u00e0 leur souverainet\u00e9 et \u00e0 leur souci de jouir pleinement des     richesses de leur pays.          Bref, nous devons \u00eatre fiers, en Tunisie, d\u2019avoir compris tr\u00e8s t\u00f4t que la     construction nationale devait \u00eatre la priorit\u00e9 des priorit\u00e9s. Ainsi, au     lendemain de l\u2019ind\u00e9pendance, nous avons consacr\u00e9 toute notre \u00e9nergie au     d\u00e9veloppement global du pays. C\u2019\u00e9tait, pour nous, le \u00ab grand djihad \u00bb. La     Tunisie en a rapidement touch\u00e9 les dividendes. Elle s\u2019est remarquablement     d\u00e9velopp\u00e9e dans tous les domaines. Le \u00ab Changement \u00bb du 7 novembre 1987 a     donn\u00e9 une forte impulsion \u00e0 ce processus. Ainsi, sous la conduite du     pr\u00e9sident Zine el-Abidine Ben Ali, la Tunisie est devenue un pays \u00e9mergent     souvent cit\u00e9 en exemple. Aujourd\u2019hui, il nous appartient de pr\u00e9server et de     d\u00e9fendre ces pr\u00e9cieux acquis, car nous sommes confront\u00e9s \u00e0 de nombreuses     pressions et menaces ext\u00e9rieures dont la plus importante est, sans conteste,     la mondialisation.          Comment notre \u00c9tat-nation pourra-t-il relever ce nouveau d\u00e9fi ? La r\u00e9ponse,     \u00e0 mon avis, ne consiste pas \u00e0 remettre en cause notre entit\u00e9 nationale.     Celle-ci restera toujours notre rep\u00e8re et le meilleur cadre pour notre     d\u00e9veloppement. Elle r\u00e9side plut\u00f4t dans la qu\u00eate d\u2019une dynamique maghr\u00e9bine.     Malgr\u00e9 tous les al\u00e9as et hypoth\u00e8ques qui en entravent la r\u00e9alisation, la     construction de l\u2019Union du Maghreb arabe (UMA) demeure \u00e0 port\u00e9e de main de     nos dirigeants et de nos peuples. \u00ab Le Maghreb est une seule contr\u00e9e     singuli\u00e8re parmi les pays \u00bb, disait Ibn Khaldoun. Son \u00e9dification doit \u00eatre     la priorit\u00e9 des nations maghr\u00e9bines. Ce sera, pour chacun d\u2019entre nous, le     gage de l\u2019ind\u00e9pendance et de la prosp\u00e9rit\u00e9. Notre combat aujourd\u2019hui pour     l\u2019int\u00e9gration de nos \u00c9tats est le prolongement logique de notre lutte, hier,     pour l\u2019ind\u00e9pendance.               <strong>(*) Fait docteur honoris causa de l\u2019universit\u00e9 de Sousse le 28 mai     2005, l\u2019ex-Premier ministre tunisien pronon\u00e7a, \u00e0 l\u2019occasion de la c\u00e9r\u00e9monie     de remise des insignes, une conf\u00e9rence intitul\u00e9e \u00ab La nation tunisienne,     entre hier et aujourd\u2019hui \u00bb. Le texte ci-dessus en reprend l\u2019essentiel.     <\/strong> <\/font><strong><font><font face=\"Arial\">(Source : Jeune     Afrique, N\u00b0 2379-2380 du 13 au 26 ao\u00fbt 2006)<\/font><\/font><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font> <\/div>\n<div align=\"center\"> <font face=\"Arial\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">Comment les     musulmans s\u2019en sortiront<\/font><\/h2>\n<p><\/strong> <\/font> <\/div>\n<div align=\"justify\"> <font face=\"Arial\"><strong><font>par RIDHA K\u00c9FI<\/font><\/strong> <strong>Pour l\u2019historien tunisien Hichem Dja\u00eft, la question n\u2019est plus de     savoir si le monde islamique va oui ou non emprunter le chemin de la     modernit\u00e9. Mais quand.      <\/strong>     Le monde arabo-musulman, dont la d\u00e9cadence a commenc\u00e9 il y a plusieurs     si\u00e8cles, est, depuis une cinquantaine d\u2019ann\u00e9es, \u00ab un environnement plein de     tumulte \u00bb et \u00ab tournant \u00e0 vide \u00bb. La parole y est b\u00e2illonn\u00e9e et le niveau     intellectuel tr\u00e8s faible, compar\u00e9 \u00e0 ce qui se produit en Occident. La mont\u00e9e     des mouvements islamistes, en r\u00e9action \u00e0 la rapide modernisation des \u00c9tats     nationaux, est comme \u00ab une revanche du culturel \u00bb, \u00ab un retour \u00e0 l\u2019endog\u00e8ne     et \u00e0 l\u2019identitaire \u00bb, d\u2019autant que le but d\u00e9clar\u00e9 de ces mouvements est de     renouer avec un pass\u00e9 glorieux, en mettant \u00e0 bas les r\u00e9gimes modernistes,     d\u2019une part, et, d\u2019autre part, en r\u00e9islamisant la soci\u00e9t\u00e9 jusque dans les     moindres aspects de la vie.      Dans un ouvrage publi\u00e9 par Fayard en 2004 et que C\u00e9r\u00e8s vient de r\u00e9\u00e9diter \u00e0     Tunis, l\u2019historien tunisien Hichem Dja\u00eft ne se contente pas de diagnostiquer     ce mal profond qui ronge la soci\u00e9t\u00e9 arabo-islamique ; il essaie aussi d\u2019en     expliquer les causes historiques, d\u2019en d\u00e9monter les m\u00e9canismes actuels et de     r\u00e9fl\u00e9chir aux moyens de sortir de la crise.           S\u2019il a longtemps constitu\u00e9 le centre du pouvoir islamique, le monde arabe a     c\u00e9d\u00e9 sous les coups qui lui ont \u00e9t\u00e9 port\u00e9s par les Mongols et les Timourides,     ainsi que par l\u2019occupation turque, qui a provoqu\u00e9 son d\u00e9clin et l\u2019a entra\u00een\u00e9     dans un profond sommeil. Dans ce monde \u00e0 la d\u00e9rive, la colonisation     europ\u00e9enne a constitu\u00e9 \u00ab un grand choc \u00bb, sinon un coup de gr\u00e2ce.           Cependant, \u00ab jusqu\u2019\u00e0 l\u2019abolition du califat ottoman en 1924 puis la vague     des ind\u00e9pendances et des \u2018\u2018r\u00e9volutions\u201d, de l\u2019Indon\u00e9sie au Maroc, il a     toujours exist\u00e9, corollairement \u00e0 la scission par nations et par aires     g\u00e9ographiques, un \u201csens islamique diffus\u201d, r\u00e9sidu de la vieille Oumma \u00bb. Les     sentiments nationaux \u00e9taient alors dirig\u00e9s contre le colonisateur. \u00ab     C\u2019\u00e9taient des sentiments de pure r\u00e9sistance. La constitution des \u00c9tats     nationaux au milieu du XXe si\u00e8cle leur a conf\u00e9r\u00e9 un contenu positif, les     r\u00e9orientant vers d\u2019autres objectifs, en prise avec la situation nouvelle, en     les int\u00e9grant dans le contexte international avec ses exigences \u00bb, \u00e9crit     Dja\u00eft.           Aussit\u00f4t constitu\u00e9s par les \u00e9lites nationalistes, plus ou moins s\u00e9cularistes     et modernistes, ces \u00c9tats nationaux n\u2019ont cependant pas tard\u00e9 \u00e0 \u00e9craser les     soci\u00e9t\u00e9s sous le poids de leurs appareils bureaucratiques et policiers. Ceci     expliquant cela, ces \u00c9tats ont \u00e9chou\u00e9 \u00e0 r\u00e9aliser leurs deux principaux     objectifs : le r\u00e8glement de la question palestinienne et la construction de     l\u2019unit\u00e9 arabe (ou celle de la Oumma islamique). De m\u00eame, les adeptes de la     modernit\u00e9 parmi les chefs d\u2019\u00c9tat &#8211; Mustapha Kemal, Riza Chah, Bourguiba &#8211; et     les intellectuels, qui ont cru pouvoir \u00ab se d\u00e9barrasser de l\u2019islam d\u2019un     trait de plume \u00bb, ont-ils vite d\u00fb se rendre \u00e0 la r\u00e9alit\u00e9, en constatant     l\u2019irr\u00e9pressible mont\u00e9e de l\u2019islamisme.           Ce mouvement enracin\u00e9 dans \u00ab la conscience d\u2019un patrimoine commun fond\u00e9 sur     la religion islamique a donc \u00e9t\u00e9 une cons\u00e9quence directe de \u00ab l\u2019effet     d\u00e9vastateur des modernisations \u00e0 outrance \u00bb. Car, comme l\u2019\u00e9crit Dja\u00eft, \u00ab     plus la s\u00e9cularisation s\u2019affirmait dans l\u2019\u00c9tat, la l\u00e9gislation, les m\u0153urs,     plus les positions de refus se durcissaient, jusqu\u2019\u00e0 ce que l\u2019on arriv\u00e2t, [comme]     en \u00c9gypte, \u00e0 la cr\u00e9ation de l\u2019association des Fr\u00e8res musulmans qui d\u00e9riva de     plus en plus vers l\u2019action politique et de propagande \u00bb.           L\u2019auteur de La Grande Discorde dissocie l\u2019islam politique actuel et l\u2019islam     traditionnel. Selon lui, \u00ab le mouvement islamiste n\u2019a ni dimension     religieuse profonde, ni dimension culturelle et intellectuelle marqu\u00e9e du     sceau de la religion, car ses bases intellectuelles sont faibles. Il a tout     simplement voulu d\u00e9passer le \u2018\u2018bricolage\u201d des r\u00e9formistes, s\u2019opposer \u00e0     l\u2019expulsion de la religion hors du domaine politique et de celui de la     l\u00e9gislation, s\u2019opposer aussi \u00e0 la passivit\u00e9 des dirigeants politiques face     aux influences ext\u00e9rieures \u00bb.           Qualifi\u00e9 tour \u00e0 tour de \u00ab force fracassante d\u2019affirmation du Moi \u00bb ou de \u00ab     r\u00e9action identitaire, d\u2019orgueil d\u00e9sesp\u00e9r\u00e9 parce que ni\u00e9 \u00bb, l\u2019islamisme est     aussi, selon l\u2019auteur, une force de r\u00e9sistance \u00e0 la puissance envahissante     de l\u2019Occident. Mais face \u00e0 cet Occident, qui, \u00ab apr\u00e8s avoir v\u00e9cu une     histoire tourment\u00e9e et cruelle, en est venu \u00e0 refuser la mort du fait de la     g\u00e9n\u00e9ralisation du bien-\u00eatre et de la vigueur du sentiment de soi \u00bb, \u00ab les     musulmans activistes n\u2019ont qu\u2019un seul atout entre leurs mains : la mort     subie et inflig\u00e9e \u00bb.           Tout en critiquant cette \u00ab force identitaire en lutte pour la vie et la     reconnaissance \u00bb, Dja\u00eft admet cependant qu\u2019elle est, depuis un quart de     si\u00e8cle, la seule force unificatrice du monde musulman, m\u00eame si ses points de     vue, aspirations et d\u00e9marches ne sont pas partag\u00e9s par tous les musulmans.              \u00c0 travers la r\u00e9islamisation de la soci\u00e9t\u00e9, les islamistes visent, on le sait,     la prise du pouvoir. Et pour y parvenir, tous les moyens sont bons \u00e0 leurs     yeux : les urnes (de pr\u00e9f\u00e9rence), mais aussi la violence (si n\u00e9cessaire). Et     si la r\u00e9volution islamiste parvenait \u00e0 s\u2019emparer du pouvoir ? Selon l\u2019auteur,     les islamistes ne pourraient pas le garder longtemps, \u00ab car on assisterait     obligatoirement \u00e0 un retour en force de la modernit\u00e9 et \u00e0 un abandon complet     de l\u2019islam. C\u2019est que le courant de la modernit\u00e9 est un torrent auquel on ne     peut r\u00e9sister, parce qu\u2019il coule dans le sens de l\u2019Histoire \u00bb.           Pour justifier son optimisme, l\u2019historien puise ses arguments dans le pass\u00e9     de l\u2019humanit\u00e9. \u00ab L\u2019examen de l\u2019histoire et de la pr\u00e9histoire, \u00e9crit-il,     permet de voir que chaque groupe humain qui innove finit par vaincre ceux     qui se maintiennent dans l\u2019ancien syst\u00e8me, que ce soit dans le domaine de la     technologie ou dans celui du mode de vie. \u00bb Or, depuis un demi-si\u00e8cle, \u00ab     c\u2019est l\u2019Occident qui est le novateur fondamental, et son r\u00f4le est loin     d\u2019\u00eatre termin\u00e9 \u00bb, ajoute-t-il.           \u00ab La modernit\u00e9 \u00e9tant aujourd\u2019hui la derni\u00e8re \u00e9tape de l\u2019\u00e9volution de     l\u2019humanit\u00e9 depuis la pr\u00e9histoire, elle impr\u00e9gnera obligatoirement toutes les     soci\u00e9t\u00e9s, de m\u00eame que la civilisation agraire toucha l\u2019ensemble de     l\u2019humanit\u00e9, ou presque. Par cons\u00e9quent, toutes les th\u00e9orisations, toutes les     interrogations, les luttes, les perplexit\u00e9s en vigueur dans le monde     musulman se situent forc\u00e9ment dans une temporalit\u00e9 passag\u00e8re \u00bb, \u00e9crit Dja\u00eft.     D\u2019autant que \u00ab les soci\u00e9t\u00e9s parviennent intuitivement \u00e0 s\u2019adapter au monde     moderne &#8211; de fait, elles en sont d\u00e9sireuses et assoiff\u00e9es de ses inventions     &#8211; tout en restant en harmonie avec elles-m\u00eames \u00bb.           Le volontarisme \u00e9tant impuissant, par d\u00e9finition, face au changement     perp\u00e9tuel, l\u2019historien appelle les \u00e9lites musulmanes \u00e0 plus d\u2019indulgence     vis-\u00e0-vis des masses : \u00ab Il est s\u00fbr que l\u2019int\u00e9riorisation de la modernit\u00e9     dans ses \u00e9l\u00e9ments fondamentaux &#8211; valeurs, science, structures du politique &#8211;     est extr\u00eamement difficile pour les soci\u00e9t\u00e9s non occidentales. Il y faut du     temps, de l\u2019effort, et surtout une mutation dans les valeurs. \u00bb Ce profond     changement de valeurs pourrait donc \u00ab exiger la succession de plusieurs     g\u00e9n\u00e9rations, d\u2019autant plus que la situation politique actuelle ne favorise     pas l\u2019acceptation des valeurs \u00e9manant de l\u2019Occident, mais conduit \u00e0     consid\u00e9rer celui-ci comme un exploiteur, un ennemi des Arabes et des     musulmans, un monde sans morale et raciste \u00bb.           La question n\u2019est donc plus de savoir si le monde arabo-musulman va enfin     emprunter le chemin vers la modernit\u00e9, car il s\u2019y est en fait d\u00e9j\u00e0 engag\u00e9     depuis un si\u00e8cle ou deux, mais d\u2019estimer le temps qu\u2019il mettra \u00e0 rejoindre     le convoi, la lenteur \u00e9tant, malgr\u00e9 tout, naturelle, aux yeux de l\u2019auteur,     tant les retards accumul\u00e9s et les blocages observ\u00e9s sont \u00e9normes.           <strong><font>(Source : Jeune Afrique, N\u00b0 2379-2380 du 13 au     26 ao\u00fbt 2006)<\/font><\/strong> \u00a0<\/font><\/div>\n<\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"> <font face=\"Arial\"><strong><\/p>\n<h2 style=\"color: red;\"><font size=\"3\">La khobza connexion<\/font><\/h2>\n<p><\/strong><\/font><\/div>\n<div align=\"justify\"> <strong><font>Par Soraya Messaoudi<\/font><\/strong><\/div>\n<div align=\"justify\"> <font>Un constat s\u2019impose : de moins en moins de Fran\u00e7ais sont   attir\u00e9s par les m\u00e9tiers de bouche et en particulier la boulangerie. M\u00e9tier   difficile s\u2019il en est.<\/font><\/div>\n<div align=\"justify\"> <font>Du coup un lobbying tunisien est en train de s\u00e9vir sur   ce business dans nos banlieues ! Plus s\u00e9rieusement, un ph\u00e9nom\u00e8ne \u00e9trange se   produit \u00e0 Bondy, comme dans d\u2019autres banlieues peut-\u00eatre, puisque toutes les   boulangeries sont peu \u00e0 peu rachet\u00e9es par des Nord-Africains. A Bondy sur une   vingtaine de boulangeries plus d\u2019une douzaine sont tenues par des Maghr\u00e9bins.<\/font><\/div>\n<div align=\"justify\"> <font>Grand symbole fran\u00e7ais, la baguette nationale subit l\u00e0   un grand revers.<\/font><\/div>\n<div align=\"justify\"> <font>Comment expliquer ce ph\u00e9nom\u00e8ne ? La qualit\u00e9 du pain s\u2019en   trouve- t-elle affect\u00e9e ?<\/font><\/div>\n<div align=\"justify\"> <font>Pourquoi ces m\u00e9tiers sont-ils d\u00e9laiss\u00e9s par les Fran\u00e7ais   dits de souche ?<\/font><\/div>\n<div align=\"justify\"> <font>Une partie des r\u00e9ponses peut para\u00eetre simpliste mais un   facteur incontestable est d\u00fb au fait que le pain est un aliment incontournable   de l\u2019art culinaire au Maghreb, il est indispensable pour accompagner les   repas. Il y a donc un attrait certain pour le pain qui explicite cet   engouement.<\/font><\/div>\n<div align=\"justify\"> <font>J\u2019ai discut\u00e9 avec mon boulanger, un jeune homme de 24   ans qui travaille dans la boulangerie de ses parents, afin d\u2019en savoir un peu   plus.<\/font><\/div>\n<div align=\"justify\"> <strong>Depuis combien de temps es-tu install\u00e9 \u00e0 Bondy ?<\/strong><\/div>\n<div align=\"justify\">     Cela fait quatre ans que mes parents ont achet\u00e9 cette boulangerie et depuis on   y travaille en famille, nous sommes trois fr\u00e8res et une s\u0153ur.<\/div>\n<div align=\"justify\"> <strong>De quelle origine es-tu ?<\/strong><\/div>\n<div align=\"justify\">     Ma m\u00e8re est fran\u00e7aise et mon p\u00e8re est tunisien.<\/div>\n<div align=\"justify\"> <strong>Quelle est ta formation ?<\/strong><\/div>\n<div align=\"justify\">     J\u2019ai un bac \u00e9lectro-technique puis j\u2019ai fait des \u00e9tudes sup\u00e9rieures de   commerce tout comme mon fr\u00e8re a\u00een\u00e9. Au d\u00e9part rien ne me destinait \u00e0 la   boulangerie et puis nous avons d\u00e9cid\u00e9 de travailler avec nos parents. Il leur   fallait quelqu\u2019un de confiance pour les seconder et les \u00e9pauler.<\/div>\n<div align=\"justify\"> <strong>Que penses-tu du fait que beaucoup de boulangeries sont rachet\u00e9es par   des gens d\u2019origine \u00e9trang\u00e8re ?<\/strong><\/div>\n<div align=\"justify\">     C\u2019est un m\u00e9tier tr\u00e8s dur, fatigant qui demande un grand investissement et   certains n\u2019ont plus envie de travailler dur. Les journ\u00e9es sont tr\u00e8s longues,   on commence assez t\u00f4t pour finir souvent tard.<\/div>\n<div align=\"justify\">     Les \u00e9trangers \u00e7a ne les d\u00e9range pas, ils sont habitu\u00e9s. Certains venus   s\u2019installer sur le tard travaillaient d\u00e9j\u00e0 dans leur pays d\u2019origine et ce   n\u2019\u00e9tait pas forc\u00e9ment facile et \u00e9vident pour eux.<\/div>\n<div align=\"justify\"> <strong>Peux-tu me parler de ta client\u00e8le ?<\/strong><\/div>\n<div align=\"justify\">     Dans le quartier la population est tr\u00e8s vari\u00e9e, les \u00e9trangers vont souvent   pr\u00e9f\u00e9rer la baguette pratique pour les familles nombreuses, les Fran\u00e7ais   pr\u00e9f\u00e8rent une tradition ou une baguette de campagne. Pendant la p\u00e9riode   estivale du fait des r\u00e9gimes, il y a une plus grande demande en pains sp\u00e9ciaux   comme le son ou le complet.<\/div>\n<div align=\"justify\">     La boulangerie est tr\u00e8s accueillante et le choix y est vari\u00e9. Depuis peu \u00e0   c\u00f4t\u00e9 des p\u00e2tisseries classiques sont m\u00eames propos\u00e9es des p\u00e2tisseries   orientales.<\/div>\n<div align=\"justify\">     Derri\u00e8re le comptoir tr\u00f4ne une belle pi\u00e8ce en sucre, sorte de troph\u00e9e que le   p\u00e2tissier a r\u00e9alis\u00e9 r\u00e9cemment lors d\u2019un stage de formation duquel il est   rentr\u00e9 dipl\u00f4m\u00e9.<\/div>\n<div align=\"justify\">     C\u2019est un nouveau visage de la France, multiculturel, et il faut dor\u00e9navant   compter avec.<\/div>\n<div align=\"justify\">     En effet apr\u00e8s avoir discut\u00e9 avec un \u00e9l\u00e8ve en boulangerie et lui avoir pos\u00e9   quelques questions j\u2019ai appris que dans sa promo sur 11 \u00e9l\u00e8ves, 8 \u00e9taient   maghr\u00e9bins, 2 Africains et 1 Fran\u00e7ais.<\/div>\n<div align=\"justify\"> <strong><font>(Source : Bondy Blog, lundi 21 aout 2006 \u00e0   11h24)<\/font><\/strong><\/div>\n<div align=\"justify\">     Lien : <a href=\"http:\/\/previon.typepad.com\/hebdo\/2006\/08\/la_khobza_conne.html\" target=\"_blank\" rel=\"noopener\">  http:\/\/previon.typepad.com\/hebdo\/2006\/08\/la_khobza_conne.html<\/a><\/div>\n<div align=\"justify\">\n<hr\/>\n<\/div>\n<div align=\"justify\">  \u00a0<\/div>\n<div align=\"justify\">\n<div align=\"center\"> <font face=\"Arial\" size=\"2\"><strong><font>AMNESTY     INTERNATIONAL      <\/font>COMMUNIQU\u00c9 DE PRESSE<\/strong>          Index AI : MDE 02\/018\/2006 (Public)     Bulletin n\u00b0 : 219     \u00c9FAI     23 ao\u00fbt 2006          Embargo : 23 ao\u00fbt 2006 00h01 TU          <strong><\/p>\n<p><font size=\"3\">Isra\u00ebl\/Liban. Des \u00e9l\u00e9ments montrent     que des infrastructures civiles ont \u00e9t\u00e9 d\u00e9lib\u00e9r\u00e9ment d\u00e9truites<\/font><\/p>\n<p><\/strong> \u00a0<\/font><\/div>\n<div>              Amnesty International a rendu publics ce mercredi 23 ao\u00fbt 2006 les r\u00e9sultats     d&rsquo;investigations montrant qu&rsquo;Isra\u00ebl a mis en \u0153uvre lors du conflit r\u00e9cent     une politique d\u00e9lib\u00e9r\u00e9e de destruction d&rsquo;infrastructures civiles libanaises,     qui s&rsquo;est traduite dans certains cas par des crimes de guerre.           Les derni\u00e8res informations publi\u00e9es par l&rsquo;organisation montrent que la     destruction par Isra\u00ebl de milliers d&rsquo;habitations, ainsi que les frappes qui     visaient de nombreux ponts et routes et des installations de stockage de     l&rsquo;eau et du carburant, faisaient partie int\u00e9grante d&rsquo;une strat\u00e9gie militaire     au Liban et ne constituaient pas des \u00abdommages collat\u00e9raux\u00bb r\u00e9sultant de la     prise pour cibles l\u00e9gitime d&rsquo;objectifs militaires.          Le rapport renforce la n\u00e9cessit\u00e9 de l&rsquo;ouverture urgente par les Nations     unies d&rsquo;une enqu\u00eate exhaustive et ind\u00e9pendante sur les graves violations du     droit international humanitaire dont se sont rendus coupables le Hezbollah     et Isra\u00ebl pendant le conflit qui les a oppos\u00e9s un mois durant.           \u00abL&rsquo;affirmation par Isra\u00ebl que les attaques des infrastructures \u00e9taient     l\u00e9gales est de toute \u00e9vidence erron\u00e9e, a d\u00e9clar\u00e9 Kate Gilmore, secr\u00e9taire     g\u00e9n\u00e9rale adjointe ex\u00e9cutive d&rsquo;Amnesty International. Nombre de violations     d\u00e9crites dans notre rapport, telles que des attaques disproportionn\u00e9es et     men\u00e9es sans discrimination, constituent des crimes de guerre. Les \u00e9l\u00e9ments     sugg\u00e8rent fortement que la destruction massive de centrales d&rsquo;eau et     d&rsquo;\u00e9lectricit\u00e9 et d&rsquo;infrastructures indispensables au transport de la     nourriture et de l&rsquo;aide humanitaire \u00e9tait d\u00e9lib\u00e9r\u00e9e et s&rsquo;inscrivait dans une     strat\u00e9gie militaire.\u00bb          Le gouvernement isra\u00e9lien a affirm\u00e9 qu&rsquo;il prenait pour cibles les positions     et les installations auxiliaires du Hezbollah et que les autres dommages     occasionn\u00e9s aux infrastructures civiles \u00e9taient dus au fait que le Hezbollah     avait utilis\u00e9 la population civile comme \u00abbouclier humain\u00bb.          \u00abLe mode, l&rsquo;\u00e9tendue et l&rsquo;intensit\u00e9 des attaques \u00f4tent toute cr\u00e9dibilit\u00e9 \u00e0     l&rsquo;affirmation d&rsquo;Isra\u00ebl selon laquelle il s&rsquo;agirait de dommages collat\u00e9raux\u00bb,     a d\u00e9clar\u00e9 Kate Gilmore.          \u00abLes victimes civiles des deux parties au conflit ont droit \u00e0 la justice. La     gravit\u00e9 des violations commises rend d&rsquo;autant plus urgente la tenue d&rsquo;une     enqu\u00eate sur la conduite des deux parties. Il faut que les auteurs de crimes     de guerre rendent des comptes et que les victimes obtiennent r\u00e9paration.\u00bb          Intitul\u00e9 Deliberate destruction or &lsquo;collateral damage&rsquo;? Israeli attacks     against civilian infrastructure, le rapport s&rsquo;appuie sur des informations de     premi\u00e8re main que l&rsquo;organisation a rassembl\u00e9es lors des entretiens avec des     dizaines de victimes, de repr\u00e9sentants des Nations unies, des Forces de     d\u00e9fense d&rsquo;Isra\u00ebl (FDI) et du gouvernement libanais qu&rsquo;elle a r\u00e9alis\u00e9s au     cours de missions de recherche r\u00e9centes au Liban et en Isra\u00ebl. Certaines     informations du rapport proviennent de d\u00e9clarations officielles et de la     presse.           Le rapport contient des \u00e9l\u00e9ments faisant \u00e9tat :          &#8211; de la destruction massive par les forces isra\u00e9liennes de quartiers et de     villages civils ;     &#8211; d&rsquo;attaques de ponts dans des zones n&rsquo;ayant pas d&rsquo;importance strat\u00e9gique     flagrante ;     &#8211; d&rsquo;attaques de stations de pompage et de traitement des eaux et de     supermarch\u00e9s, en d\u00e9pit de l&rsquo;interdiction de prendre pour cibles des     objectifs indispensables \u00e0 la survie de la population civile ;     &#8211; de d\u00e9clarations de responsables militaires isra\u00e9liens indiquant que la     destruction d&rsquo;infrastructures civiles faisait effectivement partie des     objectifs de la campagne militaire isra\u00e9lienne visant \u00e0 dresser la     population et le gouvernement libanais contre le Hezbollah.           Le rapport d\u00e9crit un mod\u00e8le d&rsquo;attaques disproportionn\u00e9es et men\u00e9es sans     discrimination, qui ont provoqu\u00e9 le d\u00e9placement de 25 p. cent de la     population civile. Ce mod\u00e8le, rattach\u00e9 aux d\u00e9clarations officielles, montre     que les attaques sur les infrastructures \u00e9taient d\u00e9lib\u00e9r\u00e9es et non pas     inh\u00e9rentes \u00e0 la poursuite d&rsquo;objectifs militaires l\u00e9gaux.           Amnesty International lance un appel en faveur de l&rsquo;ouverture de toute     urgence par les Nations unies d&rsquo;une enqu\u00eate exhaustive, ind\u00e9pendante et     impartiale sur les violations du droit international humanitaire commises     par les deux parties au conflit. L&rsquo;enqu\u00eate devra porter en particulier sur     les cons\u00e9quences de ce conflit sur la population civile ; elle devra avoir     pour objectif de d\u00e9terminer la responsabilit\u00e9 des individus dans les crimes     de droit international qui ont \u00e9t\u00e9 commis et d&rsquo;accorder des r\u00e9parations aux     victimes.          Le rapport Deliberate destruction or &lsquo;collateral damage&rsquo;? Israeli attacks     against civilian infrastructure (index AI : MDE 18\/007\/2006) est disponible     sur le site de l&rsquo;organisation, \u00e0 l&rsquo;adresse suivante : http:\/\/web.amnesty.org\/library\/index\/engmde180072006)                   Document public     Pour obtenir de plus amples informations, veuillez contacter le Service de     presse d&rsquo;Amnesty International \u00e0 Londres, au +44 20 7413 5566     Amnesty International, 1 Easton St., Londres WC1X 0DW. web : http:\/\/www.amnesty.org              Index AI: MDE 02\/018\/2006\u00a0\u00a0\u00a0\u00a0\u00a0 23 Ao\u00fbt 2006<\/div>\n<\/div>\n<div align=\"justify\">  \u00a0<\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"> <strong><font face=\"Arial\"><\/p>\n<h3 style=\"color: blue;\"><font size=\"3\">L&rsquo;AFP, porte-parole   De Tsahal?<\/font><\/h3>\n<p><font>\u00ab\u00a0Isra\u00ebl arr\u00eate le vice-Premier ministre   palestinien, membre du Hamas<\/font><\/font><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\">19 ao\u00fbt 2006 &#8211; 04:59      RAMALLAH (Cisjordanie), 19 ao\u00fbt 2006 (AFP) &#8211; Des soldats isra\u00e9liens ont arr\u00eat\u00e9   samedi matin le vice-Premier ministre palestinien, membre du Hamas, Nasser   Shaer, a-t-on appris de source palestinienne.      <font>M. Shaer a \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 son domicile \u00e0 04H30 (01H30   GMT), a d\u00e9clar\u00e9 \u00e0 l\u2019AFP son \u00e9pouse, Huda.   Selon des sources de la s\u00e9curit\u00e9 palestinienne, quelque 30 v\u00e9hicules de   l\u2019arm\u00e9e isra\u00e9lienne ont p\u00e9n\u00e9tr\u00e9 dans la ville de Ramallah pour effectuer   l\u2019arrestation\u00a0\u00bb      Dans une d\u00e9p\u00eache que nous reproduisons int\u00e9gralement ci-dessus, l\u2019Agence   France Presse annonce : \u00ab Isra\u00ebl arr\u00eate le vice-Premier ministre palestinien,   membre du Hamas \u00bb.   <\/font> <strong>Ce titre comprend deux erreurs :<\/strong>      Isra\u00ebl, qui occupe ill\u00e9galement la bande de Gaza, n\u2019a pas qualit\u00e9 pour y   proc\u00e9der \u00e0 des arrestations. En droit international, il s\u2019agit d\u2019un enl\u00e8vement   et sa mise en d\u00e9tention constitue une s\u00e9questration. M. Shaer, comme 4 autres   ministres et 26 d\u00e9put\u00e9s actuellement s\u00e9questr\u00e9s, est un otage destin\u00e9 \u00e0 \u00eatre   \u00e9chang\u00e9 contre le caporal Gilad Shalit.      Alors que le porte-parole de Tsahal a pr\u00e9sent\u00e9 cette op\u00e9ration comme faisant   partie de \u00ab la lutte contre l\u2019organisation terroriste Hamas \u00bb, M. Shaer n\u2019est   pas membre de ce parti politique. C\u2019est une personnalit\u00e9 qualifi\u00e9e qui a   accept\u00e9 de servir son peuple au sein d\u2019un gouvernement form\u00e9 par le Hamas. Nos   lecteurs se souviennent de l\u2019interview exclusive qu\u2019il donna, il y a deux   semaines, \u00e0 Silvia Cattori pour le R\u00e9seau Voltaire.      Les lecteurs d\u00e9sinform\u00e9s de l\u2019AFP pensent probablement que la qualit\u00e9 de   ministre de M. Shaer ne doit pas le soustraire \u00e0 la justice s\u2019il pratique le   terrorisme. En r\u00e9alit\u00e9, l\u2019enl\u00e8vement de notables par une force d\u2019occupation   pour servir d\u2019otage constitue un crime de guerre.      Source: R\u00e9seau Voltaire      <strong><font>(Article post\u00e9 par Alyssa, le Lundi 21 ao\u00fbt 2006   \u00e0 19h03 sur le forum Taht Essour de nawaat.org )<\/font><\/strong>\u00a0  \u00a0<\/font><\/div>\n<div> <font face=\"Arial\"><\/p>\n<hr\/>\n<p><\/font><\/div>\n<div align=\"center\"> <strong><\/p>\n<h3 style=\"color: blue;\"><font face=\"Arial\">La bavure de la r\u00e9publique\u00a0   ou la complainte des flics<\/font><\/h3>\n<p><\/strong><\/div>\n<div align=\"justify\"> <font face=\"Arial\" size=\"2\"><font><strong>Andr\u00e9 Monjardet<\/strong><\/font>     andre.monjardet@cegetel.net\u00a0\u00a0\u00a0\u00a0\u00a0       <\/font><font face=\"Arial\" size=\"2\"><strong><font>J&rsquo;peux faire   des trous dans Mohammed      J&rsquo;suis pas adroit mais j&rsquo;ai le droit      J&rsquo;peux tabasser la marocaine      J&rsquo;ai tous les droits      J&rsquo;ai pas de haine      Je suis couvert, j&rsquo;suis policier.      Je suis couvert,      c&rsquo;est moi l&rsquo;Etat,      c&rsquo;est moi la loi.      J&rsquo;passe ma journ\u00e9e dans les quartiers      \u00e0 pourchasser les \u00e9migr\u00e9s,      et \u00e0 faire chier les sans papiers      J&rsquo;suis policier pour les faire chier.      De temps en temps j&rsquo;en ram\u00e8ne un      pour distraire les policiers      et avoir droit de\u00a0 l&rsquo;tabasser      J&rsquo;traque les p\u00e9tards,      J&rsquo;matraque les f\u00eatards,      J&rsquo;arnaque les chauffards      J&rsquo;ai tous les droits, c&rsquo;est moi la loi      Je suis couvert, j&rsquo;suis policier      Je donne la mort \u00e0 bout touchant      Je donne la mort \u00e0 tout bout de champ      sans l&rsquo;intention de la donner.      J&rsquo;ai tous les droits, c&rsquo;est moi la loi.      La R\u00e9publique, je me la nique,      l&rsquo;Alg\u00e9rienne, je me la trique,      je suis couvert j&rsquo;suis policier,      c&rsquo;est moi la loi,\u00a0 j&rsquo;ai tous les droits.      Je suis couvert, j&rsquo;suis policier.   <\/font><\/strong> <strong><font>Weblog : http:\/\/perso.orange.fr\/monjardet\/<\/font><\/strong><\/font><\/div>\n<hr\/>\n<p align=\"center\"><b><a href=\"http:\/\/www.tunisnews.net\"><span>Home<\/span><span lang=\"FR-CH\"> &#8211; Accueil <\/span><span>&#8211; <\/span><span dir=\"rtl\" lang=\"AR-SA\">\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/span><\/a><\/b><\/p>\n<p align=\"center\">\u00a0<\/p>\n<p><\/body><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home &#8211; Accueil &#8211; \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629 TUNISNEWS 7\u00a0\u00e8me\u00a0ann\u00e9e, N\u00b0\u00a02284 du 23.08.2006 \u00a0archives : www.tunisnews.net L\u2019ACAT demande que les prisonniers tunisiens re\u00e7oivent dans les h\u00f4pitaux et aupr\u00e8s de sp\u00e9cialistes les soins ad\u00e9quats auxquels ils ont droit La Libert\u00e9 : Malika el-Aroud quitte la Suisse Tribune de Gen\u00e8ve : De Tunis \u00e0 Bagdad, la femme arabe dans tous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[],"tags":[60,37,29],"class_list":["post-15802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-60","tag-37","tag-fr"],"_links":{"self":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/15802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/comments?post=15802"}],"version-history":[{"count":0,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/posts\/15802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/media?parent=15802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/categories?post=15802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tunisnews.net\/ar\/wp-json\/wp\/v2\/tags?post=15802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}